{"id":585317,"date":"2026-04-17T11:04:38","date_gmt":"2026-04-17T09:04:38","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/"},"modified":"2026-04-17T11:04:41","modified_gmt":"2026-04-17T09:04:41","slug":"cour-superieure-de-justice-1-juillet-2025-3","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 1 juillet 2025"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Arr\u00eatN\u00b0276\/25V. du1 er juillet2025 (Not.23117\/24\/CD) La Cour d&#039;appel du Grand-Duch\u00e9 de Luxembourg, cinqui\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu en son audience publique dupremier juillet deux millevingt-cinql\u2019arr\u00eat qui suit dans la cause e n t r e : leminist\u00e8republic, exer\u00e7ant l&#039;action publique pour la r\u00e9pression des crimes et d\u00e9lits,appelant, e t : PERSONNE1.),n\u00e9 leDATE1.)\u00e0ADRESSE1.)au Nig\u00e9ria,actuellement d\u00e9tenu au Centre p\u00e9nitentiaire d\u2019Uerschterhaff, pr\u00e9venuetappelant. F A I T S : Les faits et r\u00e9troactes de l&#039;affairer\u00e9sultent \u00e0 suffisance de droitd&#039;un jugementrenducontradictoirementpar le tribunal d&#039;arrondissement de Luxembourg,septi\u00e8mechambre,si\u00e9geant en mati\u00e8re correctionnelle,le27 f\u00e9vrier 2025, sous le num\u00e9ro622\/2025,dont les consid\u00e9rants et le dispositif sont con\u00e7us comme suit:<\/p>\n<p>2 \u00abjugement\u00bb<\/p>\n<p>3 Contrecejugement,appelfutinterjet\u00e9pard\u00e9clarationaugreffe du tribunal d\u2019arrondissement de Luxembourgle6 mars 2025, au p\u00e9nal,parlemandataire du pr\u00e9venuPERSONNE1.), ainsi qu\u2019en date du7 mars 2025, au p\u00e9nal, par le minist\u00e8re public. En vertu de cesappelset par citation du30 avril2025,le pr\u00e9venuPERSONNE1.) futr\u00e9guli\u00e8rement requisde compara\u00eetre \u00e0 l\u2019audience publique du30 mai2025, devant la Cour d&#039;appel de Luxembourg,cinqui\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, pour y entendre statuer sur le m\u00e9rite desappelsinterjet\u00e9s. A cetteaudience,le pr\u00e9venuPERSONNE1.),assist\u00e9 de l\u2019interpr\u00e8te asserment\u00e9e Martine WEITZEL, etapr\u00e8s avoir \u00e9t\u00e9 averti de son droit de se taire et de ne pas s\u2019incriminerlui-m\u00eame, fut entendu en ses explications et d\u00e9clarations personnelles. Ma\u00eetrePhilippe STROESSER, avocat \u00e0 la Cour, demeurant \u00e0Luxembourg, d\u00e9veloppa plus amplement les moyens de d\u00e9fense et d\u2019appel du pr\u00e9venu PERSONNE1.). Madamel\u2019avocat g\u00e9n\u00e9ralJo\u00eblle NEIS, assumant les fonctions de minist\u00e8re public, fut entendueen son r\u00e9quisitoire. Lepr\u00e9venuPERSONNE1.), d\u00e9clarant renoncer \u00e0 la traduction du pr\u00e9sent arr\u00eat, eut la parole en dernier. L A C O U R prit l&#039;affaire en d\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l&#039;audience publique du1 er juillet2025, \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9, l&#039;arr\u00eatqui suit: Par d\u00e9claration du 6 mars 2015 au greffe du tribunal d\u2019arrondissement de Luxembourg,PERSONNE1.), a fait interjeter appel au p\u00e9nal contrele jugement n\u00b0 622\/2025 rendu contradictoirement \u00e0 son \u00e9gard par une chambre correctionnelle du tribunal d\u2019arrondissement en date du 27 f\u00e9vrier 2025. Le jugement attaqu\u00e9 est reproduit aux qualit\u00e9s du pr\u00e9sent arr\u00eat. Par d\u00e9claration du 6 mars 2025, d\u00e9pos\u00e9e le 7 mars 2025 au greffe du tribunal d\u2019arrondissement de Luxembourg, le procureur d\u2019Etat de Luxembourg a, \u00e0 son tour, fait interjeter appel au p\u00e9nal limit\u00e9 \u00e0PERSONNE1.)contre ce m\u00eame jugement. Ces appels, relev\u00e9s en conformit\u00e9 de l\u2019article 203 du Code de proc\u00e9dure p\u00e9nale et end\u00e9ans le d\u00e9lai l\u00e9gal, sont recevables. PERSONNE1.)fut condamn\u00e9 par ledit jugement \u00e0 une peine d\u2019emprisonnement de vingt-quatre mois et \u00e0 une amende de 1.500 euros pour avoir, depuis le mois d\u2019avril 2024 jusqu\u2019au 19 juin 2024 et notamment le 19 juin 2024, commis des infractions aux articles 8.1 a), 8.1.b)et 8-1 de la loi modifi\u00e9e du 19 f\u00e9vrier 1973<\/p>\n<p>4 concernant la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie et au r\u00e8glement grand-ducal du 26 mars 1974. A l\u2019audience de la Cour du 30 mai 2025,PERSONNE1.)n\u2019a pas contest\u00e9 les faits, mais a estim\u00e9 que la peine prononc\u00e9e \u00e0 son encontre est trop s\u00e9v\u00e8re. Il a exprim\u00e9 ses regrets et a affirm\u00e9 avoir appris la le\u00e7on. Il a mis en exergue qu\u2019il est consommateur de stup\u00e9fiants et qu\u2019il vendait des drogues essentiellement pour financer sa consommation. A sa sortie de prison, il serait ainsi amen\u00e9 \u00e0 faire une th\u00e9rapie contre son addiction. Son mandataire sollicite, par r\u00e9formation de la d\u00e9cision dont appel, \u00e0 voir r\u00e9duire le quantum de la peine d\u2019emprisonnement prononc\u00e9e \u00e0 une peine qui ne d\u00e9passerait pas les dix-huit mois et de faire abstraction du prononc\u00e9 d\u2019une amende. Reconnaissant que son mandant a des ant\u00e9c\u00e9dents sp\u00e9cifiques, il rel\u00e8ve que, depuis sa sortie de prison en 2019, il n\u2019y a plus eu de condamnation. Il y aurait \u00e9galement lieu de prendre en consid\u00e9ration que le pr\u00e9venu a fait des aveux d\u00e8s son arrestation. Concernant sa situation personnelle, il explique que son mandant s\u2019est mari\u00e9 en 2017 avec une femme de nationalit\u00e9 slovaque, qu\u2019il a un enfant de dix ans, qu\u2019il est venu en 2020 en Belgique et qu\u2019il a rejoint le Luxembourg en 2024. Il serait dans une situation financi\u00e8re pr\u00e9caire, ce d\u2019autant plus qu\u2019il devrait supporter les frais de justice de plus de 4.000 euros. La repr\u00e9sentante du minist\u00e8re public a d\u00e9clar\u00e9 ne pas s\u2019opposer \u00e0 la suppression de l\u2019amende, mais conclut pour le surplus \u00e0 la confirmation de la d\u00e9cision entreprise. Les faits r\u00e9sulteraient autant des constatations de la police, dont la fouille personnelle du pr\u00e9venu lors de laquelle 73 boules de coca\u00efne auraient \u00e9t\u00e9 trouv\u00e9es sur le pr\u00e9venu que des t\u00e9moignages recueillis, dont celui de PERSONNE2.)qui donnerait des pr\u00e9cisions sur la fr\u00e9quence des ventes de stup\u00e9fiants par le pr\u00e9venu, de sorte que la d\u00e9claration de culpabilit\u00e9 du pr\u00e9venu serait \u00e0 confirmer. Les r\u00e8gles du concours d\u2019infractions auraient correctement \u00e9t\u00e9 appliqu\u00e9es. Les peines prononc\u00e9es seraient l\u00e9gales et ad\u00e9quates au vu de la quantit\u00e9 importante de stup\u00e9fiants trouv\u00e9e sur le pr\u00e9venu. Appr\u00e9ciation de la Cour Les d\u00e9bats en instance d\u2019appel n\u2019ont pas apport\u00e9 de faits nouveaux par rapport \u00e0 ceux qui ont \u00e9t\u00e9 soumis \u00e0 l\u2019appr\u00e9ciation de la chambre correctionnelle du tribunal d\u2019arrondissement. Il se d\u00e9gage ainsi du dossier p\u00e9nal et notamment de l\u2019audition de t\u00e9moins, des constatations et observations des agents verbalisants, de l\u2019exploitation du t\u00e9l\u00e9phone du pr\u00e9venu et des expertises toxicologiques tout comme des aveux du pr\u00e9venu qu\u2019il a, durant les mois d\u2019avril 2024 jusqu\u2019au 19 juin 2024 vendu de la coca\u00efne et de l\u2019h\u00e9ro\u00efne \u00e0 diff\u00e9rentes personnes dontPERSONNE2.)et qu\u2019il a d\u00e9tenu aux fins dudit trafic, des grandes quantit\u00e9s de stup\u00e9fiants dont 50 boules<\/p>\n<p>5 de coca\u00efne et 23 boules d\u2019h\u00e9ro\u00efne saisies sur sa personne le 19 juin 2024 tout comme le produit des ventes dont 725 euros et un t\u00e9l\u00e9phone portable. Les infractions retenues sont partant rest\u00e9es \u00e9tablies en instance d\u2019appel. Les r\u00e8gles du concours d\u2019infractions ont \u00e9t\u00e9 correctement \u00e9nonc\u00e9es et appliqu\u00e9es. Les peines prononc\u00e9es sont l\u00e9gales. Au regard de la gravit\u00e9 des faits et de la personnalit\u00e9 du pr\u00e9venu qui n\u2019en est pas \u00e0 son premier forfait et qui ne justifie d\u2019aucune activit\u00e9 l\u00e9gale, la peine d\u2019emprisonnement de vingt-quatre mois est \u00e9galement ad\u00e9quate. Le pr\u00e9venu \u00e9tant sans revenus, il y a cependant lieu, par r\u00e9formation de la d\u00e9cision entreprise, de faire abstraction du prononc\u00e9 d\u2019une amende. Le jugement est \u00e0 r\u00e9former en ce senset \u00e0 confirmer pour le surplus aux motifs y retenus. Il convient de maintenir les confiscations aux motifs repris dans le jugement dont appel. P A R C E SM O T I F S : la Cour d\u2019appel, cinqui\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant contradictoirement,lepr\u00e9venuPERSONNE1.)et son mandataireentendusen leursexplications etmoyensde d\u00e9fense,etlarepr\u00e9sentantedu minist\u00e8re public entendueen son r\u00e9quisitoire, re\u00e7oitles appels dePERSONNE1.)et duminist\u00e8re publicen la forme; d\u00e9clareces appels fond\u00e9s; r\u00e9formant: rel\u00e8vePERSONNE1.)du paiement d\u2019une amende de 1.500 (mille cinqcents) euros, ainsi que de la contrainte par corps de 15 (quinze) jours; confirmepour le surplus le jugement entrepris; condamnePERSONNE1.)aux frais de sa poursuite p\u00e9nale en instance d\u2019appel, ces frais liquid\u00e9s \u00e03,75euros. Par application des textes de loi cit\u00e9s par la juridiction de premi\u00e8re instance et des articles 199, 202, 203, 209 et 211 duCode de proc\u00e9dure p\u00e9nale. Ainsi fait et jug\u00e9 par la Cour d&#039;appel du Grand-Duch\u00e9 de Luxembourg, cinqui\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, compos\u00e9e deMadame Nathalie<\/p>\n<p>6 JUNG, pr\u00e9sident de chambre, deMonsieurThierry SCHILTZ,conseiller, etde Madame Tessie LINSTER, conseiller, qui ont sign\u00e9 le pr\u00e9sent arr\u00eat avec Madame Linda SERVATY,greffi\u00e8re. La lecture de l&#039;arr\u00eat a \u00e9t\u00e9 faite en audience publique \u00e0 la Cit\u00e9 Judiciaire, B\u00e2timent CR, Plateau du St. Esprit, par MadameNathalie JUNG, pr\u00e9sident de chambre, en pr\u00e9sence deMadame Monique SCHMITZ,premieravocat g\u00e9n\u00e9ral, et de Madame LindaSERVATY,greffi\u00e8re.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-5-correctionnelle\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-5-correctionnelle\/20250727-230156\/20250701-cach05-276-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arr\u00eatN\u00b0276\/25V. du1 er juillet2025 (Not.23117\/24\/CD) La Cour d&#8217;appel du Grand-Duch\u00e9 de Luxembourg, cinqui\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu en son audience publique dupremier juillet deux millevingt-cinql\u2019arr\u00eat qui suit dans la cause e n t r e : leminist\u00e8republic, exer\u00e7ant l&#8217;action publique pour la\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[19725],"kji_year":[8463],"kji_subject":[7632],"kji_keyword":[15314,8600,9055,12307],"kji_language":[7733],"class_list":["post-585317","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-5-correctionnelle","kji_year-8463","kji_subject-penal","kji_keyword-arretn","kji_keyword-juillet","kji_keyword-justice","kji_keyword-superieure","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 1 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 1 juillet 2025\" \/>\n<meta property=\"og:description\" content=\"Arr\u00eatN\u00b0276\/25V. du1 er juillet2025 (Not.23117\/24\/CD) La Cour d&#039;appel du Grand-Duch\u00e9 de Luxembourg, cinqui\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu en son audience publique dupremier juillet deux millevingt-cinql\u2019arr\u00eat qui suit dans la cause e n t r e : leminist\u00e8republic, exer\u00e7ant l&#039;action publique pour la\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T09:04:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-1-juillet-2025-3\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-1-juillet-2025-3\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 1 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-17T09:04:38+00:00\",\"dateModified\":\"2026-04-17T09:04:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-1-juillet-2025-3\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-1-juillet-2025-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-1-juillet-2025-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 1 juillet 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 1 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/","og_locale":"ru_RU","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 1 juillet 2025","og_description":"Arr\u00eatN\u00b0276\/25V. du1 er juillet2025 (Not.23117\/24\/CD) La Cour d'appel du Grand-Duch\u00e9 de Luxembourg, cinqui\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu en son audience publique dupremier juillet deux millevingt-cinql\u2019arr\u00eat qui suit dans la cause e n t r e : leminist\u00e8republic, exer\u00e7ant l'action publique pour la\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-17T09:04:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"7 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/","name":"Cour sup\u00e9rieure de justice, 1 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-17T09:04:38+00:00","dateModified":"2026-04-17T09:04:41+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-1-juillet-2025-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 1 juillet 2025"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/585317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=585317"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=585317"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=585317"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=585317"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=585317"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=585317"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=585317"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=585317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}