{"id":591795,"date":"2026-04-18T04:13:03","date_gmt":"2026-04-18T02:13:03","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/"},"modified":"2026-04-18T04:13:07","modified_gmt":"2026-04-18T02:13:07","slug":"cour-superieure-de-justice-12-decembre-2024-n-2021-00959","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Arr\u00eat N\u00b0111\/24-VIII-COM Arr\u00eat commercial Audience publique dudouze d\u00e9cembredeux mille vingt-quatre Num\u00e9ro CAL-2021-00959du r\u00f4le Composition: Elisabeth WEYRICH, pr\u00e9sident de chambre, Yola SCHMIT,premier conseiller, Laurent LUCAS,conseiller, Amra ADROVIC, greffier. Entre: la soci\u00e9t\u00e9\u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.),\u00e9tablie et ayant son si\u00e8ge social \u00e0L-ADRESSE1.), inscrite au Registre de Commerce et des Soci\u00e9t\u00e9s de Luxembourg sous le num\u00e9ro NUMERO1.), repr\u00e9sent\u00e9e par song\u00e9rantactuellement en fonctions, appelanteaux termes d\u2019un exploit de l\u2019huissier de justice suppl\u00e9ant Marine HAAGEN, en remplacement de l\u2019huissier de justiceTom NILLESde Luxembourg, du31ao\u00fbt2021, comparaissantpar la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eMOLITOR Avocats \u00e0 la Cour, inscrite sur la liste V du tableau de l\u2019Ordre des avocats du Barreau de Luxembourg, immatricul\u00e9e au Registre de Commerce et des Soci\u00e9t\u00e9s de Luxembourg sous le num\u00e9roB211810, repr\u00e9sent\u00e9e aux fins de la pr\u00e9sente proc\u00e9dure par Ma\u00eetrePaulo LOPES DA SILVA, avocat \u00e0 la Cour, et: 1.PERSONNE1.),demeurant\u00e0L-ADRESSE2.),<\/p>\n<p>2 intim\u00e9aux fins du susdit exploitHAAGEN, comparaissant par Ma\u00eetreEdevi AMEGANDJI, avocat \u00e0 la Cour, demeurant \u00e0Luxembourg, 2.Ma\u00eetreCamille SAETTEL,avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg,pris en sa qualit\u00e9 de curateur dela soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.),\u00e9tablie et ayant son si\u00e8ge social \u00e0L-3440Dudelange,28rueGrande-Duchesse Charlotte, inscrite au Registre de Commerce et des Soci\u00e9t\u00e9s de Luxembourg sous le num\u00e9roB78157,d\u00e9clar\u00e9e en \u00e9tat de faillite suivant jugement rendu le 20 janvier 2017par le tribunal d\u2019arrondissement de Luxembourg, intim\u00e9eaux fins du susdit exploitHAAGEN, comparaissant par elle-m\u00eame, &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; LA COUR D\u2019APPEL Faits et r\u00e9troactes proc\u00e9duraux: Le 30 juin 2015, la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE3.)(ci- apr\u00e8s \u00abla soci\u00e9t\u00e9SOCIETE3.)) a adress\u00e9 \u00e0 la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.)(ci-apr\u00e8s \u00abla soci\u00e9t\u00e9SOCIETE2.)\u00bb) une facture d\u2019un montant de 22.464 euros TTC portant sur la vente d\u2019un v\u00e9hicule de marque Nissan, mod\u00e8le Alteon, portant la plaque d\u2019immatriculation NUMERO2.),ch\u00e2ssis:NUMERO3.)(ci-apr\u00e8s le \u00abCamion\u00bb). Suivant acte intitul\u00e9 \u00abcautionnement solidaire\u00bb du 1 er ao\u00fbt 2015, PERSONNE1.)s\u2019est engag\u00e9 \u00e0 titre de caution solidaire pour garantir le paiement du prix de vente du Camion au b\u00e9n\u00e9fice de la soci\u00e9t\u00e9 SOCIETE3.). Le 23 septembre 2016, la soci\u00e9t\u00e9SOCIETE2.)a c\u00e9d\u00e9 son fonds de commerce \u00e0 la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)(ci- apr\u00e8s\u00abl\u2019SOCIETE1.)\u00bb) au prix de 85.000 euros. Les parties ont convenu que le montant de 63.000 euros devrait \u00eatre vers\u00e9 sur le compte bancaire de la soci\u00e9t\u00e9SOCIETE2.)etle montant de 22.000 euros entre les mains de la soci\u00e9t\u00e9SOCIETE3.)\u00abpour le paiement des engagements concernant l\u2019acquisition et r\u00e9paration du v\u00e9hicule de marque Nissan\u00bb.<\/p>\n<p>3 L\u2019SOCIETE1.)a vir\u00e9 le montant de 63.000 euros \u00e0 la soci\u00e9t\u00e9 SOCIETE2.). Le montant de 22.000 euros n\u2019a pas \u00e9t\u00e9 r\u00e9gl\u00e9 \u00e0 la soci\u00e9t\u00e9SOCIETE3.). La soci\u00e9t\u00e9SOCIETE2.)a \u00e9t\u00e9 d\u00e9clar\u00e9e en \u00e9tat de faillite par jugement du 20 janvier 2017 et Ma\u00eetre Camille SAETTEL en a \u00e9t\u00e9 nomm\u00e9e curateur. Par acte d\u2019huissier de justice du 21 avril 2016,la soci\u00e9t\u00e9SOCIETE3.) a assign\u00e9PERSONNE1.), en sa qualit\u00e9 de caution solidaire, devant le tribunal d\u2019arrondissement de Luxembourg, si\u00e9geant en mati\u00e8re civile, pour le voir condamner \u00e0 lui payer le montant principal de 22.464 euros. Par jugement du 17 novembre 2017, la demande de la soci\u00e9t\u00e9 SOCIETE3.)a \u00e9t\u00e9 d\u00e9clar\u00e9e fond\u00e9e etPERSONNE1.)a \u00e9t\u00e9 condamn\u00e9 \u00e0 lui payer le montant de 22.464 euros, avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 compter du 18 mars 2016 jusqu\u2019\u00e0 solde, ainsi qu\u2019une indemnit\u00e9 de proc\u00e9dure de 1.000 euros. Statuant sur l\u2019appel relev\u00e9 le 22 janvier 2018 parPERSONNE1.).de ce jugement, la Cour d\u2019appel a, par arr\u00eat du 27 juin 2019, confirm\u00e9 le jugement du 17 novembre 2017.PERSONNE1.)a en outre \u00e9t\u00e9 condamn\u00e9 \u00e0 payer une indemnit\u00e9 de proc\u00e9dure de 1.000 euros pour l\u2019instance d\u2019appel. Par acte d\u2019huissier de justice du 9 octobre 2020,PERSONNE1.)a assign\u00e9 l\u2019SOCIETE1.), la soci\u00e9t\u00e9SOCIETE2.)et Ma\u00eetre Camille SAETTEL, en sa qualit\u00e9 de curateur de la soci\u00e9t\u00e9SOCIETE2.), devant le tribunal d\u2019arrondissement deLuxembourg, si\u00e9geant en mati\u00e8re commerciale, pour voir condamner l\u2019SOCIETE1.)\u00e0 lui payer le montant de 22.464 euros, avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 compter du 18 mars 2016, jusqu\u2019\u00e0 solde, au titre des condamnations prononc\u00e9es contre lui sur base du jugement du 17 novembre 2017 et de l\u2019arr\u00eat du 27 juin 2019. PERSONNE1.)a encore conclu \u00e0 la condamnation de l\u2019SOCIETE1.) \u00e0 lui payer, suivant d\u00e9compte actualis\u00e9, le montant de 4.644,90 euros au titre des frais et honoraires d\u2019avocat. Il a sollicit\u00e9 la condamnation de l\u2019SOCIETE1.)au paiement d\u2019une indemnit\u00e9 de 3.500 euros, aux frais et d\u00e9pens de l\u2019instance et \u00e0 voir d\u00e9clarer le jugement \u00e0 intervenir commun \u00e0 la soci\u00e9t\u00e9SOCIETE2.). PERSONNE1.) a bas\u00e9 sa demande \u00e0 titre principal sur la responsabilit\u00e9 d\u00e9lictuelle de l\u2019SOCIETE1.). A titre subsidiaire, il a bas\u00e9 sa demande sur l\u2019article 2028 du Code civil en tant que cautionet a d\u00e9clar\u00e9 exercer l\u2019action oblique pr\u00e9vue par<\/p>\n<p>4 l\u2019article 1166 du Code civil, \u00e9tant donn\u00e9 que la soci\u00e9t\u00e9SOCIETE2.) aurait omis d\u2019exercer une action judiciaire pour faire valoir sa cr\u00e9ance \u00e0 l\u2019encontre de l\u2019SOCIETE1.). Par jugement du 2 juillet 2021, letribunala dit la demande partiellement fond\u00e9e, a condamn\u00e9 l\u2019SOCIETE1.)\u00e0 payer \u00e0 PERSONNE1.)le montant de 24.464 euros,avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 compter de la demande en justice jusqu\u2019\u00e0 solde et a rejet\u00e9 la demande pour le surplus. L\u2019SOCIETE1.)a \u00e9t\u00e9 condamn\u00e9 \u00e0 payer \u00e0 PERSONNE1.)une indemnit\u00e9 de proc\u00e9dure de 1.000 euros, sa propre demande \u00e0 ce titre ayant \u00e9t\u00e9 rejet\u00e9e. Le jugement a \u00e9t\u00e9 d\u00e9clar\u00e9 commun \u00e0 la soci\u00e9t\u00e9SOCIETE2.)en faillite, repr\u00e9sent\u00e9e par Ma\u00eetre Camille SAETEL et l\u2019SOCIETE1.)a \u00e9t\u00e9 condamn\u00e9 \u00e0 supporter les frais et d\u00e9pens de l\u2019instance. Pour statuer ainsi, le tribunal a retenu que la demande de PERSONNE1.)bas\u00e9e sur l\u2019article 1166 du Code civil est irrecevable en vertu du principede la suspension des poursuites individuelles de l\u2019article 452 du Code de commerce. Le tribunal a retenu que dans la mesure o\u00f9PERSONNE1.)a soutenu exercerles droits et actions de la soci\u00e9t\u00e9SOCIETE2.)en sa qualit\u00e9 de cr\u00e9anci\u00e8re de l\u2019SOCIETE1.), il poursuit d\u00e8s lors, en tant que tiers par le biais de l\u2019action oblique, le recouvrement d\u2019une cr\u00e9ance relevant de l\u2019actif de l\u2019organisme failli, une telle action \u00e9tant toutefois r\u00e9serv\u00e9e au curateur seul. Quant au moyen de l\u2019SOCIETE1.)tir\u00e9 de la nullit\u00e9 de lavente de la chose d\u2019autrui en application de l\u2019article 1599 du Code civil, le tribunal a pr\u00e9cis\u00e9, que dans un souci de logique juridique, il doit tout d\u2019abord analyser si la soci\u00e9t\u00e9SOCIETE2.)a c\u00e9d\u00e9 la chose d\u2019autrui \u00e0 l\u2019SOCIETE1.). Le tribunal a relev\u00e9 au regard de la facture du 30 juin 20915 adress\u00e9e par la soci\u00e9t\u00e9SOCIETE3.)\u00e0 la soci\u00e9t\u00e9SOCIETE2.)que celle-ci comporte une clause de r\u00e9serve de propri\u00e9t\u00e9. Il a encore d\u00e9duit du contenu d\u2019une \u00abattestation\u00bb de l\u2019SOCIETE1.)du 22 septembre 2016, ainsi que de la convention de cession du fonds de commerce entre la soci\u00e9t\u00e9SOCIETE2.)et l\u2019SOCIETE1.)du 23 septembre 2016, que nonobstant la mention de deux prix diff\u00e9rents dans lesdites pi\u00e8ces, l\u2019SOCIETE1.)s\u2019est \u00e0 deux reprises express\u00e9ment engag\u00e9e \u00e0 virer le prix de vente du camion en faveur de la soci\u00e9t\u00e9SOCIETE3.), de sorte qu\u2019elle ne pouvait ignorer queSOCIETE2.)n\u2019\u00e9tait pas propri\u00e9taire du camion. Le tribunal a encore relev\u00e9 que le fait que la carte grise n\u2019\u00e9tait pas dat\u00e9e, ne permettait pas d\u2019\u00e9carter la qualit\u00e9 de propri\u00e9taire de la soci\u00e9t\u00e9SOCIETE3.)au moment de la signature du contrat de cession du fonds de commerce. Le tribunal n\u2019a en cons\u00e9quence pas fait droit au moyen tir\u00e9 de la nullit\u00e9 de la vente bas\u00e9e sur l\u2019article 1599 du Code civil.<\/p>\n<p>5 Quant \u00e0 la demande dePERSONNE1.)tendant \u00e0 voir engager la responsabilit\u00e9 d\u00e9lictuelle de l\u2019SOCIETE1.), le tribunal a relev\u00e9, en vertu des principes r\u00e9gissant les charges des preuves qu\u2019il appartient \u00e0PERSONNE1.)d\u2019\u00e9tablir que la soci\u00e9t\u00e9SOCIETE1.)a viol\u00e9 une obligation contractuelle envers la soci\u00e9t\u00e9SOCIETE2.)et que lui- m\u00eame a subi un pr\u00e9judice du fait de la faute commise par l\u2019SOCIETE1.)qui constitue \u00e0 son \u00e9gard une faute d\u00e9lictuelle. Sur base d\u2019une jurisprudence adopt\u00e9e par la Cour de cassation fran\u00e7aise, reprise par la jurisprudence luxembourgeoise, en vertu de laquelle un tiers \u00e0 un contrat peutinvoquer, sur le fondement de la responsabilit\u00e9 d\u00e9lictuelle un manquement contractuel d\u00e8s lors que ce manquement lui a caus\u00e9 un dommage, le tribunal a relev\u00e9 que nonobstant ces engagements pris en date des 22 et 23 septembre 2016 de virer le prix de ventedu camion \u00e0 la soci\u00e9t\u00e9SOCIETE3.), l\u2019SOCIETE1.)n\u2019a pas proc\u00e9d\u00e9 pas au paiement dudit montant, et qu\u2019elle a par cons\u00e9quent commis une faute contractuelle dans le cadre du contrat de cession de fonds de commerce sign\u00e9 avec la soci\u00e9t\u00e9 SOCIETE2.). Quant aupr\u00e9judice subi parPERSONNE1.)en relation causale avec la faute commise par l\u2019SOCIETE1.), le tribunal a relev\u00e9 qu\u2019en l\u2019absence de paiement par l\u2019SOCIETE1.), la soci\u00e9t\u00e9SOCIETE3.)s\u2019est retourn\u00e9e contrePERSONNE1.)en sa qualit\u00e9 de caution solidaire et que parjugement du 17 novembre 2017,PERSONNE1.)a \u00e9t\u00e9 condamn\u00e9 \u00e0 payer \u00e0 la soci\u00e9t\u00e9SOCIETE3.)le montant de 22.464 euros, avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 compter du 18 mars 2016, jusqu\u2019\u00e0 solde, ainsi qu\u2019une indemnit\u00e9 deproc\u00e9dure de 1.000 euros, ce jugement ayant \u00e9t\u00e9 confirm\u00e9 par un arr\u00eat de la Cour d\u2019appel du 27 juin 2019. Le tribunal a partant retenu que l\u2019SOCIETE1.)a commis unefaute d\u00e9lictuelle \u00e0 l\u2019\u00e9gard dePERSONNE1.)et la demande de ce dernier a \u00e9t\u00e9 d\u00e9clar\u00e9e fond\u00e9e pour le montant de (22.464 + 1.000 + 1.000 =) 24.464 euros,avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 compter de la demande en justice jusqu\u2019\u00e0 solde. Par acte d\u2019huissier de justice du 31 ao\u00fbt 2021,l\u2019SOCIETE1.)a relev\u00e9 appel du jugement du 2 juillet 2021 qui lui a\u00e9t\u00e9 signifi\u00e9 par acte d\u2019huissier de justice du 28 juillet 2021. L\u2019SOCIETE1.)demande principalement \u00e0 la Cour, par r\u00e9formation, de d\u00e9clarer nulle la vente du camion conclue entre la soci\u00e9t\u00e9SOCIETE2.) et elle-m\u00eame dans le cadre du contrat de cession du fonds de commerce du 23 septembre 2016 et, en cons\u00e9quence, \u00e0 voir rejeter toutes les demandes formul\u00e9es parPERSONNE1.)\u00e0 son encontre.<\/p>\n<p>6 Subsidiairement, l\u2019SOCIETE1.)demande \u00e0 voir dire que PERSONNE1.)ne prouve aucune faute contractuelle, sinon d\u00e9lictuelle dans son chef, ni aucun pr\u00e9judice, ni lien causal entre ces deux \u00e9l\u00e9ments. L\u2019SOCIETE1.)demande \u00e0 voir condamnerPERSONNE1.)\u00e0 lui payer une indemnit\u00e9 de proc\u00e9dure de 5.000 euros, par instance, et \u00e0 supporter les frais et d\u00e9pens des deux instances. PERSONNE1.)conclut, selon le dernier \u00e9tat de ses conclusions, \u00e0 lui donner acte de l\u2019augmentation de sa demande au montant de 28.046,10 euros correspondant au montant r\u00e9ellement pay\u00e9 \u00e0 la soci\u00e9t\u00e9SOCIETE3.)par le biais de la proc\u00e9dure de recouvrement entrepris \u00e0 son encontre, sinon \u00e0 voir confirmer le jugement entrepris du 2 juillet 2021. Il demande en tout \u00e9tat de cause \u00e0 voir condamner l\u2019SOCIETE1.)\u00e0 lui payer, par r\u00e9formation, une indemnit\u00e9 de proc\u00e9dure de 2.000 euros pour la premi\u00e8re instance et 5.000 euros pour l\u2019instance d\u2019appel. Il conclut encore \u00e0 voir condamner l\u2019SOCIETE1.)\u00e0 lui payer 3.500 euros au titre d\u2019indemnit\u00e9 pour proc\u00e9dure abusive et vexatoire sur base de l\u2019article 6-1 du Code et \u00e0 supporter les frais et d\u00e9pens de l\u2019instance d\u2019appel. Il demande finalement \u00e0 voir d\u00e9clarer l\u2019arr\u00eat \u00e0 intervenir commun \u00e0 la soci\u00e9t\u00e9SOCIETE2.)en faillite. Ma\u00eetre Camille SAETTEL, pris en sa qualit\u00e9 de curateur de la faillite de la soci\u00e9t\u00e9SOCIETE2.), se rapporte \u00e0 la sagesse de la Cour quant au bienfond\u00e9 de l\u2019appel, en relevant qu\u2019aucune demande ne se trouve formul\u00e9e \u00e0 l\u2019encontre de la soci\u00e9t\u00e9 en faillite. Discussion: Lesappels principal et incident sont recevables pour avoir \u00e9t\u00e9 introduits dans les formes et d\u00e9lai de la loi. A)Quant \u00e0 l\u2019action oblique: PERSONNE1.)r\u00e9it\u00e8re en appel son moyen tir\u00e9 de l\u2019action oblique et conclut \u00e0 voir d\u00e9clarer fond\u00e9e et justifi\u00e9e sa demande sur base de l\u2019article 1166 du Code civil dirig\u00e9e contre l\u2019SOCIETE1.). Le curateur de la faillite de la soci\u00e9t\u00e9SOCIETE2.)se rapporte \u00e0 la sagesse de la Cour et l\u2019SOCIETE1.)conclut \u00e0 la confirmation du jugement entrepris sur ce point sp\u00e9cifique. Conform\u00e9ment \u00e0 l\u2019article 1166 du Code civil,\u00ables cr\u00e9anciers peuvent exercer tous les droits et les actions de leur d\u00e9biteur, \u00e0 l\u2019exception de<\/p>\n<p>7 ceux quisont exclusivement attach\u00e9s \u00e0 la personne\u00bb. Le cr\u00e9ancier se substitue \u00e0 la personne morale d\u00e9faillante. L\u2019action oblique constitue une action attitr\u00e9e que la loi attribue au cr\u00e9ancier pour reconstituer l\u2019actif de la soci\u00e9t\u00e9 d\u00e9bitrice. L\u2019action oblique est en principe ouverte aux cr\u00e9anciers sociaux qui remplissent les conditions d\u00e9gag\u00e9es par la jurisprudence en droit commun. Elle suppose une cr\u00e9ance certaine, liquide et exigible du d\u00e9biteur n\u00e9gligent \u00e0 l\u2019encontre de son propre d\u00e9biteur (Cour d\u2019appel 20 janvier 2022, Pas.40, p.629; voir \u00e9galement: Lexis 360, r\u00e9pertoire notarial V\u00b0 Contrats et obligations, fasc.38). Cependant, en l\u2019esp\u00e8ce, la personne morale cr\u00e9anci\u00e8re d\u00e9faillante a \u00e9t\u00e9 d\u00e9clar\u00e9e en \u00e9tat de faillite par jugement du 20 janvier 2017 et Ma\u00eetreCamille SAETTEL en a \u00e9t\u00e9 nomm\u00e9e curatrice. C\u2019est \u00e0 bon droit que le tribunal a retenu que\u00abl\u2019action en recouvrement d\u2019un pr\u00e9judice relevant de la masse faillie est r\u00e9serv\u00e9e au curateur et que tombent dans cette cat\u00e9gorie les actions en responsabilit\u00e9 contre les anciens dirigeants de l\u2019entit\u00e9 faillie qui ont pu contribuer par leurs fautes \u00e0 l\u2019augmentation du passif et les actions en recouvrement de cr\u00e9ances de droit commun qui rel\u00e8veraient de l\u2019actif de la masse nonobstant toute proc\u00e9dure collective et qui seraient \u00e0 exercer contre des tiers d\u00e9biteurs de la masse\u00bb. La Cour approuve en cons\u00e9quence le tribunal d\u2019avoir retenu qu\u2019en faisant valoir qu\u2019il entend exercer les droits et actions de la soci\u00e9t\u00e9 SOCIETE2.)en sa qualit\u00e9 de cr\u00e9anci\u00e8re de l\u2019SOCIETE1.), PERSONNE1.)poursuit, en tant que tiers par le biais de l\u2019action oblique, le recouvrement d\u2019une cr\u00e9ance relevant de l\u2019action de l\u2019organisme failli, de sorte que l\u2019action introduite parPERSONNE1.), pour autant qu\u2019elle est bas\u00e9e sur l\u2019article 1166 du Code civil, est irrecevable. Le moyen tir\u00e9 de l\u2019article 1166 du Code civil a partant \u00e9t\u00e9 rejet\u00e9 \u00e0 bon droit par le tribunal. B)Quant \u00e0 la vente de la chose d\u2019autrui: L\u2019SOCIETE1.)fait grief au tribunal d\u2019avoir rejet\u00e9 son moyen tir\u00e9 de la nullit\u00e9 de la vente de la chose d\u2019autrui, en soutenant que la soci\u00e9t\u00e9 SOCIETE2.), repr\u00e9sent\u00e9e par son g\u00e9rantPERSONNE1.), l\u2019aurait tromp\u00e9 en lui vendant le Camion dont elle n\u2019\u00e9tait m\u00eame pas le propri\u00e9taire, \u00e9tant donn\u00e9 que le Camion appartenait \u00e0 la soci\u00e9t\u00e9 SOCIETE3.)en vertu d\u2019une clause de r\u00e9serve de propri\u00e9t\u00e9, tant que les frais de r\u00e9parations n\u2019\u00e9taient pas r\u00e9gl\u00e9s. L\u2019SOCIETE1.)insiste sur le fait que, contrairement \u00e0 ce que le tribunal a retenu, il n\u2019aurait d\u00e9couvert ces faits que post\u00e9rieurement \u00e0 la conclusion du contrat de cession de fonds de commerce.<\/p>\n<p>8 L\u2019SOCIETE1.)critique ainsi le jugement entrepris en ce que le tribunal, par une interpr\u00e9tation erron\u00e9e des pi\u00e8ces, a estim\u00e9, en se basant sur la date erron\u00e9e du 22 septembre 2016 de l\u2019attestation adress\u00e9e par PERSONNE2.)au garageSOCIETE3.)et sur la date de la conclusion du contrat de cession du fonds de commerce du 23 septembre 2016, que l\u2019SOCIETE1.)s\u2019\u00e9tait \u00e0 deux reprises express\u00e9ment engag\u00e9 \u00e0 virer le montant, dans un premier temps de 18.000 euros, et ensuite de 22.000 euros, en faveur du garageSOCIETE3.)et ne pouvait ignorer que la soci\u00e9t\u00e9SOCIETE2.)n\u2019\u00e9tait pas propri\u00e9taire du Camion. L\u2019appelant soutient que cette conclusion du tribunal se trouverait contredite par les pi\u00e8ces produites en cause et par les aveux de PERSONNE1.)r\u00e9sultant de son assignation introductive d\u2019instance du 9 octobre 2020. L\u2019SOCIETE1.)fait valoir que la date du 22 septembre 2016 serait manifestement erron\u00e9e, \u00e9tant donn\u00e9 que l\u2019attestation aurait \u00e9t\u00e9 \u00e9tablie et transmise au garageSOCIETE3.)seulement en annexe \u00e0 un courriel adress\u00e9 parPERSONNE2.)\u00e0PERSONNE3.), comptable du garageSOCIETE3.)en date du 26 septembre 2016. L\u2019erreur de date r\u00e9sulterait encore du fait que le contrat de cession du fonds de commerce stipulerait que le paiement du prix de vente de 22.000 euros du Camion fait partie int\u00e9grante du prix global de 85.000 euros de la vente du fonds de commerce; quePERSONNE1.) affirmerait aux termes de son assignation introductive d\u2019instance du 9 octobre 2020 \u00abque le fonds de commerce c\u00e9d\u00e9 comprenait le v\u00e9hicule de marque Nissan pr\u00e9qualifi\u00e9 pour lequel la partie requ\u00e9rante s\u2019est port\u00e9e caution; que le pr\u00e9dit v\u00e9hicule a \u00e9t\u00e9 r\u00e9troc\u00e9d\u00e9 \u00e0 la soci\u00e9t\u00e9 SOCIETE1.)SARL au prix de 22.000 euros HT conform\u00e9ment aux sp\u00e9cifications du pr\u00e9dit acte de cession du fonds de commerce (\u2026)\u00bb. L\u2019appelant conclut que la volont\u00e9 de la soci\u00e9t\u00e9SOCIETE2.)\u00e9tait de lui vendre le Camion comme faisant partie int\u00e9grante du fonds de commerce et que sa volont\u00e9 \u00e9tait d\u2019acheter le Camion en m\u00eame temps que le fonds de commerce et d\u2019en devenir le propri\u00e9taire. L\u2019unique raison pour laquelle il avait accept\u00e9 de payer une partie du prix de vente du fonds de commerce entre les mains du garageSOCIETE3.), aurait \u00e9t\u00e9 que le Camion se trouvait au garageSOCIETE3.)pour y subir des r\u00e9parations, r\u00e9parations qui \u00e9taient cens\u00e9es \u00eatre couvertes par la somme de 22.000 euros. Il pr\u00e9tend qu\u2019en date du 23septembre 2016, il lui aurait \u00e9t\u00e9 strictement impossible de savoir, ou m\u00eame de soup\u00e7onner, que la soci\u00e9t\u00e9 SOCIETE2.)n\u2019\u00e9tait pas propri\u00e9taire de ce Camion. Or, il se serait av\u00e9r\u00e9in fineque le garageSOCIETE3.)\u00e9tait rest\u00e9 propri\u00e9taire du Camion sur based\u2019une clause de r\u00e9serve de propri\u00e9t\u00e9 affectant la<\/p>\n<p>9 vente du Camion par ce dernier \u00e0 la soci\u00e9t\u00e9SOCIETE2.)en date du 30 juin 2015. L\u2019appelant soutient quePERSONNE1.)ne pourrait pas ignorer ce fait, puisqu\u2019il \u00e9tait le dirigeant de fait de la soci\u00e9t\u00e9 SOCIETE2.)et que son \u00e9pouse, g\u00e9rante unique, lui aurait laiss\u00e9 l\u2019enti\u00e8re gestion de la soci\u00e9t\u00e9. L\u2019SOCIETE1.)critique encore le jugement entrepris en ce que le tribunal a retenu que la carte grise du Camion \u00abqui n\u2019est nullement dat\u00e9e, ne permet d\u2019\u00e9carter la qualit\u00e9 de propri\u00e9taire deSOCIETE3.) au moment de la signature du contrat de cession du fonds de commerce\u00bb. Il invoque qu\u2019il r\u00e9sulterait notamment de la carte grise que le propri\u00e9taire du Camion n\u2019est pas le garageSOCIETE3.), mais la soci\u00e9t\u00e9SOCIETE4.)et que le d\u00e9tenteur du Camion est la soci\u00e9t\u00e9 SOCIETE2.). Cette carte grise lui ayant \u00e9t\u00e9 remise uniquement apr\u00e8s la conclusion de la cession du fonds de commerce par le garage SOCIETE3.), les indications y figurant excluraient la qualit\u00e9 de propri\u00e9taire du garageSOCIETE3.)au moment de la conclusion de la cession du fonds de commerce. PERSONNE1.)conteste qu\u2019il y aurait eu vente de la chose d\u2019autrui. Il soutient que la vente du Camion \u00e0 l\u2019SOCIETE1.)serait intervenue sous la condition suspensive que ce dernier paie le prix de vente de 22.000 euros directemententre les mains du garageSOCIETE3.)qui en gardait la propri\u00e9t\u00e9. Or, comme l\u2019SOCIETE1.)n\u2019aurait pas proc\u00e9d\u00e9 au paiement du prix de vente du Camion et que les parties au contrat de cession du fonds de commerce n\u2019ont pas pr\u00e9vu de terme pour le paiement duprix de vente, le transfert de propri\u00e9t\u00e9 se serait finalement r\u00e9alis\u00e9 au moment du paiement du prix de vente par l\u2019intim\u00e9, en sa qualit\u00e9 de caution. L\u2019intim\u00e9 soutient que l\u2019SOCIETE1.)aurait suque la soci\u00e9t\u00e9 SOCIETE2.)n\u2019\u00e9tait pas propri\u00e9taire du Camion au moment de la cession du fonds de commerce et que le tribunal a correctement appr\u00e9ci\u00e9 les faits de l\u2019esp\u00e8ce, la date de l\u2019attestation \u00e0 prendre en consid\u00e9ration \u00e9tant celle de l\u2019\u00e9tablissement et de la signature de celle- ci, et non celle de la communication de l\u2019attestation au garage SOCIETE3.). Il invoque que la connaissance parfaite de cet \u00e9tat de chose r\u00e9sulterait encore de la convention relative \u00e0 la cession du fonds de commerce aux termes de laquelle le paiement du prix de 22.000 euros au garageSOCIETE3.)serait faite \u00abpourl\u2019acquisitionet la r\u00e9paration\u00bb du Camion. L\u2019intim\u00e9 fait finalement valoir que l\u2019attestation litigieuse serait un document confectionn\u00e9 et sign\u00e9 par l\u2019SOCIETE1.)et que si la date ne correspondait pas \u00e0 la r\u00e9alit\u00e9, l\u2019SOCIETE1.)aurait fait usage devant<\/p>\n<p>10 la Cour d\u2019un faux document, soit aurait commis une infraction p\u00e9nalement r\u00e9prim\u00e9e. L\u2019intim\u00e9 soutient que dans ces conditions, il ne saurait y avoir vente de la chose d\u2019autrui et lavente du camion de la soci\u00e9t\u00e9SOCIETE2.) \u00e0 l\u2019SOCIETE1.)devrait \u00eatre d\u00e9clar\u00e9e valable. Appr\u00e9ciation de la Cour Aux termes de l\u2019article 1599 du Code civil, \u00abla vente de la chose d\u2019autrui est nulle; elle peut donner lieu \u00e0 des dommages et int\u00e9r\u00eats lorsque l\u2019acheteur a ignor\u00e9 que la chose f\u00fbt \u00e0autrui\u00bb. La vente op\u00e8re un transfert du droit de propri\u00e9t\u00e9 du vendeur \u00e0 l\u2019acheteur: elle n\u2019est donc valable que si le vendeur est titulaire du droit en cause, car nul ne peut transf\u00e9rer plus de droits qu\u2019il n\u2019a lui- m\u00eame (\u00abNemo plus juris ad allium transferre potest, quam ipse habet\u00bb). Lorsque l\u2019ali\u00e9nateur n\u2019est pas propri\u00e9taire de la chose qu\u2019il entend ali\u00e9ner, mais escompte le devenir \u00e0 br\u00e8ve \u00e9ch\u00e9ance, le principe du transfert imm\u00e9diat de propri\u00e9t\u00e9 se heurte \u00e0 cette impossibilit\u00e9 juridique. Il suffitque le vendeur soit propri\u00e9taire au moment du transfert de propri\u00e9t\u00e9 qui a pu \u00eatre retard\u00e9 (Dalloz Action 2014-2015\u2013Droit de la responsabilit\u00e9 n\u00b05815 et ss). Lorsque le vendeur appara\u00eet d\u00e8s lors d\u00e9pourvu de tout droit de propri\u00e9t\u00e9, la sanctionprincipale de l\u2019op\u00e9ration est la nullit\u00e9. L\u2019objectif de la nullit\u00e9 de vente de la chose d\u2019autrui est de prot\u00e9ger l\u2019acqu\u00e9reur contre un risque d\u2019\u00e9viction, \u00e0 la suite d\u2019une action diligent\u00e9e par le v\u00e9ritable propri\u00e9taire. Celle-ci doit \u00eatre prononc\u00e9e par lejuge d\u00e8s lors que la chose appartenait \u00e0 autrui et que la vente n\u2019en a pas \u00e9t\u00e9 ult\u00e9rieurement consolid\u00e9e. Les choses doivent \u00eatre remises dans leur \u00e9tat ant\u00e9rieur. L\u2019acheteur a donc droit \u00e0 la restitution du prix et, s\u2019il a \u00e9t\u00e9 de bonne foi, au remboursement des frais accessoires \u00e0 la vente. C\u2019est principalement le moment auquel doit \u00eatre appr\u00e9ci\u00e9 l\u2019absence du droit de propri\u00e9t\u00e9 qui retient l\u2019attention. Tant\u00f4t, il arrivera que la propri\u00e9t\u00e9 de la chose vendue n\u2019ait finalement pas \u00e9t\u00e9 acquise par celui qui pr\u00e9tend en disposer, tant\u00f4t le droit de propri\u00e9t\u00e9 aurait exist\u00e9, mais le disposant aura perdu ce droit au jour de la r\u00e9alisation de la vente. La nullit\u00e9 de la vente prohib\u00e9e ne saurait \u00eatre prononc\u00e9e sans que soit, au pr\u00e9alable et g\u00e9n\u00e9ralement, d\u00e9termin\u00e9 lemoment auquel il convient d\u2019appr\u00e9cier le d\u00e9faut de propri\u00e9t\u00e9 de celui qui, n\u00e9anmoins, dispose de la chose. Dans ces conditions, pour l\u2019application des sanctions de l\u2019article 1599 du Code civil, il faut que le vendeur n\u2019ait pas \u00e9t\u00e9 propri\u00e9taire au moment o\u00f9 il aurait d\u00fb transf\u00e9rer la propri\u00e9t\u00e9 au profit de l\u2019acqu\u00e9reur.<\/p>\n<p>11 L\u2019objet de l\u2019article 1599 du Code civil est de sanctionner l\u2019inaptitude du vendeur \u00e0 transf\u00e9rer un droit de propri\u00e9t\u00e9 dont il n\u2019est pas investi. Mais cette inaptitude ne peut s\u2019appr\u00e9cier qu\u2019au moment o\u00f9 doit se faire le transfert de propri\u00e9t\u00e9. Lorsque ce transfert est, par la volont\u00e9 des parties, diff\u00e9r\u00e9 par rapport \u00e0 la conclusion du contrat de vente, rien ne permet d\u2019affirmer que le vendeur non-propri\u00e9taire sera inapte \u00e0 ex\u00e9cuter, en tempsutile, son obligation de transfert. Il peut, entre- temps, acqu\u00e9rir la chose. A l\u2019inverse, un vendeur qui, lors de la naissance du contrat, serait propri\u00e9taire, est susceptible de perdre volontairement ou non, son droit de propri\u00e9t\u00e9 avant d\u2019avoir eu \u00e0 le transf\u00e9rer \u00e0 l\u2019acqu\u00e9reur. La vente sera alors nulle, bien qu\u2019elle ait \u00e9t\u00e9 consentie par un vendeur propri\u00e9taire. Ainsi, dans tous les cas o\u00f9 le vendeur n\u2019a pas l\u2019obligation de transf\u00e9rer la propri\u00e9t\u00e9 d\u00e8s la conclusion du contrat de vente, il n\u2019est ni n\u00e9cessaire ni suffisant qu\u2019il soit propri\u00e9taire de la chose vendue au moment o\u00f9 il contracte. Celui qui ne poss\u00e8de sur une chose qu\u2019un droit soumis \u00e0 une condition suspensive peut la vendre sous la m\u00eame condition, et la vente ne pourra produire que des effets limit\u00e9s, c\u2019est-\u00e0-dire un transfert de propri\u00e9t\u00e9 sous condition suspensive. Ainsi, la promesse fait par une partie de vendre une chose d\u00e9termin\u00e9e appartenant \u00e0 un tiers pour le cas o\u00f9 elle deviendrait propri\u00e9taire, constitue un engagement parfaitement liciteet oblige les deux parties. D\u00e8s lors, quand le promettant, devenu propri\u00e9taire, offre \u00e0 l\u2019autre partie de passer l\u2019acte de vente, cette derni\u00e8re n\u2019est pas fond\u00e9e \u00e0 s\u2019y refuser en soutenant que le contrat \u00e9tait entach\u00e9 de nullit\u00e9 par application de l\u2019article 1599 du Code civil(JurisClasseur Civil Code, article 1599, fasc. unique: Vente\u2013Chose pouvant \u00eatre vendues\u2013Vente de la Chose d\u2019autrui, n\u00b0 7 et ss). Ces principes expos\u00e9s,les parties sont d\u2019accord pourdireque le Camion fait partie du \u00abmat\u00e9riel\u00bb c\u00e9d\u00e9dans le cadre de la cession du fonds de commerce du 23 septembre 2016.Ceci est confirm\u00e9 par les modalit\u00e9s de r\u00e8glement du prix de la cession telles que pr\u00e9vues par les parties dans laconvention du 23 septembre 2016. Ilr\u00e9sulte des \u00e9l\u00e9ments du dossier qu\u2019au moment de la cessiondu fonds de commerce de la soci\u00e9t\u00e9SOCIETE2.)\u00e0 l\u2019SOCIETE1.), cession qui comprenait, entre autres, la cession du Camion litigieux, ce dernier appartenait toujours au garageSOCIETE3.)en vertu de la clause de r\u00e9serve de propri\u00e9t\u00e9 incluse dans la facture du 30 juin 2015 dudit Camion entre le garageSOCIETE3.)et la soci\u00e9t\u00e9SOCIETE2.). En effet, il est constant en cause sur base du jugement du tribunal du 17 novembre 2017, confirm\u00e9 par un arr\u00eat de la Cour d\u2019appel du 27 juin 2019, que la soci\u00e9t\u00e9SOCIETE2.)n\u2019a pas r\u00e9gl\u00e9 le prix de vente de 22.464 euros convenu entre ces deux parties.<\/p>\n<p>12 A cet \u00e9gard, il convient d\u2019\u00e9carter pour d\u00e9faut de pertinence l\u2019argumentation de l\u2019appelante tir\u00e9e du faitque le certificat d\u2019immatriculation renseigne comme propri\u00e9taire du Camion la soci\u00e9t\u00e9 SOCIETE4.), \u00e9tant donn\u00e9 que le certificat d\u2019immatriculation a \u00e9t\u00e9 \u00e9tabli le 27 ao\u00fbt 2010, soit cinq ans avant la vente du Camion par le garageSOCIETE3.)\u00e0 la soci\u00e9t\u00e9SOCIETE2.), de sorte qu\u2019il y a lieu d\u2019admettre que le contrat de leasing \u00e9tait arriv\u00e9 \u00e0 son terme avant la vente du Camion par le garageSOCIETE3.)\u00e0 la soci\u00e9t\u00e9SOCIETE2.) en date du 30 juin 2015. En date du 23 septembre 2016, date de la conclusion de la convention de cession du fonds de commerce entre la soci\u00e9t\u00e9SOCIETE2.)et l\u2019SOCIETE1.), le garageSOCIETE3.)\u00e9tait le v\u00e9ritable propri\u00e9taire du Camion. Les parties ont stipul\u00e9 aux termes de l\u2019acte de cession du fonds de commerce que: \u00abLe prix de ventesera vers\u00e9 lors de la signature du contrat de cession et se fera dans les termes suivants: &#8212; Le montant de 22.000 euros sera vers\u00e9 directement \u00e0 la soci\u00e9t\u00e9 SOCIETE3.)SARL,ADRESSE3.), L-ADRESSE4.)pour le paiement des engagements concernant l\u2019acquisition et r\u00e9paration du v\u00e9hicule demarque Nissan Atleon, plaqueNUMERO2.), ch\u00e2ssis:NUMERO3.) &#8212; Le montant de 63.000 euros sera vers\u00e9 sur le compte bancaire suivant:\u2026\u00bb. Cette disposition se limitant \u00e0r\u00e9gler le mode de r\u00e8glement du prix, elle ne saurait s\u2019interpr\u00e9ter en une clause suspensive ayant pour effet de retarder le transfert de propri\u00e9t\u00e9 du Camion jusqu\u2019au paiement du prix de ce dernier. Contrairement \u00e0 l\u2019all\u00e9gation dePERSONNE1.), il ne r\u00e9sulte ni de l\u2019acte de cession du fonds de commerce, ni d\u2019aucun autre \u00e9l\u00e9ment probant du dossier que la cession du fonds de commerce entre la soci\u00e9t\u00e9 SOCIETE2.)et l\u2019SOCIETE1.)se trouverait affect\u00e9e d\u2019une condition suspensive en ce qui concerne le transfertde propri\u00e9t\u00e9 du Camion litigieux. Il y a partant lieu de retenir que le transfert de propri\u00e9t\u00e9 du Camion devait intervenir d\u00e8s la signature de la cession du fonds de commerce. Il convient de rappeler que la mauvaise foi du vendeur, respectivement de l\u2019acqu\u00e9reur est inop\u00e9rante en ce qui concerne la sanction de la nullit\u00e9 d\u2019une vente de la chose d\u2019autrui, \u00e9tant donn\u00e9 que la seule sanction de la mauvaise foi de l\u2019acqu\u00e9reur consiste \u00e0 le priver du droit de demander, outre la nullit\u00e9 de la vente, des dommages-int\u00e9r\u00eats sur base de l\u2019article 1599 du Code civil.<\/p>\n<p>13 C\u2019est partant \u00e0 tort que le tribunal a retenu, pour rejeter le moyen tir\u00e9 de l\u2019article 1599 du Code civil, que l\u2019SOCIETE1.)ne pouvait ignorer que la soci\u00e9t\u00e9SOCIETE2.)n\u2019\u00e9tait pas propri\u00e9taire du Camion. Il y a lieu de retenir sur base des d\u00e9veloppements qui pr\u00e9c\u00e8dent qu\u2019\u00e0 la date du 23 septembre 2016, date de la conclusion de la cession du fonds de commerce de la soci\u00e9t\u00e9SOCIETE2.)\u00e0 l\u2019SOCIETE1.), ce dernier encourait un risque r\u00e9el d\u2019\u00e9viction en raison du droit du garage SOCIETE3.)de revendiquer la propri\u00e9t\u00e9 du Camion. En cons\u00e9quence, par r\u00e9formation,ily a lieu de prononcer la nullit\u00e9 de la vente du Camion litigieux par la soci\u00e9t\u00e9 SOCIETE2.)\u00e0 l\u2019SOCIETE1.), et partant la nullit\u00e9 partielle de la cession du fonds de commerce pour autant qu\u2019elle porte sur le Camion litigieux. La vente du Camion \u00e9tant nulle, il y a lieu en cons\u00e9quence de retenir que l\u2019appelante ne saurait avoir commis une faute en refusant de payer le prix de 22.000 euros directement entre les mains du garage SOCIETE3.). Il s\u2019ensuit, par r\u00e9formation, que la demande dePERSONNE1.)en condamnation de l\u2019SOCIETE1.)\u00e0 lui payer la somme de 24.464 euros sur base de la condamnation intervenue \u00e0 son \u00e9gard en tant que caution et en raison de l\u2019opposabilit\u00e9 d\u2019une faute contractuelle dans le chef de l\u2019SOCIETE1.)par rapport \u00e0 la soci\u00e9t\u00e9SOCIETE2.)pour d\u00e9faut de paiement du montant convenu de 22.000 euros pour l\u2019acquisition et la r\u00e9paration du Camion litigieux n\u2019est pas fond\u00e9e. C)Quant \u00e0 l\u2019appel incident dePERSONNE1.)relative aux frais et honoraires d\u2019avocat: Aux termes de ses premi\u00e8res conclusions en appel du 2 f\u00e9vrier 2022, PERSONNE1.) conclut, par r\u00e9formation, \u00e0 voir condamner l\u2019SOCIETE1.)\u00e0 lui rembourser la somme de 4.644,90 euros au titre des frais et honoraires d\u2019avocat expos\u00e9s. Cette demande ne se trouve pas r\u00e9it\u00e9r\u00e9e sur base des deux corps de conclusions subs\u00e9quents. Il a lieu de constater que l\u2019acte d\u2019appel date du 31 ao\u00fbt 2021, desorte qu\u2019est applicable au pr\u00e9sent litige l\u2019ancien article 586 du Nouveau Code de proc\u00e9dure civile qui dispose que \u00abLes conclusions d\u2019appel doivent formuler express\u00e9ment les pr\u00e9tentions de la partie et les moyens sur lesquels chacune de ces pr\u00e9tentions est fond\u00e9e. L\u2019avocat ou les avocats d\u2019une ou plusieurs parties peuvent \u00eatre invit\u00e9s \u00e0 r\u00e9capituler les moyens qui auraient \u00e9t\u00e9 successivement pr\u00e9sent\u00e9s. Les moyens qui ne sont pas r\u00e9capitul\u00e9s sont regard\u00e9s comme abandonn\u00e9s\u00bb.<\/p>\n<p>14 La demande en remboursement desfrais et honoraires constituant une pr\u00e9tention, et non pas un moyen, la Cour se doit de l\u2019analyser. La Cour a retenu par r\u00e9formation qu\u2019aucune faute, ni contractuelle ni d\u00e9lictuelle, ne se trouve \u00e9tablie dans le chef del\u2019SOCIETE1.). Par ailleurs, et\u00e0 l\u2019instar du tribunal, la Cour constate quePERSONNE1.) reste en d\u00e9faut de produire la moindre pi\u00e8ce justifiant le paiement de frais et honoraires d\u2019avocat. Sa demande est partant\u00e0 rejeter et l\u2019appel incident n\u2019est pas fond\u00e9. D)Quant \u00e0 la demande dePERSONNE1.)sur base de l\u2019article 6- 1 du Code civil: Aux termes de ses conclusions du 28 octobre 2022,PERSONNE1.) conclut \u00e0 voir condamner l\u2019SOCIETE1.)\u00e0 lui payer un montant de 3.500 euros au titre d\u2019indemnit\u00e9 pour proc\u00e9dure abusive et vexatoire sur base de l\u2019article 6-1 du Code civil. Il r\u00e9it\u00e8re cette demande aux termes de ses conclusions du 15 novembre 2023. L\u2019SOCIETE1.)ne prend pas position par rapport \u00e0 cette demande, de sorte que la recevabilit\u00e9 de celle-ci ne se trouve pas contest\u00e9e. L\u2019exercice d\u2019une action en justice ne d\u00e9g\u00e9n\u00e8re en faute pouvant donner lieu \u00e0 des dommages et int\u00e9r\u00eats que s\u2019il constitue un acte de malice ou de mauvaise foi ou, au moins, une erreur grossi\u00e8re \u00e9quipollente au dol ou si le demandeur a agi avec une l\u00e9g\u00e8ret\u00e9 bl\u00e2mable. Il convient de sanctionner, non pas le fait d\u2019avoir exerc\u00e9 \u00e0 tort une action en justice ou d\u2019y avoir r\u00e9sist\u00e9 injustement\u2013puisque l\u2019exercice d\u2019une action en justice est libre\u2013mais uniquement le fait d\u2019avoir abus\u00e9 de son droit en commettant une faute ind\u00e9pendante du seul exercice des voies de droit (Cour 17 mars 1993, n\u00b0 14446 du r\u00f4le et Cour 22 mars 1993, n\u00b0 14971 du r\u00f4le). Au vu des d\u00e9veloppements qui pr\u00e9c\u00e8dent ayant conduit la Cour \u00e0 retenirqu\u2019aucune faute ne se trouve \u00e9tablie dans le chef de l\u2019SOCIETE1.),PERSONNE1.) reste en d\u00e9faut d\u2019\u00e9tablir que l\u2019SOCIETE1.)aurait abus\u00e9 de son droit d\u2019exercer la voie de recours de l\u2019appel l\u00e9galement pr\u00e9vue contrele jugement entrepris. Sa demande est partant \u00e0 rejeter. E)Quant aux demandes accessoires:<\/p>\n<p>15 Ayant succomb\u00e9 en appel, la demande dePERSONNE1.)tendant par r\u00e9formation \u00e0 se voir allouer une indemnit\u00e9 de proc\u00e9dure de 2.000 euros pour la premi\u00e8re instance,de m\u00eame que celle tendant \u00e0 se voir allouer une indemnit\u00e9 de proc\u00e9dure de 3.500 euros pour l\u2019instance d\u2019appel ne sont pas fond\u00e9es. Au vu de l\u2019issue du litige,la demande de l\u2019SOCIETE1.)tendant par r\u00e9formation \u00e0 se voir allouer une indemnit\u00e9 de proc\u00e9durede 5.000 euros pour la premi\u00e8re instance est \u00e0 d\u00e9clarer fond\u00e9e \u00e0 concurrence de 750 euros et celle tendant se voir allouer une indemnit\u00e9 de proc\u00e9dure de 5.000 euros pour l\u2019instance d\u2019appel est fond\u00e9e \u00e0 concurrence de 1.500 euros. Par r\u00e9formation, il y aencore lieu de d\u00e9chargerl\u2019SOCIETE1.)de la condamnation \u00e0 supporter les frais et d\u00e9pens de la premi\u00e8re instance et de mettre ce frais, de m\u00eame que ceux de l\u2019instance d\u2019appel \u00e0 charge dePERSONNE1.). Le pr\u00e9sent arr\u00eat est \u00e0 d\u00e9clarer commun \u00e0lasoci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.), en faillite, repr\u00e9sent\u00e9e par son curateur Ma\u00eetre Camille SAETTEL. PAR CES MOTIFS laCour d\u2019appel, huiti\u00e8me chambre, si\u00e9geant en mati\u00e8re commerciale, statuant contradictoirement entre parties; re\u00e7oit les appels principal et incident; dit l\u2019appel incident non fond\u00e9; dit l\u2019appel principal fond\u00e9; r\u00e9formant: d\u00e9clare nulle la cession dufonds de commerce de la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.), en faillite, \u00e0lasoci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE0.)intervenue le 23 septembre 2016 pour autant qu\u2019elle porte sur le camionde marque Nissan, mod\u00e8le Alteon, plaqueNUMERO2.), ch\u00e2ssis:NUMERO3.); d\u00e9charge lasoci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE0.)de toutes les condamnations prononc\u00e9es \u00e0 son encontresur base du jugement entrepris du 2 juillet 2021;<\/p>\n<p>16 condamnePERSONNE1.)\u00e0 payer \u00e0 lasoci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e SOCIETE0.)une indemnit\u00e9 de proc\u00e9dure de 750 euros pour la premi\u00e8re instance et de 1.500 euros pour l\u2019instance d\u2019appel, ainsi qu\u2019\u00e0 supporter les frais et d\u00e9pens des deux instances; d\u00e9clare le pr\u00e9sent arr\u00eat commun \u00e0lasoci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e SOCIETE2.), en faillite, repr\u00e9sent\u00e9e par son curateur Ma\u00eetre Camille SAETTEL.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-8\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-8\/20250113-014402\/20241212-ca08-cal-2021-00959-pseudonymise-1-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arr\u00eat N\u00b0111\/24-VIII-COM Arr\u00eat commercial Audience publique dudouze d\u00e9cembredeux mille vingt-quatre Num\u00e9ro CAL-2021-00959du r\u00f4le Composition: Elisabeth WEYRICH, pr\u00e9sident de chambre, Yola SCHMIT,premier conseiller, Laurent LUCAS,conseiller, Amra ADROVIC, greffier. Entre: la soci\u00e9t\u00e9\u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.),\u00e9tablie et ayant son si\u00e8ge social \u00e0L-ADRESSE1.), inscrite au Registre de Commerce et des\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[21144],"kji_year":[8677],"kji_subject":[7724],"kji_keyword":[8683,8464,9055,12307,21175],"kji_language":[7733],"class_list":["post-591795","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-8","kji_year-8677","kji_subject-civil","kji_keyword-arret","kji_keyword-decembre","kji_keyword-justice","kji_keyword-superieure","kji_keyword-viii-com","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959\" \/>\n<meta property=\"og:description\" content=\"Arr\u00eat N\u00b0111\/24-VIII-COM Arr\u00eat commercial Audience publique dudouze d\u00e9cembredeux mille vingt-quatre Num\u00e9ro CAL-2021-00959du r\u00f4le Composition: Elisabeth WEYRICH, pr\u00e9sident de chambre, Yola SCHMIT,premier conseiller, Laurent LUCAS,conseiller, Amra ADROVIC, greffier. Entre: la soci\u00e9t\u00e9\u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.),\u00e9tablie et ayant son si\u00e8ge social \u00e0L-ADRESSE1.), inscrite au Registre de Commerce et des\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-18T02:13:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"31 \u043c\u0438\u043d\u0443\u0442\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-18T02:13:03+00:00\",\"dateModified\":\"2026-04-18T02:13:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/","og_locale":"ru_RU","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959","og_description":"Arr\u00eat N\u00b0111\/24-VIII-COM Arr\u00eat commercial Audience publique dudouze d\u00e9cembredeux mille vingt-quatre Num\u00e9ro CAL-2021-00959du r\u00f4le Composition: Elisabeth WEYRICH, pr\u00e9sident de chambre, Yola SCHMIT,premier conseiller, Laurent LUCAS,conseiller, Amra ADROVIC, greffier. Entre: la soci\u00e9t\u00e9\u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.),\u00e9tablie et ayant son si\u00e8ge social \u00e0L-ADRESSE1.), inscrite au Registre de Commerce et des\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-18T02:13:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"31 \u043c\u0438\u043d\u0443\u0442\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/","name":"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-18T02:13:03+00:00","dateModified":"2026-04-18T02:13:07+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-decembre-2024-n-2021-00959\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 12 d\u00e9cembre 2024, n\u00b0 2021-00959"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/591795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=591795"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=591795"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=591795"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=591795"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=591795"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=591795"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=591795"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=591795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}