{"id":603223,"date":"2026-04-19T09:32:55","date_gmt":"2026-04-19T07:32:55","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/"},"modified":"2026-04-19T09:32:58","modified_gmt":"2026-04-19T07:32:58","slug":"tribunal-darrondissement-24-janvier-2025-6","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 24 janvier 2025"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>No.62\/2025 Audience publique du vendredi,24 janvier 2025 (Not.3353\/23\/XC)-SP Le tribunal d\u2019arrondissement de et \u00e0 Diekirch, si\u00e9geant en mati\u00e8re correctionnelle et en composition de juge unique, a rendu en son audience publique du vendredi,vingt-quatre janvierdeux mille vingt-cinq, le jugement qui suit dans la cause E N T R E Monsieur le Procureur d\u2019Etat, partie poursuivante suivant citation du10 septembre2024, E T PERSONNE1.), n\u00e9 leDATE1.)\u00e0ADRESSE1.), demeurant \u00e0B-ADRESSE2.), pr\u00e9venuetd\u00e9fendeur au civil, en pr\u00e9sence des parties civiles 1)PERSONNE2.), n\u00e9eleDATE2.)\u00e0ADRESSE3.), demeurant \u00e0ADRESSE4.), 1) l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS), \u00e9tabli et ayant son si\u00e8ge social \u00e0 2144 Luxembourg, 4, rue Mercier, repr\u00e9sent\u00e9 parPERSONNE3.). ================================================== == F A I T S :<\/p>\n<p>2 Apr\u00e8s l\u2019appel de la cause \u00e0 l\u2019audience publique duvendredi,22 novembre 2024, lepr\u00e9sident constatal\u2019identit\u00e9du pr\u00e9venuPERSONNE1.)qui avait comparu en personne, etilluidonna connaissance de l\u2019acte ayant saisi le tribunal. Apr\u00e8s avoir \u00e9t\u00e9 averti de son droit de se taire et de ne pas s\u2019incriminer soi- m\u00eame, le pr\u00e9venuPERSONNE1.)fut interrog\u00e9 et entendu en ses explications et moyens de d\u00e9fense. Ma\u00eetreJosiane EISCHEN, avocat \u00e0 la Cour demeurant \u00e0 Diekirch, se constitua partie civile au nom et pour le compte dePERSONNE2.)contre PERSONNE1.). Ma\u00eetre Josiane EISCHEN d\u00e9posa des conclusions \u00e9crites qui furent sign\u00e9es par le pr\u00e9sident et par le greffier.Elled\u00e9veloppa ensuite ses conclusions oralement et conclut \u00e0 l\u2019adjudication de ses demandes. L\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS), comparant parPERSONNE3.), mandataire suivant procuration, se constitua partie civile contrePERSONNE1.). PERSONNE3.)d\u00e9veloppa ensuite ses conclusions oralement et elle conclut \u00e0 l\u2019adjudication de sa demande. Le Minist\u00e8re Public, repr\u00e9sent\u00e9 parManon RISCH,premiersubstitutdu Procureur d\u2019Etat, fut entendu en son r\u00e9quisitoire. Les moyens du pr\u00e9venu furent alors plus amplement d\u00e9velopp\u00e9s parMa\u00eetre Maud WALOCZCZYK, avocat \u00e0 la Cour demeurant \u00e0 Luxembourg, en remplacement deMa\u00eetre Aur\u00e9lia COHRS, avocat \u00e0 la Cour demeurant \u00e0 Luxembourg. Le pr\u00e9venu se vit attribuer la parole en dernier. Le tribunal prit l\u2019affaire en d\u00e9lib\u00e9r\u00e9 et fixa le prononc\u00e9 du jugement \u00e0 l\u2019audience publique du vendredi,20 d\u00e9cembre2024. A l\u2019audience du 20 d\u00e9cembre 2024, le prononc\u00e9 fut remis \u00e0l\u2019audience publique du vendredi 24 janvier 2025. A cette audience publique, le tribunal rendit le JUGEMENT qui suit: Au p\u00e9nal<\/p>\n<p>3 Vule proc\u00e8s-verbalnum\u00e9ro40463du3 juin2023, ainsi que le rapport num\u00e9ro 42459-1074 du 30 octobre 2023,dress\u00e9sparle commissariat de police d\u2019Atert. Vule rapportd\u2019expertise toxicologique num\u00e9ro23054456du6 juin2023du Laboratoire National de Sant\u00e9. Vu la citation \u00e0 pr\u00e9venudu10septembre2024(not.3353\/23\/XC). Vu l\u2019information adress\u00e9e par courriel le16septembre 2024 au serviceRecours contre tiersde la Caisse Nationale de Sant\u00e9. Le Parquet reproche \u00e0PERSONNE1.): \u00ab\u00e9tantconducteurd\u2019un v\u00e9hicule automoteur sur la voie publique, le03\/06\/2023vers16.30heures,sur laADRESSE5.)d\u2019ADRESSE6.)en direction deADRESSE7.)et notamment quelques m\u00e8tres avant le croisement de laADRESSE5.)et de laADRESSE8.),sans pr\u00e9judicequant aux indications detemps et de lieuxplusexactes, I.d\u2019avoir,par d\u00e9faut de pr\u00e9voyance ou de pr\u00e9caution, mais sans intention d\u2019attenter \u00e0 la personne d\u2019autrui, partant involontairement, caus\u00e9 des coups ou des blessures \u00e0PERSONNE4.), n\u00e9 leDATE3.),et \u00e0PERSONNE2.), n\u00e9ele DATE2.),notamment par l\u2019effet des pr\u00e9ventions suivantes: II.avoir circul\u00e9, m\u00eame en l\u2019absence des signes manifestes d\u2019ivresse, avec un taux d\u2019alcool d\u2019au moins1,2 g par litre de sang,en l\u2019esp\u00e8ce de1,65g par litre de sang, III.avoir circul\u00e9 alors que son organisme comportait la pr\u00e9sence de benzoylecgoninedont le taux s\u00e9rique est sup\u00e9rieur ou \u00e9gal \u00e025ng\/ml, en l\u2019esp\u00e8ce de338ng\/ml, IV. vitesse dangereuse selon les circonstances, V.d\u00e9faut de se comporter raisonnablement et prudemment de fa\u00e7on \u00e0 ne pas constituer un danger pour la circulation, VI.d\u00e9faut de se comporter raisonnablement et prudemment de fa\u00e7on \u00e0 ne pas causer un dommage aux personnes, VII.d\u00e9faut de se comporter raisonnablement et prudemment de fa\u00e7on \u00e0 nepas causer un dommage aux propri\u00e9t\u00e9s publiques ou priv\u00e9es, VIII.d\u00e9faut de conduire de fa\u00e7on \u00e0 rester constamment ma\u00eetre de son v\u00e9hicule, IX.d\u00e9faut depouvoir arr\u00eater son v\u00e9hicule dans les limites de son champ de visibilit\u00e9 vers l\u2019avant.\u00bb<\/p>\n<p>4 Les faits \u00e0 la base de la pr\u00e9sente affaire r\u00e9sultent \u00e0 suffisance des \u00e9l\u00e9ments du dossier soumis \u00e0 l\u2019appr\u00e9ciation de la chambre correctionnelle ainsi que de l\u2019instruction men\u00e9e \u00e0 l\u2019audience, notamment des constatations polici\u00e8res,ainsi que des d\u00e9clarations et aveuxdupr\u00e9venu. PERSONNE1.)estainsid\u00e9clar\u00e9convaincu: \u00e9tant conducteurd\u2019unv\u00e9hicule automobilesur la voie publique, le 3juin2023 vers 16.30 heures, sur laADRESSE5.)d\u2019ADRESSE6.)en direction deADRESSE7.)et notamment quelques m\u00e8tres avant le croisement de laADRESSE5.)et de laADRESSE8.), 1)d\u2019avoir, par d\u00e9faut de pr\u00e9voyanceetde pr\u00e9caution, mais sans intention d\u2019attenter \u00e0 la personne d\u2019autrui, partant involontairement, caus\u00e9 des coupsetdes blessures \u00e0PERSONNE4.), n\u00e9 leDATE3.), et \u00e0 PERSONNE2.), n\u00e9e leDATE2.). 2) d\u2019avoir circul\u00e9, m\u00eame en l\u2019absence de signes manifestes d\u2019ivresse, avec un taux d\u2019alcool d\u2019au moins1,2gpar litre de sang, en l\u2019esp\u00e8ce, d\u2019avoir circul\u00e9 avec un taux d\u2019alcool de1,65g par litre de sang. 3)d\u2019avoir circul\u00e9 alors que son organisme comportait la pr\u00e9sence de benzoylecgonine dont le taux s\u00e9rique est sup\u00e9rieur ou \u00e9gal \u00e025ng\/ml, en l\u2019esp\u00e8ce, d\u2019avoir circul\u00e9 alors que son organisme comportait la pr\u00e9sence de benzoylecgonine dont le taux s\u00e9rique est de338ng\/ml. 4) d\u2019avoir conduit \u00e0 une vitesse dangereuse selon les circonstances. 5)de ne pas s\u2019\u00eatrecomport\u00e9raisonnablement et prudemment de fa\u00e7on \u00e0 ne pas constituer un danger pour la circulation. 6)de ne pas s\u2019\u00eatre comport\u00e9 raisonnablement et prudemment de fa\u00e7on \u00e0 ne pas causer un dommage aux personnes. 7) de ne pas s\u2019\u00eatre comport\u00e9 raisonnablement et prudemment de fa\u00e7on \u00e0 ne pas causer un dommage aux propri\u00e9t\u00e9spubliques etpriv\u00e9es. 8) de ne pas avoir conduit de fa\u00e7on \u00e0 rester constamment ma\u00eetre de son v\u00e9hicule.<\/p>\n<p>5 9)de ne pas avoir circul\u00e9 en marche normale pr\u00e8s du bord droit de la chauss\u00e9e. Lesinfractions retenues \u00e0 chargedu pr\u00e9venuse trouvent en concours id\u00e9al entre elles, de sorte qu\u2019il y a lieu d\u2019appliquer les dispositions de l\u2019article 65 du Code p\u00e9nal qui dit que lorsque le m\u00eame fait constitue plusieurs infractions, la peine la plus forte sera seule prononc\u00e9e. Les infractions \u00e0 l\u2019article 9bis alin\u00e9a2 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 concernant la r\u00e9glementation de la circulation sur toutes les voies publiques sont punies d\u2019un emprisonnement de huit jours \u00e0 trois ans etd\u2019une amende de 500 \u00e0 12.500 euros oud\u2019une de ces peines seulement. Aux termes de l\u2019article 12 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 concernant la r\u00e9glementation de la circulation sur toutes les voies publiques, tout conducteur d\u2019un v\u00e9hicule qui a consomm\u00e9 des boissons alcooliques en quantit\u00e9 telle que le taux d\u2019alcool estd\u2019au moins 1,2 g d\u2019alcool par litre de sang ou d\u2019au moins 0,55 mg d\u2019alcool par litre d\u2019air expir\u00e9 sera condamn\u00e9 \u00e0 une peine d\u2019emprisonnement de huit jours \u00e0 trois ans et \u00e0 une amende de 500 \u00e0 10.000 euros ou \u00e0 une de ces peines seulement. Aux termes de l\u2019article 12 paragraphe 4 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 concernant la r\u00e9glementation de la circulation sur toutes les voies publiques, tout conducteur d\u2019un v\u00e9hicule dont l\u2019organisme comporte la pr\u00e9sence de t\u00e9trahydrocannabinol (THC),d\u2019amph\u00e9tamines, de m\u00e9thamph\u00e9tamines, de MDMA, de MDA, de morphine (libre), de coca\u00efne ou de benzoylecgonine (BZE) et dont le taux s\u00e9rique est \u00e9gal ou sup\u00e9rieur \u00e0 1 ng\/ml pour le THC, respectivement \u00e0 10 ng\/ml pour la morphine, respectivement \u00e0 25 ng\/ml pour les autres substances, sera condamn\u00e9 \u00e0 une peine d\u2019emprisonnement de huit jours \u00e0 trois ans et \u00e0 une amende de 500 \u00e0 10.000 euros ou \u00e0 une de ces peines seulement. Dans l\u2019appr\u00e9ciation du quantum de la peine \u00e0 prononcer \u00e0 l\u2019\u00e9garddupr\u00e9venu, la chambre correctionnelle tient compte d\u2019une part de la gravit\u00e9 objective des faitsretenus\u00e0 sa charge et d\u2019autre part de sa situation personnelle. Au vu des circonstances de l\u2019affaire, la chambre correctionnelle estime qu\u2019une peine d\u2019emprisonnement serait inad\u00e9quate car trop s\u00e9v\u00e8re, et elle d\u00e9cide de ne condamnerPERSONNE1.)qu\u2019\u00e0 une amende de 1.000 euros du chef des infractions retenues\u00e0 sa charge. Aux termes de l\u2019article 13 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 concernant la r\u00e9glementation de la circulation sur toutes les voies publiques,le juge saisi d\u2019une ou de plusieurs infractions \u00e0 la r\u00e9glementation de la circulation sur toutes les voies publiques ou de d\u00e9lits ou de crimes qui se sont joints \u00e0 ces infractions, pourra prononcer une interdiction de conduire de huit jours \u00e0 un an enmati\u00e8re de contraventions et de trois mois \u00e0 quinze ans en mati\u00e8re de d\u00e9lits ou de crimes.<\/p>\n<p>6 L\u2019interdiction de conduire est cependant obligatoire en cas de circulation en \u00e9tat d\u2019ivresse d\u2019apr\u00e8s lesdispositions du m\u00eame article 13. Au vu des circonstances de l\u2019affaireet de lasituationpersonnelledu pr\u00e9venu, la chambre correctionnelle d\u00e9cide de prononcer contrePERSONNE1.)une interdiction de conduire de34mois du chefdes infractions retenues \u00e0 sa charge. Au vudu casierjudiciaireviergedans le chefdu pr\u00e9venuPERSONNE1.), la chambre correctionnelle d\u00e9cidefinalementd\u2019assortir l\u2019interdiction de conduire \u00e0 prononcer \u00e0 son encontre du sursispartiel de 15 mois. Au civil 1) Partie civile de l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS) contrePERSONNE1.): A l\u2019audience de la chambre correctionnelle du22 novembre2024, PERSONNE3.), d\u00fbment mandat\u00e9e en vertu d\u2019une procuration dat\u00e9e du21 novembre 2024, s\u2019est constitu\u00e9 partie civile au nom et pour le compte de l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS) contre PERSONNE1.). Cette partie civile, d\u00e9pos\u00e9e sur le bureau de la chambre correctionnelle, est con\u00e7ue dans les termes suivants :<\/p>\n<p>10 Il y alieu de donner acte \u00e0 l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS) de sa constitution de partie civile. La chambre correctionnelle est comp\u00e9tente pour conna\u00eetre de cette demande civile eu \u00e9gard \u00e0 la d\u00e9cision \u00e0 intervenir au p\u00e9nal \u00e0 l\u2019\u00e9gard dePERSONNE1.). La demande civile est recevable pour avoir \u00e9t\u00e9 faite dans la forme et dans le d\u00e9lai de la loi. La partie demanderesse au civil expose qu\u2019elle est intervenue dans le cadre de l\u2019assurance-maladie dePERSONNE4.)et dePERSONNE2.)sur base de l\u2019article 82 du Code de la s\u00e9curit\u00e9 sociale et qu\u2019elle a d\u00e9bours\u00e9 le montant de 2.012,45euros pour son assur\u00e9PERSONNE4.), dont360,70 euros \u00e0 titre de frais hospitaliers, 1.396,91euros \u00e0 titre de frais m\u00e9dicaux, 14,84 euros \u00e0 titre de frais pharmaceutiqueset240euros \u00e0 titre de frais de transport. Elle expose encore qu\u2019elle a d\u00e9bours\u00e9 le montant de48.726,34 euros pour son assur\u00e9e PERSONNE2.), dont29.851,02euros \u00e0 titre de frais hospitaliers,5.069,01 euros \u00e0 titre de frais m\u00e9dicaux,444,54euros \u00e0 titre de frais pharmaceutiques, 251,08euros \u00e0 titre de frais de transport, 4.924,26 euros \u00e0 titre des massages et physioth\u00e9rapie,395,40 euros \u00e0 titre de moyen accessoires, 7.213,23 euros \u00e0 titre des soins infirmierset577,80euros \u00e0 titre d\u2019urgence. Au total, elle aurait ainsi d\u00e9bours\u00e9 la somme de50.738,79euros, somme dont elle r\u00e9clame le remboursement. Elle r\u00e9clame \u00e9galement les int\u00e9r\u00eats au taux l\u00e9gal sur cette somme \u00e0 partir du3juin2023, jour de l\u2019accident, jusqu\u2019\u00e0 solde. Eu \u00e9gard aux pi\u00e8ces vers\u00e9es au dossier, la chambre correctionnelle constate que les diff\u00e9rents chefs de pr\u00e9judice soulev\u00e9s par la demanderesse au civil, de m\u00eame que les montants y relatifs, se trouvent \u00e0 suffisance \u00e9tablis et, au vu des circonstances de l\u2019affaire, la demande est fond\u00e9e en son principe. La chambre correctionnelle d\u00e9cide ainsi de fixer le pr\u00e9judice subi par l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS) au montant r\u00e9clam\u00e9 de50.738,79euros et condamne partant le d\u00e9fendeur au civil PERSONNE1.)\u00e0 payer le pr\u00e9dit montant l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS), le tout avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 partir du3 juin2023, jour de l\u2019accident, jusqu\u2019\u00e0 solde. 2) Partie civile dePERSONNE2.)contrePERSONNE1.): A l\u2019audience du22 novembre2024, Ma\u00eetreJosiane EISCHEN, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch, s\u2019est constitu\u00e9epartie civile au nom et pour compte dePERSONNE2.)contrePERSONNE1.). Cette partie civile, d\u00e9pos\u00e9e sur le bureau du tribunal d\u2019arrondissement de Diekirch, si\u00e9geant en mati\u00e8re correctionnelle est con\u00e7ue dans les termes suivants :<\/p>\n<p>12 Il y a lieu de donner acte \u00e0PERSONNE2.)de sa constitution de partie civile. La chambre correctionnelle est comp\u00e9tente pour conna\u00eetre de cette demande civile eu \u00e9gard \u00e0 la d\u00e9cision \u00e0 intervenir au p\u00e9nal \u00e0 l\u2019\u00e9gard dePERSONNE1.). La demande civile est recevable pour avoir \u00e9t\u00e9 faite dans la forme et dans le d\u00e9lai de la loi. PERSONNE2.)r\u00e9clamele montant de 50.000 euros du chef de son dommage corporel etd\u2019atteinte \u00e0 l\u2019int\u00e9grit\u00e9physique, le montant de 15.000 euros du chef du dommage moral etde pretiumdoloris, 2.500 euros duchef depr\u00e9judice esth\u00e9tique, 1.500du chef ded\u00e9g\u00e2ts mat\u00e9riels (lunettes cass\u00e9es et vestimentaires) et1.000du chef defrais m\u00e9dicaux et para-m\u00e9dicaux. PERSONNE2.)r\u00e9clameen toutle montant total de 70.000 avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 partir de la date des faits, soit le 3 juin 2023, jusqu\u2019\u00e0 solde. La partie requ\u00e9rante sollicite\u00e0 titre subsidiairel\u2019institution d\u2019une expertise aux fins de lui permettre d\u2019\u00e9tablir pr\u00e9cis\u00e9ment le quantum de son pr\u00e9judice corporel subi, ainsi que l\u2019allocation d\u2019une provision \u00e0 hauteur de 2.500 \u20ac \u00e0 faire valoir sur ce chef de pr\u00e9judice. Finalement,PERSONNE2.)r\u00e9clame une indemnit\u00e9 de proc\u00e9dure de1.000 euros sur base de l\u2019article 194 du Code de proc\u00e9dure p\u00e9nale. La partie d\u00e9fenderesse au civil ne contestepasla demande civile en son principe. La chambre correctionnelle ne s\u2019estimeactuellementpas en mesure d\u2019\u00e9valuer le pr\u00e9judice subi parPERSONNE2.)\u00e0 la suite de l\u2019accident du3juin 2023, de sorte qu\u2019elle d\u00e9cide d\u2019ordonner une expertise. Le tribunal d\u00e9cide en l\u2019esp\u00e8ce de nommer le Dr. Marc KAYSER en tant qu\u2019expert m\u00e9dical et Ma\u00eetreLuc OLINGERen tant qu\u2019expert-calculateur, avec leur mission plus amplement d\u00e9finie au dispositif du pr\u00e9sent jugement. Le tribunal d\u00e9cide encore d\u2019allouer d\u2019ores-et-d\u00e9j\u00e0 \u00e0PERSONNE2.)une indemnit\u00e9 provisionnelle de 2.500 euros. Il y a finalement lieu d\u2019allouer \u00e0 la partie demanderesse une indemnit\u00e9 de proc\u00e9dure \u00e0 hauteur de1.000euros. Parcesmotifs,<\/p>\n<p>13 le tribunal d\u2019arrondissement de et \u00e0 Diekirch, si\u00e9geant en mati\u00e8re correctionnelle et en composition de juge unique, statuant contradictoirement et en premi\u00e8re instance, le pr\u00e9venu et d\u00e9fendeur au civilPERSONNE1.), et son mandataire, entendus en leurs explications et moyens de d\u00e9fense au p\u00e9nal et en leurs conclusions au civil,l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS)etPERSONNE2.), demandeursau civil, entendus par le biais de leurs mandataires en leurs conclusions au civil, le repr\u00e9sentantdu Minist\u00e8re Public entendu en son r\u00e9quisitoire, le pr\u00e9venu ayant eu la parole en dernier, statuant au p\u00e9nal c o n d a m n ePERSONNE1.)du chef des infractions retenues \u00e0 sa charge \u00e0 une amende d\u2019un montant deMILLE(1.000) EUROS, f i x ela dur\u00e9e de la contrainte par corps en cas de non-paiement decette amende \u00e0DIX(10) JOURS, p r o n o n c econtrePERSONNE1.)une interdiction de conduire un v\u00e9hicule automoteur des cat\u00e9gories A, B, C, D, E et F sur toutes les voies publiques pour une dur\u00e9e deTRENTE-QUATRE(34)MOISdu chef des infractions retenues \u00e0 sa charge, d i tqu\u2019il seraSURSIS\u00e0 l\u2019ex\u00e9cution deQUINZE (15) MOISdecette interdiction de conduire, i n f o r m elepr\u00e9venu qu\u2019au cas o\u00f9, dans un d\u00e9lai de 5 ans \u00e0 dater du pr\u00e9sent jugement,iln\u2019aura commis une nouvelle infraction ayant entra\u00een\u00e9 la condamnation \u00e0 une interdiction de conduire un v\u00e9hicule sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour crimes ou d\u00e9lits pr\u00e9vus par la l\u00e9gislation sur la circulation sur les voies publiques ou sur la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie, l\u2019interdiction sera r\u00e9put\u00e9e non avenue, a v e r t i tlepr\u00e9venu que, dans le cas contraire, conform\u00e9ment \u00e0 l\u2019article 628 du Code de proc\u00e9dure p\u00e9nale, la premi\u00e8re peine sera d\u2019abord ex\u00e9cut\u00e9e sans qu\u2019elle ne puisse se confondre, le cas \u00e9ch\u00e9ant, avec la nouvelle interdiction de conduire, c o n d a m n ePERSONNE1.)auxfrais de sa poursuite p\u00e9nale, ces frais \u00e9tant liquid\u00e9s \u00e0 la somme de474,99euros, statuant au civil<\/p>\n<p>14 Partie civilede l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS): d o n n ea c t e\u00e0 l\u2019\u00e9tablissement publicCAISSE NATIONALE DE SANT\u00c9 (CNS)de sa constitution de partie civile contrePERSONNE1.), sed \u00e9 c l a r ecomp\u00e9tent pour en conna\u00eetre, d \u00e9 c l a r ela demande civile recevable en la forme, lad \u00e9 c l a r efond\u00e9e, c o n d a m n ePERSONNE1.)\u00e0 payer \u00e0l\u2019\u00e9tablissementpublic CAISSE NATIONALE DE SANT\u00c9 (CNS) le montant deCINQUANTE MILLE SEPT CENT TRENTE -HUIT virgule SOIXANTE-NEUF (50.738,79) EUROS, avec les int\u00e9r\u00eats au taux l\u00e9gal \u00e0 partir du3 juin2023, jour de l\u2019accident, jusqu\u2019\u00e0 solde, d o n n e a c t e\u00e0 l\u2019\u00e9tablissement public CAISSE NATIONALE DE SANT\u00c9 (CNS) qu\u2019ilse r\u00e9serve tous autres droits, dus, moyens et actions, c o n d a m n ePERSONNE1.)aux frais de cette demande civile dirig\u00e9e contre lui. Partie civile dePERSONNE5.): d o n n e acte\u00e0PERSONNE2.)de sa constitution de partie civile, s e d \u00e9 c l a r ecomp\u00e9tent pour en conna\u00eetre, d \u00e9 c l a r elademande civile recevable en la forme, lad \u00e9 c l a r efond\u00e9e en son principe, avant tout autre progr\u00e8s,<\/p>\n<p>15 n o m m eun coll\u00e8ge d\u2019experts, compos\u00e9: -de l\u2019expert m\u00e9dical, le Dr.Marc KAYSER,expert en chirurgie orthop\u00e9dique ettraumatologique, demeurant \u00e0 L-1130Luxembourg,46, rue d\u2019Anvers, -de l\u2019expert-calculateur, Ma\u00eetreLuc OLINGER, avocat \u00e0 la Cour, demeurant \u00e0L-2340 Luxembourg,34A, rue Philippe II, avec la mission de concilier les parties si faire se peut,sinon d\u2019\u00e9valuer dans un rapport \u00e9crit, d\u00e9taill\u00e9 et motiv\u00e9le pr\u00e9judicemat\u00e9riel,moralet corporelsubi par PERSONNE2.),tel que r\u00e9clam\u00e9 dans sa constitution de partie civile,\u00e0 la suite de l\u2019accident du3 juin2023, sous r\u00e9serve des recours \u00e9ventuels des organismes de s\u00e9curit\u00e9 socialeluxembourgeois et\/ou belges, a u t o r i s eles experts \u00e0 s\u2019entourer de tous renseignements utiles et n\u00e9cessaires \u00e0 l\u2019accomplissement de la mission leur confi\u00e9e et m\u00eame \u00e0 entendre de tierces personnes, d i tqu\u2019en cas de refus, d\u2019emp\u00eachement ou de retard d\u2019un des experts, il sera pourvu \u00e0 son remplacement sur simple requ\u00eate pr\u00e9sent\u00e9e au pr\u00e9sident du si\u00e8ge par la partie la plus diligente, l\u2019autre partie d\u00fbment convoqu\u00e9e, c o n d a m n ePERSONNE1.)\u00e0 payer \u00e0PERSONNE2.)le montant de DEUXMILLECINQ CENTS(2.500) EUROS\u00e0 titre de provision, c o n d a m n ePERSONNE1.)\u00e0 payer \u00e0PERSONNE2.)le montant de MILLE(1.000) EUROS\u00e0 titre d\u2019indemnit\u00e9 de proc\u00e9dure, r \u00e9 s e r v eles frais, f i x el\u2019affaire au r\u00f4le sp\u00e9cial. Par application des articles9bis,12et 13 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 concernant la r\u00e9glementation de la circulation sur toutes les voies publiques, desarticles 118, 139et140 de l\u2019arr\u00eat\u00e9 grand-ducal modifi\u00e9 du 23 novembre 1955 portant r\u00e8glement de la circulation sur toutes les voies publiques, des articles 27, 28, 29, 30et 65 du Code p\u00e9nal, et des articles179, 182,183-1,184, 185, 189, 190, 190-1,191,194, 195,196, 628 et 628-1du Code de proc\u00e9dure p\u00e9nale. Ainsi faitetjug\u00e9parJean-Claude WIRTH,premierjuge,etprononc\u00e9 en audience publique le vendredi,24 janvier 2025,au Palais de Justice \u00e0 Diekirch parJean-Claude WIRTH, premierjuge, assist\u00e9 du greffierassum\u00e9 Saban<\/p>\n<p>16 KALABIC, en pr\u00e9sencedeMartine LEYTEM, Procureur d\u2019Etat adjoint, qui,\u00e0 l\u2019exception du repr\u00e9sentant du Minist\u00e8re Public,ont sign\u00e9 le pr\u00e9sent jugement. Ce jugement est susceptible d\u2019appel. L\u2019appel doit \u00eatre interjet\u00e9 dans les formes et d\u00e9lais pr\u00e9vus aux articles 202 et suivants du Code de proc\u00e9dure p\u00e9nale et il doit \u00eatre form\u00e9 par le pr\u00e9venu ou son avocat, la partie civile ainsi que la partie civilement responsable ou leurs avocats respectifs dans les40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement, aupr\u00e8s du greffe du Tribunal d\u2019arrondissement de Diekirch, en se pr\u00e9sentantpersonnellement pour signer l\u2019acte d\u2019appel. L\u2019appel peut \u00e9galement \u00eatre interjet\u00e9, dans les40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement par voie decourrier \u00e9lectronique\u00e0 adresser au guichet du greffe du Tribunal d\u2019arrondissement de Diekirch \u00e0 l\u2019adressetad.correctionnel.greffe@justice.etat.lu. Si le pr\u00e9venu estd\u00e9tenu,il peut d\u00e9clarer son appel au greffe du Centre p\u00e9nitentiaire.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-diekirch\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-diekirch\/20250526-012614\/20250124-tadpenal-62-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No.62\/2025 Audience publique du vendredi,24 janvier 2025 (Not.3353\/23\/XC)-SP Le tribunal d\u2019arrondissement de et \u00e0 Diekirch, si\u00e9geant en mati\u00e8re correctionnelle et en composition de juge unique, a rendu en son audience publique du vendredi,vingt-quatre janvierdeux mille vingt-cinq, le jugement qui suit dans la cause E N\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[],"kji_year":[8463],"kji_subject":[7724],"kji_keyword":[23584,23621,8460,23622,7636],"kji_language":[7733],"class_list":["post-603223","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_year-8463","kji_subject-civil","kji_keyword-arrondissement","kji_keyword-audience","kji_keyword-janvier","kji_keyword-publique","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 24 janvier 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 24 janvier 2025\" \/>\n<meta property=\"og:description\" content=\"No.62\/2025 Audience publique du vendredi,24 janvier 2025 (Not.3353\/23\/XC)-SP Le tribunal d\u2019arrondissement de et \u00e0 Diekirch, si\u00e9geant en mati\u00e8re correctionnelle et en composition de juge unique, a rendu en son audience publique du vendredi,vingt-quatre janvierdeux mille vingt-cinq, le jugement qui suit dans la cause E N\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-19T07:32:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-janvier-2025-6\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-janvier-2025-6\\\/\",\"name\":\"Tribunal d'arrondissement, 24 janvier 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-19T07:32:55+00:00\",\"dateModified\":\"2026-04-19T07:32:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-janvier-2025-6\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-janvier-2025-6\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-janvier-2025-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 24 janvier 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 24 janvier 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 24 janvier 2025","og_description":"No.62\/2025 Audience publique du vendredi,24 janvier 2025 (Not.3353\/23\/XC)-SP Le tribunal d\u2019arrondissement de et \u00e0 Diekirch, si\u00e9geant en mati\u00e8re correctionnelle et en composition de juge unique, a rendu en son audience publique du vendredi,vingt-quatre janvierdeux mille vingt-cinq, le jugement qui suit dans la cause E N\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-19T07:32:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"18 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/","name":"Tribunal d'arrondissement, 24 janvier 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-19T07:32:55+00:00","dateModified":"2026-04-19T07:32:58+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-janvier-2025-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 24 janvier 2025"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/603223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=603223"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=603223"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=603223"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=603223"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=603223"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=603223"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=603223"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=603223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}