{"id":621240,"date":"2026-04-20T11:41:15","date_gmt":"2026-04-20T09:41:15","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/"},"modified":"2026-04-20T11:41:18","modified_gmt":"2026-04-20T09:41:18","slug":"tribunal-darrondissement-30-mai-2025-2","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 30 mai 2025"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Jugement no1741\/2025 not.43579\/22\/CC 2xi.c.(s) AUDIENCE PUBLIQUE DU 30 MAI 2025 LeTribunald&#039;arrondissement de et \u00e0 Luxembourg,vingt-troisi\u00e8mechambre correctionnelle, statuant en composition dejuge unique, a rendu le jugement qui suit: dans la cause duMinist\u00e8re Publiccontre PERSONNE1.), n\u00e9leDATE1.)\u00e0ADRESSE1.)(ADRESSE2.)), demeurant\u00e0L-ADRESSE3.), comparant en personne, assist\u00e9 deMa\u00eetreCl\u00e9ment MARTINEZ, avocat \u00e0 la Cour, demeurant\u00e0 Luxembourg, -p r \u00e9 v e n u\u2013 _________________________________________________________________________ F A I T S : Par citation du23d\u00e9cembre2024,leProcureurd&#039;Etat pr\u00e8s leTribunald&#039;arrondissement de Luxembourg a requis lepr\u00e9venu de compara\u00eetre \u00e0 l&#039;audience publique du28janvier2025 devant leTribunalcorrectionnel de ce si\u00e8ge,pour y entendre statuer sur lespr\u00e9ventions suivantes: circulation : principalement : avoir pris lafuite pour \u00e9chapper aux constatations utiles;subsidiairement :ne pas avoir communiqu\u00e9 au plus t\u00f4t son identit\u00e9 \u00e0 la partie l\u00e9s\u00e9e non pr\u00e9sente, par l\u2019interm\u00e9diaire de la police; contraventions. A l\u2019audience du 28 janvier 2025, l\u2019affaire fut contradictoirement remise \u00e0 l\u2019audience publique du 5 mai 2025.<\/p>\n<p>2 A cette audience,lepr\u00e9sident constata l&#039;identit\u00e9 du pr\u00e9venuPERSONNE1.), lui donna connaissance de l\u2019acte qui a saisi leTribunalet l\u2019informa de son droit dese taire et de son droit de ne pas s\u2019incriminer soi-m\u00eame. Le t\u00e9moinPERSONNE2.)fut entendu en ses d\u00e9clarations orales apr\u00e8s avoir pr\u00eat\u00e9 le serment pr\u00e9vu \u00e0 l\u2019article 155 du Code de proc\u00e9dure p\u00e9nale. Le pr\u00e9venuPERSONNE1.)fut entendu en ses explications et moyens de d\u00e9fense. Larepr\u00e9sentanteduMinist\u00e8re Public,Charlotte MARC,substitut,r\u00e9suma l\u2019affaire etfut entendueen son r\u00e9quisitoire. Ma\u00eetreCl\u00e9ment MARTINEZ, avocat \u00e0 la Cour, demeurant \u00e0Luxembourg, d\u00e9veloppa plus amplement les moyens de d\u00e9fense du pr\u00e9venuPERSONNE1.). Le pr\u00e9venuPERSONNE1.)eut la parole en dernier. LeTribunalprit l&#039;affaire en d\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l&#039;audience publique de ce jour, date \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9,le J U G E M E N T qui suit: Vu la citation \u00e0 pr\u00e9venu du23d\u00e9cembre2024(not.43579\/22\/CC)r\u00e9guli\u00e8rement notifi\u00e9e au pr\u00e9venu. Vu le proc\u00e8s-verbal num\u00e9ro13640\/2022\u00e9tabli en date du22juillet2022par la Police Grand- Ducale,R\u00e9gionSud-Ouest, Commissariat Esch. Le Minist\u00e8re Public reproche \u00e0PERSONNE1.)d\u2019avoir,le22 juillet 2022 vers 23.25 heures, ADRESSE4.)\u00e0ADRESSE5.),commis un d\u00e9lit de fuite, sinon dene pas avoir communiqu\u00e9 au plus t\u00f4t son identit\u00e9 \u00e0 la partiel\u00e9s\u00e9enon pr\u00e9sente, par l\u2019interm\u00e9diaire de la police ainsi qu\u2019avoir commis trois contraventions au Code de la route. Le Tribunal correctionnel est comp\u00e9tent pour conna\u00eetre descontraventionslibell\u00e9essub2), 3) et 4),celles-ci se trouvant dans un lien de connexit\u00e9 avec le d\u00e9lit libell\u00e9 sub 1) dans la citation \u00e0 pr\u00e9venu. Il r\u00e9sulte du pr\u00e9dit proc\u00e8s-verbal que le 22 juillet 2022,PERSONNE3.)se pr\u00e9senta au commissariat de police pour d\u00e9clarer qu\u2019il venait d\u2019\u00eatre impliqu\u00e9 dans un accident de la circulation \u00e0 la sortie de l\u2019autoroute A4. Son v\u00e9hicule aurait \u00e9t\u00e9 heurt\u00e9 \u00e0 l\u2019arri\u00e8re, un v\u00e9hiculeRenaultMegane de couleur rouge, immatricul\u00e9NUMERO1.)(L). Le conducteur dudit v\u00e9hicule aurait quitt\u00e9 les lieux imm\u00e9diatement apr\u00e8s l\u2019accident. Entendu comme t\u00e9moin \u00e0 l\u2019audience,PERSONNE4.)d\u00e9posa s\u2019\u00eatre trouv\u00e9 dans le v\u00e9hicule d\u2019PERSONNE3.)au moment de l\u2019accident.<\/p>\n<p>3 Ild\u00e9clara que son ami aurait d\u00e9pass\u00e9 le v\u00e9hicule car celui-ci roulait tr\u00e8s lentement et qu\u2019apr\u00e8s ce d\u00e9passement, leur v\u00e9hicule aurait \u00e9t\u00e9 heurt\u00e9 \u00e0 l\u2019arri\u00e8re. Le conducteur du second v\u00e9hicule aurait imm\u00e9diatement quitt\u00e9 les lieux. Le pr\u00e9venu reconnut \u00e0 l\u2019audience qu\u2019apr\u00e8s avoir heurt\u00e9 le v\u00e9hicule d\u2019PERSONNE3.), il aurait fait marche arri\u00e8re et il aurait emprunt\u00e9 la bretelle versADRESSE6.). Il d\u00e9clara avoir agi sous la panique. Il n\u2019aurait n\u00e9anmoins pas cherch\u00e9 \u00e0 \u00e9chapper \u00e0 sa responsabilit\u00e9, comme il aurait le jour m\u00eame d\u00e9clar\u00e9 le sinistre \u00e0 son assurance. Le tribunal se doit de constater qu\u2019il est \u00e9tabli par la d\u00e9position du t\u00e9moinPERSONNE2.) que le pr\u00e9venu heurta le v\u00e9hicule d\u2019PERSONNE3.)\u00e0 l\u2019arri\u00e8re. En ce faisant, il a manqu\u00e9 de ma\u00eetrise et caus\u00e9 par son imprudence des dommages \u00e0 la propri\u00e9t\u00e9 priv\u00e9e d\u2019PERSONNE3.). Il est encore \u00e9tabli par l\u2019aveu du pr\u00e9venu qu\u2019apr\u00e8s l\u2019accident, celui-ci a fait marche arri\u00e8re sur la bretelle de sortie de l\u2019autoroute et qu\u2019il a alors emprunt\u00e9 la bretelle versADRESSE6.). Un tel comportement sur une bretelle de sortie d\u2019une autoroute n\u2019est niprudent, ni raisonnable et constitue un danger pour la circulation. Les contraventions mises \u00e0 la charge du pr\u00e9venu sont ainsi toutes \u00e9tablies. Pour ce qui est du d\u00e9lit de fuitemis \u00e0 charge du pr\u00e9venu, le tribunal constate que cette infraction est une infraction instantan\u00e9e qui ne se consume cependant pas imm\u00e9diatement apr\u00e8s le sinistre, mais se consume d\u00e8s que l\u2019auteur d\u2019un accident quitte le lieu du sinistre avant que les constatations utilesaientpu \u00eatre faites, respectivement quand il quitte le lieu du sinistre sans du moins y avoir laiss\u00e9 ses coordonn\u00e9es, respectivement avoir inform\u00e9 la police de son identit\u00e9. Il est constant en cause qu\u2019en l\u2019esp\u00e8ce, le pr\u00e9venu a quitt\u00e9 les lieux du sinistre et qu\u2019il savait, au moment o\u00f9 il fit marche arri\u00e8re, qu\u2019il venait de heurter un v\u00e9hicule. Il est encore constant en cause que le pr\u00e9venu n\u2019a pasinform\u00e9 la police de l\u2019accident qui venait de se produire. S\u2019ilen a inform\u00e9 son assureur,il n\u2019a n\u00e9anmoins pas fourni\u00e0 l\u2019assureur les coordonn\u00e9es du conducteur adverse. Le tribunal en d\u00e9duit que le but premier recherch\u00e9 par le pr\u00e9venu lors de la d\u00e9claration de sinistre \u00e9tait sa propre indemnisation par son assureur et non son identification comme auteur de l\u2019accident. Tous les \u00e9l\u00e9ments constitutifs du d\u00e9lit de fuite mis \u00e0 la charge du pr\u00e9venu sont ainsi \u00e9tablis dans son chef.<\/p>\n<p>4 PERSONNE1.)est partantconvaincupar les\u00e9l\u00e9ments du dossier r\u00e9pressif, ensembleavec lesd\u00e9bats men\u00e9s \u00e0 l&#039;audience etsesaveux : \u00abEtant conducteur d\u2019un v\u00e9hicule automoteur sur la voie publique, Le 22 juillet 2022 vers 23.25 heures,ADRESSE4.)\u00e0ADRESSE5.),enprovenance de l\u2019autoroute A4, 1)Sachant qu\u2019il a caus\u00e9 un accident, avoir pris la fuite pour \u00e9chapper aux constatations utiles, m\u00eame si l\u2019accident n\u2019est pas imputable \u00e0 sa faute, 2)D\u00e9faut de se comporter raisonnablement et prudemment de fa\u00e7on \u00e0 ne pasconstituer un danger pour la circulation, 3)D\u00e9faut de se comporter raisonnablement et prudemment de fa\u00e7on \u00e0 ne pas causer un dommage aux propri\u00e9t\u00e9s priv\u00e9es 4)D\u00e9faut de conduire de fa\u00e7on \u00e0 rester constamment ma\u00eetre de son v\u00e9hicule\u00bb Lescontraventions retenues sub3) et4)\u00e0 charge du pr\u00e9venu se trouvent en concours id\u00e9al entre elles. De m\u00eame, la contravention retenue sub 2) setrouveen concours id\u00e9al avec le d\u00e9lit de fuite retenu sub1) \u00e0 son encontre. Ces deux groupes d\u2019infractions se trouvent en concours r\u00e9el entre eux. Il y a partant lieu \u00e0 application des dispositionsdes articles 59 et65 du Code p\u00e9nalet de prononcer une amende contraventionnelle pour le groupe des deux contraventions et une amended\u00e9lictuellepour legroupe avec led\u00e9lit de fuite. Les contraventions retenues sub 3) et 4) sont sanctionn\u00e9es d\u2019une amende de 25 \u00e0 250 euros. L\u2019article 9 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 pr\u00e9cit\u00e9e sanctionne le d\u00e9lit de fuite d\u2019une peine d\u2019emprisonnement de huit jours \u00e0 trois ans ainsi que d\u2019une amende de 500 \u00e0 10.000 euros, ou d\u2019une de ces peines seulement. Eu \u00e9gard \u00e0 la gravit\u00e9 relative des contraventions retenues sub 3) et 4) \u00e0 charge du pr\u00e9venu, le tribunal estime que celles-ci sontad\u00e9quatementsanctionn\u00e9es par uneamendede50.-euros. Face \u00e0 la dangerosit\u00e9 du comportement du pr\u00e9venu apr\u00e8s l\u2019accident, ensemble avec son d\u00e9part injustifi\u00e9 des lieux, mais \u00e9galement son absence d\u2019ant\u00e9c\u00e9dents en mati\u00e8re de circulation routi\u00e8re et la dur\u00e9e d\u00e9raisonnable \u00e9coul\u00e9e depuis les faits, le tribunal estimeque le d\u00e9lit de fuite est ad\u00e9quatement sanctionn\u00e9par l\u2019amende minimalede500.-euros. L\u2019article 13 point 1. de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 pr\u00e9cit\u00e9e permet au juge saisi d\u2019une ou de plusieurs infractions \u00e0 la r\u00e9glementation de la circulation sur toutes les voies publiques ou de d\u00e9lits ou de crimes qui se sont joints \u00e0 ces infractions,de prononcer une interdiction de conduire de trois mois \u00e0 quinze ans en mati\u00e8re de d\u00e9lits.<\/p>\n<p>5 En l\u2019esp\u00e8ce, le tribunal estime qu\u2019il est appropri\u00e9 de sanctionner le d\u00e9lit de fuite commis d\u2019une interdiction de conduirede12 mois, tel que requis par le Minist\u00e8re public. L\u2019article 628 alin\u00e9a 4 du Code de proc\u00e9dure p\u00e9nale permet au Tribunal qui prononce une interdiction de conduire, d\u2019ordonner qu\u2019il sera sursis \u00e0 l\u2019ex\u00e9cution de tout ou partie de cette peine accessoire, \u00e0 condition que le condamn\u00e9 n\u2019ait pas \u00e9t\u00e9, avant le fait motivant sa poursuite, l\u2019objet d\u2019une condamnation irr\u00e9vocable \u00e0 une peine d\u2019emprisonnement correctionnel du chef d\u2019infraction aux lois et r\u00e8glements r\u00e9gissant la circulation sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour infraction aux lois et r\u00e8glements concernant la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie. Le pr\u00e9venuPERSONNE1.)n&#039;a pas subi de condamnation excluant le sursis \u00e0 l&#039;ex\u00e9cution des peines et il n&#039;est pas indigne de la cl\u00e9mence du Tribunal. Il y a partant lieu de lui accorder la faveur dusursis int\u00e9gralquant \u00e0 l\u2019interdiction de conduire \u00e0 prononcer \u00e0 son encontre. P A R C E S M O T I F S : leTribunald&#039;arrondissement de et \u00e0 Luxembourg,vingt-troisi\u00e8mechambre, compos\u00e9e de son pr\u00e9sident, si\u00e9geant enmati\u00e8re correctionnelle,statuantcontradictoirement,le pr\u00e9venuet son mandataire entendusenleursexplications et moyens de d\u00e9fense,larepr\u00e9sentanteduMinist\u00e8re Publicentendueen ses r\u00e9quisitionsetle pr\u00e9venu ayant eu la parole le dernier, s ed \u00e9 c l a r ecomp\u00e9tentpour conna\u00eetre descontraventionslibell\u00e9essub2, 3) et 4)\u00e0 charge du pr\u00e9venu, c o n d a m n elepr\u00e9venuPERSONNE1.)du chefdes contraventions en concours id\u00e9al retenues sub 3) et 4) \u00e0 sa charge \u00e0 une amende contraventionnelle decinquante(50.-) euros; c o n d a m n ele pr\u00e9venuPERSONNE1.)du chef des infractions en concours id\u00e9al retenues sub 1) et 2) \u00e0 sa charge\u00e0 une amendecorrectionnelledecinqcents(500.-) euros c o n d a m n ele pr\u00e9venuPERSONNE1.)auxfrais de sa mise en jugement, ces frais liquid\u00e9s \u00e025,22euros; f i x ela dur\u00e9e de la contrainte par corps en cas de non-paiement del\u2019amende contraventionnelle \u00e0un (1) jour etde l\u2019amende d\u00e9lictuelle\u00e0cinq(5) jours; p r o n o n c econtrele pr\u00e9venuPERSONNE1.)du chef de l\u2019infraction retenuesub 1)\u00e0 sa charge pour la dur\u00e9e dedouze(12) moisl&#039;interdiction de conduire un v\u00e9hicule automoteur des cat\u00e9gories A-F sur la voie publique; d i tqu\u2019il sera sursis \u00e0 l\u2019ex\u00e9cution del\u2019int\u00e9gralit\u00e9decette interdiction de conduire; a v e r t i tlepr\u00e9venuPERSONNE1.)qu\u2019au cas, o\u00f9 dans un d\u00e9lai de cinq ans \u00e0 dater du pr\u00e9sent jugement, il aura commis une nouvelle infraction ayant entra\u00een\u00e9 une condamnation \u00e0 une interdiction de conduire d\u2019un v\u00e9hicule sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour crimes oud\u00e9lits pr\u00e9vus par la l\u00e9gislation sur la circulation sur les voies publiques<\/p>\n<p>6 ou sur la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie, l\u2019interdiction de conduire prononc\u00e9e ci-devant sera ex\u00e9cut\u00e9e sans confusion possible avec la nouvelle peine et que les peines de la r\u00e9cidive seront encourues dans les termes de l\u2019article 56 al. 2 du code p\u00e9nal; Par application des articles 14, 16, 28, 29, 30,59et 65du Code p\u00e9nal, des articles 1,155,179, 182, 184, 189, 190, 190-1, 194, 195,196,628et 628-1du Code de proc\u00e9dure p\u00e9nale,des articles 9,13 et 14bis de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 concernant la r\u00e9glementation de la circulation sur toutes les voiespubliquesdont mention a \u00e9t\u00e9 faiteet des articles 1, 2,140 de l&#039;arr\u00eat\u00e9 grand-ducal modifi\u00e9 du 23 novembre 1955 portant r\u00e8glement de la circulation sur toutes les voies publiques qui furent d\u00e9sign\u00e9s \u00e0 l&#039;audience par le pr\u00e9sident. Ainsi fait, jug\u00e9 et prononc\u00e9 parAlexandra HUBERTY, pr\u00e9sident, en audience publique au Tribunal d\u2019arrondissement de et \u00e0 Luxembourg, Cit\u00e9 judiciaire, Plateau du Saint-Esprit, en pr\u00e9sencedeClaire KOOB,substitut,et d\u2019Alexia BIAGI, greffi\u00e8re assum\u00e9e, qui, \u00e0 l\u2019exception de larepr\u00e9sentantedu Minist\u00e8re Public, ont sign\u00e9 le pr\u00e9sent jugement. Ce jugement est susceptible d&#039;appel. L\u2019appel doit \u00eatre interjet\u00e9 dans les formes et d\u00e9lais pr\u00e9vus aux articles 202 et suivants du Code de proc\u00e9dure p\u00e9nale et il doit \u00eatre form\u00e9 par le pr\u00e9venu ou son avocat, la partie civile ainsi que la partie civilement responsable ou leurs avocats respectifs dans les40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement, aupr\u00e8s du greffe du Tribunal d\u2019arrondissement de Luxembourg, en se pr\u00e9sentantpersonnellementpour signer l\u2019acte d\u2019appel. L\u2019appel peut \u00e9galement \u00eatre interjet\u00e9, dans les40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement par voie de courrier \u00e9lectronique\u00e0 adresser au guichet du greffe du Tribunal d\u2019arrondissement de Luxembourg \u00e0 l\u2019adresse talgug@justice.etat.lu.L\u2019appel interjet\u00e9 par voie \u00e9lectronique le jour d\u2019expiration du d\u00e9lai de recours peut parvenir au greffe jusqu\u2019\u00e0 minuit de ce jour. Le courrier \u00e9lectronique par lequel appel est interjet\u00e9 doit \u00e9maner de l\u2019appelant, de son avocat ou de tout autre fond\u00e9 de pouvoir sp\u00e9cial. Dans ce dernier cas, le pouvoir est annex\u00e9 au courrier \u00e9lectronique.<\/p>\n<p>7 Si le pr\u00e9venu estd\u00e9tenu,il peut d\u00e9clarer son appel au greffe du Centre p\u00e9nitentiaire.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-luxembourg-penal\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-luxembourg-penal\/20250831-230925\/20250530-talch23-1741-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jugement no1741\/2025 not.43579\/22\/CC 2xi.c.(s) AUDIENCE PUBLIQUE DU 30 MAI 2025 LeTribunald&#8217;arrondissement de et \u00e0 Luxembourg,vingt-troisi\u00e8mechambre correctionnelle, statuant en composition dejuge unique, a rendu le jugement qui suit: dans la cause duMinist\u00e8re Publiccontre PERSONNE1.), n\u00e9leDATE1.)\u00e0ADRESSE1.)(ADRESSE2.)), demeurant\u00e0L-ADRESSE3.), comparant en personne, assist\u00e9 deMa\u00eetreCl\u00e9ment MARTINEZ, avocat \u00e0 la Cour,\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[25729],"kji_year":[8463],"kji_subject":[7632],"kji_keyword":[23584,23061,7636],"kji_language":[7733],"class_list":["post-621240","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_chamber-penal","kji_year-8463","kji_subject-penal","kji_keyword-arrondissement","kji_keyword-jugement","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 30 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 30 mai 2025\" \/>\n<meta property=\"og:description\" content=\"Jugement no1741\/2025 not.43579\/22\/CC 2xi.c.(s) AUDIENCE PUBLIQUE DU 30 MAI 2025 LeTribunald&#039;arrondissement de et \u00e0 Luxembourg,vingt-troisi\u00e8mechambre correctionnelle, statuant en composition dejuge unique, a rendu le jugement qui suit: dans la cause duMinist\u00e8re Publiccontre PERSONNE1.), n\u00e9leDATE1.)\u00e0ADRESSE1.)(ADRESSE2.)), demeurant\u00e0L-ADRESSE3.), comparant en personne, assist\u00e9 deMa\u00eetreCl\u00e9ment MARTINEZ, avocat \u00e0 la Cour,\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T09:41:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-30-mai-2025-2\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-30-mai-2025-2\\\/\",\"name\":\"Tribunal d'arrondissement, 30 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-20T09:41:15+00:00\",\"dateModified\":\"2026-04-20T09:41:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-30-mai-2025-2\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-30-mai-2025-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-30-mai-2025-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 30 mai 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 30 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 30 mai 2025","og_description":"Jugement no1741\/2025 not.43579\/22\/CC 2xi.c.(s) AUDIENCE PUBLIQUE DU 30 MAI 2025 LeTribunald'arrondissement de et \u00e0 Luxembourg,vingt-troisi\u00e8mechambre correctionnelle, statuant en composition dejuge unique, a rendu le jugement qui suit: dans la cause duMinist\u00e8re Publiccontre PERSONNE1.), n\u00e9leDATE1.)\u00e0ADRESSE1.)(ADRESSE2.)), demeurant\u00e0L-ADRESSE3.), comparant en personne, assist\u00e9 deMa\u00eetreCl\u00e9ment MARTINEZ, avocat \u00e0 la Cour,\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-20T09:41:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"12 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/","name":"Tribunal d'arrondissement, 30 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-20T09:41:15+00:00","dateModified":"2026-04-20T09:41:18+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-30-mai-2025-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 30 mai 2025"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/621240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=621240"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=621240"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=621240"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=621240"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=621240"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=621240"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=621240"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=621240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}