{"id":624472,"date":"2026-04-20T17:09:59","date_gmt":"2026-04-20T15:09:59","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/"},"modified":"2026-04-20T17:10:04","modified_gmt":"2026-04-20T15:10:04","slug":"tribunal-darrondissement-27-mai-2025-8","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 27 mai 2025"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Jugementn\u00b01660\/2025 not.41956\/24\/CC i.c. (2x) confisc. (1x) AUDIENCE PUBLIQUE DU 27MAI 2025 Le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique, a rendu le jugement qui suit: Danslacause du Minist\u00e8re Public contre PERSONNE1.) n\u00e9leDATE1.)\u00e0ADRESSE1.), demeurant \u00e0L-ADRESSE2.), comparanten personne, pr\u00e9venu Par citation du5 mai 2025,le Procureur d\u2019\u00c9tat pr\u00e8s le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg a requis lepr\u00e9venu de compara\u00eetre \u00e0 l\u2019audience publique du19 mai 2025devant le Tribunal correctionnel de ce si\u00e8ge pour yentendre statuer sur les pr\u00e9ventionssuivantes: avoir circul\u00e9 alors qu\u2019il existe un indice grave faisant pr\u00e9sumer que le conducteur se trouve sous influence de tetrahydrocannabinol (THC), d\u2019amph\u00e9tamines, de m\u00e9thamph\u00e9tamines, de MDMA, de MDA, de morphine (libre), de coca\u00efne ou de benzoylecgonine, pr\u00e9somption confirm\u00e9e par la batterie de tests standardis\u00e9s et par l\u2019examen de la sueur ou de la salive, avoir refus\u00e9 de se pr\u00eater \u00e0 une prise de sang;avoir circul\u00e9 en pr\u00e9sentant des signes faisant pr\u00e9sumer que le pr\u00e9venu se trouvaitsous influence de tetrahydrocannabinol (THC), d\u2019amph\u00e9tamines, de m\u00e9thamph\u00e9tamines, de MDMA, de MDA, de morphine (libre), de coca\u00efne ou de benzoylecgonine.<\/p>\n<p>2 \u00c0 cette audience, Monsieur leVice-Pr\u00e9sident constata l\u2019identit\u00e9du pr\u00e9venuPERSONNE1.), lui donna connaissance de l\u2019acte qui a saisi le Tribunal et l\u2019informa de son droit de garder le silence et de ne pas s\u2019incriminer soi-m\u00eame. Lepr\u00e9venuPERSONNE1.)renon\u00e7a \u00e0 l\u2019assistance d\u2019un avocat par d\u00e9claration \u00e9crite, dat\u00e9e et sign\u00e9e conform\u00e9ment \u00e0 l\u2019article 3-6 point 8 du Code de proc\u00e9dure p\u00e9nale. Le t\u00e9moinPERSONNE2.)fut entendu en ses d\u00e9clarations orales apr\u00e8s avoir pr\u00eat\u00e9 le serment pr\u00e9vu \u00e0 l\u2019article 155 du Code de proc\u00e9dure p\u00e9nale. Le pr\u00e9venuPERSONNE1.)fut entendu en ses explications. Lerepr\u00e9sentant du Minist\u00e8re Public,Adrien DE WATAZZI,PremierSubstitut du Procureur d\u2019\u00c9tat, r\u00e9suma l\u2019affaire et fut entendu en ses r\u00e9quisitions. Le pr\u00e9venu eut la parole en dernier. LeTribunal prit lesaffairesen d\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l\u2019audience de ce jour, date \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9, le JUGEMENT QUI SUIT: Vu l\u2019ensemble du dossier r\u00e9pressif constitu\u00e9 par le Minist\u00e8re Public sous la notice 41956\/24\/CCet notamment le proc\u00e8s-verbal n\u00b01807\/2024dress\u00e9 en date du 10 novembre 2024par la Police grand-ducale,Service intervention autoroutier. Vula citation \u00e0 pr\u00e9venudu 5 mai 2025 r\u00e9guli\u00e8rement notifi\u00e9e \u00e0PERSONNE1.). Le Minist\u00e8re Public reproche \u00e0PERSONNE1.), en date du10 novembre 2024 vers 1.00 heure \u00e0ADRESSE3.), en tant que conducteur d\u2019un v\u00e9hicule automoteur sur la voie publique,d\u2019avoir refus\u00e9 de se pr\u00eater \u00e0 une prise de sang alors qu\u2019il pr\u00e9sentaitun indice grave faisant pr\u00e9sumer qu\u2019il se trouvaitsous influence de tetrahydrocannabinol (THC), d\u2019amph\u00e9tamines, de m\u00e9thamph\u00e9tamines, de MDMA, de MDA, de morphine (libre), de coca\u00efne ou de benzoylecgonine, pr\u00e9somption confirm\u00e9e par la batterie de tests standardis\u00e9s et par l\u2019examen de la sueur ou de la salive,et d\u2019avoircircul\u00e9 en pr\u00e9sentant des signes faisant pr\u00e9sumerqu\u2019il se trouvait sousinfluence de tetrahydrocannabinol (THC), d\u2019amph\u00e9tamines, de m\u00e9thamph\u00e9tamines, de MDMA, de MDA, de morphine (libre), de coca\u00efne ou de benzoylecgonine. \u00c0 l\u2019audience publique du19 mai 2025, le pr\u00e9venuPERSONNE1.)a reconnules mis \u00e0 sa charge et a exprim\u00e9 son repentir. Il r\u00e9sulte\u00e0 suffisancede l\u2019ensemble des \u00e9l\u00e9ments du dossier r\u00e9pressif et notamment des constatations des agents verbalisant, des d\u00e9positions dut\u00e9moinPERSONNE2.)sousla foi du serment ainsi quedesd\u00e9bats men\u00e9s \u00e0 l\u2019audienceet notamment des aveux du pr\u00e9venuque lesinfractionsmises\u00e0sachargesont\u00e9tabliestant en fait qu\u2019en droit.<\/p>\n<p>3 Le pr\u00e9venuPERSONNE1.)est d\u00e8s lorsconvaincu: \u00ab\u00e9tant conducteur d&#039;unv\u00e9hicule automoteursur la voie publique, le10 novembre 2024 vers 1.00 heure \u00e0ADRESSE3.), 1)avoir circul\u00e9 alors qu&#039;il existe un indice grave faisant pr\u00e9sumer que le conducteur se trouve sous influence de tetrahydrocannabinol (THC) , d\u2019amph\u00e9tamines, de m\u00e9thamph\u00e9tamines, de MDMA, de MDA, de morphine (libre), de coca\u00efne ou de benzoylecgonine,pr\u00e9somption confirm\u00e9e parla batterie de test standardis\u00e9s et par l\u2019examen de la sueur ou de la salive,avoir refus\u00e9 de se pr\u00eater \u00e0 une prise de sang, 2)avoir circul\u00e9 alors qu&#039;il existe un indice grave faisant pr\u00e9sumer que le conducteur se trouve sous influence de tetrahydrocannabinol (THC), d\u2019amph\u00e9tamines, de m\u00e9thamph\u00e9tamines, de MDMA, de MDA, de morphine (libre), de coca\u00efne ou de benzoylecgonine\u00bb. Quant \u00e0 la peine Les infractionsretenues\u00e0 charge du pr\u00e9venuse trouventen concours r\u00e9el. Il y a d\u00e8s lors lieu d\u2019appliquer les dispositionsde l\u2019article 60du Code p\u00e9nal et de ne prononcer que la peine la plus forte qui pourra cependant \u00eatre \u00e9lev\u00e9e au double du maximum sans pouvoir d\u00e9passer la somme des peines encourues. Aux termes de l\u2019article 12 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955, les infractions retenues \u00e0 charge dePERSONNE1.)sont punies d\u2019une peine d\u2019emprisonnement de huit jours \u00e0 trois ans ainsi que d\u2019une amende de 500 euros \u00e0 10.000 euros,ou d\u2019une de ces peines seulement. L\u2019article 13 point 1 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 permet au juge saisi d\u2019une ou de plusieurs infractions \u00e0 la r\u00e9glementation de la circulation sur toutes les voies publiques ou de d\u00e9lits ou de crimes qui se sont joints \u00e0 ces infractions, de prononcer une interdiction de conduire de huit jours \u00e0 un an en mati\u00e8re de contraventions et de trois mois \u00e0 quinze ans en mati\u00e8re de d\u00e9lits ou de crimes. La gravit\u00e9 des infractions retenues \u00e0 charge dePERSONNE1.)justifiesa condamnation \u00e0 une amende correctionnellede1.000euros,quitient compte de sasituationfinanci\u00e8re,ainsi qu\u2019\u00e0 \u2022uneinterdiction de conduirede12moisdu chefdel\u2019infraction retenue sub1) et\u00e0 \u2022uneinterdiction de conduirede12moisdu chef de l\u2019infraction retenue sub2). En vertu de l\u2019article 628 alin\u00e9a 4 du Code de proc\u00e9dure p\u00e9nale, les juridictions peuvent, dans le cas o\u00f9 ils prononcent une interdiction de conduire un v\u00e9hicule automoteur sur la voie publique, ordonner par la m\u00eame d\u00e9cision motiv\u00e9e qu\u2019il sera sursis \u00e0 l\u2019ex\u00e9cution de tout ou partie de cette peine accessoire, \u00e0 condition que la condamn\u00e9 n\u2019ait pas \u00e9t\u00e9, avant le fait motivant sa poursuite, l\u2019objet d\u2019une condamnation irr\u00e9vocable \u00e0 une peine d\u2019emprisonnement<\/p>\n<p>4 correctionnel du chef d\u2019infraction aux lois et r\u00e8glements r\u00e9gissant la circulation sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour infraction aux lois et r\u00e8glements concernant la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie. Le pr\u00e9venuPERSONNE1.)n\u2019a pas subi jusqu\u2019\u00e0 ce jour de condamnation excluant le sursis \u00e0 l\u2019ex\u00e9cution des peines et n\u2019est pas indigne de l\u2019indulgence du Tribunal. Il y a partant lieu de lui accorder la faveur dusursis int\u00e9gralquantauxinterdictionsde conduire \u00e0 prononcer \u00e0 son encontre. Quant aux confiscations L\u2019article 31 du Code p\u00e9nal pr\u00e9voit que la confiscation sp\u00e9ciale s\u2019applique : 1\u00b0 aux biens comprenant les actifs de toute nature, corporels ou incorporels, meubles ou immeubles, tangibles ou intangibles, ainsi queles documents ou instruments juridiques, sous quelque forme que ce soit, y compris \u00e9lectronique ou num\u00e9rique, attestant la propri\u00e9t\u00e9 de ces actifs ou de droits y aff\u00e9rents biens formant l\u2019objet ou le produit, direct ou indirect d\u2019une infraction ou constituant un avantage patrimonial quelconque tir\u00e9 de l\u2019infraction, y compris les revenus de ces biens ; 2\u00b0 aux biens qui ont servi ou qui ont \u00e9t\u00e9 destin\u00e9s \u00e0 commettre l\u2019infraction, quand la propri\u00e9t\u00e9 en appartient au condamn\u00e9 ou dont il a la libre disposition, sous r\u00e9serve des droits du propri\u00e9taire de bonne foi ; 3\u00b0 aux biens qui ont \u00e9t\u00e9 substitu\u00e9s \u00e0 ceux vis\u00e9s au point 1\u00b0, y compris les revenus des biens substitu\u00e9s ; 4\u00b0 aux biens dont la propri\u00e9t\u00e9 appartient au condamn\u00e9 et dont la valeur mon\u00e9taire correspond \u00e0 celle des biens vis\u00e9s au point 1\u00b0, si ceux-ci ne peuvent \u00eatre trouv\u00e9s aux fins de confiscation; 5\u00b0 aux actifs de toute nature, corporels ou incorporels, meubles ou immeubles, tangibles ou intangibles, ainsi qu\u2019aux documents ou instruments juridiques, sous quelque forme que ce soit, y compris \u00e9lectronique ou num\u00e9rique, attestant la propri\u00e9t\u00e9 de ces actifs ou de droits y aff\u00e9rents, appartenant au condamn\u00e9 ou, sous r\u00e9serve des droits du propri\u00e9taire de bonne foi, dont il a la libre disposition, lorsque ni le condamn\u00e9, ni le propri\u00e9taire, mis en mesure de s\u2019expliquer sur les biens dont la confiscation estenvisag\u00e9e, n\u2019ont pu en justifier l\u2019origine, s\u2019il s\u2019agit d\u2019un crime ou d\u2019un d\u00e9lit puni d\u2019au moins quatre ans d\u2019emprisonnement et ayant procur\u00e9 un profit direct ou indirect. L&#039;article 18 de la loi du 19 f\u00e9vrier 1973 pr\u00e9voit en outre que, qu&#039;il y ait condamnation ou non, et sans \u00e9gard \u00e0 la qualit\u00e9 du propri\u00e9taire, la confiscation des substances prohib\u00e9es s&#039;impose. Eu \u00e9gard aux d\u00e9veloppements ci-avant, il y a lieu d\u2019ordonner laconfiscationdes objets suivants : 9 grammes de haschisch,<\/p>\n<p>5 2 grammes de cannabis, un sacventral, de couleur noirede la marque \u00abNike\u00bb, unpaquet de feuilles \u00e0 rouler de la marque \u00ab Top \u00bb, saisis suivant proc\u00e8s-verbal de saisie n\u00b0 1808\/2024 dress\u00e9 en date du 10 novembre 2024 par la Police grand-ducale, Service intervention autoroutier, 9 grammes de haschisch, saisis suivant proc\u00e8s-verbal n\u00b0 1809\/2024 dress\u00e9 en date du 10 novembre 2024 par la Police grand-ducale, Service intervention autoroutier. PAR CES MOTIFS : laseizi\u00e8mechambre du Tribunal d\u2019arrondissement de et \u00e0 Luxembourg,si\u00e9geant en mati\u00e8re correctionnelle,compos\u00e9e desonVice-Pr\u00e9sident, statuantcontradictoirement,le pr\u00e9venu entendu en ses explicationsetlerepr\u00e9sentant du Minist\u00e8re Public entendu en son r\u00e9quisitoire, condamne PERSONNE1.)du chef des infractions retenues \u00e0 sa charge \u00e0 une amende correctionnelle demille(1.000) euros,ainsi qu\u2019aux frais de sa poursuite p\u00e9nale, ces frais liquid\u00e9s \u00e035,22euros, fixela dur\u00e9e de la contrainte par corps en cas de non-paiement de l\u2019amende correctionnelle \u00e0dix (10)jours, prononce contrePERSONNE1.)pour la dur\u00e9e dedouze(12) moisl&#039;interdiction de conduire sur la voie publique du chef de l\u2019infraction retenue \u00e0 sa charge sub1), ditqu&#039;il serasursis\u00e0 l&#039;ex\u00e9cution del\u2019int\u00e9gralit\u00e9decetteinterdiction de conduire, avertitPERSONNE1.)cas o\u00f9, dans un d\u00e9lai de cinq ans \u00e0dater du pr\u00e9sent jugement, il aura commis une nouvelle infraction ayant entra\u00een\u00e9 une condamnation \u00e0 une interdiction de conduire un v\u00e9hicule sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour crimes ou d\u00e9lits pr\u00e9vus par la l\u00e9gislation sur la circulation sur les voies publiques ou sur la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie, l\u2019interdiction de conduire prononc\u00e9e ci-devant sera ex\u00e9cut\u00e9e sans confusionpossible avec la nouvelle peine. prononce contrePERSONNE1.)pour la dur\u00e9e dedouze(12) moisl&#039;interdiction de conduire sur la voie publique du chef de l\u2019infraction retenue \u00e0 sa charge sub 2), ditqu&#039;il serasursis\u00e0 l&#039;ex\u00e9cution del\u2019int\u00e9gralit\u00e9decetteinterdiction de conduire, avertit PERSONNE1.)qu\u2019au caso\u00f9, dans un d\u00e9lai de cinq ans \u00e0 dater du pr\u00e9sent jugement, ilaura commis une nouvelle infraction ayant entra\u00een\u00e9 une condamnation \u00e0 une interdiction de conduire un v\u00e9hicule sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour crimes ou d\u00e9lits pr\u00e9vus par la l\u00e9gislation sur la circulation sur les voies publiques ou sur<\/p>\n<p>6 la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie, l\u2019interdiction de conduire prononc\u00e9e ci-devant sera ex\u00e9cut\u00e9e sans confusionpossible avec la nouvelle peine, ordonne laconfiscationdes objets suivants : 9 grammes de haschisch, 2 grammes de cannabis, un sacventral, de couleur noirede la marque \u00abNike\u00bb, unpaquet de feuilles \u00e0 rouler de la marque \u00ab Top \u00bb, saisis suivant proc\u00e8s-verbal de saisie n\u00b0 1808\/2024 dress\u00e9 en date du 10 novembre 2024 par la Police grand-ducale, Service intervention autoroutier, 9 grammes de haschisch, saisis suivant proc\u00e8s-verbal n\u00b0 1809\/2024 dress\u00e9 en date du 10 novembre 2024 par la Police grand-ducale, Service intervention autoroutier. Par application des articles 14, 16,27,28, 29,30, 31et60du Code p\u00e9nal,des articles155, 179,182, 184,185,189, 190, 190-1,194,195,196,626,628 et 628-1du Code de proc\u00e9dure p\u00e9nale,desarticles 12 et13de la loi modifi\u00e9e du 14 f\u00e9vrier 1955concernant la r\u00e8glementation de la circulation sur toutes les voies publiques,ainsi que de l\u2019article 18de la loi du 19 f\u00e9vrier 1973concernant la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie, dont mention a \u00e9t\u00e9 faite. Ainsi fait, jug\u00e9 et prononc\u00e9 parJulien GROSS,Vice-Pr\u00e9sident, en audience publique au Tribunal d\u2019arrondissement de Luxembourg,assist\u00e9 deMorgane LEFEBVRE, Greffi\u00e8re,en pr\u00e9sence de Jennifer NOWAK, Substitut Principal du Procureur d\u2019\u00c9tat, qui \u00e0 l\u2019exception de la repr\u00e9sentante du Minist\u00e8re Public, ont sign\u00e9 le pr\u00e9sent jugement. Ce jugement est susceptible d&#039;appel. L\u2019appel doit \u00eatre interjet\u00e9 dans les formes et d\u00e9lais pr\u00e9vus aux articles 202 et suivants du Code de proc\u00e9dure p\u00e9nale et il doit \u00eatre form\u00e9 par le pr\u00e9venu ou son avocat, la partie civile ainsi que la partie civilement responsable ou leurs avocats respectifs dans les 40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement, aupr\u00e8s du greffe du Tribunal d\u2019arrondissement de Luxembourg, en se pr\u00e9sentantpersonnellementpour signer l\u2019acte d\u2019appel. L\u2019appel peut \u00e9galement \u00eatre interjet\u00e9, dans les40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement par voie decourrier \u00e9lectronique\u00e0 adresser au guichet du greffe du Tribunal d\u2019arrondissement de Luxembourg \u00e0 l\u2019adressetalgug@justice.etat.lu. L\u2019appel interjet\u00e9 par voie \u00e9lectronique le jour d\u2019expiration du d\u00e9lai derecours peut parvenir au greffe jusqu\u2019\u00e0 minuit de ce jour. Le courrier \u00e9lectronique par lequel appel est interjet\u00e9 doit \u00e9maner de l\u2019appelant, de son avocat ou de tout autre fond\u00e9 de pouvoir sp\u00e9cial. Dans ce dernier cas, le pouvoir est annex\u00e9 au courrier \u00e9lectronique. Si le pr\u00e9venu estd\u00e9tenu,il peut d\u00e9clarer son appel au greffe du Centre p\u00e9nitentiaire.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-luxembourg-penal\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-luxembourg-penal\/20250707-011353\/20250527-talch16-1660-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jugementn\u00b01660\/2025 not.41956\/24\/CC i.c. (2x) confisc. (1x) AUDIENCE PUBLIQUE DU 27MAI 2025 Le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique, a rendu le jugement qui suit: Danslacause du Minist\u00e8re Public contre PERSONNE1.) n\u00e9leDATE1.)\u00e0ADRESSE1.), demeurant \u00e0L-ADRESSE2.), comparanten personne,\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[25729],"kji_year":[8463],"kji_subject":[7632],"kji_keyword":[23584,25730,7636],"kji_language":[7733],"class_list":["post-624472","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_chamber-penal","kji_year-8463","kji_subject-penal","kji_keyword-arrondissement","kji_keyword-jugementn","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 27 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 27 mai 2025\" \/>\n<meta property=\"og:description\" content=\"Jugementn\u00b01660\/2025 not.41956\/24\/CC i.c. (2x) confisc. (1x) AUDIENCE PUBLIQUE DU 27MAI 2025 Le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique, a rendu le jugement qui suit: Danslacause du Minist\u00e8re Public contre PERSONNE1.) n\u00e9leDATE1.)\u00e0ADRESSE1.), demeurant \u00e0L-ADRESSE2.), comparanten personne,\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T15:10:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-27-mai-2025-8\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-27-mai-2025-8\\\/\",\"name\":\"Tribunal d'arrondissement, 27 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-20T15:09:59+00:00\",\"dateModified\":\"2026-04-20T15:10:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-27-mai-2025-8\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-27-mai-2025-8\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-27-mai-2025-8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 27 mai 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 27 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 27 mai 2025","og_description":"Jugementn\u00b01660\/2025 not.41956\/24\/CC i.c. (2x) confisc. (1x) AUDIENCE PUBLIQUE DU 27MAI 2025 Le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique, a rendu le jugement qui suit: Danslacause du Minist\u00e8re Public contre PERSONNE1.) n\u00e9leDATE1.)\u00e0ADRESSE1.), demeurant \u00e0L-ADRESSE2.), comparanten personne,\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-20T15:10:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"12 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/","name":"Tribunal d'arrondissement, 27 mai 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-20T15:09:59+00:00","dateModified":"2026-04-20T15:10:04+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-27-mai-2025-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 27 mai 2025"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/624472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=624472"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=624472"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=624472"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=624472"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=624472"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=624472"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=624472"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=624472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}