{"id":767024,"date":"2026-04-30T00:22:58","date_gmt":"2026-04-29T22:22:58","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/"},"modified":"2026-04-30T00:23:02","modified_gmt":"2026-04-29T22:23:02","slug":"cour-superieure-de-justice-4-avril-2019-4","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 4 avril 2019"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Arr\u00eat N\u00b0 58\/19 &#8212; VIII &#8212; Travail<\/p>\n<p>Exempt \u2013 appel en mati\u00e8re de droit du travail<\/p>\n<p>Audience publique du quatre avril deux mille dix -neuf<\/p>\n<p>Num\u00e9ro 43656 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Monique HENTGEN, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain BERNARD, greffier.<\/p>\n<p>Entre:<\/p>\n<p>la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e SOC.1.) , \u00e9tablie et ayant son si\u00e8ge social \u00e0 L-(&#8230;), repr\u00e9sent\u00e9e par son conseil de g\u00e9rance,<\/p>\n<p>appelante aux termes d\u2019un acte de l\u2019huissier de justice Jean -Claude STEFFEN d\u2019Esch-sur-Alzette du 1 er avril 2016,<\/p>\n<p>comparant par KLEYR GRASSO , soci\u00e9t\u00e9 en commandite simple, \u00e9tablie \u00e0 L- 2361 Strassen, 7, rue des Primeurs, inscrite sur la liste V du tableau de l\u2019ordre des avocats du barreau de Luxembourg, repr\u00e9sent\u00e9e aux fins de la pr\u00e9sente proc\u00e9dure par Ma\u00eetre Christian JUNGERS, avocat \u00e0 la Cour, demeurant \u00e0 la m\u00eame adresse,<\/p>\n<p>et:<\/p>\n<p>A.), demeurant \u00e0 L- (&#8230;),<\/p>\n<p>intim\u00e9e aux fins du pr\u00e9dit acte STEFFEN ,<\/p>\n<p>comparant par Ma\u00eetre Guy THOMAS , avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>2 LA COUR D\u2019APPEL:<\/p>\n<p>Vu l\u2019arr\u00eat de la Cour de cassation du 22 mars 2018, N\u00b0 27\/2018, num\u00e9ro 3925 du registre.<\/p>\n<p>Les faits et la proc\u00e9dure<\/p>\n<p>A.) (A.)) a \u00e9t\u00e9 engag\u00e9e, suivant contrat de travail \u00e0 dur\u00e9e d\u00e9termin\u00e9e du 19 octobre 2011, par la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e SOC.1.) (la soci\u00e9t\u00e9 SOC.1.) ) en qualit\u00e9 d\u2019agent de nettoyage pour la p\u00e9riode allant du 20 octobre au 30 novembre 2011 \u00e0 raison de 20 heures par semaine. Ce contrat de travail a \u00e9t\u00e9 prolong\u00e9 par un avenant du 21 novembre 2011 jusqu\u2019au 31 mai 2012, toujours \u00e0 raison de 20 heures par semaine.<\/p>\n<p>Par un nouvel avenant au contrat de travail du 30 d\u00e9cembre 2011, la dur\u00e9e normale de travail a \u00e9t\u00e9 port\u00e9e pour la p\u00e9riode allant du 1 er au 31 janvier 2012 \u00e0 30 heures par semaine et par un autre avenant au contrat de travail du 31 janvier 2012, la dur\u00e9e normale de travail a \u00e9t\u00e9 maintenue \u00e0 30 heures par semaine pour la p\u00e9riode allant du 1 e au 29 f\u00e9vrier 2012. Par un avenant au contrat de travail du 30 mars 2012, la dur\u00e9e normale de travail a encore une fois \u00e9t\u00e9 maintenue \u00e0 30 heures par semaine pour la p\u00e9riode allant du 1 er avril au 31 mai 2012 et par un dernier avenant au contrat de travail du 31 mai 2012, le contrat de travail a \u00e9t\u00e9 prolong\u00e9 jusqu\u2019au 19 octobre 2013, selon les parties \u00e0 raison de 20 heures par semaine.<\/p>\n<p>Par requ\u00eate du 23 mars 2015, A.) a fait convoquer la soci\u00e9t\u00e9 SOC.1.) devant le tribunal du travail de Luxembourg aux fins de la voir condamner au paiement de la majoration pour 346,82 heures suppl\u00e9mentaires qu\u2019elle a prest\u00e9es au cours d\u2019une p\u00e9riode allant du mois de mars 2012 au mois d\u2019ao\u00fbt 2012; elle a bas\u00e9 sa demande sur les articles 15 de son contrat de travail et 7.5 de la convention collective de travail pour le secteur \u00ab nettoyage de b\u00e2timents \u00bb, qu\u2019elle voulait voir interpr\u00e9ter dans le cadre des paragraphes 2 et 3 de l\u2019article L.123- 1. et de l\u2019article L.123-5. du Code du travail.<\/p>\n<p>Par un jugement rendu contradictoirement \u00e0 la date du 1 er mars 2016, le tribunal du travail a condamn\u00e9 l\u2019employeur \u00e0 payer \u00e0 son ex-salari\u00e9e la somme de 1.486,80 EUR \u00e0 titre d\u2019arri\u00e9r\u00e9s de salaires r\u00e9sultant de la majoration non pay\u00e9e de 346,82 heures de travail qualifi\u00e9es d\u2019heures suppl\u00e9mentaires.<\/p>\n<p>Sur l\u2019appel dirig\u00e9 par la soci\u00e9t\u00e9 SOC.1.) contre le jugement pr\u00e9cit\u00e9, la Cour d\u2019appel a, par un arr\u00eat rendu \u00e0 la date du 2 mars 2017 et par r\u00e9formation,<\/p>\n<p>\u00ab dit la demande de A.) fond\u00e9e pour le montant de 395,33 euros,<\/p>\n<p>partant condamn\u00e9 la soci\u00e9t\u00e9 SOC.1.) SARL \u00e0 payer \u00e0 A.) la somme de 395,33 euros avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 partir de la demande en justice, jusqu\u2019\u00e0 solde, dit la demande de la soci\u00e9t\u00e9 SOC.1.) SARL en restitution de la somme de 1.486,80 euros fond\u00e9e,<\/p>\n<p>3 partant condamn\u00e9 A.) \u00e0 payer \u00e0 la soci\u00e9t\u00e9 SOC.1.) SARL la somme de 1.486,80 euros avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 partir de la demande en justice, jusqu\u2019\u00e0 solde,<\/p>\n<p>ordonn\u00e9 la compensation des cr\u00e9ances r\u00e9ciproques,<\/p>\n<p>confirm\u00e9 le jugement entrepris pour le surplus,<\/p>\n<p>condamn\u00e9 la soci\u00e9t\u00e9 SOC.1.) SARL \u00e0 payer \u00e0 A.) une indemnit\u00e9 de proc\u00e9dure de 1.000 euros,<\/p>\n<p>rejet\u00e9 la demande de la soci\u00e9t\u00e9 SOC.1.) SARL bas\u00e9e sur l\u2019article 240 du NCPC<\/p>\n<p>condamn\u00e9 la soci\u00e9t\u00e9 SOC.1.) SARL aux frais et d\u00e9pens. \u00bb<\/p>\n<p>Pour statuer ainsi, la Cour d\u2019appel a retenu que \u00ab l\u2019interpr\u00e9tation des paragraphes (2) et (3) de l\u2019article L.123- 1 du Code du travail telle qu\u2019elle a \u00e9t\u00e9 retenue par le tribunal du travail revient \u00e0 rendre la possibilit\u00e9 offerte par le paragraphe (3) de l\u2019article L.123- 1 du Code de travail de facto inop\u00e9rante, et par la m\u00eame occasion les articles 7.5 de la Convention collective et 15 du contrat de travail.<\/p>\n<p>Au contraire et comme l\u2019a \u00e0 juste titre fait plaider l\u2019employeur, le temps de travail partiel de la salari\u00e9e pouvait partant valablement et conventionnellement \u00eatre augment\u00e9 de 50%, sans cependant pouvoir exc\u00e9der de plus de 50% la dur\u00e9e de travail journali\u00e8re et hebdomadaire normale fix\u00e9e au contrat de travail et sans que cette augmentation n\u2019aboutisse en r\u00e9alit\u00e9 \u00e0 un temps de travail sup\u00e9rieur \u00e0 un temps plein.<\/p>\n<p>Dans la mesure o\u00f9 un am\u00e9nagement voire une flexibilisation du travail \u00e0 temps partiel est l\u00e9galement permis, certes dans les limites pr\u00e9vues par la loi et de l\u2019accord des parties, il est superf\u00e9tatoire d\u2019analyser si les articles 7.5 de la convention collective, respectivement l\u2019article 15 du contrat de travail sont moins favorables pour la salari\u00e9e que l\u2019article L.123- 1 (2) et (3) et encourent la nullit\u00e9.<\/p>\n<p>Il suit des consid\u00e9rations qui pr\u00e9c\u00e8dent et conform\u00e9ment \u00e0 l\u2019article L.123- 5 du Code du travail, que sera consid\u00e9r\u00e9 comme temps de travail suppl\u00e9mentaire au sens de l\u2019article L.123-4 sous 3, le temps de travail effectu\u00e9 par la salari\u00e9e \u00e0 temps partiel au- del\u00e0 des 50% conventionnellement pr\u00e9vus. \u00bb<\/p>\n<p>Contre cet arr\u00eat, A.) s\u2019est pourvue en cassation et, par arr\u00eat du 22 mars 2018, la Cour de cassation a \u00ab cass\u00e9 et annul\u00e9 l\u2019arr\u00eat du 2 mars 2017, pr\u00e9cit\u00e9 ; d\u00e9clar\u00e9 nuls et de nul effet ladite d\u00e9cision judiciaire et les actes qui s\u2019en sont suivis, remis les parties dans l\u2019\u00e9tat o\u00f9 elles se sont trouv\u00e9es avant l\u2019arr\u00eat cass\u00e9 et, pour \u00eatre fait droit, renvoy\u00e9 les parties devant la Cour d\u2019appel, autrement compos\u00e9e \u00bb.<\/p>\n<p>Pour statuer ainsi la Cour de cassation a retenu que \u00abil r\u00e9sulte des dispositions combin\u00e9es des paragraphes (2) et (3) de l\u2019article L. 123- 1. du Code du travail que si le salari\u00e9 peut \u00eatre occup\u00e9 au- del\u00e0 des limites journali\u00e8res et hebdomadaires fix\u00e9es dans son contrat de travail \u00e0 temps partiel au sens du paragraphe (1) et que si, en vertu du paragraphe (3), alin\u00e9a 1, cette augmentation ne peut exc\u00e9der vingt pour cent de la dur\u00e9e de travail convenue, sauf stipulation contraire du<\/p>\n<p>4 contrat de travail, toujours est-il que pareille augmentation de la dur\u00e9e de travail effective par rapport \u00e0 celle convenue au contrat de travail est toujours subordonn\u00e9e \u00e0 la condition, pr\u00e9vue au paragraphe (2), que la dur\u00e9e hebdomadaire moyenne effective de travail, calcul\u00e9e sur une p\u00e9riode de travail de quatre semaines cons\u00e9cutives, ne d\u00e9passe pas la dur\u00e9e de travail hebdomadaire normale fix\u00e9e au contrat de travail, de sorte que le temps de travail effectu\u00e9 par le salari\u00e9 \u00e0 temps partiel, sur une p\u00e9riode de travail de quatre semaines cons\u00e9cutives, au- del\u00e0 des limites journali\u00e8res et hebdomadaires fix\u00e9es dans son contrat de travail \u00e0 temps partiel est, en vertu de l\u2019article L. 123- 5., alin\u00e9a 1, du Code du travail \u2013 et nonobstant toute stipulation contraire du contrat de travail ou d\u2019une convention collective \u2013 \u00e0 consid\u00e9rer comme temps de travail suppl\u00e9mentaire et, en cons\u00e9quence, \u00e0 r\u00e9mun\u00e9rer comme tel, conform\u00e9ment au dernier alin\u00e9a de l\u2019article L. 123- 5. ;<\/p>\n<p>Attendu qu\u2019en retenant que \u00ab sera consid\u00e9r\u00e9 comme temps de travail suppl\u00e9mentaire au sens de l\u2019article L.123- 4. sous 3, le temps de travail effectu\u00e9 par la salari\u00e9e \u00e0 temps partiel au- del\u00e0 des 50% conventionnellement pr\u00e9vus \u00bb, la Cour d\u2019appel a partant viol\u00e9 les dispositions vis\u00e9es au moyen\u00bb.<\/p>\n<p>Le fond<\/p>\n<p>\u00c1 la suite de l\u2019arr\u00eat de la Cour de cassation, la Cour d\u2019appel se trouve saisie de l\u2019appel dirig\u00e9 par la soci\u00e9t\u00e9 SOC.1.) contre le jugement du tribunal de travail du 1 er mars 2016 suivant exploit d\u2019huissier du 1 er avril 2016.<\/p>\n<p>Cet appel est recevable pour avoir \u00e9t\u00e9 relev\u00e9 dans les forme et d\u00e9lai de la loi.<\/p>\n<p>La soci\u00e9t\u00e9 SOC.1.) demande \u00e0 voir dire que, conform\u00e9ment \u00e0 l\u2019interpr\u00e9tation constante de l\u2019article L.123- 1. du Code du travail, il n\u2019y a pas lieu d\u2019appliquer une quelconque p\u00e9riode de r\u00e9f\u00e9rence pour l\u2019application de la tol\u00e9rance contractuelle y stipul\u00e9e, nonobstant la position de la Cour de cassation. Elle demande \u00e0 voir constater que A.) n\u2019a prest\u00e9 que 78 heures suppl\u00e9mentaires, de sorte que sa demande ne serait fond\u00e9e qu\u2019\u00e0 hauteur d\u2019un montant de 428,76 EUR.<\/p>\n<p>En cons\u00e9quence, l\u2019appelante demande \u00e0 voir ordonner la restitution du montant de 1.102,64 EUR, soit le montant de 1.531,- EUR, dont \u00e0 d\u00e9duire le montant de 428,76 EUR.<\/p>\n<p>A.) demande \u00e0 voir confirmer purement et simplement le jugement entrepris. Il convient d\u2019abord de rappeler le cadre juridique de l\u2019affaire constitu\u00e9 par l\u2019article L. 123- 1. et l\u2019article L. 123- 5. du Code du travail, ainsi que les dispositions conventionnelles, \u00e0 savoir l\u2019article 7.5 de la convention collective de travail pour le personnel du secteur \u00ab Nettoyage de b\u00e2timents \u00bb.<\/p>\n<p>Aux termes de l\u2019article L. 123- 1. du Code du travail :<\/p>\n<p>\u00ab (1) Est consid\u00e9r\u00e9 comme salari\u00e9 \u00e0 temps partiel le salari\u00e9 qui convient avec un employeur, dans le cadre d\u2019une activit\u00e9 r\u00e9guli\u00e8re, un horaire de travail dont la dur\u00e9e hebdomadaire est inf\u00e9rieure \u00e0 la dur\u00e9e normale de travail applicable dans<\/p>\n<p>5 l\u2019\u00e9tablissement en vertu de la loi ou de la convention collective de travail sur cette m\u00eame p\u00e9riode.<\/p>\n<p>(2) Les salari\u00e9s peuvent toutefois \u00eatre occup\u00e9s au- del\u00e0 des limites journali\u00e8res et hebdomadaires fix\u00e9es dans leur contrat de travail, \u00e0 condition que la dur\u00e9e hebdomadaire moyenne de travail, calcul\u00e9e sur une p\u00e9riode de travail de r\u00e9f\u00e9rence de quatre semaines cons\u00e9cutives, ne d\u00e9passe pas la dur\u00e9e de travail hebdomadaire fix\u00e9e au contrat de travail.<\/p>\n<p>\u2026..<\/p>\n<p>(3) Sauf disposition contraire du contrat de travail, la dur\u00e9e de travail journali\u00e8re et hebdomadaire effective du salari\u00e9 \u00e0 temps partiel r\u00e9sultant de l\u2019application des dispositions du paragraphe (2) ne peut exc\u00e9der de plus de vingt pour cent la dur\u00e9e de travail journali\u00e8re et hebdomadaire normale fix\u00e9e au contrat de travail.<\/p>\n<p>L\u2019application des dispositions qui pr\u00e9c\u00e8dent ne peut avoir pour effet de porter la dur\u00e9e de travail effective du salari\u00e9 \u00e0 temps partiel au- del\u00e0 de la dur\u00e9e de travail normale fix\u00e9e par la loi ou une disposition conventionnelle pour un salari\u00e9 \u00e0 temps plein du m\u00eame \u00e9tablissement ou de la m\u00eame entreprise \u2026.\u00bb.<\/p>\n<p>D\u2019apr\u00e8s l\u2019article L.123- 5. du Code du travail :<\/p>\n<p>\u00ab Est \u00e0 consid\u00e9rer comme temps de travail suppl\u00e9mentaire au sens de l\u2019article L.123- 4., sous 3, le temps de travail effectu\u00e9 par le salari\u00e9 \u00e0 temps partiel au- del\u00e0 des limites r\u00e9sultant de l\u2019application des paragraphes (2) et (3) de l\u2019article L.123- 1. (\u2026)<\/p>\n<p>Les heures de travail suppl\u00e9mentaires prest\u00e9es par le salari\u00e9 \u00e0 temps partiel en application de l\u2019alin\u00e9a 1 ouvrent droit aux majorations de salaire pr\u00e9vues par la loi en mati\u00e8re d\u2019heures suppl\u00e9mentaires \u00bb.<\/p>\n<p>L\u2019article 7.5 de la convention collective de travail pour le personnel du secteur \u00ab nettoyage de b\u00e2timents \u00bb dispose que \u00ab la dur\u00e9e normale du travail fix\u00e9e au contrat de travail des salari\u00e9s occup\u00e9s \u00e0 temps partiel peut, avec l\u2019accord du salari\u00e9, \u00eatre augment\u00e9e de 50 % par rapport au nombre d\u2019heures fix\u00e9es par le contrat de travail, sans pouvoir d\u00e9passer le maximum de quarante heures par semaine suivant les besoins de l\u2019entreprise sans qu\u2019il y ait lieu de payer des heures suppl\u00e9mentaires \u00bb. Cet article est repri s tel quel dans le contrat de travail sign\u00e9 par les parties en date du 19 octobre 2011.<\/p>\n<p>C\u2019est \u00e0 bon droit que la juridiction de premi\u00e8re instance a jug\u00e9 que les dispositions l\u00e9gales, r\u00e8glementaires, administratives et celles r\u00e9sultant des Conventions collectives d\u00e9clar\u00e9es d\u2019obligation g\u00e9n\u00e9rale qui ont trait notamment \u00e0 la dur\u00e9e du temps de travail sont d\u2019ordre public en vertu de l\u2019article L. 010. du Code du travail et que l\u2019article L.162- 12. (6) du Code du travail relatif au contenu des conventions collectives, pr\u00e9voit la nullit\u00e9 de toute stipulation contraire aux lois et aux r\u00e8glements, \u00e0 moins qu\u2019elle ne soit plus favorable pour les salari\u00e9s. La juridiction de premi\u00e8re instance a encore retenu \u00e0 juste titre que l\u2019article L.123- 1. (3) du Code du travail, bien que constituant une disposition relative au temps de travail,<\/p>\n<p>6 permet express\u00e9ment aux parties de d\u00e9roger dans le contrat de travail \u00e0 la limite de 20% de l\u2019augmentation du temps de travail normal pr\u00e9vue, de sorte que cette limite \u00e9gale \u00e0 20 % du temps de travail n\u2019est pas une disposition d\u2019ordre public.<\/p>\n<p>Pour s\u2019opposer \u00e0 la position de la Cour de cassation, la soci\u00e9t\u00e9 SOC.1.) soutient, en premier lieu, que l\u2019interpr\u00e9tation op\u00e9r\u00e9e par la Cour de cassation dans son arr\u00eat du 22 mars 2018 est contraire tant \u00e0 une jurisprudence constante en la mati\u00e8re depuis plus de dix ans qu\u2019\u00e0 l\u2019esprit de la loi.<\/p>\n<p>L\u2019appelante se r\u00e9f\u00e8re, \u00e0 cet \u00e9gard, \u00e0 un arr\u00eat de la Cour d\u2019appel du 6 d\u00e9cembre 2007 r\u00f4le n\u00b031624 et \u00e0 deux jugements du tribunal du travail de Luxembourg du 15 juillet 2014, n\u00b03136\/14 et du 27 janvier 2016, n\u00b0402\/16, ainsi qu\u2019\u00e0 un jugement du tribunal de travail d\u2019ESCH\/ALZETTE du 16 avril 2012, n\u00b01019\/12, qui auraient retenu, dans le cadre de l\u2019application des articles L.123- 1. (3) et L.123-5. du Code du travail, la possibilit\u00e9 d\u2019une augmentation du temps normal par rapport aux heures fix\u00e9es dans le contrat de travail sans tenir compte d\u2019une p\u00e9riode de r\u00e9f\u00e9rence de quatre semaines.<\/p>\n<p>L\u2019appelante se r\u00e9f\u00e8re \u00e9galement aux conclusions de l\u2019avocat g\u00e9n\u00e9ral prises dans le cadre du recours en cassation, qui a d\u00e9duit des travaux parlementaires que, \u00ab ..m\u00eame si une premi\u00e8re lecture de l\u2019article L.123- 5. du Code travail peut s\u2019appr\u00eater dans le sens voulu par la demanderesse en cassation, la motivation de la Cour d\u2019appel est conforme \u00e0 la finalit\u00e9 voulue par le l\u00e9gislateur et les juges d\u2019appel n\u2019ont pas viol\u00e9 la disposition l\u00e9gale vis\u00e9e par le premier moyen de cassation \u00bb.<\/p>\n<p>L\u2019intim\u00e9e r\u00e9plique que la Cour de cassation, en sa qualit\u00e9 de juridiction r\u00e9gulatrice, a clairement d\u00e9cid\u00e9 une application litt\u00e9rale des articles L.123- 1. et L.123- 5. du Code du travail et il ne saurait \u00eatre question de jurisprudence constante contraire ou d\u2019une interpr\u00e9tation contraire \u00e0 l\u2019esprit de la loi. En outre, les travaux parlementaires relatifs au projet de loi n\u00b04459 concernant la mise en \u0153uvre du plan national en faveur de l\u2019emploi de 1998, qui a ins\u00e9r\u00e9 l\u2019article L.123- 1. dans la l\u00e9gislation sur le droit du travail, retiendraient la p\u00e9riode de r\u00e9f\u00e9rence minimale de quatre semaines qui aurait express\u00e9ment \u00e9t\u00e9 pr\u00e9vue dans le commentaire des articles.<\/p>\n<p>La Cour de cassation a une mission supr\u00eame de l\u00e9galit\u00e9, d\u2019interpr\u00e9tation de la loi, d\u2019unification de la jurisprudence et d\u2019\u00e9laboration du droit, son attribution primordiale \u00e9tant de faire respecter par les juridictions inf\u00e9rieures la volont\u00e9 du l\u00e9gislateur et de maintenir, par l\u2019interpr\u00e9tation qu\u2019elle donne des textes dans les affaires qui lui sont d\u00e9f\u00e9r\u00e9es l\u2019unit\u00e9 de la jurisprudence, qui est la loi en action. (cf : M. Thill, La fonction des Cours Supr\u00eames pour le d\u00e9veloppement du droit, Bull. Laurent 1999- I 17, 21 et M.P. Engel, La Cour de cassation dans la tourmente, Pas. Lux. 34, chron. P. 275,281 dans La mission de la Cour de cassation, Point de vue luxembourgeois, Article de Patrick Kinsch et Myriam Pierrat, Annales du droit luxembourgeois, Bruylant, vol. 19, 2009, pp. 83- 108).<\/p>\n<p>Le seul arr\u00eat et les trois d\u00e9cisions de premi\u00e8re instance invoqu\u00e9s par l\u2019appelante ne sauraient constituer une jurisprudence de nature \u00e0 remettre en cause l\u2019interpr\u00e9tation donn\u00e9e par la Cour de cassation. Il convient d\u2019observer, \u00e0 cet<\/p>\n<p>7 \u00e9gard, concernant l\u2019arr\u00eat de 2006 invoqu\u00e9, que la Cour d\u2019appel n\u2019a pas discut\u00e9 le probl\u00e8me relatif \u00e0 la p\u00e9riode de r\u00e9f\u00e9rence, mais elle a simplement appliqu\u00e9 la convention collective de travail pour le secteur \u00ab nettoyage de b\u00e2timents \u00bb pour d\u00e9cider que l\u2019accord du salari\u00e9 de prester des heures de travail suppl\u00e9mentaires \u00e0 celles pr\u00e9vues au contrat de travail en cas de travail \u00e0 temps partiel ne peut porter que sur 50 % par rapport \u00e0 l\u2019horaire fix\u00e9 au contrat sans qu\u2019il y ait lieu \u00e0 majoration pour prestation d\u2019heures suppl\u00e9mentaires. Quant aux d\u00e9cisions de premi\u00e8re instance invoqu\u00e9es par l\u2019appelante, si elles ont op\u00e9r\u00e9, dans le cadre des affaires leur soumises, un calcul des heures suppl\u00e9mentaires correspondant \u00e0 l\u2019argumentation de l\u2019appelante, toujours est-il que la question telle que soumise \u00e0 la Cour de cassation n\u2019a pas \u00e9t\u00e9 plus amplement analys\u00e9e dans les jugements en question.<\/p>\n<p>La Cour d\u2019appel ne saurait \u00e9galement partager ni la position de l\u2019avocat g\u00e9n\u00e9ral exprim\u00e9e dans ses conclusions relatives au recours en cassation de A.) ni celle de la soci\u00e9t\u00e9 SOC.1.) selon lesquelles l\u2019esprit de la loi d\u00e9gag\u00e9 par les travaux parlementaires va dans le sens de faire abstraction de la p\u00e9riode de r\u00e9f\u00e9rence de quatre semaines et qu\u2019en l\u2019esp\u00e8ce le temps de travail partiel de la salari\u00e9e A.) pouvait valablement et conventionnellement \u00eatre augment\u00e9 de 50%, sans cependant pouvoir exc\u00e9der de plus de 50% la dur\u00e9e de travail journali\u00e8re et hebdomadaire normale fix\u00e9e au contrat de travail et sans que cette augmentation n\u2019aboutisse en r\u00e9alit\u00e9 \u00e0 un temps de travail sup\u00e9rieur \u00e0 un temps plein.<\/p>\n<p>En effet et selon la Cour de cassation, les dispositions combin\u00e9es des paragraphes (2) et (3) de l\u2019article L. 123- 1. du Code du travail sont claires et ne permettent pas d\u2019exclure la p\u00e9riode de r\u00e9f\u00e9rence de quatre semaines dans le cadre de l\u2019augmentation de la dur\u00e9e de travail effective par rapport \u00e0 celle convenue au contrat de travail.<\/p>\n<p>Par l\u2019introduction d\u2019une p\u00e9riode de r\u00e9f\u00e9rence l\u00e9gale de quatre semaines pour l\u2019ensemble des entreprises, le l\u00e9gislateur a vis\u00e9 la sauvegarde de la s\u00e9curit\u00e9 des salari\u00e9s inh\u00e9rente au droit du travail luxembourgeois. M\u00eame si le projet de loi a eu comme objectif de transcrire dans la l\u00e9gislation nationale l\u2019ensemble des mesures retenues dans le plan national en faveur de l\u2019emploi 1998 aux fins notamment d\u2019assouplir le fonctionnement des entreprises et de promouvoir le travail \u00e0 temps partiel, il ne d\u00e9coule pas des travaux parlementaires que l\u2019intention du l\u00e9gislateur ait \u00e9t\u00e9 d\u2019exclure la condition que la dur\u00e9e hebdomadaire moyenne de travail, calcul\u00e9e sur une p\u00e9riode de travail de quatre semaines cons\u00e9cutives, ne d\u00e9passe pas la dur\u00e9e de travail hebdomadaire fix\u00e9e au contrat de travail et ce pour maintenir et prot\u00e9ger les droits des salari\u00e9s. En effet, \u00e0 l\u2019instar de l\u2019intim\u00e9e, la Cour constate que le commentaire des articles du projet de loi mentionne express\u00e9ment la p\u00e9riode de r\u00e9f\u00e9rence de quatre semaines comme instrument susceptible de trouver un \u00e9quilibre entre les besoins de flexibilit\u00e9 pour l\u2019entreprise en mati\u00e8re de travail \u00e0 temps partiel et une protection ad\u00e9quate du salari\u00e9.<\/p>\n<p>Par ailleurs, l\u2019application de la p\u00e9riode de r\u00e9f\u00e9rence de quatre semaines n\u2019emp\u00eache pas l\u2019employeur de faire effectuer par le salari\u00e9, selon ses besoins et de l\u2019accord du salari\u00e9, un travail journalier ou hebdomadaire d\u00e9passant le temps fix\u00e9 au contrat de travail de 50% ou plus \u00e0 la condition qu\u2019\u00e0 la fin de la p\u00e9riode<\/p>\n<p>8 de r\u00e9f\u00e9rence de quatre semaines la moyenne des heures prest\u00e9es ne d\u00e9passe pas la dur\u00e9e de base convenue, faute de quoi des heures suppl\u00e9mentaires sont \u00e0 payer.<\/p>\n<p>L\u2019appelante fait encore valoir que l\u2019interpr\u00e9tation de la Cour de cassation est contraire aux objectifs du droit communautaire. Ainsi, la directive 97\/81\/du Conseil du 15 d\u00e9cembre 1997 concernant l&#039;accord- cadre sur le travail \u00e0 temps partiel conclu par l&#039;UNICE, le CEEP et la CES- Annexe : Accord- cadre sur le travail \u00e0 temps partiel aurait d\u00e9fini un certain nombre d\u2019objectifs que le l\u00e9gislateur luxembourgeois aurait consid\u00e9r\u00e9 comme \u00e9tant suffisamment mis en \u0153uvre par la loi du 26 f\u00e9vrier 1993.<\/p>\n<p>Les articles 5 et 7 de la directive pr\u00e9cit\u00e9e, en l\u2019occurrence : \u00ab 5 : faciliter l&#039;acc\u00e8s au travail \u00e0 temps partiel pour les hommes et les femmes en vue de pr\u00e9parer la retraite, de concilier la vie professionnelle et la vie familiale et de profiter des possibilit\u00e9s d&#039;\u00e9ducation et de formation pour am\u00e9liorer leurs comp\u00e9tences et leur progression professionnelle, dans l&#039;int\u00e9r\u00eat mutuel des employeurs et des travailleurs et d&#039;une mani\u00e8re qui favorise le d\u00e9veloppement des entreprises ; 7 : consid\u00e9rant que le pr\u00e9sent accord prend en consid\u00e9ration la n\u00e9cessit\u00e9 d&#039;am\u00e9liorer les exigences de la politique sociale, de favoriser la comp\u00e9titivit\u00e9 de l&#039;\u00e9conomie de la Communaut\u00e9 et d&#039;\u00e9viter d&#039;imposer des contraintes administratives, financi\u00e8res et juridiques telles qu&#039;elles entraveraient la cr\u00e9ation et le d\u00e9veloppement des petites et moyennes entreprises; \u00bb r\u00e9v\u00e8leraient que la directive a retenu comme but recherch\u00e9 de faciliter le d\u00e9veloppement du travail \u00e0 temps partiel sur une base volontaire et de contribuer \u00e0 l\u2019organisation flexible du temps de travail d\u2019une mani\u00e8re qui tienne compte des besoins des employeurs et des travailleurs.<\/p>\n<p>L\u2019intim\u00e9e r\u00e9plique que le m\u00e9canisme des articles pr\u00e9cit\u00e9s, tel que retenu par la Cour de cassation, prendrait en compte tant les besoins de l\u2019employeur en flexibilisation du temps partiel de travail, en permettant une augmentation de 20% de la dur\u00e9e journali\u00e8re et hebdomadaire par voie conventionnelle, que les besoins du travailleur, en emp\u00eachant que le salari\u00e9 soit embauch\u00e9 pour un temps minimal et qu\u2019il soit \u00e0 la merci des besoins de l\u2019employeur en ce qui concerne toute heure de travail suppl\u00e9mentaire r\u00e9mun\u00e9r\u00e9e comme heure normale de travail. La flexibilisation vis\u00e9e par la directive serait ainsi respect\u00e9e.<\/p>\n<p>Les consid\u00e9rations de politique sociale et de comp\u00e9titivit\u00e9 \u00e9conomique des entreprises sur le march\u00e9 du travail telles que retenues dans la directive ne sauraient mettre en \u00e9chec l\u2019\u00e9quilibre voulu par le l\u00e9gislateur luxembourgeois qui est de permettre la flexibilisation du temps de travail dans le respect des droits des salari\u00e9s et l\u2019arr\u00eat de la Cour de cassation n\u2019est pas contraire \u00e0 la directive pr\u00e9cit\u00e9e.<\/p>\n<p>La soci\u00e9t\u00e9 SOC.1.) observe enfin que son interpr\u00e9tation ne constitue pas \u00ab in concreto \u00bb une interpr\u00e9tation moins favorable au salari\u00e9.<\/p>\n<p>L\u2019article L.121- 3. du Code du travail qui permet de d\u00e9roger aux dispositions du Code du travail dans un sens plus favorable au salari\u00e9, ne pr\u00e9ciserait pas si \u00abdans un sens plus favorable\u00bb serait \u00e0 interpr\u00e9ter in abstracto ou in concreto. Or,<\/p>\n<p>9 l\u2019interpr\u00e9tation propos\u00e9e par la partie intim\u00e9e ne serait qu\u2019\u00e0 premi\u00e8re vue plus favorable, dans la mesure o\u00f9 dans une entreprise de nettoyage, le contrat de travail \u00e0 temps plein serait l\u2019exception et une telle entreprise n\u2019aurait aucun int\u00e9r\u00eat \u00e0 accorder du temps de travail additionnel si le moindre d\u00e9passement en fin de mois \u00e9tait interpr\u00e9t\u00e9 comme du temps de travail suppl\u00e9mentaire d\u00e9clenchant une majoration de 40% du salaire horaire.<\/p>\n<p>Ainsi, l\u2019interpr\u00e9tation retenue par la Cour de cassation p\u00e9naliserait les PME par rapport aux grandes entreprises disposant de plus de moyens financiers et les salari\u00e9s concern\u00e9s qui ne pourraient plus compter sur un revenu additionnel. En outre, le patronat du secteur de nettoyage et les syndicats auraient conclu une nouvelle convention collective d\u00e9but 2017 qui contiendrait la clause des 50%, ce qui d\u00e9montrerait une volont\u00e9 manifeste des syndicats de maintenir l\u2019interpr\u00e9tation donn\u00e9e jusqu\u2019\u00e0 maintenant.<\/p>\n<p>L\u2019intim\u00e9e rel\u00e8ve qu\u2019il n\u2019y aurait pas lieu d\u2019appliquer le principe de l\u2019interpr\u00e9tation plus favorable au salari\u00e9 \u00e0 une interpr\u00e9tation \u00e0 donner \u00e0 l\u2019agencement des paragraphes 2 et 3 de l\u2019article L.123- 1. du Code du travail, la v\u00e9rification en question n\u2019\u00e9tant \u00e0 faire que dans le cadre de clauses contraires au Code du travail. La seule question \u00e0 poser serait de savoir si les articles L.123- 1. et L.123- 5 stipulent une p\u00e9riode de r\u00e9f\u00e9rence de quatre semaines ou non. Dans la n\u00e9gative l\u2019analyse s\u2019arr\u00eaterait l\u00e0, dans l\u2019affirmative, il conviendrait d\u2019examiner si la convention collective ou une clause contraire dans le contrat de travail sont moins favorables au salari\u00e9.<\/p>\n<p>En outre, l\u2019interpr\u00e9tation donn\u00e9e par l\u2019appelante serait moins favorable au salari\u00e9 et contraire au code du travail en ce qu\u2019elle restreindrait les droits des salari\u00e9s.<\/p>\n<p>Aux termes de l\u2019article L.121- 3. du Code du travail :<\/p>\n<p>\u00ab Les parties au contrat de travail sont autoris\u00e9es \u00e0 d\u00e9roger aux dispositions du pr\u00e9sent titre dans un sens plus favorable au salari\u00e9.<\/p>\n<p>Est nulle et de nul effet toute clause contraire aux dispositions du pr\u00e9sent titre pour autant qu\u2019elle vise \u00e0 restreindre les droits du salari\u00e9 ou \u00e0 aggraver ses obligations\u00bb. Aux termes de l\u2019article L.162- 16. du Code du travail :<\/p>\n<p>\u00ab (6) Toute stipulation contraire aux lois et r\u00e8glements est nulle, \u00e0 moins qu\u2019elle ne soit plus favorable pour les salari\u00e9s.<\/p>\n<p>(7) Toute stipulation d\u2019un contrat de travail individuel, tout r\u00e8glement interne et toute disposition g\u00e9n\u00e9ralement quelconque, contraires aux clauses d\u2019une convention collective ou d\u2019un accord subordonn\u00e9, sont nuls, \u00e0 moins qu\u2019ils ne soient plus favorables pour les salari\u00e9s\u00bb.<\/p>\n<p>Tel que relev\u00e9 \u00e0 juste titre par l\u2019intim\u00e9e ce sont les r\u00e8glements internes ou clauses conventionnelles qui sont vis\u00e9s par le principe stipul\u00e9 aux dispositions pr\u00e9cit\u00e9es et non l\u2019interpr\u00e9tation donn\u00e9e, le cas \u00e9ch\u00e9ant, \u00e0 un texte l\u00e9gal.<\/p>\n<p>10 En tout \u00e9tat de cause, m\u00eame si l\u2019interpr\u00e9tation voulue par l\u2019appelante peut avoir une influence b\u00e9n\u00e9fique sur le march\u00e9 du travail, toujours est-il que la r\u00e9ponse donn\u00e9e par la Cour de cassation n\u2019est pas d\u00e9favorable au salari\u00e9 en ce qu\u2019elle pr\u00e9serve ses droits et emp\u00eache que l\u2019employeur ne s\u2019engage qu\u2019avec un contrat \u00e0 temps partiel tout en lui laissant toute latitude dans la d\u00e9termination des heures \u00e0 prester au- del\u00e0 de ce contrat, certes de l\u2019accord du salari\u00e9 et suivant un plan d\u2019organisation de travail, mais suivant le seul bon vouloir de l\u2019employeur obligeant le salari\u00e9 \u00e0 rester disponible sans pour autant avoir la garantie d\u2019un engagement au-del\u00e0 du temps partiel fix\u00e9.<\/p>\n<p>Il suit de ce qui pr\u00e9c\u00e8de que c\u2019est \u00e0 bon droit que la juridiction de premi\u00e8re instance a retenu que le temps de travail effectu\u00e9 par la salari\u00e9e \u00e0 temps partiel au-del\u00e0 des limites r\u00e9sultant de l\u2019application des paragraphes (2) et (3) de l\u2019article L.123- 1. du Code du travail est \u00e0 consid\u00e9rer comme temps de travail suppl\u00e9mentaire au sens de l\u2019article L.123- 4. sous 3, du Code du travail et qu\u2019en application des paragraphes (2) et (3) de l\u2019article L.123- 1. du Code du travail les parties au litige ont pu pr\u00e9voir dans le contrat de travail de A.) que la dur\u00e9e de travail de celle- ci pourrait \u00eatre augment\u00e9e de 50% par rapport au nombre d\u2019heures fix\u00e9es dans son contrat de travail, mais que la dur\u00e9e hebdomadaire moyenne de travail, calcul\u00e9e sur une p\u00e9riode de travail de quatre semaines cons\u00e9cutives, ne saurait d\u00e9passer la dur\u00e9e de travail hebdomadaire fix\u00e9e au contrat de travail.<\/p>\n<p>Au vu des pi\u00e8ces vers\u00e9es en cause et du d\u00e9compte de l\u2019intim\u00e9e, le nombre d\u2019heures suppl\u00e9mentaires s\u2019\u00e9l\u00e8ve \u00e0 346,45 heures pour la p\u00e9riode allant du 1 er<\/p>\n<p>mars au 31 ao\u00fbt 2012 et la demande de la salari\u00e9e est fond\u00e9e pour la majoration de 346,45 x 4,2915 = 1.486,80 EUR.<\/p>\n<p>Il s\u2019ensuit que le jugement entrepris est \u00e0 confirmer.<\/p>\n<p>Les indemnit\u00e9s de proc\u00e9dure<\/p>\n<p>La soci\u00e9t\u00e9 SOC.1.) demande une indemnit\u00e9 de proc\u00e9dure de 1.000,- EUR pour l\u2019instance d\u2019appel et le rejet de la demande de A.) bas\u00e9e sur l\u2019article 240 du Nouveau code de proc\u00e9dure civile tant pour la premi\u00e8re instance que pour l\u2019instance d\u2019appel, d\u00e8s lors que ses frais seraient enti\u00e8rement pris en charge par le syndicat X.) .<\/p>\n<p>A.) sollicite une indemnit\u00e9 de proc\u00e9dure de 1.250,- EUR pour l\u2019instance d\u2019appel et le rejet de la demande bas\u00e9e sur l\u2019article 240 du Nouveau code de proc\u00e9dure civile de la soci\u00e9t\u00e9 SOC.1.). Elle fait valoir que m\u00eame si le syndicat la soutient dans ses d\u00e9marches judiciaires, ce dernier ne supporte pas l\u2019enti\u00e8ret\u00e9 de ses frais dont une partie reste \u00e0 sa charge.<\/p>\n<p>L\u2019appelante n\u2019obtenant pas gain de cause, sa demande bas\u00e9e sur l\u2019article 240 du Nouveau code de proc\u00e9dure civile est \u00e0 rejeter.<\/p>\n<p>Eu \u00e9gard \u00e0 l\u2019issue du litige, il est in\u00e9quitable de laisser \u00e0 la charge de la salari\u00e9e les frais non compris dans les d\u00e9pens qu\u2019elle a expos\u00e9s pour obtenir gain de<\/p>\n<p>11 cause. Le jugement est partant \u00e0 confirmer en ce qu\u2019il a allou\u00e9 \u00e0 A.) une indemnit\u00e9 de proc\u00e9dure de 1.250,- EUR pour la premi\u00e8re instance et en tenant compte de l\u2019envergure de l\u2019affaire, il convient de lui allouer une indemnit\u00e9 de proc\u00e9dure de 1.500,- EUR pour l\u2019instance d\u2019appel.<\/p>\n<p>PAR CES MOTIFS:<\/p>\n<p>la Cour d\u2019appel, huiti\u00e8me chambre, si\u00e9geant en mati\u00e8re de droit du travail, statuant contradictoirement, sur le rapport du magistrat de la mise en \u00e9tat,<\/p>\n<p>statuant sur le renvoi ordonn\u00e9 par l\u2019arr\u00eat de la Cour de cassation du 22 mars 2018,<\/p>\n<p>re\u00e7oit l\u2019appel,<\/p>\n<p>le dit non fond\u00e9,<\/p>\n<p>confirme le jugement entrepris,<\/p>\n<p>condamne la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e SOC.1.) \u00e0 payer \u00e0 A.) une indemnit\u00e9 de proc\u00e9dure de 1.500,- EUR pour l\u2019instance d\u2019appel,<\/p>\n<p>rejette la demande de la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e SOC.1.) bas\u00e9e sur l\u2019article 240 du Nouveau code de proc\u00e9dure civile pour l\u2019instance d\u2019appel,<\/p>\n<p>condamne la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e SOC.1.) aux frais et d\u00e9pens de l\u2019instance d\u2019appel et en ordonne la distraction au profit de Ma\u00eetre Guy THOMAS, sur ses affirmations de droit.<\/p>\n<p>La lecture de cet arr\u00eat a \u00e9t\u00e9 faite \u00e0 l\u2019audience publique indiqu\u00e9e ci-dessus par Lotty PRUSSEN, pr\u00e9sident de chambre, en pr\u00e9sence du greffier Alain BERNARD.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-8\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-8\/20240827-205504\/20190404-ca8-43656a-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arr\u00eat N\u00b0 58\/19 &#8212; VIII &#8212; Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du quatre avril deux mille dix -neuf Num\u00e9ro 43656 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Monique HENTGEN, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain BERNARD,\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[21144],"kji_year":[45029],"kji_subject":[7724],"kji_keyword":[8683,8601,9055,12307,9688],"kji_language":[7733],"class_list":["post-767024","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-8","kji_year-45029","kji_subject-civil","kji_keyword-arret","kji_keyword-avril","kji_keyword-justice","kji_keyword-superieure","kji_keyword-travail","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 4 avril 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 4 avril 2019\" \/>\n<meta property=\"og:description\" content=\"Arr\u00eat N\u00b0 58\/19 - VIII - Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du quatre avril deux mille dix -neuf Num\u00e9ro 43656 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Monique HENTGEN, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain BERNARD,\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T22:23:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-4-avril-2019-4\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-4-avril-2019-4\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 4 avril 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-29T22:22:58+00:00\",\"dateModified\":\"2026-04-29T22:23:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-4-avril-2019-4\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-4-avril-2019-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-4-avril-2019-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 4 avril 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 4 avril 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/","og_locale":"ru_RU","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 4 avril 2019","og_description":"Arr\u00eat N\u00b0 58\/19 - VIII - Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du quatre avril deux mille dix -neuf Num\u00e9ro 43656 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Monique HENTGEN, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain BERNARD,\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-29T22:23:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"27 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/","name":"Cour sup\u00e9rieure de justice, 4 avril 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-29T22:22:58+00:00","dateModified":"2026-04-29T22:23:02+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-4-avril-2019-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 4 avril 2019"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/767024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=767024"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=767024"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=767024"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=767024"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=767024"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=767024"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=767024"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=767024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}