{"id":774288,"date":"2026-04-30T07:11:58","date_gmt":"2026-04-30T05:11:58","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/"},"modified":"2026-04-30T07:12:03","modified_gmt":"2026-04-30T05:12:03","slug":"tribunal-darrondissement-22-janvier-2019","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 22 janvier 2019"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Jugement en mati\u00e8reCivileNo.2019TADCH01\/13 Num\u00e9ro19859du r\u00f4le Audience publique du mardi,vingt-deuxjanvier deux mille dix-neuf. Composition: Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Vice-Pr\u00e9sident, Gilles PETRY, Premier Juge, Alain GODART, Greffier. E n t r e : PERSONNE1.),\u00e9pousePERSONNE2.),sans \u00e9tat actuel connu,demeurant \u00e0 L- ADRESSE1.); partie demanderesseaux termes d\u2019un exploit de l\u2019huissier de justiceGilbertRUKAVINAde Diekirch du29janvier 2013; comparant parMa\u00eetreDaniel BAULISCH,avocat \u00e0la Cour, demeurant \u00e0 Diekirch, assist\u00e9 de Ma\u00eetre Monique WATGEN, avocat \u00e0 la Cour, demeurant\u00e0Luxembourg; e t : 1)PERSONNE3.),infirmier,et son \u00e9pouse 2)PERSONNE4.), sans \u00e9tat actuel connu, les deuxdemeurantensemble\u00e0 L-ADRESSE2.); partiesd\u00e9fenderessesaux fins du pr\u00e9dit exploitRUKAVINA; comparant parMa\u00eetreJean-Luc GONNER,avocat \u00e0 la Cour, demeurant \u00e0 Diekirch, assist\u00e9 de Ma\u00eetre Serge MARX, avocat \u00e0 laCour, demeurant \u00e0 Luxembourg.<\/p>\n<p>2 LE TRIBUNAL Vu l\u2019ordonnance de cl\u00f4ture de l\u2019instruction du10juillet2018. Ant\u00e9c\u00e9dents proc\u00e9duraux L\u2019assignationdu 29 janvier 2013portenotammentsur (i) le partage et la liquidation de la masse successorale laiss\u00e9e par feuPERSONNE5.), (ii) la licitation des immeubles successoraux indivis entre partiespour cause d\u2019impartageabilit\u00e9 en nature, (iii) la nomination d\u2019un notaire avec la mission plus amplement d\u00e9taill\u00e9 dans l\u2019assignation, (iv) la r\u00e9duction du testament laiss\u00e9 par la d\u00e9funte au profit dePERSONNE3.)pour toute part d\u00e9passant le solde de la quotit\u00e9 disponible restant apr\u00e8s l\u2019imputation des donations re\u00e7ues du vivant de la m\u00e8re, (v) une reddition des comptes \u00e0 \u00e9tablir parPERSONNE3.), (vi) le paiement de la somme de 2.920 euros au titre de fermages encaiss\u00e9s, (vii) les frais et d\u00e9pens de l\u2019instance et (viii) une indemnit\u00e9 de proc\u00e9dure en faveur de la partie demanderesse. Par jugement civil n\u00b0 113\/2017 du 4 juillet 2017, le tribunal d\u2019arrondissement de Diekirch a re\u00e7ules demandes principale et reconventionnelle en la forme. Quant \u00e0 la demande en partage, le tribunal a, avant tout autre progr\u00e8s en cause, renvoy\u00e9l\u2019affaire devant le juge dela mise en \u00e9tat pour permettre aux partiesde prendre position surla question de savoir sous quel r\u00e9gime matrimonial les \u00e9pouxGROUPE1.)ont \u00e9t\u00e9 mari\u00e9s et si la d\u00e9termination de la masse des biens composant le cas \u00e9ch\u00e9ant la communaut\u00e9 des \u00e9poux et le partage de cette communaut\u00e9 ne constituent pas le pr\u00e9alable n\u00e9cessaire au partage de la succession d\u00e9laiss\u00e9e par PERSONNE5.). Quant \u00e0 la reddition de comptes, le tribunal a ditla demande form\u00e9e contre les \u00e9pouxGROUPE2.)non fond\u00e9e et en a d\u00e9bout\u00e9 la partie demanderesse. Pour le surplus, le tribunal a donn\u00e9acte \u00e0PERSONNE1.)qu\u2019elle renonce \u00e0 sa demande en condamnation des \u00e9pouxGROUPE2.)au paiement du montant de 2.920euros avec les int\u00e9r\u00eats l\u00e9gaux autitre de fermageset a r\u00e9serv\u00e9 lesurplus des demandes, les droits des parties et les d\u00e9pens. Comme suite \u00e0 ce jugement interlocutoire tranchant une partie du fond du litige tout en r\u00e9servant le surplus, les parties ont conclu comme suit: PERSONNE1.)demande au tribunal de constater que la d\u00e9funte n\u2019a laiss\u00e9 \u00e0 son d\u00e9c\u00e8s que des immeubles lui ayant appartenu en entier et qu\u2019elle ne s\u2019est, de son vivant, pas trouv\u00e9e en indivision avec ses enfants du chef de ces immeubles, de dire en cons\u00e9quence qu\u2019il ne s\u2019impose pas de proc\u00e9der au partage pr\u00e9alable de la communaut\u00e9 des biensGROUPE1.)etdemande d\u2019instituer, avant tout autre progr\u00e8s en cause,une expertise pour d\u00e9terminer, conform\u00e9ment \u00e0 l\u2019article 922 du Code civil, la valeur de la masse successorale globale de la d\u00e9funte, y compris celle des lib\u00e9ralit\u00e9s consenties de son vivant. PERSONNE3.)etPERSONNE4.)concluent que la succession dePERSONNE6.)a effectivement \u00e9t\u00e9 liquid\u00e9e et qu\u2019il est \u00e9vident que les biens se trouvant dans la succession de la<\/p>\n<p>3 d\u00e9funte ne font pas partie de la succession dePERSONNE6.).Ils continuent \u00e0 conclure que les donations-partagesconsenties par la d\u00e9funtesont \u00e0 \u00e9valuer conform\u00e9ment \u00e0 l\u2019article 1078 du Code civil et s\u2019opposent formellement \u00e0 toute r\u00e9\u00e9valuation. Quant \u00e0 la demande en partage PERSONNE5.)etPERSONNE6.)\u00e9taient mari\u00e9s. De leur union sont issus deux enfants; PERSONNE1.)etPERSONNE3.). PERSONNE6.)est d\u00e9c\u00e9d\u00e9 le 26 ao\u00fbt 1976.PERSONNE5.)est d\u00e9c\u00e9d\u00e9e le 29 octobre 2003. Tel qu\u2019il r\u00e9sulte des conclusions des parties prises comme suite au jugement du 4 juillet 2017, les \u00e9pouxGROUPE1.)\u00e9taient mari\u00e9s sous le r\u00e9gime de la communaut\u00e9 l\u00e9galedes biens, PERSONNE6.)est d\u00e9c\u00e9d\u00e9testat, sa succession a \u00e9t\u00e9 liquid\u00e9e et les biens d\u00e9pendant de celle dePERSONNE5.)font partie en entier de cette successionPERSONNE5.). Le tribunal constate qu\u2019il est constant en cause qu\u2019aucun contrat de mariage des \u00e9poux GROUPE1.)ne figure au dossier, que les parties sont unanimes que la succession de PERSONNE6.)a \u00e9t\u00e9 liquid\u00e9e suite \u00e0 son d\u00e9c\u00e8s etqu\u2019aucune revendication n\u2019adonc\u00e9t\u00e9 formul\u00e9e en relation avec cette succession. Par testament olographe du 14 octobre 1989,PERSONNE5.)a l\u00e9gu\u00e9 \u00e0 son filsPERSONNE3.) par pr\u00e9ciput et hors part la quotit\u00e9 disponible de sa succession. Tel qu\u2019il r\u00e9sulte des termes non contest\u00e9s de l\u2019assignation,PERSONNE3.)etPERSONNE4.) sont mari\u00e9s sous le r\u00e9gime matrimonial de la communaut\u00e9 de biens universelle aux termes d\u2019un contrat de mariage re\u00e7u par Ma\u00eetre Frank MOLITOR en date du 8 mars 1985. En application des articles 745,913et 1526du Code civil, cette succession est donc \u00e9chue pour 2\/3 \u00e0PERSONNE3.)et \u00e0PERSONNE4.)et pour 1\/3 \u00e0PERSONNE1.). Les \u00e9l\u00e9ments d\u2019actif et de passif de cette succession ressortent de la d\u00e9claration de succession du 9 ao\u00fbt 2005. Quant \u00e0 l\u2019actif, il s\u2019agit de plusieurs immeubles (\u00e9num\u00e9r\u00e9s aussi dansle jugement interlocutoire) \u00e9valu\u00e9s \u00e0 la somme de 88.200 euros, d\u2019un avoir bancaire \u00e0 hauteur de 91,94 euros et de meubles et effets personnels \u00e9valu\u00e9s \u00e0 500 euros.Dans l\u2019assignation, PERSONNE1.)fait encore \u00e9tat de comptes aupr\u00e8s de laSOCIETE1.)sans les sp\u00e9cifier quant \u00e0 leur identification ou l\u2019actif se trouvant inscrit au cr\u00e9dit de ces comptes.Quant au passif un forfait de 3.700 euros a \u00e9t\u00e9 fix\u00e9 au titre des frais fun\u00e9raires et de derni\u00e8re maladie. PERSONNE3.)etPERSONNE4.)ne s\u2019opposent pas \u00e0 sortirde l\u2019indivision successorale r\u00e9sultant du d\u00e9c\u00e8s dePERSONNE5.). L\u2019article 815 du Code civil dispose que nul ne peut \u00eatre contraint \u00e0 demeurer dans l&#039;indivision et le partage peut toujours \u00eatre provoqu\u00e9.Cette disposition consid\u00e8re l&#039;indivisioncomme un \u00e9tat transitoire que chacun des indivisaires peut toujours faire cesser. La r\u00e8gle d\u00e9coulant de l&#039;article 815 du Code civil doit\u00eatre consid\u00e9r\u00e9e comme \u00e9tant d&#039;ordre public (Cour d\u2019appel, 15.1.2003, n\u00b026612 du r\u00f4le, n\u00b0 Judoc 99837381).<\/p>\n<p>4 La demandeen partage n\u2019ayant pas \u00e9t\u00e9 autrement contest\u00e9e est partant \u00e0 recevoir dans son principe et le partage de la succession dePERSONNE5.)est \u00e0 ordonner. La demande tendant \u00e0 la nomination d\u2019un notaire avec la mission de proc\u00e9der aux op\u00e9rations de partage et de liquidation de la succession et notamment dedresser un inventaire des \u00e9l\u00e9ments actifs et passifs de la succession d\u00e9laiss\u00e9e,deproc\u00e9der \u00e0 l\u2019\u00e9valuation des biens,ded\u00e9terminer, apr\u00e8s imputation des donations d\u00e9j\u00e0 consenties, les parts de r\u00e9serve et de quotit\u00e9 disponible restante etded\u00e9terminer la part pour laquelle le testament pourra encore recevoir ex\u00e9cution est \u00e0 r\u00e9server au stade actuel de laproc\u00e9dure en attendant l\u2019expertise \u00e0 ordonner le cas \u00e9ch\u00e9ant dans le cadre de l\u2019action en r\u00e9duction du testament olographe. L\u2019issue de cette action en r\u00e9duction demeurant inconnue \u00e0 ce stade de la proc\u00e9dure, il y a \u00e9galement lieu de r\u00e9server la demande tendant\u00e0 lalicitation des immeubles indivis. Quant \u00e0 la demande en r\u00e9duction dutestament PERSONNE1.)fait valoir que le testament olographe de la d\u00e9funte ne pourrait recevoir ex\u00e9cution pour la totalit\u00e9 de la quotit\u00e9 disponible de la succession, maisseulement pour le solde restant \u00e0 d\u00e9terminer, dans la mesure o\u00f9 la d\u00e9funte auraitd\u00e9j\u00e0,de son vivant,consenti des donations entre vifs en date des 1 er mars 1982 et 5 juin 1986,qualifi\u00e9es de partage d\u2019ascendants, lesquelles devraient s\u2019imputer sur la quotit\u00e9 disponible de la succession, de sorte que le solde dela quotit\u00e9 disponibleserait encore \u00e0 d\u00e9terminer et que le testament olographe ne devrait pas d\u00e9passer ce solde. Ces donations devraient entrer en ligne de compte, comme toutes les autres donations consenties de son vivant par la d\u00e9funte, pour la d\u00e9termination de la valeur de la massede calcul sur base de l\u2019article 922 du Code civil et donc de la quotit\u00e9 disponible et de la r\u00e9serve l\u00e9gale applicables \u00e0 la succession en cause.Ellesollicite l\u2019institution d\u2019une expertise contradictoire afin de d\u00e9terminer les valeurs respectives des donations consenties entre vifs par la d\u00e9funte et de proc\u00e9der conform\u00e9ment audit article 922. PERSONNE3.)etPERSONNE4.)concluent \u00e0 l\u2019irrecevabilit\u00e9de l\u2019action, sinon qu\u2019elle est non fond\u00e9e. Ilssoul\u00e8vent l\u2019irrecevabilit\u00e9 de l\u2019action en r\u00e9ductionpour autant qu\u2019elle vise les donations-partages de 1982 et 1986 et ceen vertu de la prescription pr\u00e9vue \u00e0 l\u2019article 1077-2 du Code civil. Ils font valoir que cette action serait prescrite \u00e0 l\u2019expiration d\u2019un d\u00e9lai de cinq ans \u00e0 compter du d\u00e9c\u00e8s du donateur. Lad\u00e9funte\u00e9tant d\u00e9c\u00e9d\u00e9e le 29 octobre 2003 et l\u2019action ayant \u00e9t\u00e9 introduite le 29 janvier 2013,PERSONNE1.)serait forclose \u00e0 demander la r\u00e9duction des lib\u00e9ralit\u00e9s r\u00e9sultantdes partages d\u2019ascendantsdes 1 er mars 1982 et 5 juin 1986. A titre subsidiaire, ils soutiennent quePERSONNE1.)aurait accept\u00e9 la donation-partage du 1 er mars 1982, de sorte qu\u2019elle aurait renonc\u00e9 \u00e0 toute action en r\u00e9duction. Atitre plus subsidiaire,PERSONNE3.)etPERSONNE4.)invoquent l\u2019article 1078 du Code civil en soutenant que l\u2019\u00e9galit\u00e9 des h\u00e9ritiers serait pr\u00e9serv\u00e9e, de sorte que les h\u00e9ritiers ne sauraient plus demander une nouvelle \u00e9valuation de ces biens faite au jour dud\u00e9c\u00e8s de la d\u00e9funteet que si les biens immobiliers faisant l\u2019objet des actes de partage devraient \u00eatre \u00e9valu\u00e9s, la valeur devrait \u00eatre d\u00e9termin\u00e9e au jour des donations-partages.<\/p>\n<p>5 Ils soutiennent encore quePERSONNE1.),en\u00e9tablissantla d\u00e9claration de succession de feu sa m\u00e8re,aurait express\u00e9ment accept\u00e9 le testament olographe et reconnu que la quotit\u00e9 disponible aurait \u00e9t\u00e9 respect\u00e9e.Plus subsidiairement, ils concluent que la quotit\u00e9 disponible n\u2019aurait pas \u00e9t\u00e9 d\u00e9pass\u00e9e par le testament olographe du 14octobre 1989. Or, la preuve d\u2019un tel d\u00e9passement lui incomberait. Contrairement \u00e0 la position dePERSONNE1.), sa r\u00e9serve h\u00e9r\u00e9ditaire n\u2019aurait pas \u00e9t\u00e9 entam\u00e9e. Dans le cadre des donations-partages,PERSONNE1.)et PERSONNE3.)auraient chacun re\u00e7u des lots \u00e0 valeur \u00e9gale et le reste de l\u2019actif au jour du d\u00e9c\u00e8s de la d\u00e9funte aurait \u00e9t\u00e9 r\u00e9parti conform\u00e9ment \u00e0 la loi. PERSONNE3.)etPERSONNE4.)s\u2019opposentfinalementformellement \u00e0 une expertise aux fins de proc\u00e9der \u00e0 l\u2019\u00e9valuation des biens ayant fait l\u2019objet des donations-partages au motif que les biens auraient d\u2019ores et d\u00e9j\u00e0 \u00e9t\u00e9 \u00e9valu\u00e9s au moment du partage. 1.La recevabilit\u00e9 de la demande en r\u00e9duction PERSONNE3.)etPERSONNE4.)invoquentplusieursmoyens tendant \u00e0l\u2019irrecevabilit\u00e9 de l\u2019action en r\u00e9duction des donations-partages consenties en date des 1 er mars 1982 et 5 juin 1986. Or, ces moyens sont sans objet dans la mesure o\u00f9PERSONNE1.)ne poursuit pas la r\u00e9duction de ces donations-partages. Force est en effet de constater quePERSONNE1.)a saisi le tribunal, entre autres, d\u2019une action en r\u00e9duction du testament olographe de la d\u00e9funte du 14 octobre 1989 au profit d\u2019PERSONNE3.), le gratifiant de la quotit\u00e9 disponible de sa succession. Elle consid\u00e8re que la quotit\u00e9 disponible se trouve entam\u00e9e par l\u2019imputation des donations consenties entre vifs, dont les donations-partages en question. PERSONNE3.)etPERSONNE4.)soutiennent encore quePERSONNE1.)a accept\u00e9 le testament olographe de la d\u00e9funte du 14 octobre 1989et donc la r\u00e9partition de la masse successorale en r\u00e9sultant parle d\u00e9p\u00f4t de la d\u00e9claration de succession. Or, d\u2019une part, l\u2019\u00e9tablissement d\u2019une d\u00e9claration de succession constitue une obligationl\u00e9gale \u00e0 laquelle les h\u00e9ritiers ne peuvent se soustraire sous peine d\u2019augmentation des droits duset, d\u2019autre part, m\u00eame en admettant la validit\u00e9 de ce testament et l\u2019attribution par pr\u00e9ciput et hors part de la quotit\u00e9 disponible en r\u00e9sultant,PERSONNE1.)ne renonce pas \u00e0 l\u2019action en r\u00e9duction destin\u00e9e\u00e0 prot\u00e9ger la r\u00e9serve l\u00e9gale qui est d\u2019ordre public. Pour le surplus, il y a lieu de rappeler que l\u2019article 920 du Code civil dispose que les dispositionssoitentre vifs, soit \u00e0 cause de mort, qui exc\u00e9deront la quotit\u00e9 disponible, seront r\u00e9ductibles \u00e0cette quotit\u00e9 lors de l\u2019ouverture de la succession et qu\u2019en application de l\u2019article 1077-2 du Code civil, les donations-partages suivent les r\u00e8gles des donations entre vifs pour tout ce qui concerne l\u2019imputation, le calcul de la r\u00e9serve et la r\u00e9duction. La m\u00e9thode \u00e0 suivre est d\u00e9finie \u00e0 l\u2019article 922 du Code civil. La r\u00e9union fictive pr\u00e9vue audit article constitue une op\u00e9ration purement comptable, qui n\u2019oblige le gratifi\u00e9 \u00e0 aucune restitution et qui ne pr\u00e9juge m\u00eame pas de celle \u00e0 laquelle une<\/p>\n<p>6 r\u00e9duction, qui n\u2019est encore qu\u2019\u00e9ventuelle, pourrait le contraindre. (Michel GRIMALDI, Successions, Litec, 5 \u00e8me \u00e9dition, n\u00b0 724, p. 676). Ainsi s\u2019explique que tous les biens donn\u00e9s soient soumis \u00e0 la r\u00e9union fictive. Peu importe la personne du donataire: \u00e9tranger ou h\u00e9ritier. Peu importe, dans ce dernier cas, que la donation soit pr\u00e9ciputaire ou rapportable: preuve suppl\u00e9mentaire que la r\u00e9union fictive est totalement \u00e9trang\u00e8re au rapport. Peu importe encore la forme de la donation: donation ostensible, don manuel, donation d\u00e9guis\u00e9e ou indirecte. Peu importe enfin qu\u2019il s\u2019agisse d\u2019une donation ordinaire, d\u2019une donation-partage ou d\u2019une donation par contrat de mariage. (op. cit., n\u00b0 725, p. 676 et 677). Il faut donc r\u00e9unir toutes les donations consenties, sauf \u00e0les \u00e9valuer, le cas \u00e9ch\u00e9ant, suivant la r\u00e8gle d\u00e9rogatoire de l&#039;article 1078 du Code civil. L\u2019action en r\u00e9duction du testament olographe du 14 octobre 1989 estpartantrecevable. 2.La masse de calcul L\u2019article 922 du Code civildispose que la r\u00e9ductionse d\u00e9termine en formant une masse de tous les biens existant au d\u00e9c\u00e8s du donateur ou testateur(a).On y r\u00e9unit fictivement(c), apr\u00e8s en avoir d\u00e9duit les dettes(b), ceux dont il a \u00e9t\u00e9 dispos\u00e9 par donation entre vifs d&#039;apr\u00e8s leur \u00e9tat \u00e0 l&#039;\u00e9poque de la donation et leur valeur \u00e0 l&#039;ouverture de la succession. Si les biens ont \u00e9t\u00e9 ali\u00e9n\u00e9s, il est tenu compte de leur valeur \u00e0 l&#039;\u00e9poque de l&#039;ali\u00e9nation et, s&#039;il y a eu subrogation de la valeur des nouveaux biens au jour de l&#039;ouverture de la succession.On calculesur tous ces biens, eu \u00e9gard \u00e0 la qualit\u00e9 des h\u00e9ritiers qu&#039;il laisse, quelle est la quotit\u00e9 dont le d\u00e9funt a pu disposer. a.L\u2019actif au d\u00e9c\u00e8s dePERSONNE5.) Les \u00e9l\u00e9ments d\u2019actif r\u00e9sultent de la d\u00e9claration de succession et de l\u2019assignation. Les biensexistantdoivent \u00eatre\u00e9valu\u00e9s au d\u00e9c\u00e8s, soit \u00e0 la date du 29 octobre 2003. Aux fins de d\u00e9terminer ces valeurs, il y a lieu de proc\u00e9der par voie d\u2019expertise conform\u00e9ment aux modalit\u00e9s reprises au dispositif du pr\u00e9sent jugement. b.Le passif au d\u00e9c\u00e8s dePERSONNE5.) Les \u00e9l\u00e9ments de passifr\u00e9sultent de la d\u00e9claration de succession. Le total du passif existant vient en d\u00e9duction de la valeur de l\u2019actif existant. Reste \u00e0 y r\u00e9unirfictivement les biens donn\u00e9s, sauf \u00e0 pr\u00e9ciser que si la soustraction ci-avant mentionn\u00e9e d\u00e9gage un solde n\u00e9gatif\u2013le passif exc\u00e8de l\u2019actif\u2013le solde doit \u00eatre tenu pour nul, de sorte que la masse de calcul sera \u00e9gale \u00e0 la valeur de ces biens fictivement r\u00e9unis (op. cit. n\u00b0 723, p. 675). c.Les biens donn\u00e9s parPERSONNE5.)<\/p>\n<p>7 Les parties demanderesse et d\u00e9fenderesses qualifient les donations consenties comme des donations-partages. Consid\u00e9rant qu\u2019il existe cependant une divergence quant aux dates d\u2019\u00e9valuation des biens donn\u00e9s, il convient de d\u00e9terminer leur r\u00e9gime juridique. Quant \u00e0 l\u2019\u00e9valuation des biens donn\u00e9s,PERSONNE1.)conclut d\u2019abord comme suit: -le partage de l\u2019ann\u00e9e 1982 est soumis au r\u00e9gime applicable avant la loi du 12 mars 1982, donc la contre-valeur de cette donation doit \u00eatre fix\u00e9e, non pas \u00e0 sa valeur au moment de la donation, mais au prix de vente touch\u00e9 par les indivisairesPERSONNE3.)et PERSONNE4.)etPERSONNE5.)lors de l\u2019ali\u00e9nation faite par acte administratif du 24 f\u00e9vrier 1986 \u00e0 l\u2019Etat, soit 6.750.000 LUF ou 167.328,12 euros -le partage de l\u2019ann\u00e9e 1986estsoumis au r\u00e9gime introduit par la loi du 12 mars 1982, de sorte que la contre-valeur de cette donation est \u00e0 appr\u00e9cier au jour de la r\u00e9ception de l\u2019acte de donation, sans r\u00e9\u00e9valuation au jour du d\u00e9c\u00e8s de la donatrice, soit \u00e0 (2 x 398.000 LUF) 796.000 LUFou 19.732,32 euros. Puis,PERSONNE1.)estime que, pour satisfaire aux dispositions de l\u2019article 922 du Code civil, les valeurs des deux donations-partages des 1 er mars 1982 et 5 juin 1986 aux jours des donations respectives doivent se rajouter \u00e0 celle des biens pr\u00e9sents au d\u00e9c\u00e8s de la donatrice, pour former la valeur totale de la masse successorale et pour permettre de d\u00e9terminer les valeurs de la r\u00e9serve l\u00e9gale et de la quotit\u00e9 disponible de cette succession. Par apr\u00e8s (conclusions notifi\u00e9es le 14.2.2018),PERSONNE1.)conclut qu\u2019afin de constituer la valeur de la masse successorale au jour du d\u00e9c\u00e8s selon l\u2019article 922 du Code civil, il y a lieu de faire r\u00e9\u00e9valuer \u00e0 cette date l\u2019ensemble des lib\u00e9ralit\u00e9s consenties de son vivant par la d\u00e9funte, y comprisle partage d\u2019ascendant du 1 er mars 1982. PERSONNE3.)etPERSONNE4.)estiment que tant ce partage que celui de l\u2019ann\u00e9e 1986 seraient soumis au r\u00e9gime introduit par la loi du12mars 1982 et ce sur base de l\u2019article 11 de cettem\u00eameloi. PERSONNE3.)etPERSONNE4.)r\u00e9pliquentencorequ\u2019enpr\u00e9sence de donations-partages r\u00e9gies par l\u2019article 1078 du Codecivil, il n\u2019y pas lieu \u00e0 une quelconque r\u00e9\u00e9valuation. i.La qualificationet la consistancedes donations consenties -L\u2019acte du 1 er mars 1982 Suivant actedu 1 er mars 1982 re\u00e7u par devant le notaire Albert STREMLER, de r\u00e9sidence \u00e0 Mondorf-les-Bains,PERSONNE5.)aconsentie \u00e0PERSONNE3.)une donation entre vifs, par pr\u00e9ciput et hors part, sous le titre d\u2019un partage anticip\u00e9e conform\u00e9ment aux articles 1075 et suivants du Code civil, \u00e0 savoir 5\/8 en nue-propri\u00e9t\u00e9 d\u2019une maison d\u2019habitation avec place, jardin et toutes autres appartenances et d\u00e9pendances sis \u00e0ADRESSE3.)(n\u00b0NUMERO1.)et NUMERO2.)du cadastre)avec chargede payer \u00e0 sa s\u0153urPERSONNE1.)une soulte\u00e0 hauteur de 1.091.250 LUF. A ce titre, il y a d\u2019ores et d\u00e9j\u00e0 lieu de relever que la pleine propri\u00e9t\u00e9 de ces immeubles avait \u00e9t\u00e9 \u00e9valu\u00e9e au montant de 4.850.000 LUF. Par acte du 1 er mars 1982 re\u00e7u par devant le notaire Albert STREMLER, de r\u00e9sidence \u00e0 Mondorf-les-Bains,PERSONNE1.)a ratifi\u00e9 cet acte de donation.<\/p>\n<p>8 Il n\u2019est pas contest\u00e9 que la soulte en faveur dePERSONNE1.)a \u00e9t\u00e9 pay\u00e9e. Ceci r\u00e9sulte encore d\u2019un re\u00e7u du 2 ao\u00fbt 1982. La loi du 12 mars 1982 modifiant certaines dispositions du Code civilen mati\u00e8re de succession a introduit au Code civil les articles 1075 et suivants relatifs aux partages faits par les ascendants (chapitre VII du titre II du Livre III du Code civil). L\u2019article 11 de cette loi (non modifi\u00e9e) dispose que: Les dispositionsde la pr\u00e9sente loi seront applicables de plein droit, quelles que soient les dates des lib\u00e9ralit\u00e9s en cause, aux successions ouvertes post\u00e9rieurement \u00e0 son entr\u00e9e en vigueur. Elles s\u2019appliqueront \u00e9galement, \u00e0 moins de conventions contraires, aux successions non encore liquid\u00e9es, lorsqu\u2019aucune demande en partage n\u2019aura \u00e9t\u00e9 introduite. Consid\u00e9rant que l\u2019ouverture de la succession dePERSONNE5.)date du 29 octobre 2003, les articles 1075 et suivants du Code civil tel qu\u2019introduits par la loi du 12 mars 1982sontdonc applicablesaux pr\u00e9dits actes du1 er mars 1982. Le partage d\u2019ascendant, qui peut prendre la forme, ou de la donation-partage, ou du testament- partage, se d\u00e9finit comme \u00e9tant l\u2019acte par lequel un ascendant distribue et partagetout ou partie de ses biens, en composant lui-m\u00eame les lots. La donation-partage est une donation par laquelle l\u2019ascendant transmet irr\u00e9vocablement de son vivant ses biens aux gratifi\u00e9s et les partage entre eux. Elle r\u00e9alise une transmission et un partagedes biens de l\u2019ascendant. Tant le partageant que les gratifi\u00e9s sont partie \u00e0 l\u2019op\u00e9ration. (Cour d\u2019appel, 15.1.2003, Pas. 32, p. 326). En application de l\u2019article 1075 du Code civil, l\u2019ascendant peut imposer des charges \u00e0 un ou plusieurs de ses descendants en faveur d\u2019autres, soit pour constituer leur lot, soit pour le compl\u00e9ter. En tenant compte des termes de l\u2019acte de donation du 1 er mars 1982 et consid\u00e9rant qu\u2019en l\u2019esp\u00e8cePERSONNE5.)imposait pr\u00e9cis\u00e9ment \u00e0 son fils une charge constituant en une soulte en faveur de sa s\u0153ur pour la faire rentrer dans ses droitsen relation avec les parts indivises en nue-propri\u00e9t\u00e9 donn\u00e9es \u00e0PERSONNE3.)et que cet acte a \u00e9t\u00e9 ratifi\u00e9 le m\u00eame jour par PERSONNE1.), le tribunal qualifie l\u2019acte du 1 er mars 1982 comme donation-partage. Dans le cadre de ce partage,PERSONNE3.)\u00e9tait b\u00e9n\u00e9ficiaire d\u2019une donation avec charge et PERSONNE1.)b\u00e9n\u00e9ficiait d\u2019une donation constitu\u00e9e par le montant de cette charge. La donation consentie \u00e0PERSONNE3.)doit \u00eatre fictivement r\u00e9unie pour la valeur de l\u2019\u00e9molument net du gratifi\u00e9 (valeur donation\u2013valeur charge)et la donation consentie \u00e0 PERSONNE1.)doit \u00eatre fictivement r\u00e9unie pour la valeur de la charge. -L\u2019acte du 5 juin 1986 Suivant acte du 5 juin 1986 re\u00e7u par devant le notaire Frank BADEN, de r\u00e9sidence \u00e0 Luxembourg,PERSONNE5.)a consenti\u00e0PERSONNE3.)etPERSONNE1.)ensembledes donations entre vifs, par pr\u00e9ciput et hors part, sous le titre d\u2019un partage d\u2019ascendants conform\u00e9ment aux articles 1075 et suivants du Code civil, \u00e0 savoirdes parts indivises en pleine propri\u00e9t\u00e9 et en usufruit dans des immeubles sis \u00e0ADRESSE4.).<\/p>\n<p>9 Cet acteencourt la qualification de donation-partage et estsoumis aux articles 1075 et suivants du Code civil introduits par la loi du 12 mars 1982. Il r\u00e9sulte du contenu de cet acte qu\u2019il doit m\u00eame \u00eatre qualifi\u00e9 comme donation-partage cumulative qui \u00abse d\u00e9finit comme \u00e9tant l\u2019acte par lequel, \u00e0 la suite du d\u00e9c\u00e8s d\u2019un des parents, l\u2019ascendant survivant et les descendants communs confondent, pour les partager entre ces derniers, les biens issus de la succession du parent pr\u00e9d\u00e9c\u00e9d\u00e9 et ceux appartenant au parent survivant\u00bbet dont l\u2019\u00e9l\u00e9ment d\u00e9terminant \u00abest partant la r\u00e9union des biens en une masse commune, partag\u00e9e sous l\u2019autorit\u00e9 ou sous la m\u00e9diation de l\u2019ascendant\u00bb(Cour d\u2019appel, 15.1.2003,ibid.). En effet, dans le cadre de cette op\u00e9ration,la d\u00e9funte a consentides donations en faveur de ses enfants et,suite \u00e0 laconstitution de deux lots,lesimmeubles,dont les enfants\u00e9taient maintenantles uniquespropri\u00e9taires en vertu de ces donations et de la succession de leur p\u00e8re PERSONNE6.),ont \u00e9t\u00e9 partag\u00e9s entre eux, le touten pr\u00e9sence etsur instruction de PERSONNE5.)(p. 4 en haut dudit acte). Conform\u00e9ment \u00e0 ce qui pr\u00e9c\u00e8de, le tribunal\u00e9tantuniquement saisi du partage et de la liquidation de la succession dePERSONNE5.), il convient de prendre en consid\u00e9ration, dans le cadre des op\u00e9rations de calcul de l\u2019article 922 du Code civil, uniquement les biens donn\u00e9s par la d\u00e9funte \u00e0 ses deux enfants ensemble, \u00e0 savoir: -5\/8 en pleine propri\u00e9t\u00e9et 1\/8 en usufruit dans des immeubles inscrits au cadastre comme suit: commune deADRESSE4.), section A deADRESSE5.), n\u00b0NUMERO3.)et n\u00b0 NUMERO4.),\u00e9valu\u00e9s \u00e0 79.145 LUF, et -1\/4 en pleine propri\u00e9t\u00e9 et 1\/4 en usufruit dans des immeubles inscrits au cadastre comme suit: commune deADRESSE4.), section A deADRESSE5.), num\u00e9rosNUMERO5.), NUMERO6.),NUMERO7.),NUMERO8.),NUMERO9.) et commune de ADRESSE4.), section B deADRESSE6.), n\u00b0NUMERO10.), \u00e9valu\u00e9s \u00e0 185.200 LUF. Comme ces parts indivises ont \u00e9t\u00e9 donn\u00e9es \u00e0PERSONNE3.)etPERSONNE1.)ensemble, ils en \u00e9taient b\u00e9n\u00e9ficiaires chacun pour la moiti\u00e9. Par la suiteil convient de d\u00e9terminer les datesd\u2019\u00e9valuation et la n\u00e9cessit\u00e9 d\u2019une nouvelle \u00e9valuation des donations consenties. ii.L\u2019\u00e9valuation des donations-partages L\u2019article 1078 du Code civil dispose que nonobstant les r\u00e8gles applicables aux donations entre vifs, les biens donn\u00e9s seront, sauf convention contraire, \u00e9valu\u00e9s au jour de la donation-partage pour l\u2019imputation et le calcul de la r\u00e9serve, \u00e0 condition que tous les enfants vivants ou repr\u00e9sent\u00e9s au d\u00e9c\u00e8s de l\u2019ascendant aient re\u00e7u un lot dans le partage anticip\u00e9 et l\u2019aient express\u00e9ment accept\u00e9. Il d\u00e9coule de l\u2019analyse qui pr\u00e9c\u00e8de quant \u00e0 l\u2019acte de l\u2019ann\u00e9e 1982 que tantPERSONNE3.)que PERSONNE1.)ont re\u00e7u un lot et il r\u00e9sulte tant de l\u2019acte de donation-partage que de l\u2019acte de ratification du m\u00eame jour que les deux ont express\u00e9ment accept\u00e9 leur lot respectif.Concernant la donation-partage de 1986tantPERSONNE3.)que sa s\u0153urPERSONNE1.)ont re\u00e7uun lot qu\u2019ils ont,tous les deux,express\u00e9ment accept\u00e9.<\/p>\n<p>10 Les conditions de l\u2019article 1078 du Code civil \u00e9tant remplies concernant les deux actes de donations-partages,il y a donc lieu d\u2019\u00e9carter les r\u00e8gles d\u2019\u00e9valuation de l\u2019article 922 du Code civil pourle calcul de la valeur de ces donations etd\u2019\u00e9valuer les biens donn\u00e9sau jour de la donation-partage respective. La m\u00eame solution s\u2019impose pour l\u2019\u00e9valuation de la charge qui doit se faire au jour de l\u2019acte de 1982. Consid\u00e9rant que tant l\u2019acte del\u2019ann\u00e9e 1982 que celui de l\u2019ann\u00e9e1986 contiennent des \u00e9valuations(non contest\u00e9es, ni \u00e0 l\u2019\u00e9poque ni aujourd\u2019hui)permettant de calculer la valeur des donations consenties, il convient de charger les experts \u00e0 commettre\u00e9galementde la mission de calculerces valeurs \u00e0 partir des \u00e9valuations contenues dans lesdits actes, sans proc\u00e9der \u00e0 de nouvelles \u00e9valuations. d.La conclusion Comme le tribunal ne dispose pas des \u00e9l\u00e9ments d\u2019appr\u00e9ciation n\u00e9cessaires pour reconstituer enti\u00e8rementla masse de calcul de la quotit\u00e9 disponible et de la r\u00e9serve de la succession d\u00e9laiss\u00e9e par feuPERSONNE5.),il y a lieu de recourir \u00e0 l\u2019avis d\u2019hommes de l\u2019art avec la missiondereconstituer la masse successoraleetd\u2019\u00e9tablir la masse de calcul de la quotit\u00e9 disponible et de la r\u00e9serveconform\u00e9ment \u00e0 ce qui pr\u00e9c\u00e8de. D\u00e9pens et indemnit\u00e9s de proc\u00e9dure Au stade actuel de la proc\u00e9dure les demandesconcernantla charge des d\u00e9pens ettendant\u00e0 l\u2019octroi d\u2019une indemnit\u00e9 de proc\u00e9dure sont \u00e0 r\u00e9server. P A R C E S M O T I F S le Tribunal d\u2019arrondissement de Diekirch, si\u00e9geant en mati\u00e8re civile et en premier ressort, statuant contradictoirement et en continuation du jugement du 4 juillet 2017, le magistrat de la mise en \u00e9tat entendu en son rapport oral; ditla demande en partage de la succession dePERSONNE5.)fond\u00e9e en son principe; partantordonnele partage et la liquidation de la succession dePERSONNE5.); ditrecevablel\u2019action en r\u00e9duction du testament olographe du 14 octobre 1989; avant tout autre progr\u00e8s en cause; commeten qualit\u00e9 d\u2019experts MonsieurLucien MELCHIOR, demeurant \u00e0 Diekirch, etMa\u00eetre Alain BINGEN, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch, avec la mission de concilier les parties si faire se peut, sinon, dans un rapport \u00e9crit \u00e0 d\u00e9poser au greffe du tribunal,de reconstituer la masse successorale de la succession dePERSONNE5.)etd\u2019\u00e9tablir la masse de calcul de la quotit\u00e9 disponible et de la r\u00e9serveconform\u00e9ment \u00e0 ce qui a \u00e9t\u00e9retenudans la motivation de ce jugementet plus particuli\u00e8rement: a.quant \u00e0 l\u2019actif: \u00e9valuer les biens existant au d\u00e9c\u00e8s dePERSONNE5.), soit \u00e0 la date du 29 octobre 2003, b.quant au passif: d\u00e9terminer la consistance de ses dettes \u00e0cette m\u00eame date;<\/p>\n<p>11 c.quant aux biens donn\u00e9s:calculerla valeur des donations consenties par PERSONNE5.)en fonction des\u00e9valuations contenues dansles actes notari\u00e9s des 1 er mars 1982 et 5 juin 1986; ditque dans l\u2019accomplissement de leur mission, les experts sont autoris\u00e9s \u00e0 s\u2019entourer de tous renseignements utiles et m\u00eame d\u2019entendre des tierces personnes; fixela provision \u00e0 faire valoir sur les honoraires et frais des experts \u00e0 la somme de 1.500 euros etordonne\u00e0PERSONNE1.)de payer aux experts au plus tard le22 f\u00e9vrier 2019la somme de 1.500 euros\u00e0 titre de provision \u00e0 faire valoir sur leur r\u00e9mun\u00e9ration,sous peine de poursuite de l\u2019instance selon les dispositions de l\u2019article 468 du nouveau Code de proc\u00e9dure civile; ditque les experts devront en toutes circonstances informer le tribunal de ladate de leurs op\u00e9rations, de l\u2019\u00e9tat desdites op\u00e9rations et des difficult\u00e9s qu\u2019ils pourrontrencontrer; ditque si leurs honoraires devaient d\u00e9passer le montant de la provision vers\u00e9e, ils devront avertir le tribunal et ne continuer leurs op\u00e9rations qu\u2019apr\u00e8s consignationd\u2019une provision suppl\u00e9mentaire; ditque les experts devront d\u00e9poser leur rapport au greffe du tribunal d\u2019arrondissement pour le 21 juin 2019au plus tard; chargele juge de la mise en \u00e9tat Gilles PETRY de la surveillance de cette mesure d\u2019instruction; ditqu\u2019en cas de refus,d\u2019emp\u00eachement ou de retard desexperts, il serontremplac\u00e9spar ordonnance du juge de la mise en \u00e9tat Gilles PETRYsur simple requ\u00eate lui pr\u00e9sent\u00e9epar la partie la plus diligente, l\u2019autre partied\u00fbmentappel\u00e9e; r\u00e9servele surplus; refixela cause\u00e0 la conf\u00e9rence de mise en \u00e9tat dumardi,2 juillet 2019\u00e0 8.30heures, salle d\u2019audiencen\u00b0 Idutribunal. Ainsiprononc\u00e9en audience publique au Palais de Justice \u00e0 Diekirch par Nous,Jean-Claude KUREK,Pr\u00e9sidentdu Tribunal d\u2019Arrondissement, assist\u00e9 du greffierAlain GODART. Le Greffier LePr\u00e9sidentdu Tribunal -Alain GODART- -Jean-Claude KUREK-<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-diekirch\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-diekirch\/20240808-142602\/20190122-tad-19859-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jugement en mati\u00e8reCivileNo.2019TADCH01\/13 Num\u00e9ro19859du r\u00f4le Audience publique du mardi,vingt-deuxjanvier deux mille dix-neuf. Composition: Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Vice-Pr\u00e9sident, Gilles PETRY, Premier Juge, Alain GODART, Greffier. E n t r e : PERSONNE1.),\u00e9pousePERSONNE2.),sans \u00e9tat actuel connu,demeurant \u00e0 L- ADRESSE1.); partie demanderesseaux termes d\u2019un exploit de\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[],"kji_year":[45029],"kji_subject":[7724],"kji_keyword":[23584,8460,23061,24027,7636],"kji_language":[7733],"class_list":["post-774288","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_year-45029","kji_subject-civil","kji_keyword-arrondissement","kji_keyword-janvier","kji_keyword-jugement","kji_keyword-matierecivileno","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 22 janvier 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 22 janvier 2019\" \/>\n<meta property=\"og:description\" content=\"Jugement en mati\u00e8reCivileNo.2019TADCH01\/13 Num\u00e9ro19859du r\u00f4le Audience publique du mardi,vingt-deuxjanvier deux mille dix-neuf. Composition: Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Vice-Pr\u00e9sident, Gilles PETRY, Premier Juge, Alain GODART, Greffier. E n t r e : PERSONNE1.),\u00e9pousePERSONNE2.),sans \u00e9tat actuel connu,demeurant \u00e0 L- ADRESSE1.); partie demanderesseaux termes d\u2019un exploit de\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T05:12:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-22-janvier-2019\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-22-janvier-2019\\\/\",\"name\":\"Tribunal d'arrondissement, 22 janvier 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-30T05:11:58+00:00\",\"dateModified\":\"2026-04-30T05:12:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-22-janvier-2019\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-22-janvier-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-22-janvier-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 22 janvier 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 22 janvier 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 22 janvier 2019","og_description":"Jugement en mati\u00e8reCivileNo.2019TADCH01\/13 Num\u00e9ro19859du r\u00f4le Audience publique du mardi,vingt-deuxjanvier deux mille dix-neuf. Composition: Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Vice-Pr\u00e9sident, Gilles PETRY, Premier Juge, Alain GODART, Greffier. E n t r e : PERSONNE1.),\u00e9pousePERSONNE2.),sans \u00e9tat actuel connu,demeurant \u00e0 L- ADRESSE1.); partie demanderesseaux termes d\u2019un exploit de\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-30T05:12:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"25 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/","name":"Tribunal d'arrondissement, 22 janvier 2019 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-30T05:11:58+00:00","dateModified":"2026-04-30T05:12:03+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-22-janvier-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 22 janvier 2019"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/774288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=774288"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=774288"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=774288"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=774288"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=774288"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=774288"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=774288"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=774288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}