{"id":785676,"date":"2026-04-30T18:27:52","date_gmt":"2026-04-30T16:27:52","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/beschluss-vom-31-oktober-2023\/"},"modified":"2026-04-30T18:27:52","modified_gmt":"2026-04-30T16:27:52","slug":"beschluss-vom-31-oktober-2023","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/","title":{"rendered":"Beschluss vom 31. Oktober 2023"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<div class=\"bverfg-rubrum\">\n<p>BUNDESVERFASSUNGSGERICHT<\/p>\n<p>&#8212; 1 BvR 571\/23 &#8212;<\/p>\n<h2 class=\"has-eagle\">IM NAMEN DES VOLKES<\/h2>\n<h2>In dem Verfahren<br \/>\n\u00fcber<br \/>\ndie Verfassungsbeschwerde<\/h2>\n<p>des Herrn (&#8230;),<\/p>\n<p>&#8212; Bevollm\u00e4chtigter:<\/p>\n<p>Rechtsanwalt Thomas Hummel,<br \/>\nGr\u00fcnfinkenstra\u00dfe 5, 82194 Gr\u00f6benzell &#8212;<\/p>\n<p>gegen\n<\/p>\n<p>a) den Beschluss des Amtsgerichts Sch\u00f6neberg<\/p>\n<p>\u00a0\u00a0\u00a0vom 9. M\u00e4rz 2023 &#8212; 24 F 94\/22 -,<\/p>\n<p>\nb) den Beschluss des Amtsgerichts Sch\u00f6neberg<\/p>\n<p>\u00a0\u00a0\u00a0vom 20. Januar 2023 &#8212; 24 F 94\/22 &#8212;<\/p>\n<p>\nhat die 2. Kammer des Ersten Senats des Bundesverfassungsgerichts durch\n<\/p>\n<p class=\"left\">die Richterin Ott<\/p>\n<p class=\"left\">\nund die Richter Radtke,<\/p>\n<p class=\"left\">\nWolff<\/p>\n<p>am 31. Oktober 2023 einstimmig beschlossen:\n<\/p>\n<\/div>\n<h3>Tenor<\/h3>\n<p class=\"justify\"><strong>1. Der Beschluss des Amtsgerichts Sch\u00f6neberg vom 20. Januar 2023 &#8212; 24 F 94\/22 &#8212; verletzt den Beschwerdef\u00fchrer in seinem Recht aus Artikel 103 Absatz 1 des Grundgesetzes.<\/strong><\/p>\n<p class=\"justify\"><strong>2. Die Rechtskraft des in Ziffer 1. genannten Beschlusses wird insoweit aufgehoben, als sie einer erneuten Pr\u00fcfung und Entscheidung entgegensteht.<\/strong><\/p>\n<p class=\"justify\"><strong>3. Die Sache wird zur Entscheidung dar\u00fcber, ob der Ausspruch der Adoption aufrechtzuerhalten oder aufzuheben ist, an das Amtsgericht Sch\u00f6neberg zur\u00fcckverwiesen.<\/strong><\/p>\n<p class=\"justify\"><strong>4. Damit wird der Beschluss des Amtsgerichts Sch\u00f6neberg vom 9.\u00a0M\u00e4rz 2023 &#8212; 24 F 94\/22 &#8212; gegenstandslos.<\/strong><\/p>\n<p class=\"justify\"><strong>5. Das Land Berlin hat dem Beschwerdef\u00fchrer die notwendigen Auslagen zu erstatten.<\/strong><\/p>\n<h3>Gr\u00fcnde<\/h3>\n<p class=\"center\"><strong>G r \u00fc n d e :<\/strong><\/p>\n<p class=\"is-anchor\" id=\"1\">1<\/p>\n<p class=\"justify\">Die Verfassungsbeschwerde betrifft eine Vollj\u00e4hrigenadoption.<\/p>\n<h3><strong>I.<\/strong><\/h3>\n<p class=\"is-anchor\" id=\"2\">2<\/p>\n<p class=\"justify\">1. Im zugrundeliegenden Ausgangsverfahren hat der verwitwete, mittlerweile selbst verstorbene Vater des Beschwerdef\u00fchrers (nachfolgend: der Annehmende) die vollj\u00e4hrige Enkelin seiner Lebensgef\u00e4hrtin (nachfolgend: die Anzunehmende) als Kind angenommen.<\/p>\n<p class=\"is-anchor\" id=\"3\">3<\/p>\n<p class=\"justify\">a) Der Beschwerdef\u00fchrer ist das einzige Kind des Annehmenden und dessen 1998 vorverstorbener Ehefrau. Die Gro\u00dfmutter der Anzunehmenden war in seinen letzten Lebensjahren, etwa ab 2012, die Lebensgef\u00e4hrtin des Annehmenden, ohne dass sie mit ihm zusammenwohnte. Der Annehmende hatte mit seiner Ehefrau 1973 ein notarielles Ehegattentestament geschlossen, in dem die Ehegatten sich wechselseitig zu alleinigen Erben und den Beschwerdef\u00fchrer als Schlusserben des Letztversterbenden einsetzten.<\/p>\n<p class=\"is-anchor\" id=\"4\">4<\/p>\n<p class=\"justify\">b) Mit notariellem Antrag vom 11.\u00a0Mai 2022, der aufgrund des schlechten gesundheitlichen Zustands des Annehmenden in dessen Wohnung beurkundet wurde, beantragten der Annehmende und die Anzunehmende, dass die Anzunehmende durch den Annehmenden als Kind angenommen werden soll. Im Adoptionsverfahren vor dem Amtsgericht teilte der Beschwerdef\u00fchrer dem Gericht mit, dass der Annehmende am 3.\u00a0Juli 2022 gestorben sei. Er gehe davon aus, dass zwischen dem Annehmenden und der Anzunehmenden kein Eltern-Kind-Verh\u00e4ltnis im Sinne des \u00a7\u00a01767 BGB vorgelegen habe, zum anderen der Adoption \u00fcberwiegende Interessen des Beschwerdef\u00fchrers gem\u00e4\u00df \u00a7\u00a01769 BGB entgegenst\u00fcnden. Zugleich beantragte er Akteneinsicht. Das Amtsgericht \u00fcbermittelte dem Beschwerdef\u00fchrer den Adoptionsantrag und teilte telefonisch mit, dass es aus Datenschutzgr\u00fcnden Bedenken gegen die Akteneinsicht habe, weshalb der Beschwerdef\u00fchrer den Vortrag der Anzunehmenden nicht zur Kenntnis erhalte. Der Beschwerdef\u00fchrer beantragte zudem, ihn im Adoptionsverfahren als Beteiligten gem\u00e4\u00df \u00a7\u00a07 Abs.\u00a02 Nr.\u00a01 FamFG zu f\u00fchren. Das Amtsgericht beschied diesen Antrag nicht f\u00f6rmlich, teilte dem Beschwerdef\u00fchrer aber telefonisch mit, dass er nicht als Beteiligter hinzugezogen werde, weil dies aus Sicht des Gerichts vom Gesetzgeber nicht vorgesehen sei.<\/p>\n<p class=\"is-anchor\" id=\"5\">5<\/p>\n<p class=\"justify\">Das Amtsgericht f\u00fchrte Ermittlungen zum Eltern-Kind-Verh\u00e4ltnis zwischen dem Annehmenden und der Anzunehmenden sowie zu entgegenstehenden Interessen des Beschwerdef\u00fchrers durch. Mit Schriftsatz vom 2.\u00a0Januar 2023 teilte der den Adoptionsantrag beurkundende Notar dem Gericht mit, dass sich der Kontakt des Annehmenden \u00fcber seine Lebensgef\u00e4hrtin zu deren Enkelin intensiviert habe. Nach den Schilderungen des Annehmenden sei es zum Bruch mit dem Beschwerdef\u00fchrer gekommen, weil dieser einer Einladung zur Feier seines 80.\u00a0Geburtstags (des Annehmenden) nicht nachgekommen sei. Als Konsequenz habe der Annehmende die Anzunehmende als Berechtigte einer Patientenverf\u00fcgung und einer Vorsorgevollmacht eingesetzt. Am 14.\u00a0Dezember 2022 f\u00fchrte das Amtsgericht einen Anh\u00f6rungstermin mit der Anzunehmenden durch, von dem der Beschwerdef\u00fchrer in Kenntnis gesetzt wurde. Eine Teilnahme daran wurde ihm ausdr\u00fccklich nicht gestattet.<\/p>\n<p class=\"is-anchor\" id=\"6\">6<\/p>\n<p class=\"justify\">Mit angegriffenem Beschluss vom 20.\u00a0Januar 2023, der dem Beschwerdef\u00fchrer nicht f\u00f6rmlich zugestellt wurde, sprach das Amtsgericht die Annahme der Anzunehmenden als Kind des Annehmenden wie beantragt aus und begr\u00fcndete die Entscheidung damit, dass die gesetzlichen Voraussetzungen f\u00fcr die Annahme als Kind vorl\u00e4gen und die Entscheidung auf \u00a7\u00a7\u00a01767, 1770 BGB gest\u00fctzt werde.<\/p>\n<p class=\"is-anchor\" id=\"7\">7<\/p>\n<p class=\"justify\">c) Auf Nachfrage des Beschwerdef\u00fchrers teilte ihm das Amtsgericht mit erl\u00e4uternder Verf\u00fcgung vom 20.\u00a0Januar 2023 mit, dass am selben Tag ein stattgebender Adoptionsbeschluss ergangen sei, weil die Voraussetzungen eines Eltern-Kind-Verh\u00e4ltnisses vorl\u00e4gen. Dieses habe sich insbesondere nach der ausf\u00fchrlichen pers\u00f6nlichen Anh\u00f6rung der Anzunehmenden und der Stellungnahme des Notars vom 2.\u00a0Januar 2023 zur \u00dcberzeugung des Gerichts ergeben. Mit dieser Verf\u00fcgung wurde dem Beschwerdef\u00fchrer erstmals der Vermerk \u00fcber die Anh\u00f6rung der Anzunehmenden und der vorgenannte Schriftsatz des Notars \u00fcbermittelt.<\/p>\n<p class=\"is-anchor\" id=\"8\">8<\/p>\n<p class=\"justify\">Mit Schriftsatz vom 8.\u00a0Februar 2023 erhob der Beschwerdef\u00fchrer Anh\u00f6rungsr\u00fcge gegen den hier angegriffenen Beschluss. Das Gericht habe die Gefahr des Missbrauchs der Adoption eingehend zu pr\u00fcfen, zumal die Adoption vorliegend geeignet sei, die Regelungen im Berliner Testament der Eltern des Beschwerdef\u00fchrers zu unterlaufen. Tats\u00e4chlich aber habe das Gericht die m\u00f6glichen finanziellen Interessen der Anzunehmenden und das fehlende Eltern-Kind-Verh\u00e4ltnis au\u00dfer Acht gelassen und sein mehrmaliges Verlangen auf Anh\u00f6rung ignoriert. Im Verfahren sei ihm auch nur der Adoptionsantrag \u00fcbersandt worden. Erst mit der Verf\u00fcgung vom 20.\u00a0Januar 2023 habe der Beschwerdef\u00fchrer die Stellungnahme des Notars, die Vorsorgevollmacht zugunsten der Anzunehmenden, den Vermerk \u00fcber deren gerichtliche Anh\u00f6rung und die Stellungnahme des Notars zum Zustandekommen der Vorsorgevollmacht erhalten. Diese Vorgehensweise habe dem Beschwerdef\u00fchrer die M\u00f6glichkeit genommen, sich mit dem Vortrag der Gegenseite auseinanderzusetzen. Weiter trug der Beschwerdef\u00fchrer im Einzelnen vor, was er dem Vortrag der Anzunehmenden zum Entstehen eines Eltern-Kind-Verh\u00e4ltnisses entgegengehalten h\u00e4tte. Durch die vom Beschwerdef\u00fchrer noch vorgebrachten Informationen h\u00e4tten sich m\u00f6glicherweise finanzielle Aspekte als vorrangige Motive der Adoption best\u00e4tigt. H\u00e4tte das Gericht diesen Vortrag ber\u00fccksichtigt, w\u00e4re es m\u00f6glicherweise zu dem Schluss gekommen, dass die gesetzlichen Anforderungen einer Erwachsenenadoption nicht erf\u00fcllt seien.<\/p>\n<p class=\"is-anchor\" id=\"9\">9<\/p>\n<p class=\"justify\">Mit ebenfalls angegriffenem Beschluss vom 9.\u00a0M\u00e4rz 2023 wies das Amtsgericht die Anh\u00f6rungsr\u00fcge des Beschwerdef\u00fchrers zur\u00fcck. Der Beschwerdef\u00fchrer sei zwar nach \u00a7\u00a0188 Abs.\u00a01 Nr.\u00a01 FamFG am Adoptionsverfahren nicht beteiligt, jedoch nach \u00a7\u00a01769\u00a0BGB zum Adoptionsantrag zu h\u00f6ren. Dies sei geschehen. Er habe sich dann auch im Adoptionsverfahren mehrfach umfangreich zur Sache ge\u00e4u\u00dfert und seine Bedenken gegen die Adoption dargelegt, insbesondere dazu, dass kein Eltern-Kind-Verh\u00e4ltnis bestanden habe. Diesen Einwand habe das Gericht ausf\u00fchrlich \u00fcberpr\u00fcft. Es habe jedoch festgestellt, dass entgegen dem Einwand des Beschwerdef\u00fchrers ein die Adoption begr\u00fcndendes enges Vertrauensverh\u00e4ltnis vorgelegen habe. Da der Beschwerdef\u00fchrer nicht Beteiligter des Adoptionsverfahrens gewesen sei, habe ihm auch nicht jeglicher Vortrag der Anzunehmenden zur Stellungnahme \u00fcbermittelt werden m\u00fcssen. Die im hiesigen Verfahren vorgebrachten Angaben des Beschwerdef\u00fchrers seien nicht geeignet, die gerichtliche \u00dcberzeugung von dem Vorliegen eines \u00fcber zehn Jahre gewachsenen Verh\u00e4ltnisses von gegenseitigem Vertrauen und Beistand zu ersch\u00fcttern.<\/p>\n<p class=\"is-anchor\" id=\"10\">10<\/p>\n<p class=\"justify\">2. Mit seiner Verfassungsbeschwerde macht der Beschwerdef\u00fchrer die Verletzung von Art.\u00a0103 Abs.\u00a01, Art.\u00a01 Abs.\u00a01, Art.\u00a02 Abs.\u00a01 in Verbindung mit Art.\u00a020 Abs.\u00a03, Art. 6 Abs.\u00a01 und Art.\u00a014 Abs.\u00a01 GG geltend.<\/p>\n<p class=\"is-anchor\" id=\"11\">11<\/p>\n<p class=\"justify\">a)\u00a0Sein Anspruch auf rechtliches Geh\u00f6r (Art.\u00a0103 Abs.\u00a01 GG) sei verletzt, weil er keine Informationen des Gerichts \u00fcber den Verfahrensstand und den Sachvortrag der Beteiligten des Adoptionsverfahrens erhalten habe. Lediglich der knapp gehaltene Adoptionsantrag sei dem Beschwerdef\u00fchrer vor dem Erlass des Beschlusses vom 20.\u00a0Januar 2023 \u00fcbermittelt worden. Er habe zwar trotzdem mit mehreren Schrifts\u00e4tzen zur Sache vorgetragen. Dies sei aber nur \u201eins Blaue hinein\u201c erfolgt, weil er zum Zeitpunkt des Verfassens der Schrifts\u00e4tze \u00fcber die tragenden Argumente der Anzunehmenden nicht unterrichtet gewesen sei und dazu nicht im Einzelnen habe Stellung nehmen k\u00f6nnen. Seine Schrifts\u00e4tze seien jedoch weitergeleitet worden, wodurch die Anzunehmende sich detailliert habe \u00e4u\u00dfern und ihre Position im Verfahren habe st\u00e4rken k\u00f6nnen.<\/p>\n<p class=\"is-anchor\" id=\"12\">12<\/p>\n<p class=\"justify\">Er h\u00e4tte sich im Einzelnen zum Vorbringen der Anzunehmenden unter anderem wie folgt ge\u00e4u\u00dfert: Die Anzunehmende habe den Annehmenden nicht aus Zuneigung nach dessen erster Krebsdiagnose 2018 begleitet, der Annehmende habe ihm damals mitgeteilt, dass er die Anzunehmende bezahle, damit sie ihn zu den \u00c4rzten begleite und sie nur zu diesem Zweck ben\u00f6tige, ansonsten aber an keinem Umgang interessiert sei. Weiterhin h\u00e4tte er zu konkreten Geldabhebungen vorgetragen, welche die Anzunehmende anders vorgetragen habe, als es nach den tats\u00e4chlichen Kontobewegungen plausibel sei. Die Anzunehmende habe auch Barabhebungen in zeitlichem Zusammenhang zum Tod des Vaters vorgenommen, die sie nicht nachvollziehbar habe erkl\u00e4ren k\u00f6nnen.<\/p>\n<p class=\"is-anchor\" id=\"13\">13<\/p>\n<p class=\"justify\">Wenn dies ber\u00fccksichtigt worden w\u00e4re, w\u00e4re das Gericht m\u00f6glicherweise zu dem Ergebnis gekommen, dass die Anforderungen an eine Erwachsenenadoption nicht erf\u00fcllt seien. Es h\u00e4tte sich erhellt, dass die Anzunehmende ganz erhebliche finanzielle Interessen gehabt habe, die sie unmittelbar vor und auch in der Zeit nach dem Tod des Vaters sehr zielstrebig verwirklicht habe. Dies h\u00e4tte in Frage gestellt, ob die Beziehung zwischen dem Annehmenden und der Anzunehmenden wirklich von Solidarit\u00e4t und famili\u00e4rer Beziehung gepr\u00e4gt gewesen sei oder nicht viel mehr von den finanziellen Interessen der Anzunehmenden.<\/p>\n<p class=\"is-anchor\" id=\"14\">14<\/p>\n<p class=\"justify\">b)\u00a0Art.\u00a01 Abs.\u00a01, Art.\u00a02 Abs.\u00a01 in Verbindung mit Art.\u00a020 Abs.\u00a03 GG seien verletzt, weil die angegriffene Entscheidung \u00fcber die Annahme nicht aus einem fairen Verfahren hervorgegangen sei. Es sei offensichtlich keine Gleichbehandlung der Beteiligten erfolgt. W\u00e4hrend die Anzunehmende stets \u00fcber den Verfahrensstand im Bilde gewesen und pers\u00f6nlich angeh\u00f6rt worden sei sowie die Schrifts\u00e4tze des Beschwerdef\u00fchrers erhalten habe, sei der Beschwerdef\u00fchrer \u00fcber das Verfahren weitestgehend im Unklaren gelassen worden. Soweit sich Unterschiede aus den prozessualen Positionen erg\u00e4ben, sei auf die erheblichen materiellen Interessen des Beschwerdef\u00fchrers zu verweisen. Diese allein geb\u00f6ten es, ihm die Wahrnehmung seiner Verfahrensposition zu erm\u00f6glichen.<\/p>\n<p class=\"is-anchor\" id=\"15\">15<\/p>\n<p class=\"justify\">c) Art.\u00a014 Abs.\u00a01 GG sei verletzt. Die Vorschrift sch\u00fctze auch das Einr\u00fccken in die (alleinige) Erbenposition. Der Vater h\u00e4tte aufgrund der Bindungswirkung des Ehegattentestaments die Anzunehmende nicht als Erbin einsetzen k\u00f6nnen.<\/p>\n<p class=\"is-anchor\" id=\"16\">16<\/p>\n<p class=\"justify\">3. Das Land Berlin sah von der ihm einger\u00e4umten M\u00f6glichkeit zur Stellungahme ab. Die Anzunehmende h\u00e4lt die Verfassungsbeschwerde f\u00fcr unbegr\u00fcndet. Die Akten des Ausgangsverfahrens lagen der Kammer vor.<\/p>\n<h3><strong>II.<\/strong><\/h3>\n<p class=\"is-anchor\" id=\"17\">17<\/p>\n<p class=\"justify\">Die Kammer nimmt die Verfassungsbeschwerde zur Entscheidung an, weil dies zur Durchsetzung des Anspruchs des Beschwerdef\u00fchrers auf rechtliches Geh\u00f6r aus Art.\u00a0103 Abs.\u00a01 GG angezeigt ist (\u00a7\u00a093a Abs.\u00a02 Buchstabe\u00a0b BVerfGG). Die Entscheidung kann von der Kammer getroffen werden. Die ma\u00dfgeblichen verfassungsrechtlichen Fragen sind durch das Bundesverfassungsgericht bereits entschieden und die Verfassungsbeschwerde ist auch offensichtlich begr\u00fcndet (\u00a7\u00a093c Abs.\u00a01 Satz\u00a01 BVerfGG).<\/p>\n<p class=\"is-anchor\" id=\"18\">18<\/p>\n<p class=\"justify\">1. Die Verfassungsbeschwerde, mit der jedenfalls die R\u00fcge der Verletzung des Anspruchs auf rechtliches Geh\u00f6r (Art.\u00a0103 Abs.\u00a01 GG) zul\u00e4ssig erhoben wurde, ist in diesem Umfang begr\u00fcndet. Der angegriffene Beschluss des Amtsgerichts vom 20.\u00a0Januar 2023 verletzt den Beschwerdef\u00fchrer in seinem grundrechtsgleichen Recht aus Art.\u00a0103 Abs.\u00a01 GG.<\/p>\n<p class=\"is-anchor\" id=\"19\">19<\/p>\n<p class=\"justify\">a)\u00a0Der in Art.\u00a0103 Abs.\u00a01 GG gew\u00e4hrleistete Anspruch auf rechtliches Geh\u00f6r steht in funktionalem Zusammenhang mit der Rechtsschutzgarantie und der Justizgew\u00e4hrungspflicht des Staates (vgl. BVerfGE 81, 123 &lt;129&gt;). Der Einzelne soll nicht blo\u00dfes Objekt der richterlichen Entscheidung sein, sondern vor einer Entscheidung, die seine Rechte betrifft, zu Wort kommen, um als Subjekt Einfluss auf das Verfahren und sein Ergebnis nehmen zu k\u00f6nnen (vgl. BVerfGE 84, 188 &lt;189\u00a0f.&gt;; 86, 133 &lt;144&gt;; 89, 28 &lt;35&gt;; 107, 395 &lt;409&gt;; stRspr).<\/p>\n<p class=\"is-anchor\" id=\"20\">20<\/p>\n<p class=\"justify\">aa)\u00a0Art.\u00a0103 Abs.\u00a01 GG vermittelt allen an einem gerichtlichen Verfahren Beteiligten einen Anspruch darauf, sich zu dem verfahrensgegenst\u00e4ndlichen Sachverhalt und zur Rechtslage zu \u00e4u\u00dfern (vgl. BVerfG, Beschluss der 1.\u00a0Kammer des Zweiten Senats vom 1. August 2017 &#8212; 2\u00a0BvR 3068\/14 -, Rn.\u00a047 m.w.N.) sowie Antr\u00e4ge zu stellen und Ausf\u00fchrungen zu machen (vgl. BVerfGE 15, 303 &lt;307&gt;; 36, 85 &lt;87&gt;). Dementsprechend erfordert die Gew\u00e4hrung rechtlichen Geh\u00f6rs, einer gerichtlichen Entscheidung lediglich solche Tatsachen und Beweisergebnisse zugrunde zu legen, zu denen sich die Beteiligten vorher \u00e4u\u00dfern konnten (vgl. BVerfGE 50, 280 &lt;284&gt;; 101, 106 &lt;129&gt;; stRspr). Mit dem \u00c4u\u00dferungsrecht korrespondiert die Pflicht des Gerichts, Ausf\u00fchrungen der Beteiligten zur Kenntnis zu nehmen und in Erw\u00e4gung zu ziehen (vgl. BVerfGE 84, 188 &lt;190&gt;; 86, 133 &lt;144\u00a0ff.&gt;).<\/p>\n<p class=\"is-anchor\" id=\"21\">21<\/p>\n<p class=\"justify\">bb)\u00a0Das \u00c4u\u00dferungsrecht ist mit dem ebenfalls in Art.\u00a0103 Abs.\u00a01 GG wurzelnden Recht auf Information eng verkn\u00fcpft. Eine verfassungsrechtlichen Anforderungen gen\u00fcgende Gew\u00e4hrung rechtlichen Geh\u00f6rs erfordert, dass die Verfahrensbeteiligten erkennen k\u00f6nnen, auf welchen Tatsachenvortrag es f\u00fcr die Entscheidung ankommen kann. Sie m\u00fcssen sich unter Anwendung der gebotenen Sorgfalt \u00fcber den gesamten Verfahrensstoff unterrichten k\u00f6nnen (vgl. BVerfGE 96, 189 &lt;204&gt;; BVerfG, Beschluss der 3.\u00a0Kammer des Zweiten Senats vom 27.\u00a0Mai 2020 &#8212; 2\u00a0BvR 1809\/17 -, Rn.\u00a018). Den Gerichten obliegt in diesem Zusammenhang, von sich aus den Beteiligten alles f\u00fcr das Verfahren Wesentliche mitzuteilen (vgl. BVerfGE 72, 84 &lt;88&gt;; BVerfG, Beschluss der 1.\u00a0Kammer des Zweiten Senats vom 1. August 2017 &#8212; 2 BvR 3068\/14 -, Rn.\u00a049; Beschluss der 3.\u00a0Kammer des Zweiten Senats vom 27.\u00a0Mai 2020 &#8212; 2 BvR 1809\/17 -, Rn.\u00a018; siehe auch Remmert, in: D\u00fcrig\/Herzog\/Scholz, GG, Art.\u00a0103 Abs.\u00a01 Rn.\u00a078 &lt;Mai 2023&gt; m.w.N.). Zu den der Gegenseite in einem gerichtlichen Verfahren mitzuteilenden \u00c4u\u00dferungen eines anderen Verfahrensbeteiligten geh\u00f6ren nicht nur deren Schrifts\u00e4tze, sondern auch etwa dazu eingereichte Anlagen (vgl. BVerfGE 50, 280 &lt;284&gt; m.w.N.).<\/p>\n<p class=\"is-anchor\" id=\"22\">22<\/p>\n<p class=\"justify\">cc)\u00a0Art.\u00a0103 Abs.\u00a01 GG gilt auch im Verfahren der freiwilligen Gerichtsbarkeit und zwar unabh\u00e4ngig davon, ob die Anh\u00f6rung im Gesetz vorgesehen ist und auch bei Geltung des Untersuchungs- beziehungsweise Amtsermittlungsgrundsatzes (vgl. BVerfGE 19, 49 &lt;51&gt;; 89, 381 &lt;390&gt;). Auf eine f\u00f6rmliche Beteiligtenstellung kommt es dabei nicht an (vgl. BVerfGE 89, 381 &lt;390&gt;). Anh\u00f6rungsberechtigt im Sinne von Art.\u00a0103 Abs.\u00a01 GG k\u00f6nnen auch andere Personen sein, wenn die gerichtliche Entscheidung ihnen gegen\u00fcber materiellrechtlich wirkt (vgl. BVerfGE 60, 7 &lt;13&gt;; 89, 381 &lt;390\u00a0f.&gt;; stRspr). Zu den materiell Betroffenen in diesem Sinne geh\u00f6ren bei einer Adoption als Abk\u00f6mmlinge des Annehmenden dessen Kinder, deren rechtliche Interessen bei der Vollj\u00e4hrigenadoption \u00fcber \u00a7\u00a01769 BGB anerkannt werden (vgl. BVerfGE 89, 381 &lt;391&gt;). Da nach \u00a7\u00a01769 BGB eine Annahme Vollj\u00e4hriger nicht ausgesprochen werden darf, wenn ihr \u00fcberwiegende Interessen der Kinder des Annehmenden entgegenstehen, m\u00fcssen die Kinder auch die M\u00f6glichkeit haben, ihre Interessen im Verfahren darzulegen (vgl. BVerfGE 89, 381 &lt;391&gt;; BVerfG, Beschluss der 2. Kammer des Ersten Senats vom 20. Oktober 2008 &#8212; 1 BvR 291\/06 -, Rn. 11; BVerfG, Beschluss der 3. Kammer des Ersten Senats vom 16.\u00a0Februar 2023 &#8212; 1 BvR 1881\/21 -, Rn. 15). Der durch Art.\u00a0103 Abs.\u00a01 GG gew\u00e4hrleistete Anspruch, sich zu dem der gerichtlichen Entscheidung zugrunde liegenden Sachverhalt vor deren Erlass zu \u00e4u\u00dfern, steht nicht nur den Verfahrensbeteiligten zu, sondern auch den Personen, die nicht f\u00f6rmlich am Verfahren beteiligt sind, die aber durch die Entscheidung materiell betroffen werden. Wenn das Ergebnis der Anh\u00f6rung der Anzunehmenden im Rahmen einer Vollj\u00e4hrigenadoption entscheidungserheblich ist, ist also auch dazu zumindest Kindern des Annehmenden als dessen Abk\u00f6mmlingen und damit von der Annahme materiell Betroffenen vor der Adoptionsentscheidung die M\u00f6glichkeit zur Stellungnahme zu geben (vgl. BVerfGE 89, 381 &lt;392&gt;).<\/p>\n<p class=\"is-anchor\" id=\"23\">23<\/p>\n<p class=\"justify\">Dem tr\u00e4gt das Fachrecht jedenfalls f\u00fcr Kinder eines Annehmenden in Adoptionssachen nach \u00a7\u00a0186 Nr.\u00a01 FamFG hinreichend Rechnung. Zwar sind sie nach zum Fachrecht \u00fcberwiegend vertretener Auffassung nicht Beteiligte (\u00a7\u00a07 FamFG) des Adoptionsverfahrens (dazu n\u00e4her BGH, Beschluss vom 27.\u00a0Mai 2020 &#8212; XII ZB 54\/18 -, Rn.\u00a040\u00a0ff. m.w.N.). \u00a7\u00a0193 Satz\u00a01 FamFG r\u00e4umt ihnen aber ein Anh\u00f6rungsrecht ein, insbesondere um eine umfassende Pr\u00fcfung der Voraussetzungen des der Adoption entgegenstehenden \u00a7\u00a01769 BGB zu erm\u00f6glichen (vgl. Giers, in: Sternal, FamFG, 21.\u00a0Aufl. 2023, \u00a7\u00a0193 Rn.\u00a02).<\/p>\n<p class=\"is-anchor\" id=\"24\">24<\/p>\n<p class=\"justify\">b)\u00a0Nach diesen Ma\u00dfst\u00e4ben verletzt der Beschluss des Amtsgerichts vom 20.\u00a0Januar 2023 den Beschwerdef\u00fchrer in seinem Anspruch auf rechtliches Geh\u00f6r (Art.\u00a0103 Abs.\u00a01 GG). Die Entscheidung ist ergangen, ohne dass der Beschwerdef\u00fchrer \u00fcber den gesamten daf\u00fcr bedeutsamen Sachverhalt informiert war und ohne dass er zu diesem auf vollumf\u00e4nglicher Sachverhaltskenntnis hat Stellung nehmen k\u00f6nnen (aa). Dieser Versto\u00df ist auch durch den Beschluss \u00fcber seine fachrechtliche Anh\u00f6rungsr\u00fcge nicht geheilt worden (bb).<\/p>\n<p class=\"is-anchor\" id=\"25\">25<\/p>\n<p class=\"justify\">aa)\u00a0Das Amtsgericht hat im angegriffenen Beschluss vom 20.\u00a0Januar 2023 unter Verweis auf \u00a7\u00a7\u00a01767, 1770 BGB ausgef\u00fchrt, die gesetzlichen Voraussetzungen einer Vollj\u00e4hrigenadoption l\u00e4gen vor und auf die erfolgte schriftliche Anh\u00f6rung des Beschwerdef\u00fchrers verwiesen. Diese Anh\u00f6rung gen\u00fcgte aber nicht den aus Art.\u00a0103 Abs.\u00a01 GG folgenden Anforderungen an die Gew\u00e4hrung rechtlichen Geh\u00f6rs. Seine vor Ergehen des Adoptionsbeschlusses erfolgten Stellungnahmen beruhten nicht auf der Grundlage vollst\u00e4ndiger Informationen \u00fcber den entscheidungserheblichen Sachverhalt. Weder war ihm der Vermerk \u00fcber die pers\u00f6nliche Anh\u00f6rung der Anzunehmenden durch das Amtsgericht bekannt noch die Ausf\u00fchrungen des den Adoptionsantrag beurkundenden Notars vom 2.\u00a0Januar 2023. Der Beschwerdef\u00fchrer konnte sich dementsprechend nicht zu dortigen, f\u00fcr die Beurteilung der Voraussetzungen der Adoption nach \u00a7\u00a01767 BGB und dieser gegebenenfalls entgegenstehenden Interessen im Sinne von \u00a7\u00a01769 BGB m\u00f6glicherweise entscheidungserheblichen Inhalten \u00e4u\u00dfern.<\/p>\n<p class=\"is-anchor\" id=\"26\">26<\/p>\n<p class=\"justify\">Der angegriffene Beschluss des Amtsgerichts vom 20.\u00a0Januar 2023 beruht auch auf einer Verletzung des Anspruchs auf rechtliches Geh\u00f6r aus Art.\u00a0103 Abs.\u00a01 GG. Es ist nicht auszuschlie\u00dfen, dass die Ber\u00fccksichtigung des Vorbringens des Beschwerdef\u00fchrers, insbesondere zum Ergebnis der Anh\u00f6rung der Anzunehmenden, das Gericht zu einer anderen Beurteilung des Sachverhalts oder in einem wesentlichen Punkt zu einer anderen W\u00fcrdigung veranlasst oder im Ganzen zu einer anderen, ihm g\u00fcnstigeren Entscheidung gef\u00fchrt h\u00e4tte. Der Beschwerdef\u00fchrer hat insoweit nachvollziehbar vorgetragen, dass aufgrund des von ihm dargelegten Sachverhalts der Verdacht einer in erster Linie wirtschaftlichen Motivation der Adoption bestehe. Das w\u00fcrde nach fachrechtlich verbreiteter Auffassung eine sittliche Rechtfertigung im Sinne des \u00a7\u00a01767 Abs.\u00a01 BGB und damit die Voraussetzungen einer Vollj\u00e4hrigenadoption ausschlie\u00dfen (vgl. OLG M\u00fcnchen, Beschluss vom 8.\u00a0Juni 2009 &#8212; 31 Wx 22\/09 -, Rn. 9; Schleswig-Holsteinisches OLG, Beschluss vom 3.\u00a0Juni 2009 &#8212; 2 W 26\/09 -, Rn. 23; vgl. auch BVerfG, Beschluss der 3.\u00a0Kammer des Ersten Senats vom 16.\u00a0Februar 2023 &#8212; 1 BvR 1881\/21 -, Rn.\u00a015).<\/p>\n<p class=\"is-anchor\" id=\"27\">27<\/p>\n<p class=\"justify\">bb) Diese Verletzung des Anspruchs auf rechtliches Geh\u00f6r hat das Amtsgericht im Rahmen des Anh\u00f6rungsr\u00fcgeverfahrens nicht beseitigt. Zwar wurde dem Beschwerdef\u00fchrer \u00fcber seinen Verfahrensbevollm\u00e4chtigten im Rahmen des Verfahrens \u00fcber seine Anh\u00f6rungsr\u00fcge Akteneinsicht gew\u00e4hrt. Dies erm\u00f6glichte ihm, auf der Grundlage nun vollst\u00e4ndiger Kenntnis des entscheidungserheblichen Sachverhalts in seinem Schriftsatz vom 6.\u00a0M\u00e4rz 2023 seine Anh\u00f6rungsr\u00fcge vor Ergehen der gerichtlichen Entscheidung dar\u00fcber zu erg\u00e4nzen und zu vertiefen.<\/p>\n<p class=\"is-anchor\" id=\"28\">28<\/p>\n<p class=\"justify\">Der Beschluss des Amtsgerichts vom 9.\u00a0M\u00e4rz 2023 \u00fcber die Geh\u00f6rsr\u00fcge l\u00e4sst jedoch nicht erkennen, dass das vor und nach der Gew\u00e4hrung der Akteneinsicht erfolgte Vorbringen des Beschwerdef\u00fchrers nunmehr in einer den Gew\u00e4hrleistungen des Art.\u00a0103 Abs.\u00a01 GG gen\u00fcgenden Weise ber\u00fccksichtigt wurde. Aus Art.\u00a0103 Abs.\u00a01 GG folgt auch eine Pflicht der Gerichte, die wesentlichen, der Rechtsverfolgung und Rechtsverteidigung dienenden Tatsachenbehauptungen in den Entscheidungsgr\u00fcnden zu verarbeiten, wenn und soweit es sich nicht nach dem Rechtsstandpunkt des Gerichts um unerhebliches oder offensichtlich unsubstantiiertes Vorbringen handelt (vgl. BVerfG, Beschluss der 2.\u00a0Kammer des Ersten Senats vom 30.\u00a0August 2023 &#8212; 1\u00a0BvR 1654\/22 -, Rn.\u00a025 m.w.N.).<\/p>\n<p class=\"is-anchor\" id=\"29\">29<\/p>\n<p class=\"justify\">Daran gemessen hat das Amtsgericht dem Versto\u00df gegen den Anspruch des Beschwerdef\u00fchrers in dem Beschluss vom 20.\u00a0Januar 2023 durch den Beschluss \u00fcber die Anh\u00f6rungsr\u00fcge nicht abgeholfen. So geht es zum einen unter Verkennung der f\u00fcr das Verfahren der Vollj\u00e4hrigenadoption aus Art.\u00a0103 Abs.\u00a01 GG folgenden Anforderungen weiterhin davon aus, der Beschwerdef\u00fchrer sei als Kind des Annehmenden entscheidungserheblicher Vortrag aufgrund seiner Stellung als blo\u00df Anh\u00f6rungsberechtigter, nicht f\u00f6rmlich Beteiligter des Verfahrens, nicht vor der Entscheidung zur Kenntnis zu geben gewesen. Zum anderen verh\u00e4lt sich auch der Beschluss vom 9.\u00a0M\u00e4rz 2023 \u00fcber die Anh\u00f6rungsr\u00fcge nicht zu Kernvorbringen (vgl. Rn.\u00a028) des Beschwerdef\u00fchrers, das sowohl die Annahmevoraussetzungen nach \u00a7\u00a01767 BGB als auch der Annahme entgegenstehende Interessen im Sinne von \u00a7\u00a01769 BGB umfasst. Das Amtsgericht geht allenfalls auf das Vorliegen eines Eltern-Kind-Verh\u00e4ltnisses zwischen dem Annehmenden und der Anzunehmenden (\u00a7\u00a01767 Abs.\u00a01 BGB) ein. F\u00fcr eine Ber\u00fccksichtigung der von \u00a7\u00a01769 BGB erfassten Verm\u00f6gensinteressen (vgl. Helms, in: Staudinger, BGB, 2019, \u00a7\u00a01769 Rn.\u00a06 m.w.N.) des Beschwerdef\u00fchrers als vollj\u00e4hriges Kind des Annehmenden finden sich Anhaltspunkte weder im Rahmen der zu \u00a7\u00a01769 BGB m\u00f6glichen umfassenden Abw\u00e4gung der jeweiligen Interessen (vgl. zu dieser Einbindung in \u00a7\u00a01769 BGB Helms a.a.O., Rn.\u00a02) noch durch eine gesonderte Ber\u00fccksichtigung der Interessen des Beschwerdef\u00fchrers. Gerade ber\u00fccksichtigungsf\u00e4hige Verm\u00f6gensinteressen hatte dieser aber vorgebracht; das gilt auch f\u00fcr seinen nach der Gew\u00e4hrung von Akteneinsicht erfolgten Vortrag.<\/p>\n<h3><strong>III.<\/strong><\/h3>\n<p class=\"is-anchor\" id=\"30\">30<\/p>\n<p class=\"justify\">1. Der festgestellte Versto\u00df f\u00fchrt nicht zu einer Aufhebung des angegriffenen Adoptionsbeschlusses. Der Rechtsfolgenausspruch ist stattdessen auf die Beseitigung der Rechtskraft dieses Beschlusses und die Zur\u00fcckverweisung an das Amtsgericht zu beschr\u00e4nken. Dieses ist verpflichtet, dem Beschwerdef\u00fchrer das rechtliche Geh\u00f6r zu gew\u00e4hren und unter Ber\u00fccksichtigung seines Vorbringens dar\u00fcber zu entscheiden, ob der Adoptionsbeschluss aufzuheben oder aufrechtzuerhalten ist. Bis zu seiner Entscheidung bleiben die Wirkungen des Adoptionsbeschlusses bestehen (vgl. BVerfGE 89, 381 &lt;393&gt;; BVerfG, Beschluss der 2.\u00a0Kammer des Ersten Senats vom 20.\u00a0Oktober 2008 &#8212; 1 BvR 291\/06 -, Rn. 14; Beschluss der 3. Kammer des Ersten Senats vom 16. Februar 2023 &#8212; 1 BvR 1881\/21 -, Rn. 23).<\/p>\n<p class=\"is-anchor\" id=\"31\">31<\/p>\n<p class=\"justify\">Durch die Zur\u00fcckverweisung wird der Beschluss des Amtsgerichts vom 9.\u00a0M\u00e4rz 2023 \u00fcber die Anh\u00f6rungsr\u00fcge des Beschwerdef\u00fchrers gegenstandslos.<\/p>\n<p class=\"is-anchor\" id=\"32\">32<\/p>\n<p class=\"justify\">2. Die Anordnung der Auslagenerstattung folgt aus \u00a7\u00a034a Abs.\u00a02 BVerfGG.<\/p>\n<p class=\"is-anchor\" id=\"33\">33<\/p>\n<p class=\"justify\">Diese Entscheidung ist unanfechtbar.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/www.bundesverfassungsgericht.de\/SharedDocs\/Entscheidungen\/DE\/2023\/10\/rk20231031_1bvr057123.html\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/www.bundesverfassungsgericht.de\/SharedDocs\/Downloads\/DE\/2023\/10\/rk20231031_1bvr057123.pdf?__blob=publicationFile&#038;v=2\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Rechtsprechung im Internet (BMJV\/BfJ) : les decisions sont mises a disposition gratuitement en HTML, PDF et XML pour libre utilisation et re-utilisation.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Verfassungsbeschwerde gegen amtsgerichtlichen Adoptionsbeschluss wegen Verletzung des Anspruchs auf rechtliches Geh\u00f6r erfolgreich<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[7802],"kji_court":[8477],"kji_chamber":[12361],"kji_year":[24566],"kji_subject":[7660],"kji_keyword":[7808,8479,12529],"kji_language":[7805],"class_list":["post-785676","kji_decision","type-kji_decision","status-publish","hentry","kji_country-allemagne","kji_court-bundesverfassungsgericht","kji_chamber-2-kammer-des-ersten-senats","kji_year-24566","kji_subject-constitutionnel","kji_keyword-beschluss","kji_keyword-bundesverfassungsgericht","kji_keyword-oktober","kji_language-allemand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Beschluss vom 31. Oktober 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beschluss vom 31. Oktober 2023\" \/>\n<meta property=\"og:description\" content=\"Verfassungsbeschwerde gegen amtsgerichtlichen Adoptionsbeschluss wegen Verletzung des Anspruchs auf rechtliches Geh\u00f6r erfolgreich\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/beschluss-vom-31-oktober-2023\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/beschluss-vom-31-oktober-2023\\\/\",\"name\":\"Beschluss vom 31. Oktober 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-04-30T16:27:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/beschluss-vom-31-oktober-2023\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/beschluss-vom-31-oktober-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/beschluss-vom-31-oktober-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beschluss vom 31. Oktober 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Beschluss vom 31. Oktober 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/","og_locale":"ru_RU","og_type":"article","og_title":"Beschluss vom 31. Oktober 2023","og_description":"Verfassungsbeschwerde gegen amtsgerichtlichen Adoptionsbeschluss wegen Verletzung des Anspruchs auf rechtliches Geh\u00f6r erfolgreich","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"17 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/","name":"Beschluss vom 31. Oktober 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-04-30T16:27:52+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/beschluss-vom-31-oktober-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Beschluss vom 31. Oktober 2023"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/785676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=785676"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=785676"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=785676"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=785676"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=785676"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=785676"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=785676"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=785676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}