{"id":795718,"date":"2026-05-01T04:25:04","date_gmt":"2026-05-01T02:25:04","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/"},"modified":"2026-05-01T04:25:04","modified_gmt":"2026-05-01T02:25:04","slug":"tribunal-federal-suisse-5-mars-2018-n-4a-487-2017","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/","title":{"rendered":"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Bundesgericht<\/p>\n<p>Tribunal f\u00e9d\u00e9ral<\/p>\n<p>Tribunale federale<\/p>\n<p>Tribunal federal<\/p>\n<p>4A_487\/2017<\/p>\n<p>Arr\u00eat du 5mars 2018<\/p>\n<p>Ire Cour de droit civil<\/p>\n<p>Composition<\/p>\n<p>Mmes les juges Kiss, pr\u00e9sidente, Hohl et May Canellas.<\/p>\n<p>Greffier : M. Th\u00e9lin.<\/p>\n<p>Participants \u00e0 la proc\u00e9dure<\/p>\n<p>X.________,<\/p>\n<p>repr\u00e9sent\u00e9 par Me Jean-Marc Reymond,<\/p>\n<p>d\u00e9fendeur et recourant,<\/p>\n<p>contre<\/p>\n<p>Z.________ SA,<\/p>\n<p>repr\u00e9sent\u00e9e par Me Nicolas Gillard,<\/p>\n<p>demanderesse et intim\u00e9e.<\/p>\n<p>Objet<\/p>\n<p>contrat d&#039;h\u00f4tellerie<\/p>\n<p>recours contre l&#039;arr\u00eat rendu le 9 ao\u00fbt 2017 par la Cour d&#039;appel civile du Tribunal cantonal du canton de Vaud (PT14.048085-161965 342).<\/p>\n<p>Faits :<\/p>\n<p>A.<\/p>\n<p>La soci\u00e9t\u00e9 Z.________ SA exploite l&#039;h\u00f4tel&#8230; \u00e0 Montreux. Le 20 mai 2013, elle a conclu par \u00e9crit un contrat avec X.________, organisateur d&#039;un festival religieux hindou, pour la r\u00e9servation de chambres et d&#039;autres prestations d&#039;h\u00f4tellerie. La r\u00e9servation portait principalement sur cent vingt chambres pour deux personnes, \u00e0 occuper durant huit nuits, du 27 juillet au 4 ao\u00fbt 2013, au prix de 250 fr. par chambre et par nuit. Le contrat \u00e9tait r\u00e9dig\u00e9 en anglais.<\/p>\n<p>Selon ce contrat, il incomberait \u00e0 chaque participant de payer individuellement sa propre chambre au moment o\u00f9 il la restituerait, avec ses repas et les autres prestations re\u00e7ues de l&#039;\u00e9tablissement. L&#039;organisateur du festival n&#039;assumerait aucune responsabilit\u00e9 ni garantie en raison des \u00e9ventuels impay\u00e9s.<\/p>\n<p>Le nombre des participants \u00e9tait inconnu lors de la conclusion du contrat; l&#039;organisateur se portait toutefois garant du paiement de quatre cents nuit\u00e9es au minimum.<\/p>\n<p>Par ailleurs, le contrat permettait l&#039;annulation de la r\u00e9servation par l&#039;organisateur. Les parties convenaient que la r\u00e9servation exposait la soci\u00e9t\u00e9 h\u00f4teli\u00e8re \u00e0 une perte de gain correspondant \u00e0 quatre cents nuit\u00e9es, soit 100&#039;000 francs. Au cas o\u00f9 l&#039;organisateur d\u00e9clarerait l&#039;annulation de la r\u00e9servation moins de trente jours avant le d\u00e9but de l&#039;h\u00e9bergement convenu, il acquitterait un d\u00e9dommagement forfaitaire (\u00ab&#8230; which the parties intend as liquidated damages and not as a penalty \u00bb) au taux de 90% de cette perte, soit 90&#039;000 francs.<\/p>\n<p>Les obligations de l&#039;organisateur devaient \u00eatre garanties par trois versements \u00e0 la soci\u00e9t\u00e9 h\u00f4teli\u00e8re, soit 10&#039;000 fr. \u00e0 r\u00e9ception du contrat sign\u00e9, 35&#039;000 fr. au 15 juin 2013 et 35&#039;000 fr. au 30 du m\u00eame mois. Seuls 10&#039;000 fr. furent effectivement vers\u00e9s.<\/p>\n<p>B.<\/p>\n<p>Les cocontractants \u00e9chang\u00e8rent de nombreux courriels. D&#039;apr\u00e8s ceux de l&#039;organisateur, le nombre des participants au festival s&#039;annon\u00e7ait beaucoup plus \u00e9lev\u00e9 que pr\u00e9vu; cela causait d&#039;importantes difficult\u00e9s dans l&#039;organisation de l&#039;\u00e9v\u00e9nement. Parmi d&#039;autres embarras, l&#039;h\u00f4tel n&#039;\u00e9tait pas en mesure de fournir des repas pour le nombre des convives voulu. L&#039;organisateur annon\u00e7a plusieurs fois que si les parties ne parvenaient pas \u00e0 une solution appropri\u00e9e, il annulerait la r\u00e9servation. Il a semble-t-il d\u00e9clar\u00e9 ou confirm\u00e9 l&#039;annulation oralement, le 9 juillet 2013; la soci\u00e9t\u00e9 h\u00f4teli\u00e8re en a accus\u00e9 r\u00e9ception dans un courriel du m\u00eame jour.<\/p>\n<p>C.<\/p>\n<p>Le 13 novembre 2014, Z.________ SA a ouvert action contre X.________ devant le Tribunal civil de l&#039;arrondissement de Lausanne. Le d\u00e9fendeur devait \u00eatre condamn\u00e9 \u00e0 verser 80&#039;000 fr., soit le d\u00e9dommagement de 90&#039;000 fr. convenu moins l&#039;acompte de 10&#039;000 fr. vers\u00e9, avec int\u00e9r\u00eats au taux de 5% par an d\u00e8s le 1er septembre 2013.<\/p>\n<p>Le d\u00e9fendeur a conclu au rejet de l&#039;action.<\/p>\n<p>Le tribunal s&#039;est prononc\u00e9 le 7 juin 2016; accueillant l&#039;action, il a condamn\u00e9 le d\u00e9fendeur selon les conclusions de la demande.<\/p>\n<p>La Cour d&#039;appel civile du Tribunal cantonal a statu\u00e9 le 9 ao\u00fbt 2017 sur l&#039;appel du d\u00e9fendeur; elle a rejet\u00e9 cet appel et confirm\u00e9 le jugement.<\/p>\n<p>D.<\/p>\n<p>Agissant par la voie du recours en mati\u00e8re civile, le d\u00e9fendeur requiert le Tribunal f\u00e9d\u00e9ral de rejeter enti\u00e8rement l&#039;action.<\/p>\n<p>La demanderesse a pris position sur une demande d&#039;effet suspensif jointe au recours. Plus tard, elle a d\u00e9pos\u00e9 une r\u00e9ponse au recours apr\u00e8s l&#039;\u00e9ch\u00e9ance du d\u00e9lai qui lui \u00e9tait imparti \u00e0 cette fin; elle sollicite la restitution de ce d\u00e9lai.<\/p>\n<p>Par ordonnance du 18 octobre 2017, la Pr\u00e9sidente de la Ire Cour de droit civil a rejet\u00e9 la demande d&#039;effet suspensif.<\/p>\n<p>Consid\u00e9rant en droit :<\/p>\n<p>1.<\/p>\n<p>Les conditions de recevabilit\u00e9 du recours en mati\u00e8re civile sont satisfaites, notamment \u00e0 raison de la valeur litigieuse.<\/p>\n<p>2.<\/p>\n<p>Selon l&#039;art. 48 al. 1 LTF, un m\u00e9moire destin\u00e9 au Tribunal f\u00e9d\u00e9ral doit \u00eatre d\u00e9pos\u00e9 au plus tard le dernier jour du d\u00e9lai disponible. La restitution d&#039;un d\u00e9lai qui n&#039;a pas \u00e9t\u00e9 observ\u00e9 est r\u00e9gie par l&#039;art. 50 al. 1 LTF: elle est accord\u00e9e sur demande, lorsque la partie d\u00e9faillante ou son mandataire ont \u00e9t\u00e9 emp\u00each\u00e9s d&#039;agir avant l&#039;\u00e9ch\u00e9ance et qu&#039;ils n&#039;ont pas commis de faute.<\/p>\n<p>Par ordonnance du 20 septembre 2017, la Pr\u00e9sidente de la Ire Cour de droit civil a invit\u00e9 la demanderesse \u00e0 prendre position sur la demande d&#039;effet suspensif jointe au recours et \u00e0 d\u00e9poser sa r\u00e9ponse au recours; le d\u00e9lai imparti \u00e0 ces fins venait \u00e0 \u00e9ch\u00e9ance le 11 octobre 2017. La demanderesse a pris position \u00e0 temps sur la demande d&#039;effet suspensif; elle a en revanche d\u00e9pos\u00e9 la r\u00e9ponse hors d\u00e9lai. A l&#039;appui de sa demande de restitution, elle expose que par suite d&#039;une \u00ab lecture erron\u00e9e \u00bb de l&#039;ordonnance, son mandataire a retenu que le d\u00e9lai concernait seulement la demande d&#039;effet suspensif. Or, parce que l&#039;ordonnance ne pr\u00e9sentait aucune ambigu\u00eft\u00e9 et qu&#039;il incombait \u00e0 son destinataire de la lire attentivement, l&#039;inobservation du d\u00e9lai est la cons\u00e9quence d&#039;une faute. Il s&#039;ensuit que la demande de restitution est vou\u00e9e au rejet; il est sans importance que le mandataire de l&#039;adverse partie soit peut-\u00eatre dispos\u00e9 \u00e0 y acquiescer.<\/p>\n<p>3.<\/p>\n<p>Par le contrat du 20 mai 2013, la demanderesse s&#039;est oblig\u00e9e \u00e0 avoir dans son h\u00f4tel&#8230; cent vingt chambres pr\u00eates \u00e0 l&#039;occupation, dot\u00e9es des services concomitants (entretien; r\u00e9ception et assistance des h\u00f4tes, restauration, etc.), et \u00e0 y accueillir durant huit nuits, contre r\u00e9mun\u00e9ration, des participants au festival organis\u00e9 par le d\u00e9fendeur. La demanderesse s&#039;est ainsi oblig\u00e9e \u00e0 fournir des nuit\u00e9es en nombre ind\u00e9termin\u00e9, mais au plus neuf cent soixante. Ce contrat l&#039;emp\u00eachait de louer les chambres \u00e0 d&#039;autres clients; en cons\u00e9quence, il engendrait ou accroissait le risque que celles-ci demeurassent inoccup\u00e9es et que la demanderesse f\u00fbt priv\u00e9e de la r\u00e9mun\u00e9ration correspondante si le festival n&#039;avait pas lieu ou que les participants fussent peu nombreux. Les parties au contrat ont convenu d&#039;estimer ce risque au montant forfaitaire de 100&#039;000 fr. d&#039;apr\u00e8s le prix de quatre cents nuit\u00e9es, et de le reporter sur le d\u00e9fendeur, organisateur du festival, selon des modalit\u00e9s \u00e9galement convenues.<\/p>\n<p>Le d\u00e9fendeur n&#039;a contract\u00e9, lui, aucune obligation autre qu&#039;assumer ce risque selon ces modalit\u00e9s. La demanderesse pr\u00e9tend actuellement au d\u00e9dommagement forfaitaire qui a \u00e9t\u00e9 pr\u00e9vu parmi lesdites modalit\u00e9s; son action en paiement ne porte pas sur des dommages-int\u00e9r\u00eats pour cause d&#039;inex\u00e9cution du contrat, mais plut\u00f4t, simplement et directement, sur une prestation p\u00e9cuniaire convenue; il s&#039;agit d&#039;une action en ex\u00e9cution du contrat. L&#039;art. 97 al. 1 CO relatif \u00e0 la responsabilit\u00e9 pour cause d&#039;inex\u00e9cution n&#039;est pas en cause, et le d\u00e9fendeur ne peut donc pas s&#039;exon\u00e9rer en prouvant qu&#039;il n&#039;a commis aucune faute. Aucune des clauses du contrat ne subordonne le d\u00e9dommagement \u00e0 une faute du d\u00e9fendeur. Les discussions de la faute de cette partie, tant dans l&#039;arr\u00eat de la Cour d&#039;appel que dans le m\u00e9moire de recours au Tribunal f\u00e9d\u00e9ral, sont par cons\u00e9quent d\u00e9pourvues de pertinence. Il est constant que le d\u00e9fendeur a annul\u00e9 la r\u00e9servation avant la date pr\u00e9vue pour le d\u00e9but du festival, que celui-ci n&#039;a pas eu lieu, et qu&#039;aucun participant ne s&#039;est fait h\u00e9berger \u00e0 l&#039;h\u00f4tel&#8230;; \u00e0 premi\u00e8re vue, ces faits autorisent la demanderesse \u00e0 exiger le d\u00e9dommagement qu&#039;elle a stipul\u00e9.<\/p>\n<p>4.<\/p>\n<p>Le d\u00e9fendeur pourrait s&#039;exon\u00e9rer s&#039;il \u00e9tablissait que la demanderesse se soit trouv\u00e9e en demeure dans les pr\u00e9paratifs n\u00e9cessaires \u00e0 l&#039;h\u00e9bergement convenu, \u00e0 tel point que les conditions d&#039;une r\u00e9solution du contrat selon les art. 107 et 108 ch. 1 CO fussent accomplies; le d\u00e9fendeur pourrait alors soutenir que sa d\u00e9claration intervenue le 9 juillet 2013 n&#039;\u00e9tait pas une annulation de la r\u00e9servation telle que pr\u00e9vue dans le contrat, mais une r\u00e9solution du contrat dans son ensemble, \u00e9tendue aux clauses relatives au risque encouru par la demanderesse et report\u00e9 sur le d\u00e9fendeur. Celui-ci fait \u00e9tat, certes, d&#039;un comportement de la demanderesse pr\u00e9tendument contraire aux devoirs impos\u00e9s par le contrat, mais ses arguments ne convainquent pas.<\/p>\n<p>La demanderesse ne s&#039;est pas oblig\u00e9e \u00e0 h\u00e9berger davantage que deux cent quarante personnes \u00e0 loger dans les cent vingt chambres r\u00e9serv\u00e9es. Le d\u00e9fendeur affirme donc vainement que \u00ab si [la demanderesse] avait voulu plafonner le nombre des participants, [elle] aurait d\u00fb le faire dans le contrat d&#039;h\u00e9bergement \u00bb. Il n&#039;explique d&#039;ailleurs pas quelle est la prestation plus importante qu&#039;il attendait de sa cocontractante.<\/p>\n<p>La demanderesse aurait pr\u00e9tendument pu et d\u00fb limiter sa perte de gain en exigeant des participants qu&#039;ils acquittassent d&#039;avance le prix de leur h\u00e9bergement. Le d\u00e9fendeur se r\u00e9f\u00e8re \u00e0 une clause du contrat \u00e0 traduire comme suit: \u00ab Bien que le paiement soit exigible au moment du d\u00e9part du client, nous supposons (&#039;&#039;we presume &#039;&#039;) qu&#039;une confirmation de la r\u00e9servation n&#039;interviendra que contre complet paiement par carte de cr\u00e9dit ou d\u00e9bit&#8230; \u00bb Ce libell\u00e9 est \u00e9quivoque; il est d&#039;autant moins clair qu&#039;une \u00ab confirmation de la r\u00e9servation \u00bb n&#039;\u00e9tait semble-t-il pas pr\u00e9vue ailleurs dans le contrat. En particulier, il n&#039;\u00e9tait pas convenu que les participants dussent individuellement s&#039;annoncer aupr\u00e8s de l&#039;h\u00f4tel&#8230; avant de s&#039;y rendre le 27 juillet 2013 pour y \u00eatre h\u00e9berg\u00e9s. Dans les constatations de fait d\u00e9terminantes selon l&#039;art. 105 al. 1 LTF, il n&#039;appara\u00eet d&#039;ailleurs pas que des participants aient individuellement demand\u00e9 une confirmation de r\u00e9servation avant le 9 juillet 2013, jour de l&#039;annulation par le d\u00e9fendeur, et celui-ci ne pr\u00e9tend pas avoir all\u00e9gu\u00e9 et prouv\u00e9 de pareils faits.<\/p>\n<p>5.<\/p>\n<p>Le contrat des parties exclut textuellement, et dans son appr\u00e9ciation juridique, la Cour d&#039;appel exclut elle aussi que le d\u00e9dommagement convenu soit une peine conventionnelle sujette \u00e0 r\u00e9duction selon l&#039;art. 163 al. 3 CO. Il n&#039;est pas n\u00e9cessaire de discuter ce point car il n&#039;existe de toute mani\u00e8re aucun motif de r\u00e9duction. En particulier, aucun manquement n&#039;est imputable \u00e0 la partie cr\u00e9anci\u00e8re, et dans un contrat d&#039;h\u00f4tellerie portant sur neuf cent soixante nuit\u00e9es, une p\u00e9nalit\u00e9 calcul\u00e9e sur la base de quatre cents nuit\u00e9es n&#039;a rien d&#039;excessif.<\/p>\n<p>6.<\/p>\n<p>Le recours se r\u00e9v\u00e8le priv\u00e9 de fondement, ce qui conduit \u00e0 son rejet. A titre de partie qui succombe, son auteur doit acquitter l&#039;\u00e9molument \u00e0 percevoir par le Tribunal f\u00e9d\u00e9ral. L&#039;adverse partie n&#039;a pas d\u00e9pos\u00e9 de r\u00e9ponse en temps utile et il ne lui sera donc allou\u00e9 des d\u00e9pens qu&#039;\u00e0 raison de sa prise de position sur la demande d&#039;effet suspensif.<\/p>\n<p>Par ces motifs, le Tribunal f\u00e9d\u00e9ral prononce :<\/p>\n<p>1.<\/p>\n<p>La demande de restitution de d\u00e9lai pr\u00e9sent\u00e9e par la demanderesse est rejet\u00e9e.<\/p>\n<p>2.<\/p>\n<p>Le recours est rejet\u00e9.<\/p>\n<p>3.<\/p>\n<p>Le d\u00e9fendeur acquittera un \u00e9molument judiciaire de 4&#039;000 francs.<\/p>\n<p>4.<\/p>\n<p>Le d\u00e9fendeur versera une indemnit\u00e9 de 500 fr. \u00e0 la demanderesse, \u00e0 titre de d\u00e9pens.<\/p>\n<p>5.<\/p>\n<p>Le pr\u00e9sent arr\u00eat est communiqu\u00e9 aux parties et au Tribunal cantonal du canton de Vaud.<\/p>\n<p>Lausanne, le 5 mars 2018<\/p>\n<p>Au nom de la Ire Cour de droit civil<\/p>\n<p>du Tribunal f\u00e9d\u00e9ral suisse<\/p>\n<p>La pr\u00e9sidente : Kiss<\/p>\n<p>Le greffier : Th\u00e9lin<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/search.bger.ch\/ext\/eurospider\/live\/fr\/php\/aza\/http\/index.php?lang=fr&#038;type=highlight_simple_query&#038;page=6&#038;from_date=&#038;to_date=&#038;sort=relevance&#038;insertion_date=&#038;top_subcollection_aza=all&#038;query_words=droit+civil&#038;rank=56&#038;azaclir=aza&#038;highlight_docid=aza%3A%2F%2F05-03-2018-4A_487-2017&#038;number_of_ranks=19664\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a><\/p>\n<p class=\"kji-license-note\"><em>Source officielle Tribunal federal suisse. Contenu HTML public, PDF non garanti en version gratuite.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bundesgericht Tribunal f\u00e9d\u00e9ral Tribunale federale Tribunal federal 4A_487\/2017 Arr\u00eat du 5mars 2018 Ire Cour de droit civil Composition Mmes les juges Kiss, pr\u00e9sidente, Hohl et May Canellas. Greffier : M. Th\u00e9lin. Participants \u00e0 la proc\u00e9dure X.________, repr\u00e9sent\u00e9 par Me Jean-Marc Reymond, d\u00e9fendeur et recourant, contre Z.________ SA, repr\u00e9sent\u00e9e par Me Nicolas Gillard, demanderesse et intim\u00e9e&#8230;.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[9676],"kji_court":[9677],"kji_chamber":[9798],"kji_year":[47917],"kji_subject":[7724],"kji_keyword":[9799,9679,9680,7636],"kji_language":[7733],"class_list":["post-795718","kji_decision","type-kji_decision","status-publish","hentry","kji_country-suisse","kji_court-tribunal-federal-suisse","kji_chamber-cour-de-droit-civil","kji_year-47917","kji_subject-civil","kji_keyword-bundesgericht","kji_keyword-federal","kji_keyword-suisse","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017\" \/>\n<meta property=\"og:description\" content=\"Bundesgericht Tribunal f\u00e9d\u00e9ral Tribunale federale Tribunal federal 4A_487\/2017 Arr\u00eat du 5mars 2018 Ire Cour de droit civil Composition Mmes les juges Kiss, pr\u00e9sidente, Hohl et May Canellas. Greffier : M. Th\u00e9lin. Participants \u00e0 la proc\u00e9dure X.________, repr\u00e9sent\u00e9 par Me Jean-Marc Reymond, d\u00e9fendeur et recourant, contre Z.________ SA, repr\u00e9sent\u00e9e par Me Nicolas Gillard, demanderesse et intim\u00e9e....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\\\/\",\"name\":\"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-01T02:25:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017","og_description":"Bundesgericht Tribunal f\u00e9d\u00e9ral Tribunale federale Tribunal federal 4A_487\/2017 Arr\u00eat du 5mars 2018 Ire Cour de droit civil Composition Mmes les juges Kiss, pr\u00e9sidente, Hohl et May Canellas. Greffier : M. Th\u00e9lin. Participants \u00e0 la proc\u00e9dure X.________, repr\u00e9sent\u00e9 par Me Jean-Marc Reymond, d\u00e9fendeur et recourant, contre Z.________ SA, repr\u00e9sent\u00e9e par Me Nicolas Gillard, demanderesse et intim\u00e9e....","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"10 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/","name":"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-01T02:25:04+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-federal-suisse-5-mars-2018-n-4a-487-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal f\u00e9d\u00e9ral suisse, 5 mars 2018, n\u00b0 4A 487-2017"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/795718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=795718"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=795718"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=795718"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=795718"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=795718"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=795718"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=795718"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=795718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}