{"id":810111,"date":"2026-05-01T20:44:10","date_gmt":"2026-05-01T18:44:10","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/"},"modified":"2026-05-01T20:44:14","modified_gmt":"2026-05-01T18:44:14","slug":"tribunal-darrondissement-7-novembre-2017","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 7 novembre 2017"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH<\/p>\n<p>Jugement en mati\u00e8re Civile No. 2017TADCH01\/167<\/p>\n<p>Num\u00e9ro 17575 du r\u00f4le<\/p>\n<p>Audience publique du mardi, sept novembre de ux mille dix -sept.<\/p>\n<p>Composition: MAGISTRAT1.), Pr\u00e9sident, MAGISTRAT2.), Premier Juge, MAGISTRAT3.), Juge, GREFFIER1.), Greffier.<\/p>\n<p>E n t r e :<\/p>\n<p>PERSONNE1.), commer\u00e7ant, demeurant \u00e0 L -ADRESSE1.) ;<\/p>\n<p>partie demanderesse aux termes d\u2019un exploit de l\u2019huissier de justice HUISSIER DE JUSTICE1.) de (&#8230;) du 9 f\u00e9vrier 2012 ;<\/p>\n<p>ayant initialement comparu par Ma\u00eetre AVOCAT1.) , avocat \u00e0 la Cour, demeurant \u00e0 (&#8230;), qui a d\u00e9pos\u00e9 son mandat en cours d\u2019instance ;<\/p>\n<p>e t :<\/p>\n<p>1) PERSONNE2.), salari\u00e9, demeurant \u00e0 L-ADRESSE2.) ;<\/p>\n<p>2) PERSONNE3.), \u00e9pouse PERSONNE2.), pensionn\u00e9e, demeurant \u00e0 L-ADRESSE2.) ;<\/p>\n<p>parties d\u00e9fenderesses aux fins du pr\u00e9dit exploit HUISSIER DE JUSTICE1.) ;<\/p>\n<p>sub 1) comparant par Ma\u00eetre AVOCAT2.), avocat \u00e0 la Cour, demeurant \u00e0 (&#8230;), assist\u00e9 de Ma\u00eetre AVOCAT3.), avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg ;<\/p>\n<p>sub 2) comparant par Ma\u00eetre AVOCAT4.) , avocat \u00e0 la Cour, demeurant \u00e0 (&#8230;).<\/p>\n<p>LE TRIBUNAL :<\/p>\n<p>Vu l\u2019ordonnance de cl\u00f4ture de l\u2019instruction rendue en date du 1 er d\u00e9cembre 2015.<\/p>\n<p>Par exploit d\u2019huissier du 9 f\u00e9vrier 2012, PERSONNE1.) a fait assigner PERSONNE2.) et son \u00e9pouse PERSONNE3.) \u00e0 compara\u00eetre devant le tribunal d\u2019arrondissement de Diekirch aux fins de voir prononcer la r\u00e9solution du compromis de vente conclu entre parties, condamner solidairement, sinon in solidum, sinon chacune pour sa part les parties d\u00e9fenderesses au paiement du montant de 77.200 euros \u00e0 titre de dommages et int\u00e9r\u00eats, avec les int\u00e9r\u00eat au taux l\u00e9gal \u00e0 partir du 28 d\u00e9cembre 2011, sinon \u00e0 partir de la mise en demeure du 19 janvier 2011, sinon \u00e0 partir de la mise en demeure du 19 janvier 2012, sinon du jour de la demande en justice jusqu\u2019\u00e0 solde.<\/p>\n<p>Il sollicite encore la majoration du taux d\u2019int\u00e9r\u00eats de trois points \u00e0 partir du premier jour de l\u2019expiration du d\u00e9lai de trois mois qui suit la signification du jugement conform\u00e9ment et \u00e0 l\u2019article 14, 15 et 15- 1 de la loi modifi\u00e9e du 18 avril 2004 relative aux d\u00e9lais de paiement et aux int\u00e9r\u00eats de retard, ainsi qu\u2019une indemnit\u00e9 de proc\u00e9dure de 1.500 euros.<\/p>\n<p>Il est constant en cause qu\u2019en date du 10 janvier 2011, PERSONNE1.) et PERSONNE2.) ont sign\u00e9 un compromis de vente portant sur une maison avec terrain sise \u00e0 L-ADRESSE2.), section C d\u2019LIEU1.), n\u00b0 NUMERO1.) du cadastre, d\u2019une contenance de 4,62 ares. Le prix convenu \u00e9tait de 280.000 euros.<\/p>\n<p>Le compromis de vente fur conclu sous la condition suspensive pour PERSONNE2.) d\u2019obtenir, pour le 30 novembre 2011 au plus tard, un pr\u00eat d\u2019un \u00e9tablissement de cr\u00e9dit luxembourgeois pour le financement de l\u2019acquisition.<\/p>\n<p>A l\u2019appui de sa demande en r\u00e9solution du contrat de vente, PERSONNE1.) fait plaider que, nonobstant la r\u00e9alisation de la condition suspensive suite \u00e0 l\u2019obtention par PERSONNE2.) en date du 24 novembre 2011 d\u2019un pr\u00eat de la part de la banque BANQUE1.), et malgr\u00e9 sommation notariale de passer acte du 12 d\u00e9cembre 2012, PERSONNE2.) aurait refus\u00e9 de se pr\u00e9senter devant le notaire en vue de formaliser l\u2019acte de vente.<\/p>\n<p>Ce comportement serait fautif et autoriserait PERSONNE1.) \u00e0 solliciter la r\u00e9solution judiciaire du contrat de vente avec allocation de dommages et int\u00e9r\u00eats.<\/p>\n<p>Il base sa demande sur les articles 1183 et suivants, sinon sur les articles 1610 et 1654 et suivants du Code civil, sinon sur toute autre base \u00e0 suppl\u00e9er en cours d\u2019instance.<\/p>\n<p>Par conclusions du 6 novembre 2012, PERSONNE3.) excipe de la nullit\u00e9 du compromis de vente en vertu de l\u2019article 215 alin\u00e9a 2 du Code civil, alors qu\u2019elle n\u2019aurait pas donn\u00e9 son consentement audit compromis de vente qui aurait pour objet l\u2019ali\u00e9nation du logement familial.<\/p>\n<p>Aux termes du deuxi\u00e8me alin\u00e9a de l\u2019article 215 du Code civil, les \u00e9poux ne peuvent l&#039;un sans l&#039;autre disposer des droits par lesquels est assur\u00e9 le logement de la famille ni des meubles meublants dont il est garni. Sont concern\u00e9s tous les actes de disposition \u00e0 titre on\u00e9reux ou \u00e0 titre gratuit qui emportent ali\u00e9nation du bien servant au logement de la famille (voir en ce sens Encyclop\u00e9die Dalloz, R\u00e9pertoire de droit civil, v\u00b0 mariage (4\u00b0 effets), n\u00b0207 et 208).<\/p>\n<p>L\u2019action en nullit\u00e9 est r\u00e9serv\u00e9e au conjoint l\u00e9s\u00e9. En l\u2019occurrence l\u2019\u00e9pouse non signataire du compromis de vente se pr\u00e9vaut de la nullit\u00e9 du compromis.<\/p>\n<p>De m\u00eame, le compromis de vente en tant qu\u2019acte de disposition, se retrouve parmi les actes vis\u00e9s par l\u2019article 215 alin\u00e9a 2 du Code civil.<\/p>\n<p>PERSONNE1.) soul\u00e8ve l\u2019irrecevabilit\u00e9 de la demande en annulation d\u2019PERSONNE3.) : elle aurait d\u00fb agir par voie d\u2019action et ne saurait se limiter \u00e0 prendre des conclusions de d\u00e9fense en ce sens. PERSONNE1.) invoque \u00e9galement la prescription du droit d\u2019PERSONNE3.) de demander l\u2019annulation du compromis de vente.<\/p>\n<p>Il r\u00e9sulte effectivement de l\u2019article 215 alin\u00e9a 2 du Code civil que l\u2019action en nullit\u00e9 est ouverte \u00e0 l\u2019\u00e9poux l\u00e9s\u00e9 dans l\u2019ann\u00e9e \u00e0 partir du jour o\u00f9 il a eu connaissance de l\u2019acte, sans pouvoir jamais \u00eatre intent\u00e9e plus d\u2019un an apr\u00e8s que le r\u00e9gime matrimonial s\u2019est dissout.<\/p>\n<p>En l\u2019occurrence, PERSONNE3.) fait plaider avoir eu connaissance de l\u2019existence du compromis de vente au moment de la r\u00e9ception par elle en date du 12 d\u00e9cembre 2011 de la sommation du notaire de passer acte.<\/p>\n<p>Le moment de la prise de connaissance par PERSONNE3.) de l\u2019acte litigieux n\u2019est d\u2019aucune relevance pour trancher la question de la prescription alors que l\u2019\u00e9pouse soul\u00e8ve la nullit\u00e9 du compromis de vente comme moyen de d\u00e9fense, donc par voie d\u2019exception.<\/p>\n<p>Or, si l&#039;action en nullit\u00e9 est enferm\u00e9e dans un d\u00e9lai sp\u00e9cifique, la r\u00e8gle quae temporalia sunt ad agendum, perpetua sunt ad excipiendum s&#039;applique en la mati\u00e8re (Paris, 9 oct. 1997, JCP 1998. I. 135, n o 2, obs. Wiederkehr). L&#039;\u00e9poux dont le consentement \u00e9tait requis pourra donc toujours, malgr\u00e9 l&#039;\u00e9coulement du d\u00e9lai de prescription de l&#039;action en nullit\u00e9, opposer en d\u00e9fense l&#039;exception de nullit\u00e9 \u00e0 un tiers qui demanderait l&#039;ex\u00e9cution d&#039;un contrat conclu en contrari\u00e9t\u00e9 avec l&#039;article 215 du code civil (Civ. 1 re , 8 f\u00e9vr. 2000, n o 98-10.836 , JCP 2000. I. 245, n o 2, obs. Wiederkehr ; RTD civ. 2000. 888, obs. Vareille. &#8212; V. pour des pr\u00e9cisions \u00e0 ce sujet, Civ. 1 re , 28 f\u00e9vr. 2006, n o 02-19.809 , Juris -Data n o 032 392 ; Dr. fam. 2006, n o 121, obs. Larribau- Terneyre. &#8212; V. en outre VAREILLE, obs. sous Civ. 1 re , 3 mai 2000, RTD civ. 2000. 889, qui s&#039;interroge sur le maintien de l&#039;exception de nullit\u00e9 lorsque le bien litigieux a cess\u00e9 d&#039;\u00eatre le logement de la famille. &#8212; Adde : Civ. 1 re , 4 mars 2009, JCP 2009. I. 140, n o 12, obs. Simler).<\/p>\n<p>L\u2019exception de nullit\u00e9 est perp\u00e9tuelle. (Pr\u00e9cis Dalloz, Terr\u00e9, Simler, Lequette, Droit civil, Les obligations, n. 392, p. 325)<\/p>\n<p>Il doit par ailleurs \u00eatre admis que l\u2019action accord\u00e9e au conjoint par l\u2019article 215 alin\u00e9a 2 du Code civil tend non pas \u00e0 une inopposabilit\u00e9 de l\u2019acte, mais \u00e0 une nullit\u00e9 qui prive cet acte de<\/p>\n<p>ses effets, non seulement \u00e0 l\u2019\u00e9gard du conjoint non partie \u00e0 l\u2019acte, mais aussi dans les rapports de l\u2019autre conjoint et de son cocontractant. Cette annulation, qui sanctionne un d\u00e9passement de pouvoirs, ne peut faire na\u00eetre \u00e0 la charge du conjoint cocontractant une quelconque obligation.<\/p>\n<p>Il r\u00e9sulte des d\u00e9veloppements qui pr\u00e9c\u00e8dent que PERSONNE3.) , l\u2019\u00e9pouse non- signataire du compromis de vente actuellement litigieux peut valablement soulever la nullit\u00e9 de cet acte en d\u00e9fense \u00e0 la demande de PERSONNE1.).<\/p>\n<p>PERSONNE1.) oppose trois moyens \u00e0 la demande en annulation du compromis de vente.<\/p>\n<p>Quant au premier moyen, PERSONNE1.) fait valoir que l\u2019immeuble faisant objet de la vente n\u2019aurait pas constitu\u00e9 le logement de la famille mais une r\u00e9sidence secondaire seulement, qui serait en cette qualit\u00e9 exclue du r\u00e9gime de protection pr\u00e9vu par l\u2019article 215 alin\u00e9a 2 du Code civil. Les mentions du certificat de composition du m\u00e9nage concernant le logement familial ne jouiraient que d\u2019une pr\u00e9somption r\u00e9fragable et ne feraient foi que jusqu\u2019\u00e0 la preuve du contraire.<\/p>\n<p>Il s\u2019agirait d\u2019une question de fait devant faire l\u2019objet d\u2019une appr\u00e9ciation in concreto. En l\u2019occurrence, les \u00e9poux demeureraient ensemble depuis des ann\u00e9es dans un chalet \u00e0 ADRESSE3.).<\/p>\n<p>Il est admis que pour pouvoir \u00eatre qualifi\u00e9 de logement de la famille, l&#039;affectation de l&#039;immeuble litigieux au logement de la famille doit \u00eatre effective (voir JCL. Fasc. 30 : MARIAGE . \u2013 Organisation de la communaut\u00e9 conjugale et familiale . \u2013 Communaut\u00e9 de r\u00e9sidence (art. 215, al. 2 et 3), n\u00b0 44, CA Rennes, 1re ch., sect. A, 26 nov. 1996 : JurisData n\u00b0 1996- 048847) .<\/p>\n<p>PERSONNE1.) laisse cependant de rapporter la preuve de son affirmation que la maison sise \u00e0 ADRESSE2.) ne servirait pas de logement familial aux \u00e9poux PERSONNE2.) . Le t\u00e9moin TEMOIN1.) qui d\u00e9pose certes avoir procur\u00e9 \u00e0 PERSONNE2.) un chalet \u00e0 ADRESSE 3.) pour y r\u00e9sider : \u00ab ich besorgte auch Herrn PERSONNE2.) ein Chalet in der ADRESSE3.) um dort zu wohnen \u00bb. Cependant, l\u2019attestation, qui ne situe par ailleurs pas l\u2019\u00e9v\u00e8nement d\u00e9crit dans le temps, n\u2019est pas de nature \u00e0 \u00e9tablir que ledit chalet aurait \u00e9t\u00e9 affect\u00e9 au logement de la famille. En outre, les autres \u00e9l\u00e9ments de la cause corroborent plut\u00f4t les dires des \u00e9poux PERSONNE2.) : l\u2019int\u00e9gralit\u00e9 des courriers destin\u00e9s \u00e0 PERSONNE2.) et vers\u00e9s au dossier ont effectivement \u00e9t\u00e9 adress\u00e9s \u00e0 la maison sise \u00e0 ADRESSE2.).<\/p>\n<p>Quant au deuxi\u00e8me moyen, PERSONNE1.) fait valoir qu\u2019il n\u2019\u00e9tait tenu par aucune obligation l\u00e9gale de recueillir le consentement d\u2019PERSONNE3.) alors que la maison sise \u00e0 L- ADRESSE2.), constituerait un bien propre de PERSONNE2.) , dont il aurait, en vertu de l\u2019article 1536 du Code civil, conserv\u00e9 l\u2019administration, la jouissance et la libre disposition.<\/p>\n<p>Il y a lieu de rappeler, tel que le fait \u00e9galement plaider PERSONNE3.) , que, alors que chacun des \u00e9poux est en principe investi d&#039;un titre d&#039;intervention exclusive sur ses biens propres ou personnels (C. civ., art. 225, 1428 et 1536 ), le logement de la famille \u00e9chappe \u00e0 la ma\u00eetrise de l&#039;\u00e9poux qui en serait l&#039;unique propri\u00e9taire. L&#039;article 215, alin\u00e9a 3, r\u00e9alise ainsi en cours de r\u00e9gime la scission du couple traditionnel &quot;propri\u00e9t\u00e9-pouvoir&quot;, chaque \u00e9poux \u00e9tant cens\u00e9 avoir transf\u00e9r\u00e9 au m\u00e9nage le droit de jouissance dont il peut \u00eatre investi sur le logement familial. (voir JCL. Fasc. 30 : MARIAGE . \u2013 Organisation de la communaut\u00e9 conjugale et familiale . \u2013 Communaut\u00e9 de r\u00e9sidence (art. 215, al. 2 et 3), n\u00b041)<\/p>\n<p>L&#039;autonomie de chaque \u00e9poux par rapport \u00e0 ses biens personnels se heurte donc \u00e0 la r\u00e8gle de l&#039;article 215, alin\u00e9a 2, du C ode civil qui interdit \u00e0 un \u00e9poux de disposer sans son conjoint des droits par lesquels est assur\u00e9 le logement de la famille. Si l&#039;immeuble qui assure le logement familial constitue un bien personnel de l&#039;un des \u00e9poux, l&#039;application de l&#039;article 215, alin\u00e9a 2, pr\u00e9vaut sur la r\u00e8gle institu\u00e9e \u00e0 l&#039;article 225, au risque sinon de faire perdre \u00e0 la protection du logement familial toute sa substance et donc sa r\u00e9alit\u00e9. (R\u00e9p. Dalloz, Mariage (4 o effets), n\u00b0 289)<\/p>\n<p>Le consentement d\u2019PERSONNE3.) \u00e9tait donc n\u00e9cessaire pour proc\u00e9der \u00e0 la vente de la maison en question.<\/p>\n<p>Troisi\u00e8mement, PERSONNE1.) fait plaider que, contrairement aux dires d\u2019 PERSONNE3.), elle auait bel bien donn\u00e9 son consentement \u00e0 la vente litigieuse. Elle aurait \u00e9t\u00e9 toujours pr\u00e9sente aux n\u00e9gociations ayant pr\u00e9c\u00e9d\u00e9 la signature du compromis de vente. De m\u00eame, elle aurait \u00e9t\u00e9 pr\u00e9sente aux n\u00e9gociations post\u00e9rieures \u00e0 la conclusion du compromis de vente, n\u00e9gociations ayant tourn\u00e9 autour la question de l\u2019attribution, en compensation du prix de vente, d\u2019un appartement dans la r\u00e9sidence \u00e0 \u00e9riger en lieu et place de la maison. Il fait renvoyer aux d\u00e9clarations de TEMOIN1 .) pour \u00e9tayer ses propos.<\/p>\n<p>Quant \u00e0 la forme que doit prendre le consentement de l\u2019\u00e9poux non signataire de l\u2019acte de disposition concernant le logement de la famille, le texte de l\u2019article 215 alin\u00e9a 2 du Code civil n\u2019impose pas un \u00e9crit. Aussi n\u2019est-il pas n\u00e9cessaire que le conjoint donne son consentement par \u00e9crit et dans l&#039;acte lui-m\u00eame Le consentement peut \u00e9galement \u00eatre donn\u00e9 par anticipation, notamment dans le cadre d&#039;une procuration ou au contraire a posteriori par voie de ratification.<\/p>\n<p>La preuve du consentement du conjoint, s&#039;agissant d&#039;un fait juridique, peut en \u00eatre rapport\u00e9e par tous moyens. (CA 29 avril 2009, n\u00b0 33584 du r\u00f4le).<\/p>\n<p>Au fond, le consentement doit \u00eatre certain et sp\u00e9cial : le conjoint doit avoir conscience de l&#039;atteinte que l&#039;acte envisag\u00e9 par son \u00e9poux porte ou est susceptible de porter au maintien de la famille dans le logement. La jurisprudence ne s&#039;en tient d&#039;ailleurs pas \u00e0 exiger un accord sur le principe de l&#039;acte, mais impose de surcro\u00eet une entente sur les conditions essentielles de cet acte, notamment sur le prix de cession.<\/p>\n<p>Or, tout d\u2019abord, la simple pr\u00e9sence d\u2019PERSONNE3.) lors des n\u00e9gociations ayant entour\u00e9 la vente, pr\u00e9sence invoqu\u00e9e mais contest\u00e9e et par ailleurs non prouv\u00e9e, ne saurait \u00e9tablir dans son chef un consentement pr\u00e9cis et sp\u00e9cial, ni sur le principe de la vente projet\u00e9e, ni sur les conditions dont elle \u00e9tait assortie.<\/p>\n<p>La d\u00e9position de TEMOIN1.) , libell\u00e9e comme suit : \u00ab ich weiss noch dass Herr und Frau PERSONNE2.) sich f\u00fcr das Appartement im Erdgeschoss links entschieden haben, mit Terrasse, als Gegenleistung zum Kaufpreis \u00bb n\u2019est pas non plus de nature \u00e0 prouver le consentement d\u2019PERSONNE3.) aux conditions de la vente, dans la mesure o\u00f9 il ne r\u00e9sulte pas de cette d\u00e9claration que les conditions de prix auxquelles fait r\u00e9f\u00e9rence le t\u00e9moin comme ayant amen\u00e9 l\u2019\u00e9pouse \u00e0 faire le choix d\u2019un appartement, correspondent effectivement \u00e0 celles reprises dans le compromis de vente finalement sign\u00e9 par PERSONNE2.).<\/p>\n<p>Il s\u2019ensuit que le compromis de vente du 20 avril 2000 est nul et de nul effet.<\/p>\n<p>L\u2019analyse des autres moyens et arguments \u00e9chang\u00e9s par les parties s\u2019av\u00e8re superf\u00e9tatoire.<\/p>\n<p>Eu \u00e9gard \u00e0 l\u2019issue du litige, la demande PERSONNE1.) en allocation d\u2019une indemnit\u00e9 de proc\u00e9dure doit \u00eatre d\u00e9clar\u00e9e non fond\u00e9e.<\/p>\n<p>Il en est de m\u00eame de la demande de PERSONNE2.) et d\u2019PERSONNE3.), \u00e9tant donn\u00e9 qu\u2019ils n\u2019ont pas \u00e9tabli en quoi il serait in\u00e9quitable de laisser \u00e0 leur charge l\u2019enti\u00e8ret\u00e9 des frais non compris dans les d\u00e9pens.<\/p>\n<p>P a r c e s m o t i f s<\/p>\n<p>le tribunal d\u2019arrondissement de Diekirch, si\u00e9geant en mati\u00e8re civile, statuant contradictoirement, le juge de la mise en \u00e9tat ayant \u00e9t\u00e9 entendu en son rapport oral,<\/p>\n<p>vu l\u2019ordonnance de cl\u00f4ture de l\u2019instruction du 1 er d\u00e9cembre 2015,<\/p>\n<p>re\u00e7oit la demande en la pure forme,<\/p>\n<p>constate la nullit\u00e9 du compromis de vente du 20 avril 2000,<\/p>\n<p>dit la demande de PERSONNE1.) non fond\u00e9e,<\/p>\n<p>partant en d\u00e9boute,<\/p>\n<p>dit les demandes respectives sur base de l\u2019article 240 du nouveau Code de proc\u00e9dure civile non fond\u00e9es,<\/p>\n<p>partant, en d\u00e9boute,<\/p>\n<p>condamne PERSONNE1.) \u00e0 tous les frais et d\u00e9pens de l\u2019instance, avec distraction \u00e0 Ma\u00eetre AVOCAT4.), avocat \u00e0 la Cour, et \u00e0 Ma\u00eetre AVOCAT2.), avocat \u00e0 la Cour, qui affirment en avoir fait l\u2019avance.<\/p>\n<p>Ainsi lu en audience publique au Palais de Justice \u00e0 Diekirch, par Nous MAGISTRAT1.) , Pr\u00e9sident du Tribunal d\u2019Arrondissement, assist\u00e9 du greffier GREFFIER1.) .<\/p>\n<p>Le Greffier Le Pr\u00e9sident du Tribunal &#8212; GREFFIER1.)- &#8212; MAGISTRAT1.) &#8212;<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-diekirch\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-diekirch\/20240808-142457\/20171107-tad-17575-anonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement en mati\u00e8re Civile No. 2017TADCH01\/167 Num\u00e9ro 17575 du r\u00f4le Audience publique du mardi, sept novembre de ux mille dix -sept. Composition: MAGISTRAT1.), Pr\u00e9sident, MAGISTRAT2.), Premier Juge, MAGISTRAT3.), Juge, GREFFIER1.), Greffier. E n t r e : PERSONNE1.), commer\u00e7ant, demeurant \u00e0\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[],"kji_year":[52833],"kji_subject":[7724],"kji_keyword":[23584,8576,7636],"kji_language":[7733],"class_list":["post-810111","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_year-52833","kji_subject-civil","kji_keyword-arrondissement","kji_keyword-novembre","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 7 novembre 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 7 novembre 2017\" \/>\n<meta property=\"og:description\" content=\"TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement en mati\u00e8re Civile No. 2017TADCH01\/167 Num\u00e9ro 17575 du r\u00f4le Audience publique du mardi, sept novembre de ux mille dix -sept. Composition: MAGISTRAT1.), Pr\u00e9sident, MAGISTRAT2.), Premier Juge, MAGISTRAT3.), Juge, GREFFIER1.), Greffier. E n t r e : PERSONNE1.), commer\u00e7ant, demeurant \u00e0\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T18:44:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-7-novembre-2017\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-7-novembre-2017\\\/\",\"name\":\"Tribunal d'arrondissement, 7 novembre 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-01T18:44:10+00:00\",\"dateModified\":\"2026-05-01T18:44:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-7-novembre-2017\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-7-novembre-2017\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-7-novembre-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 7 novembre 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 7 novembre 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 7 novembre 2017","og_description":"TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement en mati\u00e8re Civile No. 2017TADCH01\/167 Num\u00e9ro 17575 du r\u00f4le Audience publique du mardi, sept novembre de ux mille dix -sept. Composition: MAGISTRAT1.), Pr\u00e9sident, MAGISTRAT2.), Premier Juge, MAGISTRAT3.), Juge, GREFFIER1.), Greffier. E n t r e : PERSONNE1.), commer\u00e7ant, demeurant \u00e0\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-01T18:44:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"13 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/","name":"Tribunal d'arrondissement, 7 novembre 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-01T18:44:10+00:00","dateModified":"2026-05-01T18:44:14+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-7-novembre-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 7 novembre 2017"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/810111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=810111"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=810111"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=810111"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=810111"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=810111"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=810111"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=810111"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=810111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}