{"id":818395,"date":"2026-05-02T20:41:26","date_gmt":"2026-05-02T18:41:26","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/"},"modified":"2026-05-02T20:41:30","modified_gmt":"2026-05-02T18:41:30","slug":"tribunal-darrondissement-4-avril-2017","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 4 avril 2017"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH<\/p>\n<p>Jugement civil n\u00b0 55\/2017 Num\u00e9ro 21638 du r\u00f4le<\/p>\n<p>Audience publique du mardi, quatre avril deux mille dix-sept.<\/p>\n<p>Composition:<\/p>\n<p>Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Juge, Conny SCHMIT, Juge,<\/p>\n<p>Alain GODART, Greffier.<\/p>\n<p>E n t r e :<\/p>\n<p>la soci\u00e9t\u00e9 anonyme SOC.1.) S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L-(\u2026), immatricul\u00e9e au Registre de Commerce et des Soci\u00e9t\u00e9s de Luxembourg sous le num\u00e9ro B(\u2026), repr\u00e9sent\u00e9e par son conseil d\u2019administration actuellement en fonctions ; partie appelante aux termes d\u2019un exploit de l\u2019huissier de justice Alex MERTZIG de Diekirch du 24 novembre 2016 ; comparant par Ma\u00eetre Daniel CRAVATTE, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch, assist\u00e9 de Ma\u00eetre Pierrot SCHILTZ, avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg ;<\/p>\n<p>e t : A.), sans \u00e9tat actuel connu, demeurant \u00e0 L-(\u2026) ; partie intim\u00e9e aux fins du pr\u00e9dit exploit MERT ZIG ; laissant d\u00e9faut .<\/p>\n<p>LE TRIBUNAL :<\/p>\n<p>Vu le jugement no. 1039\/16 rendu par le Tribunal de Paix de Diekirch en date du 8 ao\u00fbt 2016, dont le dispositif est con\u00e7u comme suit :<\/p>\n<p>\u00ab Par ces motifs :<\/p>\n<p>le tribunal de paix de Diekirch, si\u00e9geant en mati\u00e8re civile, statuant contradic toirement ;<\/p>\n<p>re\u00e7oit la demande en la forme ;<\/p>\n<p>la d\u00e9clare sans objet en ce qu\u2019elle tend \u00e0 la r\u00e9solution de la vente du 9 ao\u00fbt 2014 ;<\/p>\n<p>la d\u00e9clare non fond\u00e9e en ce qu\u2019elle porte sur une indemnit\u00e9 de rupture de ladite vente ;<\/p>\n<p>d\u00e9boute la s .a. SOC.1.) de sa demande en allocation d\u2019une indemnit\u00e9 de proc\u00e9dure ;<\/p>\n<p>condamne la s.a. SOC.1.) aux frais et d\u00e9pens de l\u2019instance. \u00bb<\/p>\n<p>Pour statuer ainsi le tribunal de paix a retenu que l\u2019usage de son droit de r\u00e9tractation sans frais du contrat de vente du 9 ao\u00fbt 2014 d\u2019une voiture automobile d\u2019occasion par A.), effectu\u00e9e au moyen d\u2019une lettre recommand\u00e9e datant du 14 ao\u00fbt 2014 adress\u00e9e \u00e0 la soci\u00e9t\u00e9 anonym e SOC.1.) S.A., \u00e9tait conforme \u00e0 l\u2019article 8 des conditions g\u00e9n\u00e9rales du contrat de vente pour en d\u00e9duire que, la r\u00e9siliation du contrat \u00e9tant intervenue, la demande tendant \u00e0 la r\u00e9solution judiciaire est devenue sans objet et que la demande tendant \u00e0 l\u2019octroi d\u2019une indemnit\u00e9 de rupture n\u2019est pas fond\u00e9e. Le premier juge a encore d\u00e9bout\u00e9 la demanderesse de sa demande en obtention d\u2019une indemnit\u00e9 de proc\u00e9dure.<\/p>\n<p>Par exploit de l\u2019huissier de justice Alex MERTZIG du 24 novembre 2016, la soci\u00e9t\u00e9 anonyme SOC.1.) S.A. a interjet\u00e9 appel contre le pr\u00e9dit jugement.<\/p>\n<p>L\u2019appel, introduit dans les formes et d\u00e9lais de la loi, est \u00e0 d\u00e9clarer recevable en la forme.<\/p>\n<p>La partie d\u00e9fenderesse n\u2019a pas constitu\u00e9 avocat \u00e0 la Cour. Par application de l\u2019article 79 alin\u00e9a 1 du Nouveau Code de Proc\u00e9dure Civile, il y a lieu de statuer par d\u00e9faut \u00e0 son \u00e9gard, l\u2019acte introductif de l\u2019instance d\u2019appel n\u2019ayant pas \u00e9t\u00e9 d\u00e9livr\u00e9 \u00e0 personne.<\/p>\n<p>La partie appelante expose que la r\u00e9tractation par lettre du 14 ao\u00fbt 2014 de la part de A.) n\u2019\u00e9tait pas valable, alors qu\u2019elle n\u2019\u00e9tait conforme ni \u00e0 la facult\u00e9 de r\u00e9tractation en faveur de l\u2019acheteur inscrite sur le contrat de vente lui-m\u00eame, ni aux stipulations de l\u2019article 8 des conditions g\u00e9n\u00e9rales annex\u00e9es au contrat, pr\u00e9voyant un droit de r\u00e9tractation conditionnel au b\u00e9n\u00e9fice de l\u2019acheteur.<\/p>\n<p>Il ressort de la lecture de la lettre du 14 ao\u00fbt 2014, envoy\u00e9e par lettre recommand\u00e9e par A.) \u00e0 la soci\u00e9t\u00e9 anonyme SOC.1.) S.A., que l\u2019intim\u00e9 invoquait \u00e0 l\u2019appui de \u00ab l\u2019annulation \u00ab de l\u2019achat de la voiture en cause, la clause inscrite sur le recto du contrat de vente, mentionnant le d\u00e9lai de 7 jours ouvrables et le fait qu\u2019il peut exercer son droit de r\u00e9tractation sans devoir payer des frais ou des p\u00e9nalit\u00e9s. Il ne fait aucune allusion \u00e0 une loi belge.<\/p>\n<p>Sur le formulaire pr\u00e9imprim\u00e9 du contrat litigieux se trouve imprim\u00e9, sur le recto, en impression grasse et tout pr\u00e8s de l\u2019endroit pr\u00e9vu pour la signature de l\u2019acheteur les mentions suivantes : \u00ab Pour le surplus, la vente est conclue aux conditions mentionn\u00e9es ci -apr\u00e8s que l\u2019Acheteur d\u00e9clare avoir lues et accept\u00e9es et dont il reconna\u00eet avoir re\u00e7u un exemplaire \u00bb et puis, en- dessous de la case destin\u00e9e \u00e0 recevoir la date du contrat et les signatures des parties, \u00ab Conditions d\u2019application sp\u00e9cifiques en cas de vente au consommateur en dehors de l\u2019entreprise du Vendeur et pour autant que la vente n\u2019ait pas lieu au comptant (article 86 \u00e0 88 de la Loi sur les pratiques du commerce du 14 juillet 1991). Dans les sept jours ouvrables \u00e0 dater du lendemain du jour de la signature du pr\u00e9sent contrat, le consommateur a le droit de renoncer sans frais \u00e0 son achat \u00e0 condition d\u2019en pr\u00e9venir le Vendeur par lettre recommand\u00e9e \u00e0 la poste \u00bb.<\/p>\n<p>M\u00eame s\u2019il est marqu\u00e9 dans le libell\u00e9 de cette facult\u00e9 de r\u00e9tractation accord\u00e9e \u00e0 l\u2019acheteur qu\u2019elle joue en cas de \u00ab vente en dehors de l\u2019entreprise du Vendeur \u00bb, cette stipulation n\u2019\u00e9tant pas pr\u00e9cis\u00e9e clairement et suffisamment pour mettre le consommateur en \u00e9tat de savoir s\u2019il se trouve dans cette situation ou non, surtout que la clause en sa faveur se trouve, en caract\u00e8res gras pr\u00e8s de l\u2019endroit o\u00f9 il signe, il y a lieu, conform\u00e9ment aux termes de l\u2019article 1602 du Code civil de l\u2019interpr\u00e9ter en faveur de l\u2019achet eur, et de d\u00e9cider que la clause s\u2019applique en l\u2019occurrence.<\/p>\n<p>Il y a par ailleurs lieu de relever dans ce contexte que sur base de l\u2019article L.221-3 du Code de la Consommation, le consommateur \u00ab a le droit de se r\u00e9tracter par \u00e9crit ou sur tout autre support durable, sans indication de motif et sans p\u00e9nalit\u00e9, dans un d\u00e9lai de quatorze jours calendrier. \u00bb<\/p>\n<p>En l\u2019esp\u00e8ce, A.) ayant par envoi recommand\u00e9 du 14 ao\u00fbt 2014, fait part \u00e0 la soci\u00e9t\u00e9 anonyme SOC.1.) S.A. de sa r\u00e9tractation du contrat conclu le 9 ao\u00fbt 2014, cette r\u00e9tractation a \u00e9t\u00e9 faite valablement, tant quant au d\u00e9lai que quant \u00e0 la forme, de sorte que le contrat litigieux a \u00e9t\u00e9 r\u00e9solu par la lettre recommand\u00e9e et depuis la date de cette lettre.<\/p>\n<p>C\u2019est d\u00e8s lors \u00e0 bon droit que le premier juge a d\u00e9bout\u00e9 la soci\u00e9t\u00e9 anonyme SOC.1.) S.A. tant de sa demande en r\u00e9solution judiciaire dudit contrat que de sa demande en indemnisation pour rupture abusive, de sorte qu\u2019il y a lieu, bien que pour des motifs diff\u00e9rents, de confirmer le jugement entrepris.<\/p>\n<p>P A R C E S M O T I F S ,<\/p>\n<p>le Tribunal d\u2019arrondissement de Diekirch, si\u00e9geant en mati\u00e8re civile et en instance d\u2019appel, statuant par d\u00e9faut \u00e0 l\u2019encontre de A.) ;<\/p>\n<p>re\u00e7oit l\u2019appel ;<\/p>\n<p>le dit non fond\u00e9 et en d\u00e9boute ;<\/p>\n<p>partant confirme le jugement entrepris ;<\/p>\n<p>condamne la soci\u00e9t\u00e9 anonyme SOC.1.) S.A. aux frais et d\u00e9pens de l\u2019instance d\u2019appel.<\/p>\n<p>Ainsi lu en audience publique au Palais de Justice \u00e0 Diekirch par Nous, Jean- Claude KUREK, Pr\u00e9sident du Tribunal d\u2019Arrondissement, assist\u00e9 du greffier Alain GODART.<\/p>\n<p>Le Greffier Le Pr\u00e9sident du Tribunal &#8212; Alain GODART &#8212; &#8212; Jean-Claude KUREK &#8212;<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-diekirch\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-diekirch\/20240808-142417\/20170404-tad-21638da-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement civil n\u00b0 55\/2017 Num\u00e9ro 21638 du r\u00f4le Audience publique du mardi, quatre avril deux mille dix-sept. Composition: Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Juge, Conny SCHMIT, Juge, Alain GODART, Greffier. E n t r e : la soci\u00e9t\u00e9 anonyme SOC.1.) S.A.,\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[],"kji_year":[52833],"kji_subject":[7724],"kji_keyword":[23584,8601,7636],"kji_language":[7733],"class_list":["post-818395","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_year-52833","kji_subject-civil","kji_keyword-arrondissement","kji_keyword-avril","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 4 avril 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 4 avril 2017\" \/>\n<meta property=\"og:description\" content=\"TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement civil n\u00b0 55\/2017 Num\u00e9ro 21638 du r\u00f4le Audience publique du mardi, quatre avril deux mille dix-sept. Composition: Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Juge, Conny SCHMIT, Juge, Alain GODART, Greffier. E n t r e : la soci\u00e9t\u00e9 anonyme SOC.1.) S.A.,\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T18:41:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-4-avril-2017\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-4-avril-2017\\\/\",\"name\":\"Tribunal d'arrondissement, 4 avril 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-02T18:41:26+00:00\",\"dateModified\":\"2026-05-02T18:41:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-4-avril-2017\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-4-avril-2017\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-4-avril-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 4 avril 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 4 avril 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 4 avril 2017","og_description":"TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement civil n\u00b0 55\/2017 Num\u00e9ro 21638 du r\u00f4le Audience publique du mardi, quatre avril deux mille dix-sept. Composition: Jean-Claude KUREK, Pr\u00e9sident, Lexie BREUSKIN, Juge, Conny SCHMIT, Juge, Alain GODART, Greffier. E n t r e : la soci\u00e9t\u00e9 anonyme SOC.1.) S.A.,\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-02T18:41:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"6 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/","name":"Tribunal d'arrondissement, 4 avril 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-02T18:41:26+00:00","dateModified":"2026-05-02T18:41:30+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-4-avril-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 4 avril 2017"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/818395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=818395"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=818395"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=818395"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=818395"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=818395"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=818395"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=818395"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=818395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}