{"id":819461,"date":"2026-05-02T23:49:26","date_gmt":"2026-05-02T21:49:26","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/"},"modified":"2026-05-02T23:49:29","modified_gmt":"2026-05-02T21:49:29","slug":"conseil-superieur-de-la-securite-sociale-20-mars-2017-2","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/","title":{"rendered":"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>GRAND-DUCHE DU LUXEMBOURG<\/p>\n<p>No. du reg.: FNS 2015\/0146 No.: 2017\/0118<\/p>\n<p>CONSEIL SUPERIEUR DE LA SECURITE SOCIALE<\/p>\n<p>Audience publique du vingt mars deux mille dix-sept<\/p>\n<p>Composition:<\/p>\n<p>M. Pierre Calmes, pr\u00e9sident de chambre \u00e0 la Cour d \u2019appel, pr\u00e9sident<\/p>\n<p>Mme Carine Flammang, conseiller \u00e0 la Cour d \u2019appel, assesseur- magistrat<\/p>\n<p>Mme Mich\u00e8le Raus, conseiller \u00e0 la Cour d \u2019appel, assesseur- magistrat<\/p>\n<p>Mme Iris Klaren, secr\u00e9taire<\/p>\n<p>ENTRE:<\/p>\n<p>X, n\u00e9 le [\u2026] , demeurant \u00e0 [\u2026] , appelant, comparant par Ma\u00eetre Arthur Schuster, avocat, Luxembourg, en remplacement de Ma\u00eetre Edmond Dauphin, avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg;<\/p>\n<p>ET:<\/p>\n<p>le Fonds national de solidarit\u00e9, \u00e9tabli \u00e0 Luxembourg, repr\u00e9sent\u00e9 par le pr\u00e9sident de son comit\u00e9-directeur actuellement en fonction, intim\u00e9, comparant par Ma\u00eetre Fran\u00e7ois Reinard, avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg.<\/p>\n<p>FNS 2015\/0146 -2-<\/p>\n<p>Par requ\u00eate d\u00e9pos\u00e9e au secr\u00e9tariat du Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale le 14 juillet 2015, X a relev\u00e9 appel d\u2019un jugement rendu par le Conseil arbitral de la s\u00e9curit\u00e9 sociale le 22 mai 2015, dans la cause pendante entre lui et le Fonds national de solidarit\u00e9, et dont le dispositif est con\u00e7u comme suit: Par ces motifs, le Conseil arbitral de la s\u00e9curit\u00e9 sociale, statuant contradictoirement et en premier ressort, quant \u00e0 la forme, d\u00e9clare le recours irrecevable en ce qu\u2019il est dirig\u00e9 contre la d\u00e9cision du Commissaire de Gouvernement \u00e0 l\u2019action sociale et recevable en ce qu\u2019il est dirig\u00e9 contre la d\u00e9cision du comit\u00e9-directeur du Fonds national de solidarit\u00e9 rendue le 29 ao\u00fbt 2014, rejette les offres de preuve formul\u00e9es par les deux parties, quant au fond: &#8212; d\u00e9clare le recours non fond\u00e9 en ce qu\u2019il tend \u00e0 voir annuler la d\u00e9cision entreprise, &#8212; pour le surplus, d\u00e9clare le recours non fond\u00e9 et en d\u00e9boute en ce qu\u2019 il tend \u00e0 voir r\u00e9former la d\u00e9cision entreprise.<\/p>\n<p>Les parties furent convoqu\u00e9es pour l\u2019audience publique du 29 avril 2016, puis pour celle du 6 mars 2017, \u00e0 laquelle le rapporteur d\u00e9sign\u00e9, Madame Carine Flammang, fit l\u2019expos\u00e9 de l\u2019affaire.<\/p>\n<p>Ma\u00eetre Arthur Schuster, pour l\u2019appelant, maintint les moyens et conclusions de la requ\u00eate d\u2019appel d\u00e9pos\u00e9e au si\u00e8ge du Conseil sup\u00e9rieur le 14 juillet 2015.<\/p>\n<p>Ma\u00eetre Fran\u00e7ois Reinard, pour l\u2019intim\u00e9, se rapporta \u00e0 prudence quant \u00e0 la recevabilit\u00e9 de l\u2019appel en la forme et conclut, quant au fond, \u00e0 la confirmation du jugement du Conseil arbitral du 22 mai 2015.<\/p>\n<p>Apr\u00e8s prise en d\u00e9lib\u00e9r\u00e9 de l\u2019affaire le Conseil sup\u00e9rieur rendit \u00e0 l\u2019audience publique de ce jour, \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9, l \u2019arr\u00eat qui suit:<\/p>\n<p>Sur base d\u2019une enqu\u00eate diligent\u00e9e le 31 juillet 2014, vers 9.45 heures, par le service de r\u00e9pression des fraudes aupr\u00e8s du Fonds national de solidarit\u00e9 (ci-apr\u00e8s FNS) en compagnie d\u2019agents de Police de A , \u00e0 l\u2019adresse d\u00e9clar\u00e9e de X &#8212; b\u00e9n\u00e9ficiaire de l\u2019allocation compl\u00e9mentaire -, le service de r\u00e9pression des fraudes a conclu \u00e0 l\u2019absence de r\u00e9sidence effective et sur base de ce constat, l\u2019int\u00e9ress\u00e9 a \u00e9t\u00e9 inform\u00e9 suivant courrier du FNS du 25 ao\u00fbt 2014, que le paiement de l\u2019allocation compl\u00e9mentaire serait arr\u00eat\u00e9 au 1 er septembre 2014 et qu\u2019une d\u00e9cision susceptible de recours lui serait envoy\u00e9e.<\/p>\n<p>Suivant courrier du 1 er septembre 2014, X a \u00e9t\u00e9 inform\u00e9 que par d\u00e9cision du 29 ao\u00fbt 2014, le comit\u00e9 directeur du FNS avait mis fin au versement de l\u2019allocation compl\u00e9mentaire au profit de l\u2019int\u00e9ress\u00e9 avec effet r\u00e9troactif au 1 er ao\u00fbt 2014, au motif qu\u2019 il ne justifiait pas d\u2019une r\u00e9sidence effective au Luxembourg.<\/p>\n<p>Par courrier du 16 septembre 2014, fait en r\u00e9ponse \u00e0 un courrier de X du 7 septembre 2014, le pr\u00e9sident du FNS a confirm\u00e9 que la d\u00e9cision du comit\u00e9 directeur restait maintenue.<\/p>\n<p>Saisi du recours dirig\u00e9 par X contre la d\u00e9cision du comit\u00e9 directeur, le Conseil arbitral de la s\u00e9curit\u00e9 sociale a, suivant jugement du 22 mai 2015, d\u00e9clar\u00e9 le recours recevable mais non fond\u00e9.<\/p>\n<p>Pour statuer ainsi, le premier juge a rejet\u00e9, comme n\u2019\u00e9tant pas fond\u00e9, le moyen de X tendant \u00e0 voir \u00e9carter des d\u00e9bats le rapport d\u2019 enqu\u00eate du service de r\u00e9pression les fraudes du 31 juillet<\/p>\n<p>FNS 2015\/0146 -3-<\/p>\n<p>2014, en l\u2019absence d\u2019une irr\u00e9gularit\u00e9 l\u2019 affectant, en soulignant que dans le cadre du litige dont il \u00e9tait saisi, il lui appartenait de tirer les cons\u00e9quences des constatations faites par les enqu\u00eateurs ayant servi de fondement \u00e0 la d\u00e9cision entreprise et d\u2019appr\u00e9cier leur force probante en tenant compte des moyens de d\u00e9fense.<\/p>\n<p>Au vu de l\u2019aspect non occup\u00e9 de fa\u00e7on continue et de la raret\u00e9 d\u2019objets personnels dans la chambre de X , et en l\u2019absence d\u2019\u00e9l\u00e9ments de preuve susceptibles d\u2019infirmer les constats et conclusions des enqu\u00eateurs, il a retenu que la condition de la r\u00e9sidence effective n\u2019 \u00e9tait, en l\u2019absence d\u2019explication de la part de l \u2019int\u00e9ress\u00e9 quant au d\u00e9faut d\u2019 effets personnels n\u00e9cessaires \u00e0 la vie de tous les jours, pas \u00e9tablie, la pr\u00e9sence de quelques d\u00e9chets d\u00e9pos\u00e9s dans un petit bac \u00e0 ordures, d\u2019 un lit pr\u00eat \u00e0 l\u2019 usage, non rang\u00e9, \u00e9tant insuffisant pour prouver l\u2019effectivit\u00e9 de la r\u00e9sidence.<\/p>\n<p>Il a finalement dit que ce constat n\u2019\u00e9tait pas mis en \u00e9chec par l\u2019attestation testimoniale &#8212; trop vague- vers\u00e9e en cause par X , ni par le bail et le paiement du loyer et des charges, ni par le relev\u00e9 des aides de l\u2019office social de la commune de A , ni par les d\u00e9clarations de composition du m\u00e9nage et de r\u00e9sidence.<\/p>\n<p>De ce jugement, appel a \u00e9t\u00e9 r\u00e9guli\u00e8rement relev\u00e9 par A suivant requ\u00eate d\u00e9pos\u00e9e le 14 juillet 2015 au secr\u00e9tariat du Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale.<\/p>\n<p>L\u2019appelant demande \u00e0 voir i) \u00ab annuler la d\u00e9cision non sign\u00e9e du 1 er septembre 2014 confirm\u00e9e par le comit\u00e9-directeur le 29 ao\u00fbt 2014 \u00bb et \u00ab la d\u00e9cision sur recours gracieux du 16 septembre 2014 \u00e9manant du pr\u00e9sident du FNS \u00bb, ii) dire que \u00ab le recours dirig\u00e9 contre la d\u00e9cision du Commissaire de Gouvernement \u00e0 l\u2019action sociale, pendant devant le Conseil arbitral, est irrecevable \u00bb dans le cadre du pr\u00e9sent recours.<\/p>\n<p>L\u2019appelant fait grief au premier juge d\u2019avoir retenu qu\u2019 il ne justifie pas d\u2019une r\u00e9sidence effective au Luxembourg au vu de l\u2019article 2, point 1, de la loi du 29 avril 1999, qui n\u2019exigerait qu\u2019un s\u00e9jour effectif et non interrompu au Grand- Duch\u00e9 de Luxembourg, sans exiger une condition de r\u00e9sidence effective \u00e0 une seule adresse. A supposer qu\u2019 il r\u00e9side chez sa m\u00e8re, fait contest\u00e9, la condition de r\u00e9sidence au Grand-Duch\u00e9 de Luxembourg serait donn\u00e9e dans son chef. Exiger d\u2019 une personne de r\u00e9sider effectivement et uniquement \u00e0 l\u2019adresse de son domicile d\u00e9clar\u00e9 constituerait une discrimination manifeste par rapport \u00e0 tout autre citoyen, plus fortun\u00e9, domicili\u00e9 au Luxembourg, prohib\u00e9e par la Constitution et par la Convention europ\u00e9enne des droits de l\u2019homme.<\/p>\n<p>X fait encore valoir qu\u2019il est la victime d\u2019un \u00ab d\u00e9ni de justice \u00bb, en ce que le premier juge n\u2019aurait pas pris position par rapport \u00e0 son argument consistant \u00e0 qualifier de violation de domicile et partant de frauduleuse, la visite effectu\u00e9e le 31 juillet 2014 par les enqu\u00eateurs, alors que de par la visite effectu\u00e9e il y aurait atteinte \u00e0 un droit garanti par la Constitution et par la Convention europ\u00e9enne des droits de l\u2019homme.<\/p>\n<p>Ce serait finalement \u00e0 tort que le premier juge a rejet\u00e9 l\u2019attestation testimoniale vers\u00e9e en cause.<\/p>\n<p>Tout en se rapportant \u00e0 prudence de justice quant \u00e0 la recevabilit\u00e9 de l \u2019appel, le FNS conclut \u00e0 voir confirmer la d\u00e9cision entreprise, en donnant \u00e0 consid\u00e9rer que la d\u00e9cision &#8212; pour la r\u00e9gularit\u00e9 de laquelle il se rapporte \u00e0 prudence de justice &#8212; a \u00e9t\u00e9 prise par le comit\u00e9 directeur sur<\/p>\n<p>FNS 2015\/0146 -4-<\/p>\n<p>base des constatations objectives faites par les enqu\u00eateurs qui ont agi dans le cadre des pouvoirs leur conf\u00e9r\u00e9s par le l\u00e9gislateur, le service de r\u00e9pression des fraudes proc\u00e9dant r\u00e9guli\u00e8rement \u00e0 des contr\u00f4les afin de v\u00e9rifier si les conditions r\u00e9gissant l\u2019octroi de l\u2019allocation compl\u00e9mentaire &#8212; dont notamment celle tenant \u00e0 la r\u00e9sidence effective &#8212; sont donn\u00e9es. Au vu du rapport d\u2019 enqu\u00eate du 31 juillet 2014, la condition de la r\u00e9sidence effective ne serait pas donn\u00e9e, les pi\u00e8ces vers\u00e9es en cause par l\u2019appelant n\u2019\u00e9tant en tout \u00e9tat de cause pas de nature \u00e0 \u00e9tablir que X aurait r\u00e9sid\u00e9 \u00e0 l\u2019adresse d\u00e9clar\u00e9e.<\/p>\n<p>Pour autant que de besoin, le FNS r\u00e9it\u00e8re l\u2019offre de preuve formul\u00e9e en premi\u00e8re instance.<\/p>\n<p>D\u2019embl\u00e9e il est \u00e0 noter que dans la mesure o\u00f9 le Conseil sup\u00e9rieur ne se trouve pas saisi d \u2019un recours contre une d\u00e9cision du Commissaire de Gouvernement \u00e0 l\u2019action sociale, le raisonnement fait \u00e0 ce titre par l\u2019appelant tombe \u00e0 faux, de sorte qu\u2019 il n\u2019y a pas lieu de s\u2019y attarder autrement.<\/p>\n<p>Quant au surplus, il est rappel\u00e9 qu\u2019 aux termes de l\u2019article 16, points 1, 2 et 3, de la loi du 30 juillet 1960 concernant la cr\u00e9ation d\u2019 un fonds national de solidarit\u00e9, \u00ab Le fonds est administr\u00e9 et g\u00e9r\u00e9 par un comit\u00e9 directeur comprenant un pr\u00e9sident et sept membres nomm\u00e9s par le Gouvernement\u2026 Le comit\u00e9 directeur repr\u00e9sente et g\u00e8re le fonds dans toutes les affaires qui n\u2019auront pas \u00e9t\u00e9 d\u00e9f\u00e9r\u00e9es \u00e0 un autre organe par la loi. Il lui appartient notamment de statuer au sujet des prestations l\u00e9gales et des demandes en restitution \u00bb.<\/p>\n<p>Aux termes de l\u2019article 33, de la loi du 29 avril 1999 portant cr\u00e9ation d\u2019 un droit \u00e0 un revenu minimum garanti, \u00ab Contre les d\u00e9cisions prises sur base du chapitre II par le service national d\u2019action sociale ou contre les d\u00e9cisions prises sur base des articles du chapitre III par le Fonds national de solidarit\u00e9, la personne concern\u00e9e dispose d\u2019 un recours devant le Conseil arbitral et devant le Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale \u00bb, \u00e9tant soulign\u00e9 que le chapitre III r\u00e9git l\u2019allocation compl\u00e9mentaire et notamment la r\u00e9vision et la suppression de la d\u00e9cision d\u2019attribution de cette allocation.<\/p>\n<p>Dans la mesure o\u00f9, dans le cadre d\u2019 un litige ayant trait \u00e0 la suppression de l\u2019allocation compl\u00e9mentaire, seules sont susceptibles d\u2019\u00eatre frapp\u00e9es d\u2019un recours, les d\u00e9cisions prises par le comit\u00e9 directeur du FNS, et o\u00f9 l\u2019unique d\u00e9cision figurant au dossier est celle du 29 ao\u00fbt 2014, notifi\u00e9e \u00e0 X suivant courrier d\u2019 information du 1 er septembre 2014, le recours de l\u2019appelant ne peut pas concerner \u00ab la d\u00e9cision non sign\u00e9e du 1 er septembre 2014 \u00bb, une telle d\u00e9cision n\u2019 existant pas, ni \u00ab la d\u00e9cision sur recours gracieux du 16 septembre 2014 \u00e9manant du pr\u00e9sident du FNS \u00bb, une telle d\u00e9cision n\u2019existant pas d\u2019avantage, mais concerne implicitement mais n\u00e9cessairement la d\u00e9cision du comit\u00e9 directeur du 29 ao\u00fbt 2014.<\/p>\n<p>Compte tenu des d\u00e9bats men\u00e9s, il y a d\u00e8s lors lieu de v\u00e9rifier si cette d\u00e9cision est r\u00e9guli\u00e8re au regard des dispositions l\u00e9gales r\u00e9gissant les d\u00e9cisions \u00e0 prendre par le comit\u00e9 directeur, \u00e9tant pr\u00e9cis\u00e9 qu\u2019aux termes de l\u2019article 39, de l\u2019arr\u00eat\u00e9 grand-ducal du 20 ao\u00fbt 1960 portant r\u00e8glement d\u2019administration publique pour l\u2019application de la loi du 30 juillet 1960 concernant la cr\u00e9ation d\u2019un fonds national de solidarit\u00e9 \u00ab Pour chaque s\u00e9ance du comit\u00e9 directeur le secr\u00e9taire dressera un proc\u00e8s -verbal des d\u00e9lib\u00e9rations et des d\u00e9cisions prises. Les proc\u00e8s- verbaux qui indiqueront la date des s\u00e9ances ainsi que les noms des membres pr\u00e9sents sont sign\u00e9s par le pr\u00e9sident et le secr\u00e9taire\u2026 \u00bb.<\/p>\n<p>FNS 2015\/0146 -5-<\/p>\n<p>Il se d\u00e9gage en l\u2019esp\u00e8ce du proc\u00e8s-verbal de la s\u00e9ance du comit\u00e9 directeur du 29 ao\u00fbt 2014, qu\u2019\u00e9taient pr\u00e9sents, le pr\u00e9sident du FNS et sept membres. Si la signature du pr\u00e9sident du FNS ainsi que celle de deux membres &#8212; sans autre pr\u00e9cision et notamment sans indication par rapport \u00e0 la qualit\u00e9 de secr\u00e9taire dans le chef de l\u2019un d\u2019eux &#8212; figurent sous le volet concernant l\u2019approbation g\u00e9n\u00e9rale des d\u00e9cisions pr\u00e9sidentielles provisoires, dont font partie 289 cas d\u2019annulation, force est de constater que le volet concernant la d\u00e9cision individuelle portant annulation de l\u2019allocation compl\u00e9mentaire dont b\u00e9n\u00e9ficiait X , avec l\u2019indication de ses coordonn\u00e9es et de sa matricule, n\u2019est rev\u00eatu d\u2019aucune signature.<\/p>\n<p>Or, ce sont les signatures requises par la loi qui authentifient la d\u00e9cision comme \u00e9tant celle qui a \u00e9t\u00e9 adopt\u00e9e au cours d\u2019 une s\u00e9ance \u00e0 la suite du vote par les personnes appel\u00e9es \u00e0 d\u00e9lib\u00e9rer sur une question de retrait de l\u2019allocation compl\u00e9mentaire. Dans la mesure o\u00f9 la d\u00e9cision individuelle portant retrait de l\u2019allocation compl\u00e9mentaire au profit de X n\u2019est pas sign\u00e9e, l\u2019\u00e9l\u00e9ment requis pour l\u2019authentifier fait d\u00e9faut, de sorte que la d\u00e9cision est d\u00e9pourvue d\u2019effet.<\/p>\n<p>Dans ces conditions et ind\u00e9pendamment de tout autre d\u00e9bat, l\u2019appel de X est \u00e0 dire fond\u00e9 et il y a lieu de retenir, par r\u00e9formation de la d\u00e9cision entreprise, que pour la p\u00e9riode concern\u00e9e par le pr\u00e9sent litige, l\u2019 int\u00e9ress\u00e9 continuait \u00e0 partir du 1 er ao\u00fbt 2014, de b\u00e9n\u00e9ficier de l\u2019allocation compl\u00e9mentaire.<\/p>\n<p>Par ces motifs,<\/p>\n<p>le Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale,<\/p>\n<p>statuant contradictoirement, sur le rapport oral de l\u2019assesseur-magistrat d\u00e9l\u00e9gu\u00e9,<\/p>\n<p>re\u00e7oit l\u2019appel en la forme,<\/p>\n<p>le dit fond\u00e9,<\/p>\n<p>partant, par r\u00e9formation de la d\u00e9cision entreprise,<\/p>\n<p>dit que pour la p\u00e9riode concern\u00e9e par le pr\u00e9sent litige, courant \u00e0 partir du 1 er ao\u00fbt 2014, l\u2019int\u00e9ress\u00e9 continuait de b\u00e9n\u00e9ficier de l\u2019allocation compl\u00e9mentaire,<\/p>\n<p>renvoie le dossier en pros\u00e9cution de cause devant le comit\u00e9 directeur du Fonds national de solidarit\u00e9.<\/p>\n<p>La lecture du pr\u00e9sent arr\u00eat a \u00e9t\u00e9 faite \u00e0 l\u2019audience publique du 20 mars 2017 par Monsieur le Pr\u00e9sident Pierre Calmes , en pr\u00e9sence de Madame Iris Klaren, secr\u00e9taire.<\/p>\n<p>Le Pr\u00e9sident, Le Secr\u00e9taire, sign\u00e9: Calmes sign\u00e9: Klaren<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/conseil-superieur-de-la-securite-sociale\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/conseil-superieur-de-la-securite-sociale\/20240806-135434\/20170320-fns20150146-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>GRAND-DUCHE DU LUXEMBOURG No. du reg.: FNS 2015\/0146 No.: 2017\/0118 CONSEIL SUPERIEUR DE LA SECURITE SOCIALE Audience publique du vingt mars deux mille dix-sept Composition: M. Pierre Calmes, pr\u00e9sident de chambre \u00e0 la Cour d \u2019appel, pr\u00e9sident Mme Carine Flammang, conseiller \u00e0 la Cour d\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[27902],"kji_chamber":[],"kji_year":[52833],"kji_subject":[7712],"kji_keyword":[17415,27907,22742,8417,27904],"kji_language":[7733],"class_list":["post-819461","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-conseil-superieur-de-la-securite-sociale","kji_year-52833","kji_subject-social","kji_keyword-conseil","kji_keyword-grand-duche","kji_keyword-securite","kji_keyword-sociale","kji_keyword-superieur","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017\" \/>\n<meta property=\"og:description\" content=\"GRAND-DUCHE DU LUXEMBOURG No. du reg.: FNS 2015\/0146 No.: 2017\/0118 CONSEIL SUPERIEUR DE LA SECURITE SOCIALE Audience publique du vingt mars deux mille dix-sept Composition: M. Pierre Calmes, pr\u00e9sident de chambre \u00e0 la Cour d \u2019appel, pr\u00e9sident Mme Carine Flammang, conseiller \u00e0 la Cour d\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T21:49:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\\\/\",\"name\":\"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-02T21:49:26+00:00\",\"dateModified\":\"2026-05-02T21:49:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/","og_locale":"ru_RU","og_type":"article","og_title":"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017","og_description":"GRAND-DUCHE DU LUXEMBOURG No. du reg.: FNS 2015\/0146 No.: 2017\/0118 CONSEIL SUPERIEUR DE LA SECURITE SOCIALE Audience publique du vingt mars deux mille dix-sept Composition: M. Pierre Calmes, pr\u00e9sident de chambre \u00e0 la Cour d \u2019appel, pr\u00e9sident Mme Carine Flammang, conseiller \u00e0 la Cour d\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-02T21:49:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"12 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/","name":"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-02T21:49:26+00:00","dateModified":"2026-05-02T21:49:29+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/conseil-superieur-de-la-securite-sociale-20-mars-2017-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Conseil sup\u00e9rieur de la s\u00e9curit\u00e9 sociale, 20 mars 2017"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/819461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=819461"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=819461"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=819461"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=819461"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=819461"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=819461"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=819461"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=819461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}