{"id":819903,"date":"2026-05-03T00:17:27","date_gmt":"2026-05-02T22:17:27","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/"},"modified":"2026-05-03T00:17:30","modified_gmt":"2026-05-02T22:17:30","slug":"cour-superieure-de-justice-15-fevrier-2017-4","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>1 Arr\u00eat N\u00b042\/17\u2013II-CIV. Arr\u00eat civil. Audience publique du quinze f\u00e9vrier deux mille dix-sept. Num\u00e9ro 41446 du registre. Composition: Christiane RECKINGER, pr\u00e9sidente de chambre; Gilbert HOFFMANN, premier conseiller; Karin GUILLAUME,premier conseiller, et Chris ANTONY, greffier assum\u00e9. E n t r e: la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)SARL,\u00e9tablie et ayant son si\u00e8ge social \u00e0 L-ADRESSE1.), repr\u00e9sent\u00e9e par son g\u00e9rant actuellement en fonctions, enregistr\u00e9e au registre de commerce et des soci\u00e9t\u00e9s de Luxembourg sous le num\u00e9roNUMERO1.), appelante aux termes d\u2019un exploit de l\u2019huissier de justice Frank SCHAAL de Luxembourg en date du 26 juin 2014, comparant par Ma\u00eetre David TRAVESSA MENDES, avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg, e t: 1.)PERSONNE1.),demeurant \u00e0 L-ADRESSE2.), 2.)PERSONNE2.), demeurant \u00e0 L-ADRESSE2.), intim\u00e9s aux fins du pr\u00e9dit exploit SCHAAL,<\/p>\n<p>2 comparant par Ma\u00eetre Luc MAJERUS, avocat \u00e0 la Cour, demeurant \u00e0 Esch-sur- Alzette, LA COUR D&#039;APPEL: Suivant acte notari\u00e9 de vente du 9 d\u00e9cembre 2010, la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)a vendu \u00e0PERSONNE1.)et \u00e0 son \u00e9pousePERSONNE2.) une maisond\u2019habitation sise \u00e0LIEU1.)pourle prix de 340.000 euros. Aux termes de l\u2019article 11 dudit acte, la soci\u00e9t\u00e9SOCIETE1.)s\u2019\u00e9tait engag\u00e9e \u00e0 effectuer dans les quatre mois de l\u2019acte de vente des travaux de r\u00e9novation de l\u2019immeuble pour un montant de 50.000 euros. Les travaux pr\u00e9cit\u00e9s n\u2019ayant pas \u00e9t\u00e9 r\u00e9alis\u00e9s au mois de novembre 2011, il a \u00e9t\u00e9 convenu entre parties que les acqu\u00e9reurs ex\u00e9cuteront eux-m\u00eames les travaux contre paiement par la venderesse de la somme de 19.000 euros. La soci\u00e9t\u00e9SOCIETE1.)n\u2019ayant r\u00e9gl\u00e9 aux \u00e9pouxPERSONNE1.)-PERSONNE2.) que le montant de 13.500 euros et ceux-ci ayant d\u00fb, en raison des travaux, reporter de dix mois leur emm\u00e9nagement dans la maison et continuer \u00e0 payer un loyer pendant cette p\u00e9riode, les \u00e9pouxPERSONNE1.)-PERSONNE2.)ont assign\u00e9 la soci\u00e9t\u00e9SOCIETE1.)en paiement de la somme de 16.200 euros (5.500 \u00e0 titre de solde des travaux et 10.700 \u00e0 titre de loyers). Par jugement du 7 mai 2014, le tribunal d\u2019arrondissement de Luxembourg a d\u00e9clar\u00e9 la demande fond\u00e9e pour la somme de 15.843,30 euros (5.500 + 10.343,30) que la soci\u00e9t\u00e9SOCIETE1.)a \u00e9t\u00e9 condamn\u00e9e \u00e0 payer aux \u00e9poux PERSONNE1.)-PERSONNE2.). La soci\u00e9t\u00e9SOCIETE1.)a r\u00e9guli\u00e8rement relev\u00e9 appel de ce jugement, signifi\u00e9 en date des 21 mai et 2 juin 2014, par exploit d\u2019huissier du 26 juin 2014. Elle ne conteste pas redevoir le montant de 5.500 euros au titre du solde du montant des travaux tel que retenu par les parties dans leur accord du mois de novembre 2011. Elle fait toutefois valoir que ledit accord est intervenu pour solde de tous comptes.Elle formule une offre de preuve en ce sens par l\u2019audition du mandataire des parties venderesses. A titre subsidiaire, elle se r\u00e9serve le droit de d\u00e9f\u00e9rer le serment litisd\u00e9cisoire aux parties intim\u00e9es sur les faits offerts en preuve. A titre encore plussubsidiaire, la soci\u00e9t\u00e9SOCIETE1.)conteste \u00eatre responsable du retard des travaux et elle conteste le lien de causalit\u00e9 entre le retard des travaux et le paiement des loyers jusqu\u2019au mois de janvier 2012 inclus. En effet, tout retard post\u00e9rieur \u00e0 l\u2019accord du mois de novembre 2011 serait imputable aux intim\u00e9s, puisqu\u2019ils \u00e9taient charg\u00e9s des travaux \u00e0 partir de cette date, de sorte que seuls les loyers redus entre le 9 avril 2011 (quatre mois apr\u00e8s l\u2019acte notari\u00e9) et le 20 novembre 2011 (date de la confirmation \u00e9crite de l\u2019accord entre parties) seraient \u00e0 mettre en compte. Par ailleurs, la soci\u00e9t\u00e9SOCIETE1.)conteste le montant du loyer tel que r\u00e9clam\u00e9, d\u00e8s lors qu\u2019aucun contrat de bail ne serait vers\u00e9 en cause et que les extraits bancaires ne renseigneraient que le paiement de ce chef d\u2019un montant de 6.284 euros.<\/p>\n<p>3 Les \u00e9pouxPERSONNE1.)-PERSONNE2.) contestent que l\u2019accord du 20 novembre 2011 soit intervenu pour solde de tous comptes. La somme de 19.000 euros correspondrait \u00e0 la valeur des travaux restant \u00e0 faire dans la maison. Les acomptes vers\u00e9s l\u2019auraient \u00e9t\u00e9 en ex\u00e9cution de cet accord qui n\u2019aurait aucun caract\u00e8re indemnitaire et forfaitaire et n\u2019exclurait pas l\u2019indemnisation d\u2019un pr\u00e9judice ult\u00e9rieur. L\u2019offre de preuve de la partie appelante serait irrecevable, d\u00e8s lors qu\u2019en tant qu\u2019ancien mandataire des appelants, Ma\u00eetre R\u00e9guia AMIALI, appel\u00e9e \u00e0 t\u00e9moigner, serait tenue au secret professionnel et d\u00e8s lors que la preuve par t\u00e9moins serait irrecevable au-del\u00e0 de la somme de 2.500 euros. La preuve par voie de serment litisd\u00e9cisoire serait \u00e9galement irrecevable en vertu des articles 1355 et suivants du code civil et elle serait d\u00e9pourvue de pertinence. C\u2019est, tout d\u2019abord, \u00e0 bon droit que les juges de premi\u00e8re instance ont d\u00e9clar\u00e9 la demande des \u00e9pouxPERSONNE1.)-PERSONNE2.)fond\u00e9e pour le montant non contest\u00e9 de 5.500 euros au titre du solde red\u00fb sur le montant des travaux tel que retenu par les parties dans leur accord du mois de novembre 2011. Concernant les dommages-int\u00e9r\u00eats r\u00e9clam\u00e9s par les intim\u00e9s du chef de loyers pay\u00e9s entre le mois d\u2019avril 2011 et le mois de janvier 2012, il est constant en cause que la soci\u00e9t\u00e9SOCIETE1.)n\u2019a pas r\u00e9alis\u00e9 tous les travaux de transformation dans le d\u00e9lai stipul\u00e9 \u00e0 l\u2019acte notari\u00e9 et que les parties ont convenu, au mois de novembre 2011, que les acqu\u00e9reurs ach\u00e8veraient eux-m\u00eames les travaux contre paiement par les vendeurs du montant de 19.000euros. La soci\u00e9t\u00e9SOCIETE1.)soutient que le pr\u00e9dit accord a \u00e9t\u00e9 conclu pour solde de tous comptes entre parties. L\u2019accord en question n\u2019a pas \u00e9t\u00e9 r\u00e9dig\u00e9 par \u00e9crit. Il en est fait \u00e9tat dans un courrier adress\u00e9 par le mandataire des intim\u00e9s \u00e0 la soci\u00e9t\u00e9SOCIETE1.)par lequel cette derni\u00e8re est invit\u00e9e \u00e0 r\u00e9gler pour le 14 novembre 2011 le premier acompte de 5.000 euros sur la somme de 19.000 euros \u00abpour la reprise des travaux de la maison de mon mandant\u00bb. Il ne d\u00e9coule pas de ce courrier que le montant de 19.000 euros avait un caract\u00e8re forfaitaire. La soci\u00e9t\u00e9SOCIETE1.)entend prouver la r\u00e9alit\u00e9 de ses pr\u00e9tentions par l\u2019audition d\u2019un t\u00e9moin. Aux termes de l\u2019article 1341 du code civil \u00abil doit \u00eatre pass\u00e9 acte devant notaires ou sous signatures priv\u00e9es de tous actes juridiques portant sur une somme ou valeur exc\u00e9dant celle qui est fix\u00e9e par r\u00e8glement grand-ducal\u00bb, soit le montant de 2.500.-euros (cf. r\u00e8glement grand-ducal du 22 d\u00e9cembre 1986, ensemble celui du 1 er ao\u00fbt 2001). Les \u00e9pouxPERSONNE1.)-PERSONNE2.)n\u2019ayant pas la qualit\u00e9 de commer\u00e7ants, la preuve \u00e0 leur encontre est soumise aux dispositions de l&#039;article 1341 du Code civil et la preuve par t\u00e9moins n\u2019est pas admissible.<\/p>\n<p>4 La soci\u00e9t\u00e9SOCIETE1.)s\u2019\u00e9tait encore r\u00e9serv\u00e9e le droit de d\u00e9f\u00e9rer aux intim\u00e9s le serment litisd\u00e9cisoire sur les faits offerts en preuve. Elle n\u2019a cependant pas formul\u00e9 d\u2019offre de preuve en ce sens. Il est constant en cause que la soci\u00e9t\u00e9SOCIETE1.),qui s\u2019\u00e9tait engag\u00e9e \u00e0 effectuer des travaux de r\u00e9novation dans la maison vendue dans les quatre mois de l\u2019acte notari\u00e9 de vente sign\u00e9 en date du 9 d\u00e9cembre 2010, c\u2019est-\u00e0-dire jusqu\u2019au 9 avril 2011, n\u2019a pas rempli ses obligations, d\u00e8s lors que les travaux n\u2019\u00e9taient pas encore achev\u00e9s au mois de novembre 2011. Il n\u2019est par ailleurs pas contest\u00e9 que les \u00e9pouxPERSONNE1.)-PERSONNE2.) n\u2019ont emm\u00e9nag\u00e9 dans leur nouvelle maison qu\u2019au mois de janvier 2012. M\u00eame s\u2019ils ont pris en charge eux-m\u00eames les travaux \u00e0 partir du mois de novembre 2011, force est de relever que ceux-ci avaient d\u00e9j\u00e0 pris \u00e0 cette date un retard de sept mois imputable \u00e0la partie appelante et qu\u2019ils n\u2019\u00e9taient pas achev\u00e9s. Il s\u2019ensuit que la soci\u00e9t\u00e9SOCIETE1.)est responsable du retard d\u2019ach\u00e8vement des travaux pour la totalit\u00e9 de la p\u00e9riode concern\u00e9e, de sorte que c\u2019est \u00e0 bon droit que la demande en dommages-int\u00e9r\u00eats a \u00e9t\u00e9 d\u00e9clar\u00e9e fond\u00e9e pour le montant de 10.343,30 euros correspondant aux loyers pay\u00e9s par lesintim\u00e9s entre le 10 avril 2011 et le mois de janvier 2012 pour la location d\u2019un appartement \u00e0LIEU2.), loyers dont le paiement est justifi\u00e9 par le contrat de bail et les virements vers\u00e9s en cause. Le jugement entrepris est partant \u00e0 confirmer dans toute sa teneur. La soci\u00e9t\u00e9SOCIETE1.)r\u00e9clame une indemnit\u00e9 de proc\u00e9dure de 1.000 euros pour la premi\u00e8re instance et de 2.000 euros pour l\u2019instance d\u2019appel. Le jugement entrepris est \u00e0 confirmer pour avoir d\u00e9bout\u00e9 la soci\u00e9t\u00e9SOCIETE1.), qui a succomb\u00e9, de sa demande en obtention d\u2019une indemnit\u00e9 de proc\u00e9dure en premi\u00e8re instance. Au vu du sort de l\u2019appel de la soci\u00e9t\u00e9SOCIETE1.), elle est de m\u00eame \u00e0 d\u00e9bouter de sa demande en octroi d\u2019une indemnit\u00e9 de proc\u00e9dure pour l\u2019instance d\u2019appel. En revanche, \u00e9tant donn\u00e9 qu\u2019il serait in\u00e9quitable de laisser \u00e0 la charge des \u00e9poux PERSONNE1.)-PERSONNE2.)la totalit\u00e9 des frais irr\u00e9p\u00e9tibles expos\u00e9s par eux pour leur d\u00e9fense en appel, il y a lieu de leur accorder une indemnit\u00e9 de proc\u00e9dure de 1.000 euros pour l\u2019instance d\u2019appel. P A R C E S M O T I F S la Cour d\u2019appel, deuxi\u00e8me chambre, si\u00e9geant en mati\u00e8re civile, statuant contradictoirement et sur le rapport dumagistrat de la mise en \u00e9tat, re\u00e7oit l\u2019appel en la forme; le dit non fond\u00e9; confirmele jugement entrepris;<\/p>\n<p>5 d\u00e9boutela soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)de sa demande en octroi d\u2019une indemnit\u00e9 de proc\u00e9dure; condamnela soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)\u00e0 payer \u00e0 PERSONNE1.)et \u00e0 son \u00e9pousePERSONNE2.)une indemnit\u00e9 de proc\u00e9dure de 1.000 euros; condamnela soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)\u00e0 tous les frais et d\u00e9pens de l\u2019instance d\u2019appel.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-2-civil\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-2-civil\/20250928-230043\/20170215-cach02-41446-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 Arr\u00eat N\u00b042\/17\u2013II-CIV. Arr\u00eat civil. Audience publique du quinze f\u00e9vrier deux mille dix-sept. Num\u00e9ro 41446 du registre. Composition: Christiane RECKINGER, pr\u00e9sidente de chambre; Gilbert HOFFMANN, premier conseiller; Karin GUILLAUME,premier conseiller, et Chris ANTONY, greffier assum\u00e9. E n t r e: la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)SARL,\u00e9tablie\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[15306],"kji_year":[52833],"kji_subject":[7724],"kji_keyword":[8457,9055,12307],"kji_language":[7733],"class_list":["post-819903","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-2-civil","kji_year-52833","kji_subject-civil","kji_keyword-fevrier","kji_keyword-justice","kji_keyword-superieure","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017\" \/>\n<meta property=\"og:description\" content=\"1 Arr\u00eat N\u00b042\/17\u2013II-CIV. Arr\u00eat civil. Audience publique du quinze f\u00e9vrier deux mille dix-sept. Num\u00e9ro 41446 du registre. Composition: Christiane RECKINGER, pr\u00e9sidente de chambre; Gilbert HOFFMANN, premier conseiller; Karin GUILLAUME,premier conseiller, et Chris ANTONY, greffier assum\u00e9. E n t r e: la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)SARL,\u00e9tablie\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T22:17:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-15-fevrier-2017-4\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-15-fevrier-2017-4\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-02T22:17:27+00:00\",\"dateModified\":\"2026-05-02T22:17:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-15-fevrier-2017-4\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-15-fevrier-2017-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-15-fevrier-2017-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/","og_locale":"ru_RU","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017","og_description":"1 Arr\u00eat N\u00b042\/17\u2013II-CIV. Arr\u00eat civil. Audience publique du quinze f\u00e9vrier deux mille dix-sept. Num\u00e9ro 41446 du registre. Composition: Christiane RECKINGER, pr\u00e9sidente de chambre; Gilbert HOFFMANN, premier conseiller; Karin GUILLAUME,premier conseiller, et Chris ANTONY, greffier assum\u00e9. E n t r e: la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE1.)SARL,\u00e9tablie\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-02T22:17:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"8 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/","name":"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-02T22:17:27+00:00","dateModified":"2026-05-02T22:17:30+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-15-fevrier-2017-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 15 f\u00e9vrier 2017"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/819903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=819903"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=819903"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=819903"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=819903"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=819903"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=819903"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=819903"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=819903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}