{"id":825204,"date":"2026-05-03T15:20:25","date_gmt":"2026-05-03T13:20:25","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/"},"modified":"2026-05-10T12:17:15","modified_gmt":"2026-05-10T10:17:15","slug":"acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/","title":{"rendered":"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\/21.5T8LSB.L1-4 \u2013 2023-05-03"},"content":{"rendered":"<div class=\"kji-decision\">\n<p class=\"kji-summary\">Relator: S?RGIO ALMEIDA. 1.\u2013Embora o sinistrado deva ter um perito que o represente na junta m\u00e9dica (art.\u00ba 139\/5, CPT), n\u00e3o resulta da lei que tenha de ser aquele que ele pr\u00f3prio indicaria, mesmo que j\u00e1 o tenha acompanhado anteriormente em junta que acabou por n\u00e3o ser conclusiva, por carecer de novos elementos. Para que seja esse concreto perito o examinando tem a possibilidade de o fazer comparecer.<\/p>\n<p>2.\u2013Tendo sido o exame singular efetuado por m\u00e9dico perito em medicina legal e sem carecer de parecer(es) da especialidade, a lei n\u00e3o imp\u00f5em que a junta seja composta por dois ortopedistas.<\/p>\n<p>3.\u2013Embora o juiz seja o perito dos peritos, n\u00e3o lhe cabe divergir do laudo dos mesmos sem que ponderosas raz\u00f5es o motivem.<\/p>\n<p>4.\u2013A fundamenta\u00e7\u00e3o do relat\u00f3rio da junta deve ser clara, podendo todavia ser sucinta. <\/p>\n<p>5.\u2013Se a seguradora n\u00e3o aceitou as incapacidades tempor\u00e1rias e realizada a junta m\u00e9dica a senten\u00e7a a condenou nessa parte, n\u00e3o pode dizer-se que a pretens\u00e3o do sinistrado tenha ficado totalmente vencida e que \u00e9 ele o respons\u00e1vel pelo pagamento de custas.<\/p>\n<p> (Elaborado pelo relator)<\/p>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/www.dgsi.pt\/jtrl.nsf\/33182fc732316039802565fa00497eec\/1c21b296936dbf00802589ac0050b6af?OpenDocument&#038;ExpandSection=1\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a><\/p>\n<p class=\"kji-license-note\"><em>Portails officiels portugais (DGSI \/ Tribunal Constitucional). Republication en metadata_only par prudence licencielle ; consulter la source officielle pour le texte authentique.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relator: S?RGIO ALMEIDA. 1.?Embora o sinistrado deva ter um perito que o represente na junta m?dica (art.? 139\/5, CPT), n?o resulta da lei que tenha de ser aquele que ele pr?prio indicaria, mesmo que j? o tenha acompanhado anteriormente em junta que acabou por n?o ser conclusiva, por carecer de novos elementos. Para que seja esse concreto perito o examinando tem a possibilidade de o fazer comparecer. 2.?Tendo sido o exame singular efetuado por m?dico perito em medicina legal e sem carecer de parecer(es) da especialidade, a lei n?o imp?em que a junta seja composta por dois ortopedistas. 3.?Embora o juiz seja o perito dos peritos, n?o lhe cabe divergir do laudo dos mesmos sem que ponderosas raz?es o motivem. 4.?A fundamenta??o do relat?rio da junta deve ser clara, podendo todavia ser sucinta. 5.?Se a seguradora n?o aceitou as incapacidades tempor?rias e realizada a junta m?dica a senten?a a condenou nessa parte, n?o pode dizer-se que a pretens?o do sinistrado tenha ficado totalmente vencida e que ? ele o respons?vel pelo pagamento de custas. (Elaborado pelo relator)<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[7762],"kji_court":[51416],"kji_chamber":[],"kji_year":[24566],"kji_subject":[7612],"kji_keyword":[63023,53496,35398,25424,63022],"kji_language":[7770],"class_list":["post-825204","kji_decision","type-kji_decision","status-publish","hentry","kji_country-portugal","kji_court-tribunal-da-relacao-de-lisboa","kji_year-24566","kji_subject-fiscal","kji_keyword-embora","kji_keyword-junta","kji_keyword-perito","kji_keyword-relator","kji_keyword-tenha","kji_language-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\/21.5T8LSB.L1-4 \u2013 2023-05-03 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\/21.5T8LSB.L1-4 \u2013 2023-05-03\" \/>\n<meta property=\"og:description\" content=\"Relator: S?RGIO ALMEIDA. 1.?Embora o sinistrado deva ter um perito que o represente na junta m?dica (art.? 139\/5, CPT), n?o resulta da lei que tenha de ser aquele que ele pr?prio indicaria, mesmo que j? o tenha acompanhado anteriormente em junta que acabou por n?o ser conclusiva, por carecer de novos elementos. Para que seja esse concreto perito o examinando tem a possibilidade de o fazer comparecer. 2.?Tendo sido o exame singular efetuado por m?dico perito em medicina legal e sem carecer de parecer(es) da especialidade, a lei n?o imp?em que a junta seja composta por dois ortopedistas. 3.?Embora o juiz seja o perito dos peritos, n?o lhe cabe divergir do laudo dos mesmos sem que ponderosas raz?es o motivem. 4.?A fundamenta??o do relat?rio da junta deve ser clara, podendo todavia ser sucinta. 5.?Se a seguradora n?o aceitou as incapacidades tempor?rias e realizada a junta m?dica a senten?a a condenou nessa parte, n?o pode dizer-se que a pretens?o do sinistrado tenha ficado totalmente vencida e que ? ele o respons?vel pelo pagamento de custas. (Elaborado pelo relator)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T10:17:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u043c\u0438\u043d\u0443\u0442\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\\\/\",\"name\":\"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\\\/21.5T8LSB.L1-4 \u2013 2023-05-03 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-03T13:20:25+00:00\",\"dateModified\":\"2026-05-10T10:17:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\\\/21.5T8LSB.L1-4 \u2013 2023-05-03\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\/21.5T8LSB.L1-4 \u2013 2023-05-03 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/","og_locale":"ru_RU","og_type":"article","og_title":"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\/21.5T8LSB.L1-4 \u2013 2023-05-03","og_description":"Relator: S?RGIO ALMEIDA. 1.?Embora o sinistrado deva ter um perito que o represente na junta m?dica (art.? 139\/5, CPT), n?o resulta da lei que tenha de ser aquele que ele pr?prio indicaria, mesmo que j? o tenha acompanhado anteriormente em junta que acabou por n?o ser conclusiva, por carecer de novos elementos. Para que seja esse concreto perito o examinando tem a possibilidade de o fazer comparecer. 2.?Tendo sido o exame singular efetuado por m?dico perito em medicina legal e sem carecer de parecer(es) da especialidade, a lei n?o imp?em que a junta seja composta por dois ortopedistas. 3.?Embora o juiz seja o perito dos peritos, n?o lhe cabe divergir do laudo dos mesmos sem que ponderosas raz?es o motivem. 4.?A fundamenta??o do relat?rio da junta deve ser clara, podendo todavia ser sucinta. 5.?Se a seguradora n?o aceitou as incapacidades tempor?rias e realizada a junta m?dica a senten?a a condenou nessa parte, n?o pode dizer-se que a pretens?o do sinistrado tenha ficado totalmente vencida e que ? ele o respons?vel pelo pagamento de custas. (Elaborado pelo relator)","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-10T10:17:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"1 \u043c\u0438\u043d\u0443\u0442\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/","name":"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\/21.5T8LSB.L1-4 \u2013 2023-05-03 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-03T13:20:25+00:00","dateModified":"2026-05-10T10:17:15+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/acordao-tribunal-da-relacao-de-lisboa-processo-7000-21-5t8lsb-l1-4-2023-05-03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Ac\u00f3rd\u00e3o Tribunal da Rela\u00e7\u00e3o de Lisboa \u2013 Processo 7000\/21.5T8LSB.L1-4 \u2013 2023-05-03"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/825204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=825204"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=825204"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=825204"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=825204"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=825204"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=825204"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=825204"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=825204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}