{"id":828053,"date":"2026-05-04T00:12:38","date_gmt":"2026-05-03T22:12:38","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/"},"modified":"2026-05-04T00:12:42","modified_gmt":"2026-05-03T22:12:42","slug":"tribunal-darrondissement-8-novembre-2016","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 8 novembre 2016"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>1<\/p>\n<p>Jugt no 2893\/2016 not. 7441\/15\/CD<\/p>\n<p>r\u00e9tabl. lieux<\/p>\n<p>AUDIENCE PUBLIQUE DU 8 NOVEMBRE 2016<\/p>\n<p>Le tribunal d&#039;arrondissement de et \u00e0 Luxembourg, seizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit :<\/p>\n<p>Dans la cause du minist\u00e8re public contre<\/p>\n<p>P1.), n\u00e9 le (\u2026) \u00e0 (\u2026), demeurant \u00e0 L- (\u2026), (\u2026),<\/p>\n<p>&#8212; p r \u00e9 v e n u &#8212; ______________________________<\/p>\n<p>F A I T S :<\/p>\n<p>Par citation du 19 septembre 2016 Monsieur le procureur d&#039;Etat pr\u00e8s le tribunal d&#039;arrondissement de et \u00e0 Luxembourg a cit\u00e9 le pr\u00e9venu \u00e0 compara\u00eetre \u00e0 l&#039;audience publique du 20 octobre 2016 devant le tribunal correctionnel de ce si\u00e8ge pour y entendre statuer sur les pr\u00e9ventions de :<\/p>\n<p>infractions aux articles 13 et 17 de la loi du 19 janvier 2004 concernant la protection de la nature et des ressources naturelles<\/p>\n<p>A cette audience Madame le vice- pr\u00e9sident constata l&#039;identit\u00e9 du pr\u00e9venu et lui donna connaissance des actes qui ont saisi le tribunal.<\/p>\n<p>Les t\u00e9moins T1.) et T2.) furent entendus s\u00e9par\u00e9ment en leurs d\u00e9clarations orales apr\u00e8s avoir pr\u00eat\u00e9 le serment pr\u00e9vu \u00e0 l\u2019article 155 du code d\u2019instruction criminelle.<\/p>\n<p>P1.) fut entendu en ses explications et moyens de d\u00e9fense.<\/p>\n<p>Le repr\u00e9sentant du minist\u00e8re public, Monsieur Claude HIRSCH , premier substitut du procureur d\u2019Etat, r\u00e9suma l\u2019affaire et fut entendu en son r\u00e9quisitoire.<\/p>\n<p>Le tribunal prit les affaire s en d\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l&#039;audience publique de ce jour, date \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9,<\/p>\n<p>L E J U G E M E N T Q U I S U I T :<\/p>\n<p>Vu le proc\u00e8s-verbal num\u00e9ro 54 15 SW du 20 janvier 2015 dress\u00e9 par l\u2019Administration de la nature et des for\u00eats, conservation de la nature &#8212; entit\u00e9 mobile.<\/p>\n<p>Vu la citation du 19 septembre 2016 (notice 7441\/15\/CD) r\u00e9guli\u00e8rement notifi\u00e9e au pr\u00e9venu.<\/p>\n<p>Le minist\u00e8re public reproche \u00e0 P1.), comme auteur, coauteur ou complice,<\/p>\n<p>1) au cours de l&#039;ann\u00e9e 2012, sinon durant l&#039;ann\u00e9e 2013, dans la commune de LIEU1.) , section (&#8230;), n\u00b0 NO.), au lieu-dit &quot;LIEUDIT1.)&quot;,<\/p>\n<p>principalement, en infraction \u00e0 l&#039;article 13 alin\u00e9a 1 de la loi du 19 janvier 2004 relative \u00e0 la protection de la nature et des ressources naturelles,<\/p>\n<p>apr\u00e8s avoir coup\u00e9 les arbres en 2009 ou 2010 , avoir arrach\u00e9 les racines de ces arbres et donc proc\u00e9d\u00e9 au d\u00e9frichement d&#039;un fonds forestier autrefois compos\u00e9 d&#039;arbres \u00e9pic\u00e9as afin de le transformer en terre arable, sans disposer de l&#039;autorisation minist\u00e9rielle pr\u00e9alable,<\/p>\n<p>subsidiairement, en infraction \u00e0 l&#039;article 17 alin\u00e9a 1 de la loi du 19 janvier 2004 relative \u00e0 la protection de la nature et des ressources naturelles,<\/p>\n<p>d&#039;avoir, sans disposer de l&#039;autorisation du ministre ayant dans ses attributions la protection de l&#039;environnement, d\u00e9truit un biotope compos\u00e9 de haies, arbustes et arbres en les coupant \u00e0 ras le sol et en enlevant les racines desdites plantations afin d&#039;\u00e9viter qu&#039;elles ne repoussent ;<\/p>\n<p>2) depuis l&#039;ann\u00e9e 2012, sinon l&#039;ann\u00e9e 2013, et jusqu&#039;\u00e0 la date de la pr\u00e9sente citation, dans la commune de LIEU1.) , section (&#8230;), n\u00b0 NO.), au lieu-dit &quot;LIEUDIT1.)&quot;,<\/p>\n<p>en infraction \u00e0 l&#039;article 13 alin\u00e9a 4 de la loi du 19 janvier 2004 relative \u00e0 la protection de la nature et des ressources naturelles,<\/p>\n<p>\u00e9tant propri\u00e9taire d&#039;un fonds forestier ayant subi une coupe rase au courant de l&#039;ann\u00e9e 2009, sinon de l&#039;ann\u00e9e 2010, n\u2019avoir proc\u00e9d\u00e9 qu\u2019\u00e0 la plantation de quelques arbres isol\u00e9s n\u2019\u00e9quivalant pas au fonds forestier initial du point de vue production et \u00e9cologie.<\/p>\n<p>Les faits<\/p>\n<p>Les faits tels qu\u2019ils r\u00e9sultent du dossier r\u00e9pressif et des d\u00e9bats \u00e0 l\u2019audience peuvent se r\u00e9sumer comme suit :<\/p>\n<p>Le 16 octobre 2014 Tom KINNEN, garde forestier du secteur de LIEU3.) a inform\u00e9 l\u2019administration de la nature et des for\u00eats que P1.) , propri\u00e9taire du terrain inscrit au cadastre de la commune de LIEU1.) , Section (&#8230;) sous le num\u00e9ro NO.), a proc\u00e9d\u00e9 \u00e0 un changement d\u2019affectation d\u2019un fonds forestier en terre labourable sans autorisation du Ministre de l\u2019Environnement.<\/p>\n<p>Le 17 juillet 2010 P1.) avait introduit une demande aupr\u00e8s du minist\u00e8re de l\u2019Environnement en vue d\u2019obtenir l\u2019autorisation pour transformer son terrain consid\u00e9r\u00e9 comme un bois, en une terre labourable. Il avait propos\u00e9 des mesures conservatoires consistant \u00e0 transformer diff\u00e9rentes parcelles dans la commune de LIEU2.) , consid\u00e9r\u00e9es comme terres labourables, en un verger.<\/p>\n<p>Suite \u00e0 deux avis n\u00e9gatifs, l\u2019un \u00e9tabli par le garde forestier du secteur de LIEU3.) en date du 3 novembre 2010, l\u2019autre \u00e9tabli par l\u2019administration de la nature et des for\u00eats en date du 4 janvier 2011, le Minist\u00e8re du d\u00e9veloppement durable et des infrastructures, d\u00e9partement de l\u2019environnement n\u2019a pas donn\u00e9 une suite favorable \u00e0 la demande de P1.).<\/p>\n<p>En date du 29 janvier 2015 T1.), chef de brigade principal de l\u2019administration de la nature et des for\u00eats a envoy\u00e9 un courrier \u00e0 P1.) pour l\u2019inviter \u00e0 se pr\u00e9senter pour audition en date du 10 f\u00e9vrier 2015. Ce dernier l\u2019a inform\u00e9 qu\u2019il ne pouvait pas se pr\u00e9senter \u00e0 la date propos\u00e9e et lui a fait parvenir sa prise de position \u00e9crite du 1 er f\u00e9vrier 2015.<\/p>\n<p>Dans ce courrier P1.) a d\u00e9clar\u00e9 \u00eatre d\u2019avis que le terrain inscrit sous le num\u00e9ro cadastral NO.) n\u2019\u00e9tait pas propice \u00e0 constituer un bois. Comme sa demande en changement d\u2019affectation avec des mesures compensatoires dans la commune de LIEU2.) lui a \u00e9t\u00e9 refus\u00e9e et qu\u2019il n\u2019a pas de terrain dans la commune de LIEU1.) pour proposer d\u2019autres mesures conservatoires, il a conclu qu\u2019il se voyait oblig\u00e9 de vendre cette parcelle.<\/p>\n<p>T2.), exploitant le terrain de P1.) en tant que terre labourable, a \u00e9t\u00e9 entendu le 8 mars 2016 et a d\u00e9clar\u00e9 que les sapins qui se trouvaient sur le terrain, ont tous \u00e9t\u00e9 coup\u00e9s en 2009 ou en 2010. Ce n\u2019est qu\u2019en 2012 ou 2013 qu\u2019il y a eu un fraisage du sol .<\/p>\n<p>A l\u2019audience du 20 octobre 2016, P1.) a reconnu les infractions lui reproch\u00e9es en d\u00e9clarant ne pas comprendre pourquoi sa demande en changement d\u2019affectation avec mesures compensatoires lui a \u00e9t\u00e9 refus\u00e9e.<\/p>\n<p>Le t\u00e9moin T2.) , entendu sous la foi du serment, a maintenu ses d\u00e9clarations faites le 8 mars 2016.<\/p>\n<p>Le t\u00e9moin T1.) a r\u00e9it\u00e9r\u00e9 les constatations act\u00e9es au proc\u00e8s-verbal n\u00b054 15 SW du 20 janvier 2015. Elle a pr\u00e9cis\u00e9 qu\u2019il n\u2019\u00e9tait pas interdit de couper des arbres, mais d\u2019en arracher les racines et de fraiser le sol, r\u00e9alisant de ce fait un changement d\u2019affectation du sol en question.<\/p>\n<p>En droit<\/p>\n<p>L\u2019article 13 de la loi du 19 janvier 2004 sanctionne le changement d\u2019affectation de fonds forestiers.<\/p>\n<p>Le tribunal constate que ni la loi du 19 janvier 2004 ni les travaux parlementaires aff\u00e9rents ne d\u00e9finissent la notion de fonds forestier.<\/p>\n<p>Le terme de fonds forestier est un homonyme pour le terme de for\u00eat. Le terme de for\u00eat est d\u00e9fini comme \u00ab une grande \u00e9tendue de terrain couverte d\u2019arbres ; ensemble des grands arbres qui occupent, qui couvrent cette \u00e9tendue \u00bb (LAROUSSE).<\/p>\n<p>En l\u2019esp\u00e8ce, il r\u00e9sulte des photos au dossier r\u00e9pressif prises en 2001, 2004 et 2007 que le terrain litigieux \u00e9tait recouvert de sapins, sapins ayant disparu sur la photo a\u00e9rienne du terrain prise en 2010. Sur la photo a\u00e9rienne du terrain prise en 2013 ne figurent toujours pas de nouveaux sapins.<\/p>\n<p>Il ressort encore du relev\u00e9 parcellaire du 24 octobre 2014 que le terrain appartenant \u00e0 P1.) et inscrit sous le num\u00e9ro cadastral NO.) , y est r\u00e9pertori\u00e9 en tant que bois.<\/p>\n<p>Le pr\u00e9venu ayant lui-m\u00eame fait une demande en vue d\u2019un changement d\u2019affectation d\u2019un bois en terre labourable en juillet 2010, il est \u00e9tabli que le terrain inscrit au cadastre de la commune<\/p>\n<p>de LIEU1.), section (\u2026), sous le num\u00e9ro cadastral NO.), constitue un fonds forestier au sens de l\u2019article 13 de la loi du 19 janvier 2004.<\/p>\n<p>Il est constant en cause que P1.) a arrach\u00e9 les sapins se trouvant sur son terrain et qu\u2019en 2012 ou 2013, il a proc\u00e9d\u00e9 au fraisage du sol.<\/p>\n<p>Par le fait d\u2019avoir arrach\u00e9 les racines des sapins et d\u2019avoir proc\u00e9d\u00e9 au fraisage du sol qui actuellement est exploit\u00e9 en tant que terre labourable, il y a eu changement d\u2019affectation de la for\u00eat en terre arable au sens de l\u2019article 13 alin\u00e9a 1 er de la loi du 19 janvier 2004. P1.) ne disposant pas de l\u2019autorisation minist\u00e9rielle requise, l\u2019infraction libell\u00e9e sub 1) principalement est \u00e9tablie dans son chef.<\/p>\n<p>En ce qui concerne l\u2019infraction sub 2), il est constant en cause que P1.) a proc\u00e9d\u00e9 \u00e0 une coupe rase de son terrain en 2009, 2010 en faisant couper tous les sapins s\u2019y trouvant. Au regard des dispositions de l\u2019article 13 alin\u00e9a 4 de la loi du 19 janvier 2004, il avait un d\u00e9lai de trois ans apr\u00e8s le d\u00e9but des travaux d\u2019abattage pour proc\u00e9der \u00e0 la reconstitution de peuplements forestiers \u00e9quivalents.<\/p>\n<p>P1.) \u00e9tant en aveu de ne pas avoir proc\u00e9d\u00e9 \u00e0 la reconstitution de peuplements forestiers \u00e9quivalents et au regard des photos annex\u00e9es au proc\u00e8s-verbal il est \u00e9galement \u00e0 retenir dans les liens de l\u2019infraction libell\u00e9e sub 2).<\/p>\n<p>P1.) est partant convaincu par les d\u00e9bats men\u00e9s \u00e0 l\u2019audience, ses aveux partiels et les d\u00e9clarations des t\u00e9moins, ensemble les \u00e9l\u00e9ments du dossier r\u00e9pressif :<\/p>\n<p>\u00ab comme auteur ayant commis les infractions ,<\/p>\n<p>1) au cours de l&#039;ann\u00e9e 2012, sinon durant l&#039;ann\u00e9e 2013, dans la commune de LIEU1.), section (&#8230;), n\u00b0 NO.), au lieu-dit &quot;LIEUDIT1.)&quot;,<\/p>\n<p>en infraction \u00e0 l&#039;article 13 alin\u00e9a 1 de la loi du 19 janvier 2004 relative \u00e0 la protection de la nature et des ressources naturelles,<\/p>\n<p>d&#039;avoir proc\u00e9d\u00e9 \u00e0 un changement d&#039;affectation de fonds forestiers, sans disposer de l&#039;autorisation du Ministre de l\u2019Environnement,<\/p>\n<p>en l&#039;esp\u00e8ce, apr\u00e8s avoir coup\u00e9 les arbres en 2009 ou 2010, avoir arrach\u00e9 les racines de ces arbres et donc proc\u00e9d\u00e9 au d\u00e9frichement d&#039;un fonds forestier autrefois compos\u00e9 d&#039;arbres \u00e9pic\u00e9as afin de le transformer en terre arable, sans disposer de l&#039;autorisation minist\u00e9rielle pr\u00e9alable,<\/p>\n<p>2) depuis l&#039;ann\u00e9e 2012, sinon l&#039;ann\u00e9e 2013, et jusqu&#039;\u00e0 la date de la pr\u00e9sente citation, dans la commune de LIEU1.) , section (&#8230;), n\u00b0 NO.), au lieu-dit &quot;LIEUDIT1.)&quot;,<\/p>\n<p>en infraction \u00e0 l&#039;article 13 alin\u00e9a 4 de la loi du 19 janvier 2004 relative \u00e0 la protection de la nature et des ressources naturelles,<\/p>\n<p>en sa qualit\u00e9 de propri\u00e9taire d&#039;un fonds forestier ayant subi une coupe rase, ne pas avoir pris dans le d\u00e9lai de trois ans apr\u00e8s le d\u00e9but des travaux d&#039;abattage les mesures n\u00e9cessaires \u00e0 la reconstitution de peuplements forestiers \u00e9quivalent, du point de vue production et \u00e9cologie, au peuplement exploit\u00e9,<\/p>\n<p>en l&#039;esp\u00e8ce, \u00e9tant propri\u00e9taire d&#039;un fonds forestier ayant subi une coupe rase au courant de l&#039;ann\u00e9e 2009, sinon de l&#039;ann\u00e9e 2010, n\u2019avoir proc\u00e9d\u00e9 qu\u2019\u00e0 la plantation de<\/p>\n<p>quelques arbres isol\u00e9s n\u2019\u00e9quivalant pas au fonds forestier initial du point de vue production et \u00e9cologie \u00bb.<\/p>\n<p>La peine<\/p>\n<p>Les infractions retenues sub 1) et 2) \u00e0 charge de P1.) se trouvent en concours r\u00e9el.<\/p>\n<p>En application de l\u2019article 60 du code p\u00e9nal il y a lieu de ne prononcer que la peine la plus forte qui peut \u00eatre \u00e9lev\u00e9e au double du maximum.<\/p>\n<p>L\u2019article 64 de la loi du 19 janvier 2004 sur la protection de la nature et des ressources naturelles pr\u00e9voit que toute infraction aux dispositions de l\u2019article 13 de la m\u00eame loi est punie d&#039;un emprisonnement de huit jours \u00e0 six mois et d&#039;une amende de 251 \u00e0 750.000 euros, ou d&#039;une de ces peines seulement.<\/p>\n<p>La gravit\u00e9 des infractions commises justifient la condamnation du pr\u00e9venu P1.) \u00e0 une amende de 1.000 \u20ac.<\/p>\n<p>Au vu du casier n\u00e9ant du pr\u00e9venu et des r\u00e9quisitions du minist\u00e8re public, il y a lieu d\u2019assortir l\u2019amende \u00e0 prononcer du sursis int\u00e9gral.<\/p>\n<p>En application de l\u2019article 65 (6) de la loi du 19 janvier 2004, le Tribunal doit ordonner, aux frais du contrevenant, le r\u00e9tablissement des lieux dans leur \u00e9tat ant\u00e9rieur.<\/p>\n<p>Il y a d\u00e8s lors lieu de condamner P1.) \u00e0 r\u00e9tablir le fonds forestier ayant exist\u00e9 sur le terrain inscrit au cadastre de la commune de LIEU1.) , section (&#8230;) , sous le n\u00b0 NO.), au lieu- dit \u00ab LIEUDIT1.) \u00bb.<\/p>\n<p>En l\u2019esp\u00e8ce, le Tribunal fixe \u00e0 9 mois le d\u00e9lai end\u00e9ans lequel P1.) doit, sous peine d\u2019une astreinte, proc\u00e9der au r\u00e9tablissement des lieux \u00e0 partir du jour o\u00f9 le pr\u00e9sent jugement sera coul\u00e9 en force de chose jug\u00e9e.<\/p>\n<p>P A R C E S M O T I F S :<\/p>\n<p>le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg, seizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant contradictoirement, P1.) entendu en ses explications et moyens de d\u00e9fense et le repr\u00e9sentant du m inist\u00e8re public entendu en ses r\u00e9quisitions,<\/p>\n<p>c o n d a m n e P1.) du chef des infractions retenues \u00e0 sa charge \u00e0 une amende de mille (1.000) \u20ac, ainsi qu&#039;aux frais de sa poursuite p\u00e9nale, liquid\u00e9s \u00e0 24,97 \u20ac ;<\/p>\n<p>f i x e la dur\u00e9e de la contrainte par corps en cas de non- paiement de l\u2019amende \u00e0 20 (vingt) jours ;<\/p>\n<p>d i t qu\u2019il sera sursis \u00e0 l\u2019ex\u00e9cution de l\u2019int\u00e9gralit\u00e9 de cette peine d\u2019amende ;<\/p>\n<p>a v e r t i t P1.) qu\u2019au cas o\u00f9, dans un d\u00e9lai de cinq ans \u00e0 dater du pr\u00e9sent jugement, il aura commis une nouvelle infraction ayant entra\u00een\u00e9 une condamnation \u00e0 une peine d\u2019emprisonnement ou \u00e0 une peine plus grave pour crime ou d\u00e9lit de droit commun, la peine d\u2019amende prononc\u00e9e ci-devant sera ex\u00e9cut\u00e9e sans confusion possible avec la nouvelle peine et que les peines de la r\u00e9cidive seront encourues dans les termes de l\u2019article 56 alin\u00e9a 2 du code p\u00e9nal ;<\/p>\n<p>o r d o n n e le r\u00e9tablissement des lieux en leur \u00e9tat ant\u00e9rieur du terrain inscrit au cadastre de la commune de LIEU1.) , Section (&#8230;) sous le num\u00e9ro NO.) au lieu-dit \u00ab LIEUDIT1.) \u00bb aux frais de P1.) ;<\/p>\n<p>d i t que ce r\u00e9tablissement des lieux doit se faire dans un d\u00e9lai de neuf (9) mois \u00e0 partir du jour o\u00f9 le pr\u00e9sent jugement sera coul\u00e9 en force de chose jug\u00e9e, sous peine d\u2019une astreinte de cinquante (50) \u20ac par jour de retard ;<\/p>\n<p>f i x e la dur\u00e9e maximale de l\u2019astreinte \u00e0 trois cents (300) jours.<\/p>\n<p>Par application des articles 14, 16, 27, 28, 29, 30, 60 et 66 du code p\u00e9nal, des articles 155, 179, 182, 184, 189, 190, 190- 1, 194, 195, 196, 626, 627, 628, 628- 1 du code d&#039;instruction criminelle, ainsi que des articles 13, 64 et 65 de la loi du 19 janvier 2004 concernant la protection de la nature et des ressources naturelles, dont mention a \u00e9t\u00e9 faite.<\/p>\n<p>Ainsi fait et jug\u00e9 par Fran\u00e7oise ROSEN, vice- pr\u00e9sident, Sandra ALVES et Jackie MAROLDT, juges, et prononc\u00e9 par le vice- pr\u00e9sident en audience publique au tribunal d\u2019arrondissement \u00e0 Luxembourg, en pr\u00e9sence de Jim POLFER, substitut du procureur d\u2019Etat, et de Nicola DEL BENE, greffier assum\u00e9, qui, \u00e0 l&#039;exception du repr\u00e9sentant du minist\u00e8re public, ont sign\u00e9 le pr\u00e9sent jugement.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-luxembourg-penal\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-luxembourg-penal\/20240828-012655\/20161108-talux16-2893a-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 Jugt no 2893\/2016 not. 7441\/15\/CD r\u00e9tabl. lieux AUDIENCE PUBLIQUE DU 8 NOVEMBRE 2016 Le tribunal d&#8217;arrondissement de et \u00e0 Luxembourg, seizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit : Dans la cause du minist\u00e8re public contre P1.), n\u00e9 le (\u2026)\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[25729],"kji_year":[61603],"kji_subject":[7632],"kji_keyword":[23584,8576,7636],"kji_language":[7733],"class_list":["post-828053","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_chamber-penal","kji_year-61603","kji_subject-penal","kji_keyword-arrondissement","kji_keyword-novembre","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 8 novembre 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 8 novembre 2016\" \/>\n<meta property=\"og:description\" content=\"1 Jugt no 2893\/2016 not. 7441\/15\/CD r\u00e9tabl. lieux AUDIENCE PUBLIQUE DU 8 NOVEMBRE 2016 Le tribunal d&#039;arrondissement de et \u00e0 Luxembourg, seizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit : Dans la cause du minist\u00e8re public contre P1.), n\u00e9 le (\u2026)\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-03T22:12:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-8-novembre-2016\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-8-novembre-2016\\\/\",\"name\":\"Tribunal d'arrondissement, 8 novembre 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-03T22:12:38+00:00\",\"dateModified\":\"2026-05-03T22:12:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-8-novembre-2016\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-8-novembre-2016\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-8-novembre-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 8 novembre 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 8 novembre 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 8 novembre 2016","og_description":"1 Jugt no 2893\/2016 not. 7441\/15\/CD r\u00e9tabl. lieux AUDIENCE PUBLIQUE DU 8 NOVEMBRE 2016 Le tribunal d'arrondissement de et \u00e0 Luxembourg, seizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit : Dans la cause du minist\u00e8re public contre P1.), n\u00e9 le (\u2026)\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-03T22:12:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"13 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/","name":"Tribunal d'arrondissement, 8 novembre 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-03T22:12:38+00:00","dateModified":"2026-05-03T22:12:42+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-8-novembre-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 8 novembre 2016"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/828053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=828053"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=828053"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=828053"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=828053"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=828053"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=828053"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=828053"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=828053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}