{"id":843792,"date":"2026-05-06T00:11:35","date_gmt":"2026-05-05T22:11:35","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/"},"modified":"2026-05-06T00:11:39","modified_gmt":"2026-05-05T22:11:39","slug":"tribunal-darrondissement-24-mai-2016","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 24 mai 2016"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement civil n\u00b085\/2016 Num\u00e9ro 15998 du r\u00f4le Audience publique du mardi,vingt-quatre maideux milleseize. Composition: Annette GANTREL, Pr\u00e9sidente, Charles KIMMEL, Premier Juge, Gilles PETRY, Juge des Tutelles, Alain GODART, Greffier. E n t r e : PERSONNE1.),demeurant \u00e0 L-ADRESSE1.), faisant le commerce sous la d\u00e9nomination SOCIETE1.),ayant son si\u00e8ge social \u00e0 L-ADRESSE1.)et exer\u00e7ant son activit\u00e9 de fait \u00e0 L- ADRESSE2.); appelantaux termes d\u2019un exploit de l\u2019huissier de justice Patrick KURDYBAN de Luxembourg du 30 avril 2010; intim\u00e9 sur appel incident, comparant parMa\u00eetre Dani\u00e8le WAGNER, avocat \u00e0 la Cour, demeurant \u00e0Diekirch, assist\u00e9e de Ma\u00eetre Fran\u00e7ois MOYSE, avocat \u00e0 la Cour, demeurant \u00e0Luxembourg; e t : PERSONNE2.), sans \u00e9tat connu, demeurant \u00e0 L-ADRESSE3.);<\/p>\n<p>2 intim\u00e9aux fins du pr\u00e9dit exploit KURDYBAN; appelant par appel incident, ayant initialementcomparuparMa\u00eetre Gilbert REUTER, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch,comparant actuellement parMa\u00eetre Edith REIFF, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch,assist\u00e9ede Ma\u00eetre Elisabeth MACHADO, avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg. LE TRIBUNAL: Vu l\u2019ordonnance de cl\u00f4ture de l\u2019instruction rendue en date du5mai 2015. Faits et r\u00e9troactes Par exploit d\u2019huissier du 22 juillet 2009,PERSONNE2.)a fait donner citation \u00e0 PERSONNE1.), faisant le commerce sous la d\u00e9nominationSOCIETE1.), \u00e0 compara\u00eetredevant le Tribunal de paix de Diekirch pour voir prononcer la nullit\u00e9 du contrat de vente conclu entre parties le 1 ier septembre 2008, portant sur un v\u00e9hicule d\u2019occasion de la marque BMW, mod\u00e8le 330D TOURING, sur base des articles 1110 et suivants, 1116 et1134 du Code civil. Le 22 mars 2010, le Tribunal de paix a rendu un jugement dont le dispositif est con\u00e7u comme suit: \u00abd\u00e9clarela demande fond\u00e9e sur base de l\u2019article 1110 du Code civil; partantprononcela nullit\u00e9 du contrat de vente conclu en date du 1 ier septembre 2008 entre parties et portant sur le v\u00e9hicule de marque BMW, mod\u00e8le 333D TOURING, n\u00b0 ch\u00e2ssis NUMERO1.); condamnele sieurPERSONNE1.)\u00e0 restituer le prix de vente de \u20ac 9.500.-au sieur PERSONNE2.), avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 partir du 13 mars 2009, date de la mise en demeure par courrier recommand\u00e9, jusqu\u2019\u00e0 solde et ordonneau sieurPERSONNE2.)de restituer le pr\u00e9dit v\u00e9hicule au sieurPERSONNE1.), faisant le commerce sous la d\u00e9nominationSOCIETE1.); condamnele sieurPERSONNE1.)\u00e0 une indemnit\u00e9 de proc\u00e9dure de \u20ac 350.-; lecondamneaux frais et d\u00e9pens de l\u2019instance\u00bb. Les faits gisant \u00e0 la base de la demande-tels qu\u2019ils ressortent du jugement du 22 mars 2010- sont les suivants:<\/p>\n<p>3 \u00ab(\u2026 \u2026)PERSONNE2.)fait valoir qu\u2019au moment d\u2019acheter le v\u00e9hicule d\u2019occasion BMW, mod\u00e8le 330D TOURING, pour un prix de vente de \u20ac 9.500.-, le compteur kilom\u00e9trique dudit v\u00e9hicule indiquait 143.500 km. Le contrat de vente stipule que le v\u00e9hicule se trouve dans un bon \u00e9tat g\u00e9n\u00e9ral. En date du 16 f\u00e9vrier 2009 le v\u00e9hicule est tomb\u00e9 en panne, suite \u00e0 une cassure du turbocompresseur. Le garage BMWSOCIETE2.)a constat\u00e9, apr\u00e8s inspection, que les caract\u00e9ristiques r\u00e9elles du v\u00e9hicule sont totalement diff\u00e9rentes desindications fournies par la partie venderesse au moment de la vente, alors que le nombre de kilom\u00e8tres parcourus par le v\u00e9hicule n\u2019est pas de 143.500 km, mais de 224.032 km, conform\u00e9ment \u00e0 la lecture de la carte \u00e9lectronique du v\u00e9hicule en question. De surcro\u00eet le kilom\u00e9trage affich\u00e9 par la carte \u00e9lectronique reste bloqu\u00e9, ce qui confirme que le compteur du v\u00e9hicule a fait l\u2019objet de manipulation(\u2026 \u2026)\u00bb. Pour d\u00e9cider comme il l\u2019a fait, le Tribunal de paix a retenu-en substance-qu\u2019\u00aben cas de vente d\u2019une voiture automobile d\u2019occasion le prix de vente est fix\u00e9 en fonction du kilom\u00e9trage parcouru et de l\u2019\u00e2ge du v\u00e9hicule et doit \u00eatre consid\u00e9r\u00e9 comme constituant pour l\u2019acheteur une qualit\u00e9 dont la consid\u00e9ration a \u00e9t\u00e9 la cause d\u00e9terminante du contrat. En effet, en mati\u00e8re de vente d\u2019un v\u00e9hicule d\u2019occasion le fait qu\u2019un v\u00e9hicule a parcouru 143.500 km ou 224.032 km constitue une forte diff\u00e9rence de kilom\u00e9trage, ayant une incidence non n\u00e9gligeable sur l\u2019usure des diff\u00e9rents organes du v\u00e9hicule. Ainsi, par exemple, la rupture du turbocompresseur est plus probable \u00e0 un kilom\u00e9trage \u00e9lev\u00e9, c\u2019est-\u00e0-dire \u00e0 plus de 200.000 km, qu\u2019\u00e0 un kilom\u00e9trage de 140.000 km. Par voie de cons\u00e9quence la demande est fond\u00e9e sur base de l\u2019article 1110 du Code civil(\u2026 \u2026)\u00bb. De ce jugement,PERSONNE1.)a r\u00e9guli\u00e8rement relev\u00e9 appel par exploit de l\u2019huissier de justice Patrick KURDYBAN du 30 avril 2010. PERSONNE1.)reproche au juge de paix d\u2019avoir annul\u00e9 le contrat de vente conclu entre parties apr\u00e8s avoir retenu que le kilom\u00e9trage parcouru par le v\u00e9hicule a constitu\u00e9 pourPERSONNE2.) une qualit\u00e9 substantielle d\u00e9cisive, alors qu\u2019en pr\u00e9sence d\u2019une voiture d\u2019occasion \u00e2g\u00e9e de huit ans, \u00abla qualit\u00e9 substantielle ne r\u00e9side plus n\u00e9cessairement dans le kilom\u00e9trage, mais plut\u00f4t dans l\u2019\u00e9tat g\u00e9n\u00e9ral de la voiture\u00bb; que \u00able kilom\u00e9trage devient-dans ce cas-une qualit\u00e9 accessoire du contrat\u00bb laquelle ne saurait \u00eatre d\u00e9terminante dans le processus d\u00e9cisionnel du vendeur potentiel; que, par ailleurs, la constatation faite par le juge de paix qu\u2019un nombre plus \u00e9lev\u00e9 de kilom\u00e8tres parcourus aurait eu une incidence non n\u00e9gligeable sur l\u2019usure des diff\u00e9rents \u00e9l\u00e9ments du v\u00e9hicule ne serait pas pertinente, alors qu\u2019en l\u2019occurrence la rupture du turbocompresseur serait \u00e0 attribuer non pas \u00e0 \u00abla diff\u00e9rence de kilom\u00e9trage\u00bb, mais \u00e0 l\u2019utilisation non ad\u00e9quate de la voiture parPERSONNE2.); que le crit\u00e8re d\u00e9cisif pour PERSONNE2.)de conclure la vente aurait consist\u00e9 en la r\u00e9duction du prix de vente \u00e0 concurrence de 2.500 \u20ac consentie parPERSONNE1.)suite\u00e0 la renonciation dePERSONNE2.) \u00e0 toute garantie. Dans un ordre d\u2019id\u00e9es subsidiaires-et au cas o\u00f9 le Tribunal de c\u00e9ans devrait confirmer le jugement entrepris-PERSONNE1.)estime qu\u2019il y a lieu de prendre en consid\u00e9ration les d\u00e9gradations survenues \u00e0la voiture en raison de son utilisation parPERSONNE2.)lors de la p\u00e9riode entre la conclusion du contrat, 1 ier septembre 2008, et la date du jugement \u00e0 intervenir suite \u00e0 l\u2019appel interjet\u00e9. SelonPERSONNE1.), il y aurait lieu de retrancher le montant de 3.000 \u20ac du prix de vente de 9.200 \u20ac.<\/p>\n<p>4 Le dispositif de l\u2019acte d\u2019appel se lit comme suit: \u00abrecevoir le pr\u00e9sent appel en la forme; quant au fond, dire l\u2019appel fond\u00e9 et justifi\u00e9; en cons\u00e9quence, voir r\u00e9former le jugement dont appel en ce qu\u2019il aprononc\u00e9 la nullit\u00e9 du contrat de vente conclu en date du 1 ier septembre 2008, a condamn\u00e9 le sieurPERSONNE1.)\u00e0 restituer le prix de vente de 9.500.-euros au sieurPERSONNE2.), avec les int\u00e9r\u00eats l\u00e9gaux, et a ordonn\u00e9 au sieurPERSONNE2.)de restituer ledit v\u00e9hicule au sieurPERSONNE1.), faisant le commerce sous la d\u00e9nominationSOCIETE1.); d\u00e9clarer au contraire le contrat de vente du 1 ier septembre 2008 parfaitement valable; subsidiairement, prendre en compte le temps de l\u2019utilisation de la voiture parl\u2019acheteur et de soustraire le montant de 3.000.-euros au prix de vente au moment de la restitution, soit le montant de 6.500.-euros; voir condamner la partie intim\u00e9ePERSONNE2.), \u00e0 tous les frais et d\u00e9pens des deux instances, au v\u0153u de l\u2019article 238du Nouveau Code de proc\u00e9dure civile; condamner l\u2019intim\u00e9e au paiement d\u2019une indemnit\u00e9 de proc\u00e9dure de 1.000 .-euros sur la base de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile dans la mesure o\u00f9 ce sont les agissements fautifs et pr\u00e9judiciables de cette derni\u00e8re qui ont oblig\u00e9 l\u2019appelante \u00e0 agir en justice afin d\u2019assurer la protection de ses int\u00e9r\u00eats\u00bb. PERSONNE2.)a relev\u00e9 appel incident, critiquant le juge de paix de n\u2019avoir pas d\u00e9clar\u00e9 fond\u00e9e l\u2019action sur base des dispositions de l\u2019article 1116 duCode civil, alors que-entre autres \u00e9l\u00e9ments-PERSONNE1.)\u00aben ayant d\u00e9lib\u00e9r\u00e9ment trafiqu\u00e9 le compteur kilom\u00e9trique du v\u00e9hicule et, en tout \u00e9tat de cause, en ayant consenti \u00e0 vendre le v\u00e9hicule litigieux dont le compteur kilom\u00e9trique \u00e9tait trafiqu\u00e9, ad\u00e9lib\u00e9r\u00e9ment eu la volont\u00e9 de tromper son acheteur\u00bb. Subsidiairement,PERSONNE2.)conclut \u00e0 la confirmation pure et simple du jugement entrepris. Il s\u2019oppose \u00e0 voir r\u00e9duire \u00e0 6.500 \u20ac le montant quePERSONNE1.)doit restituer. Il r\u00e9clame une indemnit\u00e9de proc\u00e9dure de 1.500 \u20ac sur base de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile et le montant de 2.000 \u20ac \u00e0 titre de dommages et int\u00e9r\u00eats pour proc\u00e9dure abusive et vexatoire. Revu le jugement civil n\u00b0 121\/2011, num\u00e9ro 15998 du r\u00f4le, rendu par le Tribunal d\u2019arrondissement de Diekirch le 8 novembre 2011. Aux termes du dispositif de ce jugement, le Tribunal a re\u00e7u les appels principal et incident, a dit l\u2019appel incident non fond\u00e9, en a d\u00e9bout\u00e9PERSONNE2.), a dit l\u2019appel principal fond\u00e9, a, par r\u00e9formation, dit le contrat de vente conclu entre parties en date du 1 ier septembre 2008 parfaitement valable, a dit non fond\u00e9es les demandes respectives des parties en allocation d\u2019une indemnit\u00e9 de proc\u00e9dure, a dit la demande dePERSONNE2.)en obtention de dommages et<\/p>\n<p>5 int\u00e9r\u00eats non fond\u00e9e, l\u2019en a d\u00e9bout\u00e9 et a condamn\u00e9PERSONNE2.)aux frais et d\u00e9pens des deux instances. Par arr\u00eat du 13 juin 2013 (arr\u00eat n\u00b0 47\/2013, num\u00e9ro 3207 du registre),la Cour de cassation a cass\u00e9 et annul\u00e9 le jugement rendu le 8 novembre 2011 sous le num\u00e9ro 15998 du r\u00f4le et a d\u00e9clar\u00e9 nuls et de nul effet ladite d\u00e9cision judiciaire et les actes qui s\u2019en sont suivis et a remis les parties dans l\u2019\u00e9tat o\u00f9 elles se sont trouv\u00e9es avant le jugement cass\u00e9 et pour \u00eatre fait droit, les a renvoy\u00e9es devant le Tribunal d\u2019arrondissement de Diekirch autrement compos\u00e9. DISCUSSION I)Quant \u00e0 l\u2019appel incident PERSONNE2.)estime avoir rapport\u00e9 la preuve incontestable de la mauvaise foi de PERSONNE1.)et des manouvres dolosives d\u00e9ploy\u00e9es par celui-ci pour le convaincre d\u2019acqu\u00e9rir une voiture affect\u00e9e d\u2019un vice portant sur une qualit\u00e9 essentielle. PERSONNE2.)ajoute que-comme la pr\u00e9sence de manipulations du compteur kilom\u00e9trique se trouve av\u00e9r\u00e9e-PERSONNE1.)est \u00e0 consid\u00e9rer \u00abcomme complice des agissements d\u2019un tiers, soit qu\u2019il en ait \u00e9t\u00e9 l\u2019instigateur, soit m\u00eame que, les ayant connus, il en ait sciemment profit\u00e9\u00bb. PERSONNE2.)soutient encore que \u00abm\u00eame si le Tribunal devait arriver \u00e0 la conclusion qu\u2019il n\u2019aurait pas rapport\u00e9 la preuve de la connaissance de l\u2019existence du vice parPERSONNE1.) et que celui-ci avait n\u00e9anmoins vendu le v\u00e9hicule en omettant d\u00e9lib\u00e9r\u00e9ment de l\u2019en informer\u00bb, il y aurait lieu \u00abde faire application de la jurisprudenceiniti\u00e9e par la Cour de cassation fran\u00e7aise ayant retenu, s\u2019agissant d\u2019un vendeur professionnel, que le vendeur professionnel est tenu d\u2019une obligation de renseignement \u00e0 l\u2019\u00e9gard de son client et qu\u2019il lui incombe de prouver qu\u2019il a ex\u00e9cut\u00e9 son obligation\u00bb. PERSONNE2.)conclut qu\u2019\u00aben omettant d\u2019informer son cocontractant de l\u2019existence de manipulations du compteur kilom\u00e9trique, sinon du nombre r\u00e9el de kilom\u00e8tres parcourus par le v\u00e9hicule,PERSONNE1.)n\u2019a pas respect\u00e9 son obligation de renseignement \u00e0 l\u2019\u00e9gard de son cocontractant\u00bb. Il est de principe que celui qui demande l\u2019annulation d\u2019un contrat pour dol doit prouver non seulement l\u2019existence de man\u0153uvres, c.\u00e0.d. de mensonges et r\u00e9ticences dolosives de son cocontractant, mais encore la mauvaise foi dece dernier ainsi que le caract\u00e8re d\u00e9terminant de l\u2019erreur provoqu\u00e9e par les man\u0153uvres dans la conclusion du contrat (cf:Cour,9 f\u00e9vrier 2000, Pas 31, p. 356). La jurisprudence luxembourgeoise admet le dol non seulement en cas de man\u0153uvres positives tendant \u00e0 induire le contractant en erreur, mais \u00e9galement au cas o\u00f9 des qualit\u00e9s essentielles pour permettre un consentement \u00e9clair\u00e9 sont tues de mani\u00e8re d\u00e9lib\u00e9r\u00e9e: il s\u2019agit alors d\u2019un dol par r\u00e9ticence. L\u2019intention requise n\u2019est pas celle de causer un pr\u00e9judice, mais celle de tromper, en suscitant l\u2019erreur ou en profitant de celle-ci. Il faut par ailleurs que l\u2019erreur provoqu\u00e9e par les man\u0153uvres dolosives ait \u00e9t\u00e9 d\u00e9terminante pour le cocontractant, mais il n\u2019est pas n\u00e9cessaire qu\u2019elle ait port\u00e9 sur la substance de la chose. Le dol peut \u00eatre sanctionn\u00e9 alors m\u00eame qu\u2019il n\u2019a entra\u00een\u00e9 qu\u2019une erreur sur la valeur ou sur les motifs, voire une qualit\u00e9 non substantielle. La<\/p>\n<p>6 r\u00e9ticence dolosive appara\u00eet comme l\u2019inex\u00e9cution intentionnelle de l\u2019obligation d\u2019information. Elle rend toujours excusable l\u2019erreur provoqu\u00e9e (cf: La Responsabilit\u00e9 Civile, par Georges. Ravarani, 3 e \u00e9dition, n\u00b0 485; Arr\u00eat civil du 27 janvier 2016, n\u00b0 41956 du r\u00f4le). En l\u2019occurrence,PERSONNE2.)reste en d\u00e9faut d\u2019\u00e9tablir dans le chef dePERSONNE1.)-qui a achet\u00e9 la voiture litigieuse le 23 ao\u00fbt 2008 aupr\u00e8s deSOCIETE3.)en Allemagne,affichant\u00e0 ce moment un kilom\u00e9trage de 143.787\u2013qu\u2019ila \u00e9t\u00e9 complice d\u2019un tiers, \u00e0 supposer que des man\u0153uvres dolosives aient \u00e9man\u00e9 de ce tiers, ouqu\u2019ila \u00e9t\u00e9 lui-m\u00eame \u00e0 l\u2019origine de man\u0153uvres frauduleuses qui auraient provoqu\u00e9 un vice de consentement dans le chef dePERSONNE2.)de nature \u00e0 justifier l\u2019annulation de la vente dont s\u2019agit. Aucune r\u00e9ticence dolosive n\u2019\u00e9tant \u00e9tablie dans le chef dePERSONNE1.), il ne saurait \u00eatre question d\u2019une inex\u00e9cution intentionnelle de l\u2019obligation de renseignement \u00e0 sa charge. L\u2019appel incident relev\u00e9 parPERSONNE2.)est partant \u00e0 d\u00e9clarer non fond\u00e9. II)Quant \u00e0 l\u2019appel principal PERSONNE1.)reproche au juge de paixd\u2019avoir retenu que \u00able kilom\u00e9trage parcouru aurait pr\u00e9sent\u00e9 pourPERSONNE2.)une qualit\u00e9 substantielle d\u00e9cisive pour l\u2019amener \u00e0 contracter la vente\u00bb. PERSONNE1.)soutientquePERSONNE2.)\u00abresterait en d\u00e9faut de prouver que s\u2019il avait connu lekilom\u00e9trage r\u00e9el du v\u00e9hicule au moment de la vente cela l\u2019aurait emp\u00each\u00e9 de contracter\u00bb; que, de toute fa\u00e7on,PERSONNE2.)\u00abaurait d\u00fb se renseigner sur l\u2019\u00e9tat g\u00e9n\u00e9ral du v\u00e9hicule qu\u2019il se proposait d\u2019acqu\u00e9rir alors qu\u2019il est lui-m\u00eame revendeur de v\u00e9hicules automobiles\u00bb; que, n\u2019ayant pas suffi \u00e0 l\u2019obligation de se renseigner \u00e0 son tour, son erreur, \u00e0 supposer que erreur il y aiteu dans son chef, serait \u00e0 consid\u00e9rer comme \u00e9tant inexcusable. Aux termes de l\u2019article 1110 du Code civil \u00abl&#039;erreur ne peut\u00eatre une cause de nullit\u00e9 que si elle a pour objet la substance de la chose\u00bb. L\u2019erreur est d\u00e9finie comme une repr\u00e9sentation inexacte de la r\u00e9alit\u00e9 contractuelle. L\u2019erreur n\u2019est une cause de nullit\u00e9 que si elle a port\u00e9 sur la substance-m\u00eame de la chose qui en est l\u2019objet. L\u2019erreur sur les qualit\u00e9s substantielles est traditionnellement d\u00e9finie comme la croyance erron\u00e9e en une qualit\u00e9 de l\u2019objet du contrat, qualit\u00e9 en fait inexistante. L\u2019erreur sur une qualit\u00e9 substantielle r\u00e9side dans l\u2019absence d\u2019une qualit\u00e9 attendue ou promise. L\u2019erreur sur la substance est normalement appr\u00e9ci\u00e9e in concreto, c&#039;est-\u00e0-dire par rapport \u00e0 la psychologie de la victime de l\u2019erreur, mais il est encore admis que le fait que la qualit\u00e9 d\u00e9faillante est habituellement substantielle inabstracto, c\u2019est que dans l\u2019opinion publique commune elle est consid\u00e9r\u00e9e comme substantielle, peut constituer un indice faisant pr\u00e9sumer qu\u2019elle a aussi \u00e9t\u00e9 substantielle pour l\u2019errans (cf: Cour d\u2019appel 27 janvier 1999, num\u00e9ro du r\u00f4le 21159). La charge de la preuve de l\u2019erreur p\u00e8se naturellement sur l&#039;errans, demandeur en nullit\u00e9. L\u2019erreur est un fait juridique qui peut \u00eatre \u00e9tabli par tous moyens. Quant \u00e0 l\u2019objet de la preuve, celui-ci est double, voire triple. Le demandeur doit tout d&#039;abord d\u00e9montrer la r\u00e9alit\u00e9 de son erreur. Cette premi\u00e8re d\u00e9monstration est elle-m\u00eame double puisqu&#039;elle oblige \u00e0 \u00e9tablir, d&#039;une part, que le consentement a \u00e9t\u00e9 donn\u00e9 dans une certaine croyance et, d&#039;autre part, que cette<\/p>\n<p>7 croyance \u00e9tait contraire \u00e0 la r\u00e9alit\u00e9. Lavictime de l&#039;erreur doit ensuite prouver que celle-ci avait un objet tel que la nullit\u00e9 soit encourue. Sp\u00e9cialement, il lui appartient d&#039;\u00e9tablir que la m\u00e9prise a port\u00e9 sur une qualit\u00e9 substantielle de la chose. Le demandeur doit enfin \u00e9tablir que son erreur a eu un caract\u00e8re d\u00e9terminant. Ce troisi\u00e8me \u00e9l\u00e9ment se confond le plus souvent avec le pr\u00e9c\u00e9dent (cf:Jurisclasseur, Code civil, Art. 1110,n\u00b080, 81 et 82). En mati\u00e8re de vente de v\u00e9hicules automobiles, il est de jurisprudence constante que le kilom\u00e9trage fait partie des qualit\u00e9s substantielles (cf: Jurisclasseur, Code civil, Art. 1110, n\u00b013). Ainsi, la jurisprudence fran\u00e7aise retient que la vente peut \u00eatre annul\u00e9e pour vice de consentement lorsque le compteur indiquait lors de la vente un kilom\u00e9trage inf\u00e9rieur d\u2019un tiers environ \u00e0 celui r\u00e9ellement parcouru, m\u00eame si le prix pay\u00e9 correspondait \u00e0 la valeur du v\u00e9hicule (cf:CA Bordeaux, 25mars 1985: Juris-Data n\u00b01985-040774) ou encore que la vente d&#039;un v\u00e9hicule automobile d&#039;occasion affichant un kilom\u00e9trage consid\u00e9rablement inf\u00e9rieur au kilom\u00e9trage r\u00e9el suffit \u00e0 d\u00e9montrer l&#039;erreur sur la substance dans la mesure o\u00f9 le consentement de l&#039;acqu\u00e9reur a \u00e9t\u00e9 d\u00e9termin\u00e9 par l&#039;id\u00e9e fausse qu&#039;il avait du kilom\u00e9trage minor\u00e9 dans une tr\u00e8s large proportion, en l\u2019esp\u00e8ce d\u2019environ 70.000 kilom\u00e8tres(cf:CA Douai, 17mai 2004: Juris- Data n\u00b02004-250136). La Cour d\u2019appel luxembourgeoise retient pareillement que \u00abpeu importe la marque et le mod\u00e8le de voiture, une divergence d\u2019une certaine importance entre le kilom\u00e9trage affich\u00e9 au moment de la conclusion du contrat et le kilom\u00e9trage r\u00e9el-divergence qui est n\u00e9cessairement le fruit d\u2019un traficage de nature \u00e0 faire perdre au client toute confiance dans la voiture- emp\u00eache normalement un client, s\u2019il en a eu connaissance, de contracter\u00bb (cf: Jugement civil TAL du 1 ier avril 2014, n\u00b0 76\/2014, 8 i\u00e8me chambre, n\u00b0 151.688 du r\u00f4le). En l\u2019occurrence, la diff\u00e9rence de kilom\u00e9trage \u00e0 raison de (224.032-143.500) = 80.532 kilom\u00e8tres constitue une qualit\u00e9 substantielle qui \u00e9tait d\u00e9terminante pourPERSONNE2.)lors de la conclusion du contrat de vente litigieux, \u00e9tant pr\u00e9cis\u00e9 qu\u2019il n\u2019est \u00e9tabli par aucun \u00e9l\u00e9ment du dossier qu\u2019\u00e0 ce momentPERSONNE2.)a rev\u00eatu la qualit\u00e9 de professionnel qui aurait, le cas \u00e9ch\u00e9ant,exig\u00e9 un examen plus approfondide la voiture,PERSONNE2.)-contrairement aux all\u00e9gations dePERSONNE1.)-n\u2019a, \u00e0 aucun stade de la proc\u00e9dure, fait lui-m\u00eame une d\u00e9claration par laquelle il aurait reconnu pour vraiela qualit\u00e9 de professionneldans son chef, de nature \u00e0 produire contre lui des cons\u00e9quences juridiques. La diff\u00e9rence de kilom\u00e9trage justifie donc l\u2019annulation de lavente. L\u2019appel principal est partant \u00e0 d\u00e9clarer non fond\u00e9. Quant \u00e0 la r\u00e9duction du montant de la condamnation PERSONNE1.)conclut, dans un ordre d\u2019id\u00e9es subsidiaires et au cas o\u00f9 l\u2019annulation de la vente serait prononc\u00e9e, \u00e0 voir \u00abprendre en consid\u00e9ration le temps \u00e9chu entre la conclusion du contrat le 1 ier septembre 2011 et la date du jugement \u00e0 intervenir\u00bb, \u00e0 voir \u00abcompenser l\u2019utilisation de la voiture par l\u2019acqu\u00e9reur pendant ladite p\u00e9riode\u00bb, ce d\u2019autant plus quePERSONNE1.), suite \u00e0 l\u2019usage inappropri\u00e9 de la part dePERSONNE2.), ne r\u00e9cup\u00e9rerait qu\u2019un \u00abv\u00e9hicule fortement d\u00e9grad\u00e9 par la faute de l\u2019acqu\u00e9reur et n\u00e9cessitant maintes r\u00e9parations\u00bb.<\/p>\n<p>8 PERSONNE2.)s\u2019oppose \u00e0 toute r\u00e9duction. Il est de principe que la nullit\u00e9 a un effet r\u00e9troactif,c\u2019est-\u00e0-dire qu\u2019il faut, en principe, faire dispara\u00eetre toute trace de l\u2019acte annul\u00e9, ou, si l\u2019on pr\u00e9f\u00e8re remettre les parties dans l\u2019\u00e9tat o\u00f9 elles \u00e9taient avant l\u2019acte. La nullit\u00e9 entra\u00eene restitution des prestations d\u00e9j\u00e0 re\u00e7ues par le biais d\u2019une actionsemblable \u00e0 l\u2019action en r\u00e9p\u00e9tition de l\u2019indu. En effet, en effa\u00e7ant le contrat en vertu duquel ces prestations ont \u00e9t\u00e9 accomplies, on leur enl\u00e8ve leur cause. Tout se passe donc comme si le paiement avait \u00e9t\u00e9 fait sans aucune obligation. De droit commun, larestitution doit \u00eatre int\u00e9grale: tout ce qui a \u00e9t\u00e9 re\u00e7u en ex\u00e9cution du contrat doit \u00eatre restitu\u00e9. En mati\u00e8re de vente, le vendeur doit ainsi restituer le prix de vente et l\u2019acheteur le v\u00e9hicule. (cf: jugement civil TAL du 1 ier avril 2014, 8 i\u00e8me chambre, n\u00b0 151.688 du r\u00f4le). Lorsque la nullit\u00e9 d\u2019un contrat est prononc\u00e9e pour vice de consentement-tel est le cas en l\u2019esp\u00e8ce, le contrat de vente litigieux est \u00e0 d\u00e9clarer nul en raison de l\u2019erreur sur une qualit\u00e9 substantielle dans le chef dePERSONNE2.)-les parties doivent restituer ce qu\u2019elles ont re\u00e7u l\u2019une de l\u2019autre, de mani\u00e8re \u00e0 revenir \u00e0 la situation ant\u00e9rieure. Dans cette op\u00e9ration, une indemnit\u00e9 peut \u00eatre due au vendeur tenu de restituer le prix de vente et, le cas \u00e9ch\u00e9ant, les int\u00e9r\u00eats de celui-ci, afin de tenir compte de l\u2019avantage dont a joui l\u2019acqu\u00e9reur du fait de l\u2019usage de la chose et pour \u00e9viter que ce dernier ne b\u00e9n\u00e9ficie d\u2019un enrichissement sans cause (cf: Cour d\u2019appel 12 mars 2008, Pas. 34, p. 189). A supposer quePERSONNE1.)ait voulu baser sa demande en r\u00e9duction du montant \u00e0 restituer \u00e0PERSONNE2.)sur les principes de l\u2019enrichissement sans cause, force est de constater qu\u2019il n\u2019a pas autrement expliqu\u00e9 cette base juridique et n\u2019a pas fourni au Tribunal des \u00e9l\u00e9ments circonstanci\u00e9s qui permettraient d\u2019\u00e9tablir dans le chef dePERSONNE2.)un enrichissement entra\u00eenant un appauvrissement corr\u00e9latif dans le chef dePERSONNE1.). La demande dePERSONNE1.)en r\u00e9duction de la condamnation prononc\u00e9e \u00e0 son encontre en premi\u00e8re instance est partant \u00e0 d\u00e9clarer non fond\u00e9e. Quant \u00e0 la demande dePERSONNE2.)en obtention du montant de 2.000 \u20ac \u00e0 titre d\u2019indemnit\u00e9 pour proc\u00e9dure abusive et vexatoire et quant aux indemnit\u00e9s de proc\u00e9dure PERSONNE2.)est \u00e0 d\u00e9bouter de sa demande en obtention d\u2019une indemnit\u00e9 pour proc\u00e9dure abusive et vexatoire, alors qu\u2019il n\u2019est pas \u00e9tabli quePERSONNE1.), en interjetant appel contre le jugement du 22 mars 2010, a agi avec une l\u00e9g\u00e8ret\u00e9 bl\u00e2mable, ce d\u2019autant plus que le droit de relever appel d\u2019une d\u00e9cision qui n\u2019a pas donn\u00e9 gain de cause est \u00e0 consid\u00e9rer comme constituant le droit le plus strict de l\u2019appelant. PERSONNE1.)r\u00e9clame une indemnit\u00e9 de proc\u00e9dure de 1.500 \u20ac sur base de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile. Cette demande est \u00e0 d\u00e9clarer non fond\u00e9e, ce au regard du sort r\u00e9serv\u00e9 au pr\u00e9sent litige. Par contre, le Tribunal dispose des \u00e9l\u00e9ments d\u2019appr\u00e9ciation suffisants pour fixer \u00e0 1.250 \u20ac l\u2019indemnit\u00e9 de proc\u00e9dure devant revenir \u00e0PERSONNE2.)au titre des frais par lui expos\u00e9s en instance d\u2019appel.<\/p>\n<p>9 P A R C E S M O T I F S: le Tribunal d\u2019arrondissement de Diekirch, si\u00e9geant en mati\u00e8re civile et d\u2019appel, statuant contradictoirement, sur le rapport du magistrat de lamise en \u00e9tat, revu l\u2019arr\u00eat du 13 juin 2013 (arr\u00eat n\u00b0 47\/2013, num\u00e9ro 3207 du registre) rendu par la Cour de cassation; d\u00e9clarerecevables tant l\u2019appel principal qu\u2019incident; lesditnon fond\u00e9s; ditnon fond\u00e9e la demande dePERSONNE1.)en r\u00e9ductionde la condamnation prononc\u00e9e \u00e0 son encontre en premi\u00e8re instance; d\u00e9boutePERSONNE2.)de sa demande en obtention d\u2019une indemnit\u00e9 pour proc\u00e9dure abusive et vexatoire; d\u00e9boutePERSONNE1.)de sa demande en obtention d\u2019une indemnit\u00e9 de proc\u00e9dure; condamnePERSONNE1.)\u00e0 payer \u00e0PERSONNE2.)une indemnit\u00e9 de proc\u00e9dure de 1.250 \u20ac; condamnePERSONNE1.)\u00e0 tous les frais et d\u00e9pens de l\u2019instance. Ainsi lu en audience publique au Palais de Justice \u00e0 Diekirch, par Nous Annette GANTREL, Pr\u00e9sidente duTribunal d\u2019Arrondissement, assist\u00e9e du greffier Alain GODART. Le Greffier La Pr\u00e9sidente du Tribunal -Alain GODART- -Annette GANTREL-<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-diekirch\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-diekirch\/20240808-142600\/20160524-tad-15998-pseudonymise.-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement civil n\u00b085\/2016 Num\u00e9ro 15998 du r\u00f4le Audience publique du mardi,vingt-quatre maideux milleseize. Composition: Annette GANTREL, Pr\u00e9sidente, Charles KIMMEL, Premier Juge, Gilles PETRY, Juge des Tutelles, Alain GODART, Greffier. E n t r e : PERSONNE1.),demeurant \u00e0 L-ADRESSE1.), faisant le commerce\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[],"kji_year":[61603],"kji_subject":[7724],"kji_keyword":[23584,7636],"kji_language":[7733],"class_list":["post-843792","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_year-61603","kji_subject-civil","kji_keyword-arrondissement","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 24 mai 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 24 mai 2016\" \/>\n<meta property=\"og:description\" content=\"TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement civil n\u00b085\/2016 Num\u00e9ro 15998 du r\u00f4le Audience publique du mardi,vingt-quatre maideux milleseize. Composition: Annette GANTREL, Pr\u00e9sidente, Charles KIMMEL, Premier Juge, Gilles PETRY, Juge des Tutelles, Alain GODART, Greffier. E n t r e : PERSONNE1.),demeurant \u00e0 L-ADRESSE1.), faisant le commerce\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T22:11:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-mai-2016\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-mai-2016\\\/\",\"name\":\"Tribunal d'arrondissement, 24 mai 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-05T22:11:35+00:00\",\"dateModified\":\"2026-05-05T22:11:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-mai-2016\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-mai-2016\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/tribunal-darrondissement-24-mai-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 24 mai 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 24 mai 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/","og_locale":"ru_RU","og_type":"article","og_title":"Tribunal d'arrondissement, 24 mai 2016","og_description":"TRIBUNAL D\u2019ARRONDISSEMENT DE DIEKIRCH Jugement civil n\u00b085\/2016 Num\u00e9ro 15998 du r\u00f4le Audience publique du mardi,vingt-quatre maideux milleseize. Composition: Annette GANTREL, Pr\u00e9sidente, Charles KIMMEL, Premier Juge, Gilles PETRY, Juge des Tutelles, Alain GODART, Greffier. E n t r e : PERSONNE1.),demeurant \u00e0 L-ADRESSE1.), faisant le commerce\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-05T22:11:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"20 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/","name":"Tribunal d'arrondissement, 24 mai 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-05T22:11:35+00:00","dateModified":"2026-05-05T22:11:39+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/tribunal-darrondissement-24-mai-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 24 mai 2016"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/843792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=843792"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=843792"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=843792"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=843792"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=843792"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=843792"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=843792"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=843792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}