{"id":851800,"date":"2026-05-07T00:17:28","date_gmt":"2026-05-06T22:17:28","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/"},"modified":"2026-05-07T00:17:33","modified_gmt":"2026-05-06T22:17:33","slug":"cour-superieure-de-justice-23-fevrier-2016","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Arr\u00eat n\u00b0 142\/16 Ch.c.C. du 23 f\u00e9vrier 2016. (Not. : 4274\/15\/XD)<\/p>\n<p>La chambre du conseil de la Cour d&#039;appel du Grand- Duch\u00e9 de Luxembourg a rendu le vingt-trois f\u00e9vrier deux mille seize l&#039;arr\u00eat qui suit:<\/p>\n<p>Vu l\u2019ordonnance de non- informer rendue le 11 d\u00e9cembre 2015 par un juge d\u2019instruction pr\u00e8s le tribunal d&#039;arrondissement de Diekirch ;<\/p>\n<p>Vu l&#039;appel relev\u00e9 de cette ordonnance le 17 d\u00e9cembre 2015 re\u00e7ue au greffe du tribunal d\u2019arrondissement de Diekirch par d\u00e9claration du mandataire de<\/p>\n<p>1) la soci\u00e9t\u00e9 anonyme SO C1.) S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L- (\u2026), (\u2026), partie civile,<\/p>\n<p>2) la soci\u00e9t\u00e9 anonyme SOC2.) S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L- (\u2026), (\u2026), partie civile,<\/p>\n<p>Vu les informations donn\u00e9es par lettres recommand\u00e9es \u00e0 la poste le 13 janvier 2016 aux parties civiles et \u00e0 son conseil pour la s\u00e9ance du vendredi 29 janvier 2016;<\/p>\n<p>Entendus en cette derni\u00e8re s\u00e9ance:<\/p>\n<p>Ma\u00eetre Christian BILTGEN, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch, comparant pour les parties civiles SOC1.) S.A. et SOC2.) S.A., en ses moyens d\u2019appel;<\/p>\n<p>Monsieur l\u2019avocat g\u00e9n\u00e9ral Marc HARPES, assumant les fonctions de minist\u00e8re public, en ses conclusions;<\/p>\n<p>Apr\u00e8s avoir d\u00e9lib\u00e9r\u00e9 conform\u00e9ment \u00e0 la loi;<\/p>\n<p>LA CHAMBRE DU CONSEIL DE LA COUR D&#039;APPEL :<\/p>\n<p>Par d\u00e9claration du 17 d\u00e9cembre 2015 au greffe du tribunal d&#039;arrondissement de et \u00e0 Diekirch la soci\u00e9t\u00e9 anonyme SOC1.) S.A. et la soci\u00e9t\u00e9 anonyme SOC2.) S.A. ont relev\u00e9 appel de l&#039;ordonnance rendue le 11 d\u00e9cembre 2015 par le juge d&#039;instruction pr\u00e8s le susdit tribunal dans l\u2019affaire portant le n\u00b0 not. 4274\/15\/XD.<\/p>\n<p>L&#039;ordonnance entreprise est jointe au pr\u00e9sent arr\u00eat.<\/p>\n<p>Par courrier d\u00e9pos\u00e9 le 24 ao\u00fbt 2015 au cabinet du juge d\u2019instruction, les soci\u00e9t\u00e9s anonymes SOC1.) S.A. et SOC2.) S.A. ont<\/p>\n<p>d\u00e9pos\u00e9 plainte avec constitution de partie civile contre la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l. et sa g\u00e9rante, Mme A.), la soci\u00e9t\u00e9 de droit belge SOC4.) et son g\u00e9rant, M. B.), et contre la soci\u00e9t\u00e9 SOC5.) s. \u00e0 r. l. et ses g\u00e9rants M. et Mme C1.) et C2.), en exposant que la soci\u00e9t\u00e9 SOC1.) S.A. avait acquis en vertu d\u2019un compromis de vente conclu le 2 d\u00e9cembre 2014 avec la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l. un terrain \u00e0 b\u00e2tir sis \u00e0 LIEU1.) pour y construire un immeuble r\u00e9sidentiel; que la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l. a, en violation dudit compromis de vente, \u00e9vinc\u00e9 les soci\u00e9t\u00e9s SOC1.) S.A. et SOC2.) S.A. du projet immobilier pour faire r\u00e9aliser celui-ci par la soci\u00e9t\u00e9 SOC5.) s. \u00e0 r. l. qui a charg\u00e9 la soci\u00e9t\u00e9 SOC4.) de proc\u00e9der \u00e0 des travaux d\u2019excavation sur le terrain en question; que la soci\u00e9t\u00e9 SOC4.) a d\u00e9truit le panneau publicitaire que la soci\u00e9t\u00e9 SOC1.) S.A. avait plac\u00e9 sur le terrain afin de promouvoir la vente future des appartements \u00e0 construire; que lors d\u2019un entretien t\u00e9l\u00e9phonique entre M. D.) de SOC1.) S.A. et M. C1.) ce dernier a affirm\u00e9 qu\u2019il avait le panneau publicitaire de la soci\u00e9t\u00e9 SOC1.) S.A. dans son bureau et qu\u2019il a en outre prononc\u00e9 les paroles suivantes: \u00ab Je vais vous sortir de vos bureaux avec toutes mes forces \u00bb. La soci\u00e9t\u00e9 SOC2.) S.A. avait \u00e9t\u00e9 d\u00e9sign\u00e9e par la soci\u00e9t\u00e9 SOC1.) S.A. comme entreprise charg\u00e9e de la construction de la r\u00e9sidence et figurait \u00e0 ce titre sur le panneau publicitaire; que la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l. a utilis\u00e9 les plans de construction avec le terrain en violation de la propri\u00e9t\u00e9 intellectuelle de la soci\u00e9t\u00e9 SOC2.) S.A.<\/p>\n<p>La soci\u00e9t\u00e9 SOC1.) S.A. fait \u00e9tat d\u2019un pr\u00e9judice de 200.000 \u20ac r\u00e9sultant \u00ab du manque \u00e0 gagner de la perte d\u2019une chance de pouvoir proc\u00e9der \u00e0 la vente du terrain \u00e0 b\u00e2tir et des appartements construits \u00bb et la soci\u00e9t\u00e9 SOC2.) S.A. invoque un pr\u00e9judice de 400.000 \u20ac r\u00e9sultant \u00ab du manque \u00e0 gagner de la perte d\u2019une chance de pouvoir proc\u00e9der \u00e0 la facturation au promoteur des constructions \u00e0 \u00e9riger de sa part et de l\u2019atteinte \u00e0 sa propri\u00e9t\u00e9 intellectuelle \u00bb.<\/p>\n<p>Les parties plaignantes demandent l\u2019ouverture d\u2019une instruction judiciaire du chef de d\u00e9faut d\u2019autorisation d\u2019\u00e9tablissement dans le chef des soci\u00e9t\u00e9s SOC4.) et SOC5.) s. \u00e0 r. l., de travail clandestin, de contrefa\u00e7on, de destruction immobili\u00e8re et mobili\u00e8re, de menaces, d\u2018association sinon d\u2019organisation en bande et de concurrence d\u00e9loyale.<\/p>\n<p>C\u2019est \u00e0 bon droit et pour des motifs que la chambre du conseil de la Cour adopte que le juge d&#039;instruction a refus\u00e9 d\u2019instruire en distinguant correctement entre les causes de refus d\u2019instruire tenant \u00e0 l\u2019action civile, sanctionn\u00e9es par l&#039;irrecevabilit\u00e9 de la constitution de partie civile en application de l\u2019article 58 (3) du code d&#039;instruction criminelle, et les causes de refus d\u2019instruire tenant \u00e0 l\u2019action publique vis\u00e9es \u00e0 l&#039;article 57 (3) du m\u00eame code et aboutissant \u00e0 une ordonnance de non-informer. En application de cette distinction, le juge d&#039;instruction a d\u00e9clar\u00e9 \u00e0 juste titre irrecevable la constitution de partie civile quant \u00e0 l\u2019infraction all\u00e9gu\u00e9e \u00e0 la loi du 2 septembre 2013 r\u00e9glementant l\u2019acc\u00e8s aux professions d\u2019artisan, de commer\u00e7ant d\u2019industriel ainsi qu\u2019\u00e0 certaines professions lib\u00e9rales et aux articles 571-1 du code du travail. Le minist\u00e8re public a v\u00e9rifi\u00e9 l\u2019existence d\u2019une autorisation d\u2019\u00e9tablissement dans le chef des soci\u00e9t\u00e9s SOC4.) et SOC5.) s. \u00e0 r. l. M\u00eame \u00e0 supposer que ces soci\u00e9t\u00e9s n\u2019aient pas dispos\u00e9 d\u2019une autorisation d\u2019\u00e9tablissement au d\u00e9but des op\u00e9rations de construction, ce fait n\u2019est pas<\/p>\n<p>susceptible de causer un quelconque pr\u00e9judice direct et personnel aux parties plaignantes. En r\u00e9alit\u00e9, le pr\u00e9judice \u00e9conomique dont les parties plaignantes font \u00e9tat n\u2019a pas \u00e9t\u00e9 caus\u00e9 par la pr\u00e9tendue absence d\u2019une autorisation d\u2019\u00e9tablissement dans le chef des soci\u00e9t\u00e9s SOC4.) et SOC5.) s. \u00e0 r. l., mais par la violation all\u00e9gu\u00e9e du compromis de vente conclu avec la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l.<\/p>\n<p>C\u2019est encore \u00e0 bon droit que le juge d&#039;instruction a d\u00e9clar\u00e9 irrecevable la plainte avec constitution de partie civile du chef des soi- disant menaces dont il est fait \u00e9tat dans la plainte. En effet, la victime de ces menaces de M. C1.) est M. D.) et non la soci\u00e9t\u00e9 SOC1.) S.A. Or M. D.) ne s\u2019est pas constitu\u00e9 partie civile.<\/p>\n<p>La chambre du conseil de la Cour constate encore que les paroles que M. C1.) auraient prononc\u00e9es ne peuvent pas \u00eatre qualifi\u00e9es de menaces verbales d\u2019un attentat punissable de peines criminelles ou d\u00e9lictuelles \u00e9tant donn\u00e9 que l\u2019attentat au sens des articles 327 et 330 du code p\u00e9nal dont M. D.) aurait \u00e9t\u00e9 menac\u00e9 ne ressort pas des paroles cit\u00e9es, pr\u00eat\u00e9es \u00e0 M. C1.). En outre, ces paroles ne sont pas susceptibles de rev\u00eatir une quelconque autre qualification p\u00e9nale. Il y a encore lieu d\u2019ent\u00e9riner la d\u00e9cision entreprise en ce que le juge d&#039;instruction a refus\u00e9 d\u2019informer quant aux faits d\u00e9nonc\u00e9s dans la plainte qualifi\u00e9s de destruction immobili\u00e8re et mobili\u00e8re, infraction \u00e0 la loi modifi\u00e9e du 30 juillet 2002 sur certaines pratiques commerciales et la concurrence d\u00e9loyale et association de malfaiteurs (article 322 du code p\u00e9nal) et organisation criminelle (article 324bis du code p\u00e9nal). Il ne ressort pas de la plainte que le panneau publicitaire de la soci\u00e9t\u00e9 SOC1.) S.A. aurait \u00e9t\u00e9 d\u00e9truit volontairement sur ordre du repr\u00e9sentant l\u00e9gal de la soci\u00e9t\u00e9 SOC4.), une infraction commise sur l\u2019initiative d\u2019un simple pr\u00e9pos\u00e9 ne pouvant pas engager la responsabilit\u00e9 p\u00e9nale de la soci\u00e9t\u00e9. En outre, la pr\u00e9tendue destruction du panneau publicitaire de la soci\u00e9t\u00e9 SOC1.) S.A. reste hypoth\u00e9tique \u00e9tant donn\u00e9 que la partie plaignante indique elle-m\u00eame que le panneau en question se trouverait dans les bureaux de la soci\u00e9t\u00e9 SOC5.) s. \u00e0 r. l.<\/p>\n<p>Les \u00e9l\u00e9ments de fait fournis dans leur plainte par les soci\u00e9t\u00e9s anonymes SOC1.) S.A. et SOC2.) S.A. ne permettent pas de soup\u00e7onner les personnes y vis\u00e9es d\u2019avoir form\u00e9 une association, voire une organisation criminelle, dans le but d\u2019attenter aux personnes et aux propri\u00e9t\u00e9s des plaignantes. Les faits d\u00e9nonc\u00e9s ne peuvent davantage rev\u00eatir la qualification d\u2019une infraction \u00e0 l&#039;article 14 de la loi du 30 juillet 2002 r\u00e9glementant certaines pratiques commerciales, sanctionnant la concurrence d\u00e9loyale et transposant la directive 97\/55\/CE du Parlement Europ\u00e9en et du Conseil modifiant la directive 84\/450\/CEE sur la publicit\u00e9 trompeuse afin d\u2019y inclure la publicit\u00e9 comparative.<\/p>\n<p>Commet un acte de concurrence d\u00e9loyale au sens de l&#039;article 14 de la loi \u00ab toute personne qui exerce une activit\u00e9 commerciale, industrielle, artisanale ou lib\u00e9rale qui, par un acte contraire soit aux usages honn\u00eates en mati\u00e8re commerciale, industrielle, artisanale ou lib\u00e9rale, soit \u00e0 un engagement contractuel, enl\u00e8ve ou tente d\u2019enlever \u00e0 ses concurrents ou \u00e0<\/p>\n<p>l\u2019un d\u2019eux une partie de leur client\u00e8le ou porte atteinte ou tente de porter atteinte \u00e0 leur capacit\u00e9 de concurrence \u00bb.<\/p>\n<p>Or, en l\u2019esp\u00e8ce, m\u00eame \u00e0 supposer les faits d\u00e9nonc\u00e9s \u00e9tablis en la cause, il n\u2019en ressort pas que les parties vis\u00e9es dans la plainte auraient voulu enlever ou tent\u00e9 d\u2019enlever aux soci\u00e9t\u00e9s SOC1.) S.A. et SOC2.) S.A. une partie de leur client\u00e8le ou porter atteinte ou tenter de porter atteinte \u00e0 leur capacit\u00e9 de concurrence. La chambre du conseil de la Cour constate en outre que les parties plaignantes ne font pas \u00e9tat d\u2019un pr\u00e9judice \u00e9conomique pour perte de client\u00e8le, mais pour perte de la chance d\u2019accomplir un projet immobilier et de r\u00e9aliser le b\u00e9n\u00e9fice financier escompt\u00e9.<\/p>\n<p>Quant \u00e0 l\u2019atteinte \u00e0 sa propri\u00e9t\u00e9 intellectuelle d\u00e9nonc\u00e9e par la soci\u00e9t\u00e9 SOC2.) S.A., il y a lieu de noter que la plaignante expose qu\u2019elle a \u00e9tabli les plans de construction sur commande de la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l. et que celle-ci a utilis\u00e9 ces plans pour obtenir l\u2019autorisation de construire. Or, ces \u00e9l\u00e9ments factuels ne permettent pas de conclure \u00e0 une violation de la loi du 18 avril 2001 sur les droits d\u2019auteur, les droits voisins et les bases de donn\u00e9es. La circonstance que la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l. aurait utilis\u00e9 les plans confectionn\u00e9s \u00e0 sa demande par la soci\u00e9t\u00e9 SOC2.) S.A. pour obtenir une autorisation de construire ne porte pas atteinte au droit moral de l\u2019auteur des plans puisque les plans furent pr\u00e9cis\u00e9ment command\u00e9s et \u00e9tablis \u00e0 ces fins. Quant \u00e0 ce fait, la chambre du conseil de la Cour constate encore que la soci\u00e9t\u00e9 SOC2.) S.A. ne fait pas \u00e9tat d\u2019un pr\u00e9judice \u00e9conomique pour atteinte \u00e0 son droit moral d\u2019auteur.<\/p>\n<p>A supposer que la soci\u00e9t\u00e9 SOC3.) s. \u00e0 r. l. e\u00fbt viol\u00e9 le compromis de vente qui la liait \u00e0 la soci\u00e9t\u00e9 SOC1.) S.A. en ex\u00e9cutant le projet immobilier avec d\u2019autres entreprises partenaires, elle est susceptible d\u2019avoir engag\u00e9 sa responsabilit\u00e9 civile, ce qui n\u2019implique cependant pas que ses faits et agissements rev\u00eatent une quelconque qualification p\u00e9nale.<\/p>\n<p>P A R C E S M O T I F S<\/p>\n<p>re\u00e7oit l\u2019appel;<\/p>\n<p>le dit non fond\u00e9;<\/p>\n<p>confirme l&#039;ordonnance entreprise;<\/p>\n<p>condamne les parties appelantes solidairement aux frais de l\u2019instance d\u2019appel, liquid\u00e9s \u00e0 20,30 \u20ac.<\/p>\n<p>Ainsi fait et jug\u00e9 par la chambre du conseil de la Cour d&#039;appel du Grand- Duch\u00e9 de Luxembourg \u00e0 Luxembourg, Cit\u00e9 Judiciaire, Plateau du St. Esprit, o\u00f9 \u00e9taient pr\u00e9sents:<\/p>\n<p>Camille HOFFMANN, pr\u00e9sident de chambre, Mireille HARTMANN, premier conseiller,<\/p>\n<p>Carole KERSCHEN, conseiller,<\/p>\n<p>qui ont sign\u00e9 le pr\u00e9sent arr\u00eat avec le greffier assum\u00e9 Simone ANGEL.<\/p>\n<p>Grand-Duch\u00e9 de Luxembourg Tribunal d\u2019Arrondissement de et \u00e0 Diekirch Cabinet du Juge d\u2019Instruction Claudine DE LA HAMETTE Palais de Justice BP 164 L-9202 Diekirch ( 80 32 14 23 \u2022 80 74 14<\/p>\n<p>Not : 4274\/15\/XD SOC1.) SA et SOC2.) SA c\/ SOC3.) S\u00e0rl, Slag, SOC4.) Scrl, Nillen, SOC5.) s\u00e0rl, C1.) et C2.) (Pri\u00e8re de mentionner dans toute correspondance)<\/p>\n<p>C02<\/p>\n<p>Diekirch, le 11 d\u00e9cembre2015<\/p>\n<p>ORDONNANCE<\/p>\n<p>Nous Claudine DE LA HAMETTE, juge d\u2019instruction pr\u00e8s le Tribunal d\u2019arrondissement de et \u00e0 Diekirch,<\/p>\n<p>Vu la plainte avec constitution de partie civile d\u00e9pos\u00e9e au greffe du tribunal d\u2019arrondissement de et \u00e0 Diekirch en date du 24 ao\u00fbt 2015 par Ma\u00eetre Christian BILTGEN, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch au nom et pour le compte de<\/p>\n<p>1) la soci\u00e9t\u00e9 anonyme SOC1.) S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L-(\u2026), (\u2026), repr\u00e9sent\u00e9e par son conseil d\u2019administration actuellement en fonctions, 2) la soci\u00e9t\u00e9 anonyme SOC2.) S.A., \u00e9tablie et ayant son si\u00e8ge \u00e0 L-(\u2026), (\u2026), repr\u00e9sent\u00e9e par son conseil d\u2019administration actuellement en fonctions,<\/p>\n<p>contre<\/p>\n<p>1) la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, \u00e9tablie et ayant son si\u00e8ge social \u00e0 L-(\u2026), (\u2026), 2) A.), g\u00e9rante de la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, demeurant \u00e0 L-(\u2026), (\u2026), 3) la soci\u00e9t\u00e9 de droit belge SOC4.) scrl, \u00e9tablie \u00e0 B- (\u2026), (\u2026), 4) B.), g\u00e9rant de la soci\u00e9t\u00e9 SOC4.) scrl, adresse professionnelle \u00e0 B- (\u2026), (\u2026) 5) SOC5.) s\u00e0rl, \u00e9tablie et ayant son si\u00e8ge \u00e0 L-(\u2026), (\u2026), 6) C1.), g\u00e9rant administratif de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, demeurant \u00e0 L-(\u2026), (\u2026) 7) C2.), g\u00e9rante technique de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, demeurant \u00e0 B-(\u2026), (\u2026)<\/p>\n<p>du chef de<\/p>\n<p>\u2022 d\u00e9faut d\u2019autorisation d\u2019\u00e9tablissement, \u2022 travail clandestin, \u2022 contrefa\u00e7on, \u2022 destruction immobili\u00e8re et mobili\u00e8re,<\/p>\n<p>\u2022 menaces, \u2022 association, sinon organisation en bande, \u2022 concurrence d\u00e9loyale.<\/p>\n<p>Vu le courrier de Ma\u00eetre Christian BILTGEN du 9 d\u00e9cembre 2015 en compl\u00e9ment de la plainte avec constitution de partie civile d\u00e9pos\u00e9e le 24 ao\u00fbt 2015 ;<\/p>\n<p>Vu le r\u00e9quisitoire du Parquet du 16 octobre 2015, aux termes desquelles le Procureur d\u2019Etat adjoint conclut comme suit :<\/p>\n<p>\u00ab En vertu des dispositions de l\u2019article 56 du code d\u2019instruction criminelle, toute personne qui se pr\u00e9tend l\u00e9s\u00e9e par un crime ou un d\u00e9lit peut mettre en mouvement l\u2019action publique en se constituant partie civile.<\/p>\n<p>A l\u2019appui de sa demande, le plaignant doit d\u00e9crire avec pr\u00e9cision le fait mat\u00e9riel en lui-m\u00eame ainsi que le pr\u00e9judice duquel il souffre avec une pr\u00e9cision suffisante permettant une imputation \u00e0 un auteur pr\u00e9cis. Il sera ensuite de la mission du juge d\u2019instruction de rassembler les \u00e9l\u00e9ments de preuve.<\/p>\n<p>En l\u2019esp\u00e8ce, les parties plaignantes font d\u2019abord \u00e9tat de l\u2019\u00e9chec d\u2019une op\u00e9ration commerciale en relation avec la conclusion d\u2019un compromis de vente portant sur terrain \u00e0 b\u00e2tir ainsi que la promotion et la construction d\u2019un immeuble \u00e0 appartements entre la s.a. SOC1.) et la s.\u00e0 r.l. SOC3.) . Ils pr\u00e9tendent que la s.a. SOC2.) aurait dress\u00e9 les plan de la future construction au profit de SOC3.) mais qu\u2019\u00e0 ce stade des tractations la partie venderesse aurait proc\u00e9d\u00e9 \u00e0 une seconde vente du m\u00eame terrain \u00e0 la s.\u00e0 r.l. SOC5.) , qui, en faisant usage des plans dress\u00e9s par SOC2.) , aurait charg\u00e9 la s.c.r.l. de droit belge SOC4.) des travaux d\u2019excavation sur le site. Ils invoquent encore d\u2019autres faits accessoires auxquels ils donnent une connotation p\u00e9nale.<\/p>\n<p>En se constituent partie civile la s.a. SOC1.) qualifie le pr\u00e9judice accru comme ressortant de la perte d\u2019une chance de pouvoir proc\u00e9der \u00e0 la vente du terrain \u00e0 b\u00e2tir et des appartements construits, outre la clause p\u00e9nale de 10 % d\u2019un montant de 28.000 \u20ac, tandis que la s.a. SOC2.) demande r\u00e9paration de son pr\u00e9judice r\u00e9sultant de la perte d\u2019une chance de pouvoir proc\u00e9der \u00e0 la facturation au promoteur des constructions \u00e0 \u00e9riger de sa part et de l\u2019atteinte \u00e0 sa propri\u00e9t\u00e9 intellectuell e.<\/p>\n<p>Comme l\u2019action publique \u00e0 engager \u00e0 la demande d\u2019une victime d\u00e9pend de la recevabilit\u00e9 de sa demande civile, il y a lieu de se prononcer d\u2019abord sur la r\u00e9gularit\u00e9 de la demande civile avant de se prononcer sur la question de savoir s\u2019il y a lieu d\u2019engager l\u2019action publique sur initiative de la victime. Il est en effet de jurisprudence constante qu\u2019avant de pouvoir requ\u00e9rir le juge d\u2019instruction de proc\u00e9der \u00e0 une information judiciaire il y a lieu de v\u00e9rifier la r\u00e9gularit\u00e9 de la demande civile. La question de la comp\u00e9tence du juge r\u00e9pressif est d\u2019ordre public et doit m\u00eame \u00eatre soulev\u00e9e d\u2019office. (en ce sens : Cour 19.12.1958 ; 17; 377).<\/p>\n<p>Le pr\u00e9judice dont la r\u00e9paration est demand\u00e9e est partant un \u00e9l\u00e9ment essentiel de la recevabilit\u00e9 de la plainte avec constitution de partie civile.<\/p>\n<p>L\u2019article 58 du code d\u2019instruction criminelle permet entre autres au minist\u00e8re public de contester cette partie civile.<\/p>\n<p>Il ressort de la formulation m\u00eame de l\u2019article 56 du code d\u2019instruction criminelle que la mise en mouvement de l\u2019action publique, qui est g\u00e9n\u00e9ralement de la comp\u00e9tence du minist\u00e8re public, ne peut intervenir \u00e0 l\u2019initiative de la pr\u00e9tendue victime d\u2019une infraction que si cette derni\u00e8re souffre d\u2019un pr\u00e9judice r\u00e9el qui se trouve \u00eatre en relation causale directe avec les infractions reproch\u00e9es. Pour se prononcer sur la recevabilit\u00e9 de la constitution de partie civile, s\u2019il n\u2019appartient pas au procureur<\/p>\n<p>d\u2019Etat ni encore au juge d\u2019instruction de se prononcer d\u00e9finitivement sur le quantum du pr\u00e9judice \u00e0 ce stade de la proc\u00e9dure, il leur appartient cependant d\u2019en v\u00e9rifier l\u2019existence du moins en substance, ainsi que sa naissance dans le pr\u00e9tendu fait p\u00e9nal.<\/p>\n<p>La question de la recevabilit\u00e9 de la constitution de partie civile tois\u00e9e, il s\u2019impose d\u2019analyser si, pour des causes affectant l\u2019action publique elle-m\u00eame, les faits peuvent l\u00e9galement comporter une poursuite ou s\u2019ils sont susceptibles de recevoir une qualification p\u00e9nale. Pour ce faire, la partie civile doit \u00e9noncer le fait p\u00e9nal dans lequel son pr\u00e9tendu pr\u00e9judice aurait trouv\u00e9 naissance avec une pr\u00e9cision permettant une analyse juridique.<\/p>\n<p>La partie civile a donn\u00e9 aux faits \u00e9nonc\u00e9s dans sa plainte les qualifications p\u00e9nales suivantes. Il s\u2019impose partant d\u2019analyser si le pr\u00e9tendu dommage peut trouver sa gen\u00e8se dans lesdits faits.<\/p>\n<p>1. Infractions \u00e0 la loi du 2 septembre 2011 r\u00e9glementant l\u2019acc\u00e8s aux professions d\u2019artisan, de commer\u00e7ant, d\u2019industriel ainsi qu\u2019\u00e0 certaines professions lib\u00e9rales, ainsi qu\u2019aux articles 571-1 et suivants du code du travail. Les plaignants soutiennent que les soci\u00e9t\u00e9s SOC3.) s.\u00e0 r.l., SOC4.) s.c.r.l. et SOC5.) s.\u00e0 r.l. ne disposeraient pas des autorisations minist\u00e9rielles requises et versent \u00e0 l\u2019appui de leur affirmation des r\u00e9ponses par courrier \u00e9lectronique des pr\u00e9pos\u00e9s du Minist\u00e8re de l\u2019\u00e9conomie documentant ce fait. Une consultation de la base de donn\u00e9es informatis\u00e9e du minist\u00e8re concern\u00e9 par le soussign\u00e9 Procureur d\u2019Etat a d\u00e9montr\u00e9 que toutes les soci\u00e9t\u00e9s commerciales vis\u00e9es par la plainte disposent \u00e0 ce jour des autorisations requises. (Annexes) Ainsi, la s.c.r.l. de droit belge SOC4.) a effectu\u00e9e la d\u00e9claration pr\u00e9alable pr\u00e9vue et est actuellement conforme \u00e0 la loi jusqu\u2019au 3 ao\u00fbt 2016. Les soci\u00e9t\u00e9s de droit luxembourgeois, SOC5.) s.\u00e0 r.l. et SOC3.) s.\u00e0 r.l. disposent des autorisations minist\u00e9rielles requises depuis le 21 septembre 2015 respectivement 30 juin 2015. Si les autorisations minist\u00e9rielles faisaient encore d\u00e9faut \u00e0 un certain moment, quod non, les parties civiles restent en d\u00e9faut d\u2019\u00e9tablir en quoi un d\u00e9faut d\u2019autorisation d\u2019\u00e9tablissement dans la personne des soci\u00e9t\u00e9s commerciales vis\u00e9es par leur plainte serait directement \u00e0 l\u2019origine de la perte \u00e0 gagner de laquelle elles demandent r\u00e9paration.<\/p>\n<p>A d\u00e9faut de pr\u00e9judice en relation causale directe avec l\u2019infraction d\u00e9nonc\u00e9e, la plainte est \u00e0 d\u00e9clarer irrecevable pour autant qu\u2019elle est fond\u00e9e sur une infraction \u00e0 la loi du 2 septembre 2011 r\u00e9glementant l\u2019acc\u00e8s aux professions d\u2019artisan, de commer\u00e7ant, d\u2019industriel ainsi qu\u2019\u00e0 certaines professions lib\u00e9rales, ainsi qu\u2019aux articles 571-1 et suivants du code du travail.<\/p>\n<p>2. Destruction immobili\u00e8re et mobili\u00e8res. La partie civile sub 2) fait \u00e9tat dans l\u2019\u00e9nonc\u00e9 des faits de la destruction d\u2019un panneau publicitaire et impute ce fait \u00e0 la soci\u00e9t\u00e9 SOC4.) . Il ne s\u2019agit pas d\u2019un immeuble au sens de l\u2019article 521 du code p\u00e9nal Force est de constater qu\u2019elle ne pr\u00e9sente pas de pr\u00e9tention indemnitaire de ce fait. En effet, la s.a. SOC2.) demande exclusivement r\u00e9paration d\u2019un pr\u00e9judice de \u20ac 400.000 r\u00e9sultant du<\/p>\n<p>manque \u00e0 gagner de la perte d\u2019une chance de pouvoir proc\u00e9der \u00e0 la facturation au promoteur des constructions \u00e0 \u00e9riger de sa part et de l\u2019atteinte \u00e0 sa propri\u00e9t\u00e9 intellectuelle.<\/p>\n<p>A d\u00e9faut de pr\u00e9judice en relation avec l\u2019infraction d\u00e9nonc\u00e9e, la plainte est \u00e0 d\u00e9clarer irrecevable pour autant qu\u2019elle vise ce fait.<\/p>\n<p>La bande publicitaire se trouve d\u2019ailleurs, conform\u00e9ment au libell\u00e9 de sa plainte, encore dans les bureaux de M. C1.).<\/p>\n<p>3. Menaces d\u2019attentat pr\u00e9vues \u00e0 l\u2019article 327 du code p\u00e9nal. Les parties civiles font \u00e9tat de menaces pr\u00e9tendument dirig\u00e9es par Monsieur C1.) \u00e0 destination de Monsieur D.) . D.) est le g\u00e9rant statutaire des soci\u00e9t\u00e9s anonymes SOC1.) et SOC2.), plaignants et parties civiles dans ce dossier. Force est cependant de constater que le sieur D.) ne pr\u00e9sente pas de pr\u00e9tention indemnitaire personnelle du chef de la pr\u00e9tendue infraction. Il n\u2019a pas port\u00e9 plainte en nom personnel.<\/p>\n<p>Or, nul ne plaide par procureur.<\/p>\n<p>La demande est partant \u00e0 d\u00e9clarer irrecevable pour d\u00e9faut de qualit\u00e9s pour agir dans le chef des parties civiles.<\/p>\n<p>A titre subsidiaire Si les parties civiles auraient encore \u00e9t\u00e9 victimes de l\u2019infraction reproch\u00e9e, force est de constater qu\u2019elles ne pr\u00e9sentent pas de pr\u00e9tention indemnitaire de ce fait. A d\u00e9faut de pr\u00e9judice en relation causale directe avec l\u2019infraction d\u00e9nonc\u00e9e, la plainte est \u00e0 d\u00e9clarer irrecevable.<\/p>\n<p>A titre plus subsidiaire Pour qu\u2019il y ait menace punissable il faut que l\u2019agent ait menac\u00e9 verbalement d\u2019un attentat contre les personnes ou les propri\u00e9t\u00e9s, punissable d\u2019une peine criminelle. Si la pr\u00e9tendue victime d\u2019une infraction peut, en se constituant partie civile, mettre en mouvement l\u2019action publique contre l\u2019auteur pr\u00e9sum\u00e9 des faits, encore faut-il analyser si pour des causes affectant l\u2019action publique elle -m\u00eame, les faits peuvent l\u00e9galement comporter une poursuite. A l\u2019appui de leur demande les parties civiles soutiennent que C1.) aurait tenu le 26 juin 2015 par voie t\u00e9l\u00e9phonique les propos suivants: \u00ab je vais vous sortir de vos bureaux avec toutes mes forces \u00bb. Il est de jurisprudence constante que pour pouvoir \u00eatres qualifi\u00e9s mena\u00e7antes, les paroles prononc\u00e9es doivent \u00eatres susceptible d\u2019inspirer une crainte s\u00e9rieuse. De simples bravades ou un \u00e9change de mots un peu plus muscl\u00e9s que la normale, respectivement un emportement passager ne constituent pas des menaces au sens de la loi.<\/p>\n<p>A la lumi\u00e8re de ces pr\u00e9cisions, les propos avanc\u00e9s par les plaignants et imput\u00e9s \u00e0 C1.) ne sont pas susceptibles de recevoir une qualification p\u00e9nale de sorte que le soussign\u00e9 \u00e9met des conclusions de non informer quant \u00e0 ce point de la plainte. 4. Infraction \u00e0 la loi modifi\u00e9e du 30 juillet 2002 sur certaines pratiques commerciales et la concurrence d\u00e9loyale.<\/p>\n<p>Principalement En l\u2019esp\u00e8ce les parties civiles se limitent \u00e0 r\u00e9clamer globalement contre toutes les personnes vis\u00e9es r\u00e9paration d\u2019un manque \u00e0 gagner commercial sans autre pr\u00e9cision et sans m\u00eame qualifier plus en avant quel comportement serait constitutif de l\u2019infraction reproch\u00e9e au vu des \u00e9l\u00e9ments constitutifs de l\u2019infraction.<\/p>\n<p>La partie civile est partant \u00e0 d\u00e9clarer irrecevable.<\/p>\n<p>A titre subsidiaire.<\/p>\n<p>Les articles 14 et 22 de la loi disposent que \u00ab commet un acte de concurrence d\u00e9loyale toute personne qui exerce une activit\u00e9 commerciale, industrielle, artisanale ou lib\u00e9rale qui, par un acte contraire soit aux usages honn\u00eates en mati\u00e8re commerciale, industrielle, artisanale ou lib\u00e9rale, soit \u00e0 un engagement contractuel, enl\u00e8ve ou tente d\u2019enlever \u00e0 ses concurrents ou \u00e0 l\u2019un d\u2019eux une partie de leur client\u00e8le ou porte atteinte ou tente de porter atteinte \u00e0 leur capacit\u00e9 de concurrence \u00bb.<\/p>\n<p>Il \u00e9tait de l\u2019intention du l\u00e9gislateur de r\u00e9primer par les dispositions des articles 14 et 22 de la loi, le fait pour un commer\u00e7ant d\u2019entraver la libert\u00e9 de d\u00e9cision de la client\u00e8le en usant de m\u00e9thodes particuli\u00e8rement agressives. (documents parlementaires n\u00b0 4844, commentaire des articles, sub. article 14 p. 17)<\/p>\n<p>La loi entend ainsi \u00e9viter que le jeu de la libre concurrence existant entre les acteurs de la vie \u00e9conomique dans la recherche d\u2019une client\u00e8le potentielle ne soit fauss\u00e9 par le comportement qualifi\u00e9 irr\u00e9gulier de l\u2019un d\u2019eux.<\/p>\n<p>L\u2019infraction suppose la r\u00e9union d\u2019un \u00e9l\u00e9ment mat\u00e9riel et d\u2019un \u00e9l\u00e9ment moral.<\/p>\n<p>L\u2019\u00e9l\u00e9ment mat\u00e9riel peut \u00eatre d\u00e9fini comme suit : \u2022 un acteur de la vie \u00e9conomique \u2022 qui par un acte contraire aux usages honn\u00eates ou \u00e0 un engagement contractuel \u2022 enl\u00e8ve ou tente d\u2019enlever \u00e0 ses concurrents sa client\u00e8le ou porte atteinte \u00e0 la capacit\u00e9 de concurrence<\/p>\n<p>Quant \u00e0 l\u2019\u00e9l\u00e9ment moral, le dol g\u00e9n\u00e9ral est requis.<\/p>\n<p>Quant \u00e0 la s.\u00e0 r.l. SOC3.) Les faits d\u00e9crits \u00e0 l\u2019appui de la plainte ne peuvent recevoir la qualification de l\u2019infraction vis\u00e9e. En effet, SOC3.) et SOC1.) ne se trouvant pas en relation concurrentielle entre eux, l\u2019un agissant en tant que propri\u00e9taire et l\u2019autre en tant qu\u2019acqu\u00e9reur du terrain querell\u00e9.<\/p>\n<p>Les pr\u00e9tentions de la s.a. SOC1.) sont partant de nature purement civile de sorte que le soussign\u00e9 \u00e9met des conclusions de non- informer, les faits ne pouvant recevoir une qualification p\u00e9nale.<\/p>\n<p>Quant \u00e0 la s.c.r.l. de droit belge SOC4.) Si la soci\u00e9t\u00e9 SOC4.) de par un objet social quelque peu similaire, est encore susceptible de se trouver dans une situation de concurrence avec le plaignant sub 2), quod non, au vu des pi\u00e8ces produites en cause par les plaignants, SOC4.) est intervenu en vertu d\u2019un contrat d\u2019entreprise conclu avec SOC5.) . SOC4.) n\u2019\u00e9tait partant pas en relation concurrentielle directe avec une des parties civiles, li\u00e9es quant \u00e0 elles par diff\u00e9rents contrats \u00e0 la s.\u00e0 r.l. SOC3.).<\/p>\n<p>Pour le surplus, les plaignants n\u2019invoquent pas au niveaux des faits qu\u2019il suspectent les dirigeants sociaux de la soci\u00e9t\u00e9 SOC4.) d\u2019avoir eu l\u2019intention de poser un acte de concurrence d\u00e9loyale en acceptant de la part du ma\u00eetre d\u2019\u0153uvre le march\u00e9 portant sur l\u2019excavation d\u2019un terrain.<\/p>\n<p>A la lumi\u00e8re de ces pr\u00e9cisions, les faits d\u00e9crits ne sont pas susceptibles de recevoir une qualification p\u00e9nale, de sorte que le soussign\u00e9 \u00e9met des conclusions de non informer quant \u00e0 ce point de la plainte.<\/p>\n<p>Quant \u00e0 SOC5.) s.\u00e0 r.l. Alors m\u00eame que la s.\u00e0 r.l. SOC5.) , est intervenue en tant que \u00ab ma\u00eetre d\u2019ouvrage \u00bb en chargeant SOC4.) de travaux d\u2019excavation sur le terrain litigieux, les plaignants n\u2019invoquent pas dans leur expos\u00e9 des faits qu\u2019ils suspectent SOC5.) d\u2019avoir jou\u00e9 un r\u00f4le actif respectivement que ses dirigeants aient fait usage de proc\u00e9d\u00e9s contraires aux pratiques du march\u00e9 dans l\u2019obtention du march\u00e9 \u00e0 leur d\u00e9triment. Or, le seul fait d\u2019accepter un engagement portant sur la promotion d\u2019un terrain, n\u2019est pas suffisant pour asseoir une poursuite p\u00e9nale. A la lumi\u00e8re de ces pr\u00e9cisions, les faits avanc\u00e9s par les plaignants ne sont pas susceptibles de recevoir une qualification p\u00e9nale de sorte que le soussign\u00e9 \u00e9met \u00e0 titre subsidiaire des conclusions de non informer quant \u00e0 ce point de la plainte.<\/p>\n<p>5. infraction aux articles 1, 3, 82, et 83 de la loi modifi\u00e9e du 18 avril 2001 sur les droits d\u2019auteur, les droits voisins et les bases de donn\u00e9es<\/p>\n<p>La partie civile sub 2) la s.a. SOC2.) r\u00e9clame r\u00e9paration de l\u2019atteinte \u00e0 sa propri\u00e9t\u00e9 intellectuelle par usurpation des plans de construction confectionn\u00e9s. Elle \u00e9value son pr\u00e9judice \u00e0 \u20ac 400.000, toutes causes confondues.<\/p>\n<p>Aux termes de la loi, toute atteinte m\u00e9chante ou frauduleuse port\u00e9e aux droits de l&#039;auteur prot\u00e9g\u00e9s au titre de la pr\u00e9sente loi, (\u2026) constitue le d\u00e9lit de contrefa\u00e7on. Est coupable du m\u00eame d\u00e9lit, quiconque, sciemment, vend, offre en vente, importe, exporte, fixe, reproduit, communique, transmet par fil ou sans fil, met \u00e0 la disposition du public et de mani\u00e8re g\u00e9n\u00e9rale, met ou remet en circulation, \u00e0 titre on\u00e9reux ou gratuit, une \u0153uvre, une prestation (\u2026) sans autorisation de l&#039;auteur, (\u2026).<\/p>\n<p>Force est de constater que la plaignante se limite \u00e0 \u00e9noncer divers faits sans les imputer \u00e0 un auteur pr\u00e9cis et avance une pr\u00e9tention indemnitaire non individualis\u00e9e contre les personnes vis\u00e9es par sa plainte.<\/p>\n<p>Cette individualisation tant des faits aux auteurs pr\u00e9sum\u00e9s que des dommages faisant d\u00e9faut, la partie civile est \u00e0 d\u00e9clarer irrecevable.<\/p>\n<p>A titre subsidiaire SOC2.), verse \u00e0 l\u2019appui de sa plainte une farde contenant 19 pi\u00e8ces contenant entre autres les plans d\u2019une construction, des factures en relation avec la confection des plans d\u2019une construction \u00e0 LIEU2.) , ainsi que 6 photos montrant le stade actuel du pr\u00e9tendu projet.<\/p>\n<p>Ces photos montrent un terrain sur lequel a \u00e9t\u00e9 r\u00e9alis\u00e9e une excavation. Aucun immeuble n\u2019y a \u00e9t\u00e9 construit ou s\u2019y trouve en construction.<\/p>\n<p>Le juge d\u2019instruction recherche dans sa mission l\u00e9gale les \u00e9l\u00e9ments de preuve d\u2019une infraction qui a eu lieu. C\u2019est la saisine in rem. Il n\u2019est de pas de sa mission de rechercher des infractions \u00e0 venir.<\/p>\n<p>Le fait mat\u00e9riel brut qualifiable d\u2019infraction \u00e0 la l\u00e9gislation sur les droits d\u2019auteur consisterait en l\u2019esp\u00e8ce dans l\u2019utilisation par un tiers des plans de construction sur lesquels SOC2.) pr\u00e9tend disposer d\u2019un droit.<\/p>\n<p>Or, ce fait n\u2019est pas r\u00e9alis\u00e9 actuellement et la plaignante invoque partant un fait hypoth\u00e9tique.<\/p>\n<p>Les faits avanc\u00e9s ne sont partant pas susceptibles de recevoir actuellement une qualification p\u00e9nale de sorte que le soussign\u00e9 \u00e9met \u00e0 titre subsidiaire des conclusions de non informer quant \u00e0 ce point de la plainte<\/p>\n<p>6. association form\u00e9e dans le but d\u2019attenter aux personnes ou aux propri\u00e9t\u00e9s, organisation criminelle pr\u00e9vue par les articles 322 et suivants du code p\u00e9nal<\/p>\n<p>Les parties civiles avancent \u00e0 l\u2019appui de leur plainte des faits oscillant autour d\u2019une querelle n\u00e9e entre commer\u00e7ants \u00e0 propos d\u2019une op\u00e9ration de promotion d\u2019un immeuble \u00e0 appartements et de la vente du terrain sur lequel l\u2019immeuble devait \u00eatre construit. Ils qualifient les comportements incrimin\u00e9s d\u2019association respectivement organisation en bande sans autre pr\u00e9cision. Afin de lutter contre la criminalit\u00e9 organis\u00e9e, le l\u00e9gislateur a \u00e9rig\u00e9 en infraction l&#039;appartenance et la participation \u00e0 une association de malfaiteurs et \u00e0 une organisation criminelle. Ainsi, outre les poursuites p\u00e9nales pour les infractions commises par les personnes qui entretiennent des liens avec ces types de groupement, ces personnes peuvent \u00eatre sanctionn\u00e9es par le fait d&#039;\u00eatre membre ou de procurer leur aide \u00e0 ces groupements.<\/p>\n<p>Une association de malfaiteurs se d\u00e9finit comme \u00e9tant un groupe organis\u00e9 qui a pour but de commettre contre les personnes ou les propri\u00e9t\u00e9s des attentats constituant des crimes ou des d\u00e9lits.<\/p>\n<p>Une organisation criminelle quant \u00e0 elle est une association structur\u00e9e de plus de deux personnes, \u00e9tablie dans le temps, en vue de commettre de fa\u00e7on concert\u00e9e, des crimes et d\u00e9lits punissables d&#039;un emprisonnement de trois ans ou d&#039;une peine plus grave, pour obtenir, directement ou indirectement, des avantages patrimoniaux.<\/p>\n<p>Le terme \u00ab organisation de la bande \u00bb de l\u2019article 322 du Code p\u00e9nal signifie un groupement volontaire exclusif de toute id\u00e9e de rassemblement accidentel. (SCHUIND, p.324). Le rassemblement doit \u00eatre volontaire et avec l\u2019intention pr\u00e9existante d\u2019attenter \u00e0 la loi.<\/p>\n<p>La jurisprudence a encore \u00e9mis certains crit\u00e8res pour qu\u2019il puisse y avoir une organisation. Il s\u2019agit entre autres de l\u2019existence d\u2019une hi\u00e9rarchie, de la distribution pr\u00e9alable des r\u00f4les, de la r\u00e9partition anticipative du butin, de l\u2019existence de lieux de rendez-vous, de l\u2019organisation de cachettes et de d\u00e9p\u00f4ts.<\/p>\n<p>Le simple fait de la pluralit\u00e9 d\u2019auteurs ou la commission d\u2019infractions en groupe n\u2019est pas suffisant pour constituer le d\u00e9lit sp\u00e9cial de l\u2019association de malfaiteurs.<\/p>\n<p>Or, les plaignants se limitent \u00e0 \u00e9noncer assez sommairement diff\u00e9rents faits, pour la majorit\u00e9 purement civils, sur lesquels ils greffent sans autre pr\u00e9cision ni analyse une qualification p\u00e9nale.<\/p>\n<p>Il ressort par ailleurs des d\u00e9veloppements ci-avant sub 1) \u00e0 5), que le minist\u00e8re public a \u00e9mis des conclusions tendant soit \u00e0 voir d\u00e9clarer la proc\u00e9dure irrecevable pour d\u00e9faut de pr\u00e9judice r\u00e9el et direct en relation avec le fait avanc\u00e9, soit qu\u2019il n\u2019y a pas lieu \u00e0 informer alors que les faits avanc\u00e9s ne peuvent l\u00e9galement comporter une poursuite respectivement qu\u2019ils ne sont pas susceptibles de recevoir une qualification p\u00e9nale.<\/p>\n<p>Le r\u00e9cit des faits \u00e0 la base de la plainte, ne r\u00e9v\u00e8le aucun \u00e9l\u00e9ment permettant de conclure que les personnes vis\u00e9es aient commis une infraction respectivement qu\u2019ils aient form\u00e9 un groupement en vu de commettre les infractions. Ils ne peuvent l\u00e9galement donner lieu \u00e0 une poursuite p\u00e9nale de sorte que le soussign\u00e9 Procureur d\u2019Etat \u00e9met des conclusions de non- informer. \u00bb<\/p>\n<p>Vu le transmis du Parquet du 12 d\u00e9cembre 2015 suivant lequel Monsieur le Procureur d\u2019Etat adjoint maintient ses conclusions \u00e9crites du 16 octobre 2015 suite au courrier de Ma\u00eetre Christian BILTGEN du 9 d\u00e9cembre 2015, compl\u00e9tant sa plainte avec constitution de partie civile du 24 ao\u00fbt 2015;<\/p>\n<p>Le juge d&#039;instruction est tenu de v\u00e9rifier non seulement sa comp\u00e9tence et l\u2019existence d\u2019une cause de non-informer suivant l&#039;article 57 (3) du code d&#039;instruction criminelle, mais encore, et cela d\u2019office, la recevabilit\u00e9 de la plainte avec constitution de partie civile, surtout lorsqu\u2019en l\u2019absence de r\u00e9quisitoire introductif du minist\u00e8re public, sa saisine se fonde exclusivement sur celle-ci. Il lui appartient ainsi, en application de l&#039;article 58 du code d&#039;instruction criminelle, de relever un \u00e9ventuel d\u00e9faut d\u2019int\u00e9r\u00eat personnel de la partie civile et de d\u00e9clarer la constitution de partie civile irrecevable. ( Arr\u00eat n\u00b0 249\/13 Ch.c.C. du 13 mai 2013 ; Not. : 12579\/11\/CD)<\/p>\n<p>Aux termes de l\u2019article 56 du code d\u2019instruction criminelle, toute personne qui se pr\u00e9tend l\u00e9s\u00e9e par un crime ou un d\u00e9lit, peut en portant plainte se constituer partie civile devant le juge d\u2019instruction. Comme la loi ne pr\u00e9cise pas autrement les conditions de recevabilit\u00e9 de cette constitution de partie civile, il y a lieu de se r\u00e9f\u00e9rer aux r\u00e8gles g\u00e9n\u00e9rales de l\u2019action civile quant \u00e0 ces conditions.<\/p>\n<p>A ce titre il y a lieu de relever qu\u2019il doit y avoir n\u00e9cessairement un lien de causalit\u00e9 entre l\u2019infraction invoqu\u00e9e et le pr\u00e9judice all\u00e9gu\u00e9. La jurisprudence unanime sinon du moins largement majoritaire exige que ce lien de causalit\u00e9 soit direct et exclut donc le pr\u00e9judice caus\u00e9 indirectement par l\u2019infraction en cause.<\/p>\n<p>D\u2019une mani\u00e8re g\u00e9n\u00e9rale il doit s\u2019agir d\u2019un pr\u00e9judice personnel et certain, n\u00e9 et actuel, d\u00e9coulant directement de l\u2019infraction poursuivie. Au vu des d\u00e9veloppements qui pr\u00e9c\u00e8dent, conform\u00e9ment au r\u00e9quisitoire de Monsieur le Procureur d\u2019Etat adjoint du 16 octobre 2015 et par adoption des motifs y expos\u00e9s,<\/p>\n<p>il y a lieu de d\u00e9clarer irrecevable la plainte avec constitution de partie civile d\u00e9pos\u00e9e en date du 24 ao\u00fbt 2015 par Ma\u00eetre Christian BILTGEN, avocat \u00e0 la Cour, au nom et pour le compte de la soci\u00e9t\u00e9 anonyme SOC1.) S.A. et de la soci\u00e9t\u00e9 anonyme SOC2.) S.A. contre la soci\u00e9t\u00e9 S OC3.) s\u00e0rl, A.), g\u00e9rante de la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, la soci\u00e9t\u00e9 de droit belge SOC4.) scrl, B.), g\u00e9rant de la soci\u00e9t\u00e9 SOC4.) scrl, la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, C1.), g\u00e9rant administratif de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl et C2.), g\u00e9rante technique de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, en ce qui concerne les qualifications suivantes :<\/p>\n<p>1. Infractions \u00e0 la loi du 2 septembre 2011 r\u00e9glementant l\u2019acc\u00e8s aux professions d\u2019artisan, de commer\u00e7ant, d\u2019industriel ainsi qu\u2019\u00e0 certaines professions lib\u00e9rales, ainsi qu\u2019aux articles 571-1 et suivants du code du travail, ceci en raison du d\u00e9faut de pr\u00e9judice en relation directe avec lesdites infractions ;<\/p>\n<p>2. Menaces d\u2019attentat pr\u00e9vues \u00e0 l\u2019article 327 du code p\u00e9nal en ce qui concerne le pr\u00e9tendu pr\u00e9judice subi par D.) de ce chef, D.) n\u2019ayant pas d\u00e9pos\u00e9 plainte avec constitution de partie civile en son nom personnel ;<\/p>\n<p>3. Infraction aux articles 1, 3, 82 et 83 de la loi modifi\u00e9e du 18 avril 2001 sur les droits d\u2019auteur, les droits voisins et les bases de donn\u00e9es, ceci en raison du fait que les faits d\u00e9crits ne sont pas imput\u00e9s \u00e0 un\/des auteurs pr\u00e9cis et que le pr\u00e9judice invoqu\u00e9 ne peut \u00eatre qualifi\u00e9 de n\u00e9 et actuel ;<\/p>\n<p>il n\u2019y a pas lieu d\u2019informer contre la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, A.), g\u00e9rante de la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, la soci\u00e9t\u00e9 de droit belge SOC4.) scrl, B.), g\u00e9rant de la soci\u00e9t\u00e9 SOC4.) scrl, la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, C1.), g\u00e9rant administratif de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl et C2.), g\u00e9rante technique de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl du chef des faits vis\u00e9s dans la plainte avec constitution de partie civile d\u00e9pos\u00e9e le 24 ao\u00fbt 2015 par Ma\u00eetre Christian BILTGEN, avocat \u00e0 la Cour, au nom et pour le compte de la soci\u00e9t\u00e9 anonyme SOC1.) S.A. et la soci\u00e9t\u00e9 anonyme SOC2.) S.A. au cabinet d\u2019instruction du tribunal d\u2019arrondissement de et \u00e0 Diekirch en ce qui concerne les qualifications suivantes :<\/p>\n<p>1. Destruction immobili\u00e8re et mobili\u00e8re, ceci en raison du fait qu\u2019un panneau de publicit\u00e9 ne tombe pas sous la qualification de l\u2019article 521 du Code p\u00e9nal et que les faits d\u00e9crits ne tombent pas non plus sous la qualification de l\u2019article 528 du Code p\u00e9nal, C1.) ayant indiqu\u00e9 \u00e0 D.) que le panneau en question se trouvait toujours dans son bureau ; les faits d\u00e9crits ne faisant pas \u00e9tat de faits pr\u00e9cis d\u2019endommagement ou de destruction, ne peuvent ainsi recevoir aucune qualification p\u00e9nale ;<\/p>\n<p>2. Menaces d\u2019attentat pr\u00e9vues \u00e0 l\u2019article 327 du code p\u00e9nal en ce qui concerne le pr\u00e9tendu pr\u00e9judice subi par la soci\u00e9t\u00e9 anonyme SOC1.) S.A. et la soci\u00e9t\u00e9 anonyme SOC2.) S.A. de ce<\/p>\n<p>chef, les propos imput\u00e9s \u00e0 C1.), \u00e0 savoir : \u00ab je vais vous sortir de vos bureaux de toutes avec toutes mes forces \u00bb ne pouvant pas recevoir de qualification p\u00e9nale ;<\/p>\n<p>3. Infraction \u00e0 la loi modifi\u00e9e du 30 juillet 2002 sur certaines pratiques commerciales et la concurrence d\u00e9loyale, les faits d\u00e9crits aux termes de la plainte avec constitution de partie civile ne pouvant recevoir aucune qualification p\u00e9nale ;<\/p>\n<p>4. association form\u00e9e dans le but d\u2019attenter aux personnes ou aux propri\u00e9t\u00e9s, organisation criminelle pr\u00e9vue par les articles 322 et suivants du code p\u00e9nal, les faits d\u00e9crits aux termes de la plainte avec constitution de partie civile ne pouvant recevoir aucune qualification p\u00e9nale.<\/p>\n<p>Par ces motifs<\/p>\n<p>DECLARONS irrecevable la plainte avec constitution de partie civile d\u00e9pos\u00e9e en date du 24 ao\u00fbt 2015 par Ma\u00eetre Christian BILTGEN, avocat \u00e0 la Cour, au nom et pour le compte de la soci\u00e9t\u00e9 anonyme SOC1.) S.A. et la soci\u00e9t\u00e9 anonyme SOC2.) S.A. contre la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, A.), g\u00e9rante de la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, la soci\u00e9t\u00e9 de droit belge SOC4.) scrl, B.), g\u00e9rant de la soci\u00e9t\u00e9 SOC4.) scrl, la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, C1.), g\u00e9rant administratif de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl et C2.), g\u00e9rante technique de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, en ce qui concerne les qualifications suivantes :<\/p>\n<p>1. Infractions \u00e0 la loi du 2 septembre 2011 r\u00e9glementant l\u2019acc\u00e8s aux professions d\u2019artisan, de commer\u00e7ant, d\u2019industriel ainsi qu\u2019\u00e0 certaines professions lib\u00e9rales, ainsi qu\u2019aux articles 571-1 et suivants du code du travail 2. Menaces d\u2019attentat pr\u00e9vues \u00e0 l\u2019article 327 du code p\u00e9nal (en ce qui concerne le pr\u00e9tendu pr\u00e9judice subi par D. ) de ce chef) 3. Infraction aux articles 1, 3, 82 et 83 de la loi modifi\u00e9e du 18 avril 2001 sur les droits d\u2019auteur, les droits voisins et les bases de donn\u00e9es<\/p>\n<p>DISONS qu\u2019il n\u2019y a pas lieu d\u2019informer contre la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, A.), g\u00e9rante de la soci\u00e9t\u00e9 SOC3.) s\u00e0rl, la soci\u00e9t\u00e9 de droit belge SOC4.) scrl, B.), g\u00e9rant de la soci\u00e9t\u00e9 SOC4.) scrl, la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, C1.), g\u00e9rant administratif de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl et C2.), g\u00e9rante technique de la soci\u00e9t\u00e9 SOC5.) s\u00e0rl, E.) et F.) du chef des faits vis\u00e9s dans la plainte avec constitution de partie civile d\u00e9pos\u00e9e le 24 ao\u00fbt 2015 par Ma\u00eetre Christian BILTGEN, avocat \u00e0 la Cour, au nom et pour le compte de la soci\u00e9t\u00e9 anonyme SOC1.) S.A. et la soci\u00e9t\u00e9 anonyme SOC2.) S.A. au cabinet d\u2019instruction du tribunal d\u2019arrondissement de et \u00e0 Diekirch en ce qui concerne les qualifications suivantes :<\/p>\n<p>1. Destruction immobili\u00e8re et mobili\u00e8re 2. Menaces d\u2019attentat pr\u00e9vues \u00e0 l\u2019article 327 du code p\u00e9nal (en ce qui concerne le pr\u00e9tendu pr\u00e9judice subi par la s oci\u00e9t\u00e9 anonyme SOC1.) S.A. et la soci\u00e9t\u00e9 anonyme SOC2.) S.A. de ce chef) 3. Infraction \u00e0 la loi modifi\u00e9e du 30 juillet 2002 sur certaines pratiques commerciales et la concurrence d\u00e9loyale 4. association form\u00e9e dans le but d\u2019attenter aux personnes ou aux propri\u00e9t\u00e9s, organisation criminelle pr\u00e9vue par les articles 322 et suivants du code p\u00e9nal ORDONNONS la notification de la pr\u00e9sente ordonnance \u00e0 la soci\u00e9t\u00e9 anonyme SOC1.) S.A. et \u00e0 la soci\u00e9t\u00e9 anonyme SOC2.) S.A. ;<\/p>\n<p>Ainsi fait au cabinet d\u2019instruction \u00e0 Diekirch, date qu\u2019en t\u00eate.<\/p>\n<p>Le Juge d\u2019Instruction Claudine DE LA HAMETTE<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-du-conseil\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-du-conseil\/20240808-130622\/20160223-cachaco-142a-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arr\u00eat n\u00b0 142\/16 Ch.c.C. du 23 f\u00e9vrier 2016. (Not. : 4274\/15\/XD) La chambre du conseil de la Cour d&#8217;appel du Grand- Duch\u00e9 de Luxembourg a rendu le vingt-trois f\u00e9vrier deux mille seize l&#8217;arr\u00eat qui suit: Vu l\u2019ordonnance de non- informer rendue le 11 d\u00e9cembre 2015\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[23318],"kji_year":[61603],"kji_subject":[7724],"kji_keyword":[8683,8457,9055,12307],"kji_language":[7733],"class_list":["post-851800","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-du-conseil","kji_year-61603","kji_subject-civil","kji_keyword-arret","kji_keyword-fevrier","kji_keyword-justice","kji_keyword-superieure","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016\" \/>\n<meta property=\"og:description\" content=\"Arr\u00eat n\u00b0 142\/16 Ch.c.C. du 23 f\u00e9vrier 2016. (Not. : 4274\/15\/XD) La chambre du conseil de la Cour d&#039;appel du Grand- Duch\u00e9 de Luxembourg a rendu le vingt-trois f\u00e9vrier deux mille seize l&#039;arr\u00eat qui suit: Vu l\u2019ordonnance de non- informer rendue le 11 d\u00e9cembre 2015\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T22:17:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"36 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-23-fevrier-2016\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-23-fevrier-2016\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-06T22:17:28+00:00\",\"dateModified\":\"2026-05-06T22:17:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-23-fevrier-2016\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-23-fevrier-2016\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-23-fevrier-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/","og_locale":"ru_RU","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016","og_description":"Arr\u00eat n\u00b0 142\/16 Ch.c.C. du 23 f\u00e9vrier 2016. (Not. : 4274\/15\/XD) La chambre du conseil de la Cour d'appel du Grand- Duch\u00e9 de Luxembourg a rendu le vingt-trois f\u00e9vrier deux mille seize l'arr\u00eat qui suit: Vu l\u2019ordonnance de non- informer rendue le 11 d\u00e9cembre 2015\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-06T22:17:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"36 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/","name":"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-06T22:17:28+00:00","dateModified":"2026-05-06T22:17:33+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-23-fevrier-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 23 f\u00e9vrier 2016"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/851800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=851800"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=851800"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=851800"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=851800"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=851800"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=851800"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=851800"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=851800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}