{"id":878234,"date":"2026-05-11T00:22:54","date_gmt":"2026-05-10T22:22:54","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/"},"modified":"2026-05-11T00:22:58","modified_gmt":"2026-05-10T22:22:58","slug":"cour-superieure-de-justice-12-mars-2015-n-0312-40215","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Exempt &#8212; appel en mati\u00e8re de droit du travail.<\/p>\n<p>Audience publique du douze mars deux mille quinze.<\/p>\n<p>Num\u00e9ro 40215 du r\u00f4le<\/p>\n<p>Composition: Carlo HEYARD, pr\u00e9sident de chambre, Ria LUTZ, premier conseiller, Th\u00e9a HARLES-WALCH, premier conseiller, Isabelle HIPPERT, greffier.<\/p>\n<p>E n t r e :<\/p>\n<p>la soci\u00e9t\u00e9 anonyme A S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L-(\u2026), repr\u00e9sent\u00e9e par son conseil d\u2019administration actuellement en fonctions,<\/p>\n<p>appelante aux termes d\u2019un exploit de l\u2019huissier de justice Gilles HOFFMANN d\u2019Esch-sur-Alzette du 28 mai 2013,<\/p>\n<p>intim\u00e9e sur appel incident,<\/p>\n<p>comparant par Ma\u00eetre Aur\u00e9lia FELTZ , avocat \u00e0 la Cour \u00e0 Luxembourg,<\/p>\n<p>e t :<\/p>\n<p>B, demeurant \u00e0 F-(\u2026),<\/p>\n<p>intim\u00e9 aux fins du susdit exploit HOFFMANN,<\/p>\n<p>appelant par incident,<\/p>\n<p>comparant par Ma\u00eetre Franck FARJAUDON, avocat \u00e0 la Cour \u00e0 Luxembourg.<\/p>\n<p>2 LA COUR D&#039;APPEL:<\/p>\n<p>Vu l\u2019ordonnance de cl\u00f4ture de l\u2019instruction du 14 octobre 2014.<\/p>\n<p>Ou\u00ef le magistrat de la mise en \u00e9tat en son rapport oral \u00e0 l\u2019audience.<\/p>\n<p>Par requ\u00eate du 5 avril 2012, B fit convoquer son ancien employeur, la soci\u00e9t\u00e9 anonyme A, ci-apr\u00e8s A en abr\u00e9g\u00e9, devant le tribunal du travail pour lui r\u00e9clamer suite \u00e0 ses deux licenciements qu\u2019il qualifia d\u2019abusifs, diff\u00e9rents montants indemnitaires plus amplement d\u00e9taill\u00e9s dans la pr\u00e9dite requ\u00eate.<\/p>\n<p>Au service de A en tant que plaquiste depuis le 6 janvier 2011, B fut licenci\u00e9 avec pr\u00e9avis le 24 mai 2011, dispens\u00e9 de travailler pendant le pr\u00e9avis en date du 26 mai 2011 pour ensuite \u00eatre licenci\u00e9 avec effet imm\u00e9diat le 30 mai 2011, en raison de trois absences sur chantier en dates des 25, 26 et 27 mai 2011 et pour avoir \u00e9t\u00e9 le 30 mai 2011, au caf\u00e9, pendant les heures de service, en \u00e9tat d\u2019\u00e9bri\u00e9t\u00e9.<\/p>\n<p>Les motifs du licenciement avec pr\u00e9avis lui furent communiqu\u00e9s suite \u00e0 sa demande par lettre recommand\u00e9e du 1er juillet 2011, ces motifs ayant trait \u00e0 des fautes professionnelles commises sur plusieurs chantiers.<\/p>\n<p>Le salari\u00e9 contesta tant la pr\u00e9cision que la r\u00e9alit\u00e9 et la gravit\u00e9 des motifs libell\u00e9s \u00e0 l\u2019appui des deux licenciements.<\/p>\n<p>Par jugement du 17 avril 2013 le tribunal du travail a d\u00e9clar\u00e9 irrecevable l\u2019offre de preuve de la soci\u00e9t\u00e9 anonyme A S.A. en ce qu\u2019elle a trait aux motifs du licenciement avec effet imm\u00e9diat ; a d\u00e9clar\u00e9 abusif le licenciement avec effet imm\u00e9diat intervenu \u00e0 l\u2019\u00e9gard de B le 30 mai 2011 ; a d\u00e9clar\u00e9 non fond\u00e9e la demande de B en paiement d\u2019une indemnit\u00e9 compensatoire de cong\u00e9 non pris ; a d\u00e9clar\u00e9 fond\u00e9e la demande de B en paiement d\u2019une indemnit\u00e9 compensatoire de pr\u00e9avis \u00e0 concurrence de 5.536.- euros ; a condamn\u00e9 la soci\u00e9t\u00e9 anonyme A S.A. \u00e0 payer \u00e0 B le montant de 5.536.- euros avec les int\u00e9r\u00eats l\u00e9gaux \u00e0 partir du 5 avril 2012, jusqu\u2019\u00e0 solde ; a dit que le taux d\u2019int\u00e9r\u00eat sera major\u00e9 de trois points \u00e0 l\u2019expiration d\u2019un d\u00e9lai de trois mois \u00e0 compter de la notification du pr\u00e9sent jugement ; a d\u00e9clar\u00e9 non fond\u00e9e la demande de B en ex\u00e9cution provisoire de la condamnation au paiement d\u2019une indemnit\u00e9 compensatoire de pr\u00e9avis ; avant tout autre progr\u00e8s en cause, a admis la soci\u00e9t\u00e9 anonyme A S.A. \u00e0 prouver par l\u2019audition de trois t\u00e9moins diff\u00e9rents faits \u00e0 la base du licenciement.<\/p>\n<p>Pour statuer comme il l\u2019a fait, le tribunal du travail, apr\u00e8s avoir rappel\u00e9 le principe selon lequel en pr\u00e9sence de deux licenciements, intervenus cons\u00e9cutivement, le premier avec pr\u00e9avis et le second avec effet imm\u00e9diat, il y avait lieu d\u2019examiner la<\/p>\n<p>3 r\u00e9gularit\u00e9 des deux licenciements, chacun des licenciements intervenus \u00e9tant susceptible d\u2019avoir caus\u00e9 un pr\u00e9judice sp\u00e9cifique, a analys\u00e9 en premier lieu la r\u00e9gularit\u00e9 du licenciement avec effet imm\u00e9diat, qui a d\u00e9finitivement mis fin \u00e0 la relation de travail.<\/p>\n<p>Le tribunal du travail a ensuite d\u00e9cid\u00e9 que les motifs du pr\u00e9dit licenciement sont r\u00e9dig\u00e9s de fa\u00e7on pr\u00e9cise, mais que la gravit\u00e9 des faits reproch\u00e9s au salari\u00e9 ne justifiait pas un tel licenciement. A cet \u00e9gard la motivation est la suivante : \u00ab Il r\u00e9sulte du dossier que le 26 mai 2011, l\u2019employeur a envoy\u00e9 au requ\u00e9rant un courrier le dispensant avec effet imm\u00e9diat de travailler. M\u00eame si, au vu des pi\u00e8ces de la partie d\u00e9fenderesse, le requ\u00e9rant n\u2019a accus\u00e9 r\u00e9ception du courrier du 26 mai 2011 que le 28 mai 2011 et qu\u2019il n\u2019est pas \u00e9tabli que le requ\u00e9rant ait eu connaissance de la dispense de travail avant le 28 mai 2011, la partie d\u00e9fenderesse est mal venue \u00e0 qualifier de faute grave les d\u00e9parts pr\u00e9matur\u00e9s du requ\u00e9rant du chantier \u00e0 des dates o\u00f9, suivant les termes de son courrier du 26 mai 2011, elle ne souhaitait plus sa pr\u00e9sence sur le lieu de travail. Quant \u00e0 l\u2019absence injustifi\u00e9e du requ\u00e9rant en date du 25 mai 2011, veille de la notification de la dispense de travail, elle ne saurait, \u00e0 elle seule, constituer un fait suffisamment grave pour justifier le licenciement avec effet imm\u00e9diat intervenu. \u00bb<\/p>\n<p>Quant au licenciement avec pr\u00e9avis, dont il a analys\u00e9 la r\u00e9gularit\u00e9 par la suite, le tribunal a retenu pour partie le caract\u00e8re pr\u00e9cis des motifs \u00e9nonc\u00e9s et il a ensuite admis avant tout autre progr\u00e8s en cause l\u2019employeur \u00e0 prouver par t\u00e9moins les faits formul\u00e9s dans l\u2019offre preuve ci-avant reprise.<\/p>\n<p>La soci\u00e9t\u00e9 A SA a r\u00e9guli\u00e8rement relev\u00e9 appel du pr\u00e9dit jugement par acte de l\u2019huissier de justice Gilles HOFFMANN d\u2019Esch-sur-Alzette du 28 mai 2013.<\/p>\n<p>L\u2019appelante demande de d\u00e9clarer son appel fond\u00e9 et, par r\u00e9formation du jugement, de dire que chacun des faits reproch\u00e9s au salari\u00e9 dans la lettre de licenciement avec effet imm\u00e9diat constitue \u00e0 lui seul un motif suffisamment grave pour justifier le renvoi imm\u00e9diat du salari\u00e9, partant de d\u00e9clarer le licenciement avec effet imm\u00e9diat justifi\u00e9 et r\u00e9gulier et de la d\u00e9charger des condamnations intervenues \u00e0 son encontre en premi\u00e8re instance.<\/p>\n<p>Elle soutient que la dispense de travail accord\u00e9e au salari\u00e9 le 26 mai 2011 n\u2019a pu produire des effets qu\u2019\u00e0 partir du 28 mai 2011, de sorte qu\u2019elle ne peut constituer une justification aux absences du salari\u00e9 du chantier les 25, 26 mai 2011 et \u00e0 son d\u00e9part pr\u00e9matur\u00e9 le 27 mai 2011, comportement qui constitue d\u2019apr\u00e8s elle bien un acte d\u2019insubordination justifiant le deuxi\u00e8me licenciement sans pr\u00e9avis.<\/p>\n<p>Elle formule encore une offre preuve par t\u00e9moins aux fins de prouver la r\u00e9alit\u00e9 des motifs gisant \u00e0 la base du licenciement avec effet imm\u00e9diat.<\/p>\n<p>4 Concernant le licenciement avec pr\u00e9avis, l\u2019appelante fait grief aux juges de premi\u00e8re instance d\u2019avoir rejet\u00e9 le motif tenant \u00e0 l\u2019attitude agressive et mena\u00e7ante du requ\u00e9rant \u00e0 l\u2019\u00e9gard de ses coll\u00e8gues de travail pour \u00eatre impr\u00e9cis et demande \u00e0 ce qu\u2019il soit d\u00e9clar\u00e9 pr\u00e9cis et retenu dans l\u2019offre de preuve.<\/p>\n<p>L\u2019intim\u00e9 rel\u00e8ve appel incident du jugement en ce qu\u2019il a d\u00e9cid\u00e9 que l\u2019\u00e9nonciation des motifs contenus dans la lettre de cong\u00e9diement avec effet imm\u00e9diat du 30 mai 2011 est suffisamment pr\u00e9cise.<\/p>\n<p>Subsidiairement, il conteste toute absence non justifi\u00e9e sur les chantiers et conclut \u00e0 la confirmation du jugement par adoption de ses motifs.<\/p>\n<p>Il interjette encore appel incident de la d\u00e9cision prise relative \u00e0 l\u2019indemnit\u00e9 de cong\u00e9s non pris qu\u2019il r\u00e9clame \u00e0 nouveau en instance d\u2019appel.<\/p>\n<p>Chacune des parties r\u00e9clame une indemnit\u00e9 de proc\u00e9dure sur base de l\u2019article 240 du NCPC.<\/p>\n<p>Il y a lieu de rappeler que le salari\u00e9 fut licenci\u00e9 avec pr\u00e9avis le 24 mai 2011, dispens\u00e9 de travailler deux jours plus tard, soit le 26 mai 2011, finalement, licenci\u00e9 avec effet imm\u00e9diat le 30 mai 2011.<\/p>\n<p>Les motifs gisant \u00e0 la base du licenciement avec effet imm\u00e9diat ayant d\u00e9finitivement mis fin \u00e0 la relation de travail en date du 30 mai 2011 sont de la teneur suivante :<\/p>\n<p>\u00ab Monsieur, Nous avons constat\u00e9 vos absences sur le chantier les mercredi 25 et jeudi 26 mai 2011 \u00e0 partir de 13heures 30. De plus, le vendredi 27 mai, vous avez quitt\u00e9 le chantier \u00e0 11heures 30. Ce jour m\u00eame, nous vous avons pris en flagrant d\u00e9lit au caf\u00e9 pendant vos heures de service en \u00e9tat d\u2019\u00e9bri\u00e9t\u00e9. Nous avons \u00e9t\u00e9 contraints de reprendre le v\u00e9hicule car vous n\u2019\u00e9tiez plus en mesure de conduire. Ce qui constitue une faute grave. De ce fait, ainsi que la loi nous y autorise, nous vous communiquons votre licenciement pour faute grave. (\u2026). \u00bb<\/p>\n<p>Le salari\u00e9, qui interjette appel incident, fait grief \u00e0 la juridiction du travail d\u2019avoir d\u00e9cid\u00e9 que les motifs invoqu\u00e9s \u00e0 l\u2019appui du susdit licenciement r\u00e9pondent au caract\u00e8re de pr\u00e9cision requis par la loi et la jurisprudence.<\/p>\n<p>Or, dans la mesure o\u00f9 les griefs querell\u00e9s d\u2019impr\u00e9cis, tels que r\u00e9dig\u00e9s dans le courrier de licenciement, permettent \u00e0 B d\u2019en appr\u00e9cier la nature et la port\u00e9e et de prouver le cas \u00e9ch\u00e9ant la fausset\u00e9 et aux juridictions du travail de v\u00e9rifier que les motifs s\u2019identifient \u00e0 ceux analys\u00e9s en cours de proc\u00e9dure, les motifs ont \u00e9t\u00e9 indiqu\u00e9s avec suffisamment de pr\u00e9cision, de sorte que ce moyen est \u00e0 \u00e9carter et le jugement \u00e0 confirmer sur ce point.<\/p>\n<p>L\u2019appelante reproche au tribunal du travail d\u2019avoir qualifi\u00e9 le licenciement d\u2019abusif en consid\u00e9rant, eu \u00e9gard \u00e0 la dispense de travail accord\u00e9e au salari\u00e9 le 26 mai 2011, qu\u2019elle serait malvenue de consid\u00e9rer le comportement de ce dernier \u00e0 partir de cette date comme \u00e9tant d\u2019une gravit\u00e9 suffisante pour justifier un licenciement sans pr\u00e9avis, d\u00e8s lors qu\u2019en le dispensant de travailler, elle a manifest\u00e9 le souhait de ne plus avoir sa pr\u00e9sence sur le lieu de travail.<\/p>\n<p>Elle soutient que cette mise \u00e0 pied notifi\u00e9e le 26 mai 2011 n\u2019a pu produire des effets qu\u2019\u00e0 partir du 28 mai 2011 au plus t\u00f4t, de sorte que le salari\u00e9, dont les obligations restent les m\u00eames pendant la p\u00e9riode de pr\u00e9avis, ne pouvait se comporter les 25, 26 et 27 mai 2911 comme s\u2019il avait d\u00e9j\u00e0 \u00e9t\u00e9 dispens\u00e9 de travailler.<\/p>\n<p>Par adoption des motifs du tribunal du travail qui a de fa\u00e7on judicieuse retenu d\u2019une part que \u00ab M\u00eame si, au vu des pi\u00e8ces de la partie d\u00e9fenderesse, le requ\u00e9rant n\u2019a accus\u00e9 r\u00e9ception du courrier du 26 mai 2011 que le 28 mai 2011 et qu\u2019il n\u2019est pas \u00e9tabli que le requ\u00e9rant a eu connaissance de la dispense de travail avant le 28 mai 2011, la partie d\u00e9fenderesse est mal venue \u00e0 qualifier de faute grave les d\u00e9parts pr\u00e9matur\u00e9s du requ\u00e9rant du chantier \u00e0 des dates o\u00f9, suivant les termes de son courrier du 26 mai 2011, elle ne souhaitait plus sa pr\u00e9sence sur le lieu de travail \u00bb, et, d\u2019autre part, que \u00ab quant \u00e0 l\u2019absence injustifi\u00e9e du requ\u00e9rant en date du 25 mai 2011 , veille de la notification de la dispense de travail, elle ne saurait, \u00e0 elle seule, constituer un fait suffisamment grave pour justifier le licenciement avec effet imm\u00e9diat intervenu \u00bb, le jugement d\u00e9f\u00e9r\u00e9 est \u00e0 confirmer sur ce point.<\/p>\n<p>Par ailleurs et dans la mesure o\u00f9 le 30 mai 2011, soit le jour o\u00f9 le licenciement avec effet imm\u00e9diat a \u00e9t\u00e9 prononc\u00e9 par l\u2019employeur, le salari\u00e9 b\u00e9n\u00e9ficiait de la dispense de travail, l\u2019employeur ne pouvait plus justifier le licenciement par le comportement du salari\u00e9 ce jour-l\u00e0, soit par le fait qu\u2019il a \u00e9t\u00e9 trouv\u00e9 en \u00e9tat d\u2019\u00e9bri\u00e9t\u00e9 au caf\u00e9,<\/p>\n<p>Au vu du caract\u00e8re abusif du licenciement avec effet imm\u00e9diat, c\u2019est encore \u00e0 bon droit que le tribunal du travail a allou\u00e9 au salari\u00e9, conform\u00e9ment \u00e0 l\u2019article L.124- 6 du code du travail, une indemnit\u00e9 compensatoire de pr\u00e9avis de deux mois, correspondant, d\u2019apr\u00e8s les fiches de salaires vers\u00e9es, \u00e0 un montant de 2 x 173&#215;16, soit 5.536,euros.<\/p>\n<p>Le jugement est partant \u00e0 confirmer \u00e0 cet \u00e9gard.<\/p>\n<p>Par adoption des motifs du tribunal du travail qui a correctement relev\u00e9 que le contrat de travail avait d\u00e9finitivement pris fin le 30 mai 2011, le salari\u00e9 ne pouvait pr\u00e9tendre \u00e0 une indemnit\u00e9 de cong\u00e9 non pris pour la p\u00e9riode post\u00e9rieure, soit pour la p\u00e9riode de pr\u00e9avis non respect\u00e9, m\u00eame s\u2019il s\u2019est vu attribuer une indemnit\u00e9 compensatoire de pr\u00e9avis de deux mois, le jugement est \u00e0 confirmer sur ce point.<\/p>\n<p>Dans la mesure o\u00f9 la juridiction de premi\u00e8re instance a, en ce qui concerne le licenciement avec pr\u00e9avis, seulement ordonn\u00e9 dans le dispositif une mesure d\u2019instruction, l\u2019appel imm\u00e9diat dirig\u00e9 par l\u2019employeur contre la d\u00e9cision n\u2019est pas recevable.<\/p>\n<p>N\u2019ayant pas \u00e9tabli en quoi il serait in\u00e9quitable de laisser \u00e0 leur charge une partie des frais non compris dans les d\u00e9pens, les demandes respectives des parties bas\u00e9es sur l\u2019article 240 du NCPC sont \u00e0 rejeter.<\/p>\n<p>PAR CES MOTIFS :<\/p>\n<p>la Cour d\u2019appel, troisi\u00e8me chambre, si\u00e9geant en mati\u00e8re de droit du travail, statuant contradictoirement, sur le rapport oral du magistrat de la mise en \u00e9tat,<\/p>\n<p>d\u00e9clare les appels principal et incident dirig\u00e9s contre le chef du jugement relatif au licenciement avec effet imm\u00e9diat recevables<\/p>\n<p>les dit non fond\u00e9s,<\/p>\n<p>partant confirme le jugement entrepris,<\/p>\n<p>d\u00e9clare l\u2019appel dirig\u00e9 contre le chef du jugement ayant trait au licenciement avec pr\u00e9avis irrecevable,<\/p>\n<p>rejette les demandes des parties bas\u00e9es sur l\u2019article 240 du NCPC,<\/p>\n<p>condamne l\u2019employeur aux frais de l\u2019instance.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-3\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-3\/20240827-143216\/20150312-40215-arret-a-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Exempt &#8212; appel en mati\u00e8re de droit du travail. Audience publique du douze mars deux mille quinze. Num\u00e9ro 40215 du r\u00f4le Composition: Carlo HEYARD, pr\u00e9sident de chambre, Ria LUTZ, premier conseiller, Th\u00e9a HARLES-WALCH, premier conseiller, Isabelle HIPPERT, greffier. E n t r e : la\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[15890],"kji_year":[78562],"kji_subject":[7724],"kji_keyword":[13671,27837,9055,16636,12307],"kji_language":[7733],"class_list":["post-878234","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-3","kji_year-78562","kji_subject-civil","kji_keyword-appel","kji_keyword-exempt","kji_keyword-justice","kji_keyword-matiere","kji_keyword-superieure","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215\" \/>\n<meta property=\"og:description\" content=\"Exempt - appel en mati\u00e8re de droit du travail. Audience publique du douze mars deux mille quinze. Num\u00e9ro 40215 du r\u00f4le Composition: Carlo HEYARD, pr\u00e9sident de chambre, Ria LUTZ, premier conseiller, Th\u00e9a HARLES-WALCH, premier conseiller, Isabelle HIPPERT, greffier. E n t r e : la\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T22:22:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 \u043c\u0438\u043d\u0443\u0442\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\"},\"datePublished\":\"2026-05-10T22:22:54+00:00\",\"dateModified\":\"2026-05-10T22:22:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/","og_locale":"ru_RU","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215","og_description":"Exempt - appel en mati\u00e8re de droit du travail. Audience publique du douze mars deux mille quinze. Num\u00e9ro 40215 du r\u00f4le Composition: Carlo HEYARD, pr\u00e9sident de chambre, Ria LUTZ, premier conseiller, Th\u00e9a HARLES-WALCH, premier conseiller, Isabelle HIPPERT, greffier. E n t r e : la\u2026","og_url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-10T22:22:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"11 \u043c\u0438\u043d\u0443\u0442"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/","url":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/","name":"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/ru\/#website"},"datePublished":"2026-05-10T22:22:54+00:00","dateModified":"2026-05-10T22:22:58+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/cour-superieure-de-justice-12-mars-2015-n-0312-40215\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/ru\/avocats-en-droit-penal-a-paris-conseil-et-defense-strategique\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/ru\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 12 mars 2015, n\u00b0 0312-40215"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/ru\/#website","url":"https:\/\/kohenavocats.com\/ru\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/ru\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/ru\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision\/878234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/media?parent=878234"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_country?post=878234"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_court?post=878234"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_chamber?post=878234"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_year?post=878234"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_subject?post=878234"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_keyword?post=878234"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/ru\/wp-json\/wp\/v2\/kji_language?post=878234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}