{"id":609069,"date":"2026-04-19T18:29:51","date_gmt":"2026-04-19T16:29:51","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/"},"modified":"2026-04-19T18:29:55","modified_gmt":"2026-04-19T16:29:55","slug":"tribunal-darrondissement-12-mars-2026-n-2025-09383","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 12 mars 2026, n\u00b0 2025-09383"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Jugement commercial 2026TALCH25\/00180 Audience publique dujeudi,douzemarsdeux mille vingt-six. Num\u00e9roTAL-2025-09383du r\u00f4le Composition: Tania CARDOSO, Vice-pr\u00e9sidente; Geraldine HEIN, juge-d\u00e9l\u00e9gu\u00e9e; Serge BERNARD, juge-d\u00e9l\u00e9gu\u00e9; KenBERENS, greffier. E n t r e : la soci\u00e9t\u00e9anonymeSOCIETE1.)SA, \u00e9tablie et ayant son si\u00e8ge social \u00e0L- ADRESSE1.), repr\u00e9sent\u00e9e par sonconseil d\u2019administrationactuellement en fonctions et inscrite au Registre de Commerce et des Soci\u00e9t\u00e9s de Luxembourg sous le num\u00e9ro NUMERO1.), \u00e9lisant domicile en l\u2019\u00e9tude de Ma\u00eetreMa\u00efka SKOROCHOD , avocat \u00e0 la Cour, demeurant \u00e0Esch-sur-Alzette, partiedemanderesse,comparant par Ma\u00eetreMa\u00efka SKOROCHOD ,avocat\u00e0 la Cour, susdite, et: la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.)SARL, \u00e9tablie et ayant son si\u00e8ge social \u00e0 L-ADRESSE2.), repr\u00e9sent\u00e9e par son g\u00e9rant actuellement en fonctions et inscrite au Registre de Commerce et des Soci\u00e9t\u00e9s de Luxembourg sous le num\u00e9roNUMERO2.), partie d\u00e9fenderesse, comparant parMa\u00eetre Emilie BOHN, avocat, en remplacement deMa\u00eetreNicolas BAUER,avocat\u00e0 la Cour,tous deuxdemeurant \u00e0 Luxembourg.<\/p>\n<p>3 F a i t s : Par acte de l\u2019huissier de justiceTom NILLESdemeurant\u00e0Esch-sur-Alzetteen date du29 octobre2025,lademanderesseafait donner assignation\u00e0 lad\u00e9fenderesse \u00e0 compara\u00eetre le vendredi,21novembre2025\u00e0 09.00 heures devant le tribunal d\u2019arrondissement de et \u00e0 Luxembourg, deuxi\u00e8me chambre, si\u00e9geant en mati\u00e8re commerciale, Cit\u00e9 Judiciaire, B\u00e2timent CO, 1 er \u00e9tage, salle CO1.01, pour y entendre statuer sur le m\u00e9rite de la demande contenue dans ledit acte d\u2019huissier ci-apr\u00e8s reproduit :<\/p>\n<p>4 L\u2019affaire fut inscrite sous le num\u00e9roTAL-2025-09383du r\u00f4le pour l\u2019audience publique du21novembre2025devant la deuxi\u00e8me chambre, si\u00e9geant en mati\u00e8re commerciale. La cause fut renvoy\u00e9e devant lavingt-cinqui\u00e8me chambre. L\u2019affaire futde nouveauutilement retenue \u00e0 l\u2019audience du3f\u00e9vrier2026lors de laquelle les d\u00e9bats eurent lieu comme suit : Ma\u00eetreMa\u00efka SKOROCHOD ,mandataire de la partie demanderesse, donna lecture de l\u2019assignation et exposa ses moyens. Ma\u00eetre Emilie BOHN,enremplacement de Ma\u00eetre Nicolas BAUER, mandataire de la partie d\u00e9fenderesse, r\u00e9pliqua et exposa ses moyens. Sur ce, le tribunal prit l\u2019affaire en d\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l\u2019audience publique de ce jour le j u g e m e n t q u i s u i t: Faits Suivant lettre de mission du 3 octobre 2023(ci-apr\u00e8s la \u00abLettre de mission\u00bb), la soci\u00e9t\u00e9 anonymeSOCIETE1.)SA (ci-apr\u00e8s \u00abSOCIETE1.)\u00bb) a \u00e9mis \u00e0 l\u2019attention de la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.)SARL diverses factures portant sur des prestations de service, parmi lesquelles les deux suivantes, pour un montant total de 29.764,80 EUR: -facture n\u00b0 I21121377 du 27 ao\u00fbt 2024 d\u2019un montant de 18.603,-EUR (ci-apr\u00e8s la \u00abFacture du 27 ao\u00fbt 2024\u00bb), -facture n\u00b0 25\/02\/21004512 du 20 f\u00e9vrier 2025 d\u2019un montant de 11.161,80 EUR (ci-apr\u00e8s la \u00abFacture du 20 f\u00e9vrier 2025\u00bb), (ci-apr\u00e8s ensemble les \u00abFactures\u00bb). En date du 11 d\u00e9cembre 2024,SOCIETE1.)a adress\u00e9 un rappel de paiement par courriel \u00e0SOCIETE2.), en y joignant la Facture du 27 ao\u00fbt 2024. En date du 20 d\u00e9cembre 2024, une r\u00e9union s\u2019est tenue entreSOCIETE1.)et SOCIETE2.)pour \u00e9tablir un bilan des prestations r\u00e9alis\u00e9es et de la facturation y aff\u00e9rente. Faute de paiement des Factures,SOCIETE1.)a, en date du 31 mars 2025, par l\u2019interm\u00e9diaire de son mandataire, envoy\u00e9 \u00e0SOCIETE2.)une mise en demeure par courrier recommand\u00e9 avec avis de r\u00e9ception sign\u00e9 le 2 avril 2025. Le montant r\u00e9clam\u00e9 reste actuellement en souffrance.<\/p>\n<p>5 Proc\u00e9dure Par exploit d\u2019huissier de justice du 29 octobre 2025,SOCIETE1.)a fait donner assignation \u00e0SOCIETE2.)\u00e0 compara\u00eetre devant le tribunal d\u2019arrondissement de et \u00e0 Luxembourg, si\u00e9geant en mati\u00e8re commerciale. Pr\u00e9tentions et moyens des parties Aux termes de son assignation,SOCIETE1.)sollicite \u00e0 voir: -condamnerSOCIETE2.)\u00e0 payer \u00e0SOCIETE1.)la somme de 29.764,80 EUR au titre des Factures impay\u00e9es, avec les int\u00e9r\u00eats de retard applicables aux cr\u00e9ances r\u00e9sultant de transactions commerciales en vertu de la loi modifi\u00e9e du 18 avril 2004 relative aux d\u00e9lais de paiement et aux int\u00e9r\u00eats de retard (ci-apr\u00e8s la \u00ab Loi de 2004 \u00bb) \u00e0 compter de la date d\u2019\u00e9ch\u00e9ance respective des Factures, sinon du 11 d\u00e9cembre 2024, sinon du 2 avril 2025, sinon \u00e0 partir de la demande en justice, jusqu\u2019\u00e0 solde ; -condamnerSOCIETE2.)\u00e0 payer \u00e0SOCIETE1.)la somme de 1.500,-EUR au titre de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile; -ordonner l\u2019ex\u00e9cution provisoire sans caution du pr\u00e9sent jugement; -condamnerSOCIETE2.)aux frais et d\u00e9pens de l\u2019instance. A l\u2019appui de sa demande de paiement au titre des Factures,SOCIETE1.)fait valoir que ni la Facture du 27 ao\u00fbt 2024, ayant pour objet un acompte sur les prestations d\u00e9j\u00e0 r\u00e9alis\u00e9es en 2024, ni la Facture du 20 f\u00e9vrier 2025, relative \u00e0 des prestations r\u00e9alis\u00e9es d\u2019octobre 2024 \u00e0 janvier 2025, n\u2019ont fait l\u2019objet de la moindre contestation s\u00e9rieuse end\u00e9ans un bref d\u00e9lai de la part deSOCIETE2.). Se fondant sur le d\u00e9tail des prestations du 1 er novembre 2023 au 30 septembre 2024, qui aurait \u00e9t\u00e9 communiqu\u00e9 \u00e0SOCIETE2.)pendant la r\u00e9union du 20 d\u00e9cembre 2024, puis par courriel du 28 janvier 2025,SOCIETE1.)donne \u00e0 consid\u00e9rer que, pour les 312,40 heures prest\u00e9es, dont celles objet de la Facture du 27 ao\u00fbt 2024, il reste encore un solde \u00e0 facturer de 27.088,-EUR sur un total de 50.088,-EUR. Se fondant sur le d\u00e9tail des prestations du 1 er octobre 2024 au 21 f\u00e9vrier 2025, SOCIETE1.)affirme que, pour les 170,95 heures prest\u00e9es, dont celles objet de la Facture du 20 f\u00e9vrier 2025, il reste encore un solde \u00e0 facturer de 25.245,75 EUR sur un total de 34.245,75 EUR. A ce titre,SOCIETE1.)fait valoir qu\u2019elle a, dans un souci de conciliation, propos\u00e9, notamment lors de la r\u00e9union du 20 d\u00e9cembre 2024 ainsi que dans la mise en demeure du 31 mars 2025, d\u2019accorder, en cas de paiement des Factures par SOCIETE2.), un geste commercial de 15.000,-EUR ainsi qu\u2019 un apurement du solde restant \u00e0 facturer pour les prestations r\u00e9alis\u00e9es au 30 septembre 2024. Les Factures n\u2019ayant pas \u00e9t\u00e9 r\u00e9gl\u00e9es, aucun accord amiable n\u2019aurait pu \u00eatre trouv\u00e9.<\/p>\n<p>6 SOCIETE1.)indique ensuite que ce n\u2019est qu\u2019en date du 25 avril 2025 queSOCIETE2.) a \u00e9mis des contestations relatives aux Factures. Ces contestations seraient toutefois tardives. A l\u2019audience des plaidoiries,SOCIETE1.)expose entretenir une relation d\u2019affaires de longue date avecSOCIETE2.)et explique que l\u2019estimation de ses honoraires dans la Lettre de mission\u00e0 un montant compris entre 3.000,-et 6.000,-EUR correspond, d\u2019une part, \u00e0 une estimation annuelle \u00e9tablie par exercice comptable, et, d\u2019autre part, ne couvre que les prestations enlien avec la mission d\u00e9crite dans ladite lettre. Toutes les prestations hors champ contractuel, telles que celles vis\u00e9es par les Factures, n\u2019auraient \u00e9t\u00e9 fournies que sur demande du client et seraient \u00e0 facturer en suppl\u00e9ment, en ce qu\u2019elles exc\u00e9deraient le p\u00e9rim\u00e8tre de la mission initiale et ne sauraient \u00eatre incluses dans l\u2019estimation pr\u00e9cit\u00e9e. Il s\u2019agirait en l\u2019esp\u00e8ce de prestations ne pr\u00eatant pas \u00e0 discussion, la Facture du 20 f\u00e9vrier 2025 se rapportant \u00e0 un contr\u00f4le en mati\u00e8re de TVA sur les ann\u00e9es 2020 \u00e0 2024 et la Facture du 27 ao\u00fbt 2024 concernantun litige avec laSOCIETE3.), laquelle aurait refus\u00e9 de remettre les documents de 2022 indispensables pour l\u2019\u00e9tablissement de la comptabilit\u00e9 de 2023 et obligeantSOCIETE1.)ainsi \u00e0 refaire la comptabilit\u00e9 deSOCIETE2.)de 2022. Les parties se seraient m\u00eame mises d\u2019accord pour que le contr\u00f4le TVA se d\u00e9roule dans les locaux deSOCIETE1.). Un accompagnement consid\u00e9rable aurait \u00e9t\u00e9 fourni \u00e0 SOCIETE2.), tel que cela r\u00e9sulterait des d\u00e9tails de prestations fournis et des \u00e9changes de courriels du mois de janvier2025. SOCIETE1.)souligne que, m\u00eame apr\u00e8s l\u2019envoi du d\u00e9tail des prestations \u00e0 SOCIETE2.), cette derni\u00e8re n\u2019a contest\u00e9 ni leur commande, ni leur qualit\u00e9, ni leur quantit\u00e9.SOCIETE2.)serait d\u2019ailleurs en aveu de la r\u00e9alisation de prestations suppl\u00e9mentaires parSOCIETE1.)par rapport \u00e0 celles pr\u00e9vues dans la Lettre de mission, alors qu\u2019elle aurait pay\u00e9 pour celles en lien avec l\u2019ann\u00e9e 2022.SOCIETE2.) aurait aussi, par courriel du 23 janvier 2025, indiqu\u00e9 qu\u2019elle n\u2019aurait jamais dit qu\u2019elle ne payerait pas la Facture du 27 ao\u00fbt 2024. SOCIETE1.)souligne encore, en se fondant sur son courrier du 21 mai 2025, que son tarif horaire moyen ne saurait \u00eatre qualifi\u00e9 d\u2019excessif. En r\u00e9ponse \u00e0SOCIETE2.),SOCIETE1.)soutient que le rappel de paiement du 11 d\u00e9cembre 2024 vaut preuve d\u2019envoi et de r\u00e9ception de la Facture du 27 ao\u00fbt 2024. Ceci serait encore confirm\u00e9 par un courriel du 28 janvier 2025, par lequelSOCIETE1.) a communiqu\u00e9 \u00e0SOCIETE2.)le d\u00e9tail des prestations vis\u00e9es par cette facture d\u2019acompte, document qui aurait d\u00e9j\u00e0 \u00e9t\u00e9 soumis \u00e0SOCIETE2.)lors de la r\u00e9union du 20 d\u00e9cembre 2024. La mise en demeure du 31 mars 2025 prouverait \u00e0 son tour l\u2019envoi et la r\u00e9ception de la Facture du 20 f\u00e9vrier 2025. Quant aux contestations dont se pr\u00e9vautSOCIETE2.), leur teneur ne serait pas \u00e9tablie par la r\u00e9union du 20 d\u00e9cembre 2024. La demande, par courriel du 23 janvier 2025, de la part deSOCIETE2.)du d\u00e9tail des prestations vis\u00e9es par la Facture du 27 ao\u00fbt 2024 ne saurait pas non plus \u00eatre qualifi\u00e9e de contestation s\u00e9rieuse. Dans le courrier du 25 avril 2025 envoy\u00e9 par son mandataire,SOCIETE2.)soul\u00e8verait l\u2019absence de n\u00e9gociation pr\u00e9alable des suppl\u00e9ments, sans n\u00e9anmoins \u00e9mettre de contestations s\u00e9rieuses.<\/p>\n<p>7 S\u2019agissant des amendes \u00e9mises par l&#039;Administration de l&#039;enregistrement, des domaines et de la TVA (ci-apr\u00e8s l\u2019 \u00abAED\u00bb) \u00e0 l\u2019encontre deSOCIETE2.),SOCIETE1.) fait valoir que sa responsabilit\u00e9 ne saurait \u00eatre engag\u00e9e. En effet,SOCIETE2.)ayant elle-m\u00eame mis fin au mandat deSOCIETE1.), cette derni\u00e8re n\u2019aurait plus \u00e9t\u00e9 en charge du d\u00e9p\u00f4t des d\u00e9clarations TVA litigieuses. SOCIETE2.)sollicite \u00e0 voir: -rejeter l\u2019ensemble des pr\u00e9tentions deSOCIETE1.); -condamnerSOCIETE1.)\u00e0 payer\u00e0SOCIETE2.)la somme de 2.000,-EUR au titre de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile. Pour s\u2019opposer \u00e0 la demande en paiement deSOCIETE1.),SOCIETE2.)fait valoir que les Factures sont contest\u00e9es parSOCIETE2.)tant dans leur principe que dans leur quantum. L\u2019article 109 du Code de commerce n\u2019aurait pas vocation \u00e0 s\u2019appliquer, alors que SOCIETE1.)ne prouverait pas la r\u00e9ception parSOCIETE2.)des Factures. En outre, la r\u00e9union du 20 d\u00e9cembre 2024 constituerait une contestation s\u00e9rieuse en temps utile de la Facture du 27 ao\u00fbt 2024. Il en serait de m\u00eame pour le courrier du 25 avril 2025 envoy\u00e9 par son mandataire pour contester les Factures.SOCIETE2.)conclut que les Factures ne sont pas \u00e0 consid\u00e9rer comme des factures accept\u00e9es. SOCIETE2.)soul\u00e8ve par ailleurs que le montant des honoraires deSOCIETE1.) d\u00e9passerait largement le montant annuel de 3.000, -EUR tel que fix\u00e9 contractuellement.SOCIETE1.)resterait en d\u00e9faut de prouver que les prestations litigieuses, engendrant des frais suppl\u00e9mentaires, ont fait l\u2019objet d\u2019une n\u00e9gociation pr\u00e9alable et, partant, d\u2019un accord expr\u00e8s de la part deSOCIETE2.)tel qu\u2019exig\u00e9 par la Lettre de mission. Les factures n\u00b0 I21109823 du 29 novembre 2023 de 3.654,-EUR et n\u00b0 I21117979 du 31 mai 2024 de5.862,20 EUR, soit plus de 9.000,-EUR en l\u2019espace de huit mois, et toutes deux pay\u00e9es parSOCIETE2.), exc\u00e9deraient d\u00e9j\u00e0, \u00e0 elles seules, le montant annuel convenu. Elle pr\u00e9cise qu\u2019elle ne conteste pas l\u2019existence de certaines prestations effectu\u00e9es en dehors du cadre contractuel, mais les montants r\u00e9clam\u00e9s au titre des Factures. Elle soutient en particulier que le taux horaire appliqu\u00e9 parSOCIETE1.)seraitcontestable d\u00e8s lors qu\u2019il n\u2019aurait pas fait l\u2019objet d\u2019une n\u00e9gociation pr\u00e9alable avec elle, contrairement \u00e0 ce qu\u2019exigerait la Lettre de mission. SOCIETE2.)donne \u00e9galement \u00e0 consid\u00e9rer que le geste commercial de 15.000,- EUR, sup\u00e9rieur au montant annuel pr\u00e9vu dans la Lettre de mission, prouve que SOCIETE1.)gonfle artificiellement ses factures. En outre,SOCIETE2.)conteste, pour autant que de besoin, la r\u00e9alit\u00e9 et l\u2019ex\u00e9cution effective des prestations parSOCIETE1.). Les Factures ne pr\u00e9ciseraient en effet pas les prestations qui auraient \u00e9t\u00e9 r\u00e9alis\u00e9es parSOCIETE1.). Les fichiers d\u00e9taillant les prestations, qui n\u2019auraient \u00e9t\u00e9 communiqu\u00e9s parSOCIETE1.)que tardivement, ne<\/p>\n<p>8 rem\u00e9dieraient pas \u00e0 cette insuffisance, d\u00e8s lors qu\u2019ils ne permettraient pas d\u2019\u00e9tablir le lien entre les prestations qui y figurent et les Factures. Enfin, pour d\u00e9montrer que les prestations ont \u00e9t\u00e9 mal ex\u00e9cut\u00e9es, voire non ex\u00e9cut\u00e9es, parSOCIETE1.),SOCIETE2.)invoque trois amendes, de 700,-EUR, 500,-EUR et 200,-EUR, inflig\u00e9es \u00e0 son encontre par l\u2019AED pour non-d\u00e9p\u00f4t de d\u00e9clarations de TVA. Motifs de la d\u00e9cision La demande principale, introduite dans les forme et d\u00e9lai de la loi,est recevable en la pure forme. I.La demande en paiement des Factures Le tribunal rappelle que, suivant l&#039;article 58 du Nouveau Code de proc\u00e9dure civile, \u00abil incombe \u00e0 chaque partie de prouver conform\u00e9ment \u00e0 la loi les faits n\u00e9cessaires au succ\u00e8s de sa pr\u00e9tention\u00bb. L\u2019article 1315 du Code civil pr\u00e9voit que \u00abcelui qui r\u00e9clame l&#039;ex\u00e9cution d&#039;une obligation, doit la prouver. R\u00e9ciproquement, celui qui se pr\u00e9tend lib\u00e9r\u00e9, doit justifier le paiement ou le fait qui a produit l&#039;extinction de son obligation\u00bb. Au vu de ces principes directeurs qui r\u00e9gissent la charge de la preuve, il incombe \u00e0 SOCIETE1.)de prouver l\u2019obligation de paiement au titre des Factures dans le chef de SOCIETE2.). En application de l\u2019article 109 du Code de commerce, les engagements commerciaux peuvent \u00eatre prouv\u00e9s par la facture accept\u00e9e. Cet article instaure une pr\u00e9somption l\u00e9gale, irr\u00e9fragable, de l\u2019existence de la cr\u00e9ance affirm\u00e9e dans la facture accept\u00e9e pour le seul contrat de vente. Pour les autres contrats commerciaux, tel qu\u2019en l\u2019esp\u00e8ce, la facture accept\u00e9e n\u2019engendre qu\u2019une pr\u00e9somption simple de l\u2019existence de la cr\u00e9ance, le juge \u00e9tant libre d\u2019admettre ou de refuser l\u2019acceptation de la facture comme pr\u00e9somption suffisante de l\u2019existence de la cr\u00e9ance affirm\u00e9e (Cour de cassation, 24 janvier 2019, n\u00b0 16\/2019 ; Cour d\u2019appel, 4e chambre, 6 mars 2019, n\u00b0 44848 du r\u00f4le). Le commer\u00e7ant qui n\u2019est pas d\u2019accord au sujet de la facture de son cocontractant doit prendre l\u2019initiative d\u2019\u00e9mettre des protestations pr\u00e9cises valant n\u00e9gation de la dette affirm\u00e9e end\u00e9ans un bref d\u00e9lai \u00e0 partir de la r\u00e9ception de la facture (Cour d\u2019appel,12 juillet 1995, n\u00b0 16844 du r\u00f4le). L\u2019obligation de protester existe quelle que soit la partie de la facture que le client conteste, l\u2019existence m\u00eame du contrat, les conditions du march\u00e9, la date de la facture, l\u2019identit\u00e9 entre les choses fournies et les choses factur\u00e9es, ou bien la conformit\u00e9 de la fourniture avec les qualit\u00e9s promises (Andr\u00e9 CLOQUET, La facture, n\u00b0 446 et suivants). La dur\u00e9e du d\u00e9lai de protestation d\u00e9pend du temps n\u00e9cessaire pour contr\u00f4ler la fourniture ou la prestation, la facture et la concordance entre l\u2019une et l\u2019autre. Il y a lieu<\/p>\n<p>9 \u00e0 cet \u00e9gard de tenir compte de la nature du contrat, de son objet, du comportement r\u00e9ciproque des parties, bref de toutes les circonstances de la cause (Andr\u00e9 CLOQUET, ouvrage pr\u00e9cit\u00e9, n\u00b0 586 et 587). La jurisprudence suivie par les tribunaux luxembourgeois fait tendre ce d\u00e9lai vers la dur\u00e9e d\u2019un mois, qui devrait normalement suffire \u00e0 un commer\u00e7ant diligent pour soigner sa correspondance courante (TAL, 7 juillet 2015, n\u00b0 167775 du r\u00f4le). Or, pour que joue le principe de l\u2019acceptation de la facture, il faut que le client contre lequel il est invoqu\u00e9 ait re\u00e7u la facture. C\u2019est au fournisseur qu\u2019il incombe de rapporter la preuve non seulement qu\u2019il a \u00e9tabli la facture, mais encore qu\u2019il l\u2019aitenvoy\u00e9e et qu\u2019elle est parvenue au client (Andr\u00e9 CLOQUET, ouvrage pr\u00e9cit\u00e9, n\u00b0 405). Si la charge de la preuve de l\u2019envoi de la facture et de la r\u00e9ception de celle-ci par le destinataire incombe au fournisseur, celui-ci peut apporter cette preuve par tous moyens de droit, y compris la pr\u00e9somption (Eric DIRIX et Gabri\u00ebl-Luc BALLON, La facture, Kluwer, n\u00b0 47). En l\u2019esp\u00e8ce,SOCIETE2.)conteste la r\u00e9ception des Factures. Le tribunal constate qu\u2019il ne saurait \u00eatre d\u00e9duit des pi\u00e8ces produites aux d\u00e9bats que les Factures ont \u00e9t\u00e9 r\u00e9ceptionn\u00e9es parSOCIETE2.)\u00e0 une date proche de leur \u00e9mission. Le tribunal rel\u00e8ve toutefois queSOCIETE1.)prouve \u00e0 suffisance la remise de la Facture du 27 ao\u00fbt 2024 \u00e0SOCIETE2.)par le biais du rappel de paiement portant la mention \u00abREMINDER 2\u00bb envoy\u00e9 par courriel du 11 d\u00e9cembre 2024, auquel \u00e9tait annex\u00e9e ladite facture. Quant \u00e0 la remise de la Facture du 20 f\u00e9vrier 2025, elle est \u00e9tablie par la mise en demeure du 31 mars 2025 par courrier recommand\u00e9, d\u00fbment avis\u00e9 le 2 avril 2025, incluant en pi\u00e8ce jointe ladite facture. Ainsi, il y a lieu de retenir que la Facture du 27 ao\u00fbt 2024 a \u00e9t\u00e9 r\u00e9ceptionn\u00e9e par SOCIETE2.)au plus tard le 11 d\u00e9cembre 2024 et la Facture du 20 f\u00e9vrier 2025 au plus tard le2 avril 2025. Pour mettre en \u00e9chec la th\u00e9orie de la facture accept\u00e9e, il appartient \u00e0SOCIETE2.)de rapporter la preuve qu\u2019elle a \u00e9mis des contestations pr\u00e9cises et circonstanci\u00e9es end\u00e9ans un bref d\u00e9lai \u00e0 l\u2019\u00e9gard des Factures. Il est admis que le fait de ne pas \u00e9mettre de contestations end\u00e9ans un bref d\u00e9lai contre une facture permet de pr\u00e9sumer que le client commer\u00e7ant marque son accord sur la facture et ses mentions (Cour d\u2019appel, 4\u00e8me Chambre, 6 mars 2019, n\u00b0 44848 du r\u00f4le). Il y a lieu d\u2019analyser les diff\u00e9rentes factures s\u00e9par\u00e9ment. 1.Quant \u00e0 la Facture du 27 ao\u00fbt 2024 SOCIETE2.)affirme qu\u2019elle a contest\u00e9 la Facture du 27 ao\u00fbt 2024 pendant la r\u00e9union du 20 d\u00e9cembre 2024, ainsi que par courrier du 25 avril 2025.<\/p>\n<p>10 Si la r\u00e9union du 20 d\u00e9cembre 2024 est intervenue end\u00e9ans un bref d\u00e9lai apr\u00e8s la date de r\u00e9ception de la facture parSOCIETE1.), le tribunal constate qu\u2019aucun compte- rendu de r\u00e9union, ni aucun autre document, qui lui permettrait de v\u00e9rifier la r\u00e9alit\u00e9 des contestations invoqu\u00e9es et d\u2019appr\u00e9cier leur teneur, n\u2019est vers\u00e9 aux d\u00e9bats. SOCIETE2.)reste ainsi en d\u00e9faut de prouver qu\u2019elle a \u00e9mis des contestations pr\u00e9cises et circonstanci\u00e9es pour mettre en \u00e9chec l\u2019application du principe de la facture accept\u00e9e tir\u00e9 de l\u2019article 109 du Code de commerce. En ce qui concerne les contestations par courrier du 25 avril 2025, elles sont, quant \u00e0 elles, \u00e0 qualifier de tardives alors qu\u2019elles sont intervenues plus de quatre mois apr\u00e8s la r\u00e9ception de la facture litigieuse. Dans ces conditions, il y a lieu de retenir que le principe de la facture accept\u00e9e trouve application pour la Facture du 27 ao\u00fbt 2024. La Facture du 27 ao\u00fbt 2024 est, d\u00e8s lors, \u00e0 consid\u00e9rer comme facture accept\u00e9e et engendre, en pr\u00e9sence d\u2019un contrat d\u2019entreprise, une pr\u00e9somption simple de la cr\u00e9ance, susceptible d\u2019\u00eatre renvers\u00e9e par la preuve contraire de la part de SOCIETE2.). Cette pr\u00e9somption op\u00e8re donc un renversement de la charge de la preuve en ce qu\u2019il appartient au destinataire, en l\u2019occurrence \u00e0SOCIETE2.), de rapporter la preuve positive que les montants factur\u00e9s ne sont pas dus, que la cr\u00e9ance est \u00e9teinte ou inexistante, respectivement qu\u2019elle n\u2019est pas d\u00e9bitrice de celle-ci, ce pour les motifs qu\u2019il lui appartient d\u2019\u00e9tablir. Pour ce faire,SOCIETE2.)affirme quele montant annuel fix\u00e9 contractuellement pour les prestations deSOCIETE1.)est de 3.000,-EUR. Elle ajoute que les prestations litigieuses d\u00e9passent largement ce montant, sans avoir fait l\u2019objet d\u2019une n\u00e9gociation et donc d\u2019un accord pr\u00e9alable de sa part. En l\u2019esp\u00e8ce, l\u2019article 3 de la Lettre de mission stipule que: \u00abSur base de notre exp\u00e9rience nous estimons nos honoraires pour les prestations d\u00e9crites sous le point 1 compris dans une fourchette annuelle entre 3.000,-\u20ac et 6.000,- \u20ac HT. Si au cours de la mission, des frais suppl\u00e9mentaires devaient \u00eatre engag\u00e9s, ceux-ci seraient n\u00e9goci\u00e9s avec vous sur base de nos tarifs horaires qui varient en fonction des responsabilit\u00e9s de l\u2019exp\u00e9rience du personnel employ\u00e9\u00bb. Il ressort de l\u2019article 1 er de la m\u00eame lettre, quela mission deSOCIETE1.)comprend les prestations suivantes: \u00ab-Tenue des livres comptables et\/ou \u00e9tablissement des comptes annuels et autres reportings l\u00e9gaux (suivant d\u00e9tail donn\u00e9 en annexe 1); -Etablissement des d\u00e9clarations fiscales (suivant d\u00e9tail donn\u00e9 en annexe 2); -Secr\u00e9tariat juridique (suivant d\u00e9tail donn\u00e9 en annexe 3)\u00bb.<\/p>\n<p>11 Par courriel du 23 janvier 2025,SOCIETE1.)a fourni les explications suivantes \u00e0 SOCIETE2.)sur les prestations vis\u00e9es par la Facture du 27 ao\u00fbt 2024 : \u00abD\u2019ailleurs lors de notre r\u00e9union du 20 d\u00e9cembre 2024 je vous avais expliqu\u00e9 de long et de large le d\u00e9tail de nos prestations au 30\/09\/2024 qui \u00e9taient largement li\u00e9es \u00e0 votre litige vous opposant au groupeENSEIGNE1.)et laSOCIETE3.)avec notamment des travaux de recherche et d\u2019investigation n\u00e9cessaires \u00e0 votre avocate Me Cohrs pour pr\u00e9parer votre d\u00e9fense aupr\u00e8s des tribunaux. Toute cette partie importante pour vous r\u00e9sultait dans la reconfection de la comptabilit\u00e9 de l\u2019exercice 2022suite au refus du groupeENSEIGNE1.)\/SOCIETE3.)de nous donner les \u00e9l\u00e9ments n\u00e9cessaires de 2022 \u00e0 la pr\u00e9paration de la compta 2023. (prestations non couvertes dans le budget initial pour l\u2019ann\u00e9e 2023)\u00bb. A ce courriel,SOCIETE2.)a r\u00e9pondu ce qui suitpar courriel du m\u00eame jour : \u00abMais pour faire bref j\u2019ai ne jamais dis non plus que je ne payerais pas?? Envoie-les d\u00e9comptes ainsi que le d\u00e9tails et je m\u2019occuperais de faire les n\u00e9cessaires de mon compte prive\u00bb. En outre, le d\u00e9tail des prestations vers\u00e9 parSOCIETE1.), lequeln\u2019a pas \u00e9t\u00e9 contest\u00e9 parSOCIETE2.), comprendde nombreuses r\u00e9f\u00e9rences \u00e0 \u00ab2022\u00bb, \u00abMe Cohrs\u00bb, \u00abAvocat\u00bb. Au regard de ce qui pr\u00e9c\u00e8de ainsi que des d\u00e9veloppements des parties \u00e0 l\u2019audience des plaidoiries, il est \u00e9tabli que les prestations vis\u00e9es par la Facture du 27 ao\u00fbt 2024 r\u00e9sultent d\u2019un litige opposantSOCIETE2.)\u00e0laSOCIETE3.), laquelle a refus\u00e9 de remettre \u00e0SOCIETE1.)les documents de 2022 indispensables pour l\u2019\u00e9tablissement de la comptabilit\u00e9 de 2023. Ces prestations n\u2019\u00e9tant pas pr\u00e9vues par l\u2019article 1 er de la Lettre de mission, elles sont \u00e0 qualifier de prestations suppl\u00e9mentaires non incluses dans la fourchette annuelle entre 3.000,-EUR et 6.000,-EUR hors TVA. SOCIETE2.)ne saurait ainsi argumenter que laFacture du 27 ao\u00fbt 2024ne serait pas due alors que le montant factur\u00e9 d\u00e9passerait celui pr\u00e9vu par la Lettre de mission. Pour renverser la pr\u00e9somption simple de la cr\u00e9ance,SOCIETE2.)invoque par ailleurs l\u2019absence de n\u00e9gociation pr\u00e9alable des tarifs appliqu\u00e9s parSOCIETE1.)pour les prestations suppl\u00e9mentaires. Le tribunal rappelle que la facture accept\u00e9e \u00e9tablit \u00e0 l\u2019\u00e9gard du d\u00e9biteur commer\u00e7ant non seulement la cr\u00e9ance du fournisseur, mais aussi l\u2019existence du contrat qui sous- tend l\u2019\u00e9mission de la facture et les conditions de celui-ci. Dans la mesure o\u00f9 l\u2019acceptation de la facture constitue une manifestation d\u2019accord au sujet de l\u2019existence et des modalit\u00e9s du contrat et o\u00f9, suivant les d\u00e9veloppements ci- avant, l\u2019obligation de protester existe quelle que soit la partie de la facture quele client conteste, en ce compris la m\u00e9thode de facturation op\u00e9r\u00e9e ou les tarifs mis en compte, il aurait appartenu \u00e0SOCIETE2.)de protester en temps utile, \u00e0 la r\u00e9ception de la Facture du 27 ao\u00fbt 2024.<\/p>\n<p>12 SOCIETE2.)ne saurait d\u00e8s lors se pr\u00e9valoir utilement d\u2019une pr\u00e9tendue facturation par SOCIETE1.)de prestations suppl\u00e9mentaires \u00e0 un taux horaire fix\u00e9 unilat\u00e9ralement, sans respecter les modalit\u00e9s pr\u00e9vues par les stipulations contractuelles convenues entre parties. Les d\u00e9veloppements faits parSOCIETE2.)dans ce contexte manquent partant de pertinence, alors qu\u2019elle aaccept\u00e9, malgr\u00e9la pr\u00e9tendue absence de n\u00e9gociation pr\u00e9alable,la Facture du 27 ao\u00fbt 2024 ainsi que les tarifs et modalit\u00e9s de facturation des prestations suppl\u00e9mentaires, non seulement en gardant le silence apr\u00e8s sa r\u00e9ception, mais encore en envoyant le courriel du 23 janvier 2025pr\u00e9cit\u00e9. Le tribunal souligne en outre que la proposition parSOCIETE1.)d\u2019un geste commercial de 15.000,-EUR, destin\u00e9e \u00e0 encourager le r\u00e8glement des Factures, ne constitue pas, \u00e0 elle seule, un \u00e9l\u00e9ment probant d\u2019un taux horaire excessif ou d\u2019une majoration artificielle des montants factur\u00e9s. SOCIETE2.)met encore en doute la r\u00e9alit\u00e9 et l\u2019ex\u00e9cution effective des prestations par SOCIETE1.), en invoquant un manque de pr\u00e9cision de la Facture du 27 ao\u00fbt 2024. Or, l\u2019ex\u00e9cution des prestations factur\u00e9es parSOCIETE1.)r\u00e9sulte \u00e0 suffisance des pi\u00e8ces produites aux d\u00e9bats, sp\u00e9cialement dutimesheetet des \u00e9changes entre les parties. En outre, le tribunal rel\u00e8ve qu\u2019il ne ressort pas desdites pi\u00e8ces que SOCIETE2.)aurait reproch\u00e9 \u00e0SOCIETE1.)une quelconque inex\u00e9cution. Pour faire \u00e9chec \u00e0 la demande de paiement,SOCIETE2.)fait enfin valoir que SOCIETE1.)n\u2019a pas, voire pas correctement, ex\u00e9cut\u00e9 ses obligations contractuelles alors qu\u2019elle aurait re\u00e7u trois amendes de la part de l\u2019AED pour non-d\u00e9p\u00f4t ou d\u00e9p\u00f4t tardif des d\u00e9clarations de TVA. En l\u2019esp\u00e8ce, il r\u00e9sulte des pi\u00e8ces produites aux d\u00e9bats qu\u2019il s\u2019agit: -d\u2019une fixation d\u2019un acompte provisionnel de 500,-EUR pour non-d\u00e9p\u00f4t de la d\u00e9claration de TVA du mois de novembre 2024; -d\u2019une fixation d\u2019un acompte provisionnel de 200,-EUR pour non-d\u00e9p\u00f4t de la d\u00e9claration de TVA du mois de d\u00e9cembre 2024; et -d\u2019une amende de 700,-EUR pour non-d\u00e9p\u00f4t de la d\u00e9claration de TVA du mois de janvier 2025. Le tribunal constate tout d\u2019abord qu\u2019il s\u2019agit, contrairement \u00e0 ce qui est plaid\u00e9 par SOCIETE2.), d\u2019une seule amende et de deux acomptes provisionnels. Le tribunal observe ensuite que, la facture litigieuse datant du 27 ao\u00fbt 2024, elle ne peut pas porter sur les prestations li\u00e9es aux d\u00e9clarations de TVA de novembre 2024 \u00e0 janvier 2025. Il y a partant lieu de conclure que les contestations actuellement \u00e9mises par SOCIETE2.)ne sont pas de nature \u00e0 renverser la pr\u00e9somption simple d\u2019acceptation de la Facture du 27 ao\u00fbt 2024 et, ainsi, la pr\u00e9somption d\u2019existence de la cr\u00e9ance affirm\u00e9e dans cette facture accept\u00e9e.<\/p>\n<p>13 La demande deSOCIETE1.)visant \u00e0 obtenir le paiement de la Facture du 27 ao\u00fbt 2024 est d\u00e8s lors \u00e0 dire fond\u00e9e, sur base de la th\u00e9orie de la facture accept\u00e9e, pour le montant r\u00e9clam\u00e9 de18.603,-EUR. 2.Quant \u00e0 la Facture du 20 f\u00e9vrier 2025 S\u2019agissant de la Facture du 20 f\u00e9vrier 2025,SOCIETE2.)se pr\u00e9vaut de contestations \u00e9mises dans le courrier du 25 avril 2025, lequel fait express\u00e9ment r\u00e9f\u00e9rence \u00e0 ladite facture et aux termes duquel elle \u00abentend formuler de s\u00e9rieuses contestations quant \u00e0 la r\u00e9gularit\u00e9 et au bien-fond\u00e9 des cr\u00e9ances invoqu\u00e9es\u00bb et reproche \u00e0SOCIETE1.) que \u00ables montants factur\u00e9s exc\u00e8dent tr\u00e8s largement le plafond susmentionn\u00e9\u00bb. Elle y souligne \u00e9galement que \u00abtoute facturation suppl\u00e9mentaire, au-del\u00e0 des montants convenus, doit faire l\u2019objet d\u2019une n\u00e9gociation pr\u00e9alable\u00bb, en reprochant \u00e0SOCIETE1.) \u00abqu\u2019aucune n\u00e9gociation pr\u00e9alable n\u2019a eu lieu pour les prestations suppl\u00e9mentaires factur\u00e9es\u00bb. Elle ajoute que \u00ables prestations ont \u00e9t\u00e9 effectu\u00e9es sans concertation pr\u00e9alable quant \u00e0 leur port\u00e9e, leur n\u00e9cessit\u00e9 ou leur co\u00fbt\u00bb et que \u00ables tarifs horaires appliqu\u00e9s ont \u00e9t\u00e9 unilat\u00e9ralement fix\u00e9s\u00bb. Le tribunal retient que ces contestations deSOCIETE2.), intervenues un peu plus de trois semaines apr\u00e8s la date de r\u00e9ception de la facture, respectent la condition du bref d\u00e9lai. Il r\u00e9sulte du courrier queSOCIETE2.)conteste \u00e0 la fois le co\u00fbt et l\u2019utilit\u00e9 des prestations suppl\u00e9mentaires faisant l\u2019objet de la facture. Plus pr\u00e9cis\u00e9ment, elle conteste le bien-fond\u00e9 des honoraires r\u00e9clam\u00e9s alors qu\u2019ils d\u00e9passent le montant pr\u00e9vu dans la Lettre de mission et se rapportent \u00e0 des prestations r\u00e9alis\u00e9es sans n\u00e9gociation pr\u00e9alable entre les parties, notamment quant au tarif horaire applicable. Le tribunal constate que ces contestations sont suffisamment pr\u00e9cises pour mettre en \u00e9chec l\u2019application du principe de la facture accept\u00e9e d\u00e9duit de l\u2019article 109 du Code de commerce. Dans ces conditions, il y a lieu de retenir que le principe de la facture accept\u00e9e ne trouve pas application pour la Facture du 20 f\u00e9vrier 2025. La demande aff\u00e9rente deSOCIETE1.)doit d\u00e8s lors \u00eatre analys\u00e9e au regard du droit commun des contrats et des r\u00e8gles de preuve \u00e9dict\u00e9es par les articles 58 du Nouveau Code de proc\u00e9dure civile et 1315 du Code civil pr\u00e9cit\u00e9s. En vertu de l\u2019article 1134 du Code civil, les conventions l\u00e9galement form\u00e9es tiennent lieu de loi \u00e0 ceux qui les ont faites et les conventions form\u00e9es doivent \u00eatre ex\u00e9cut\u00e9es de bonne foi. Il s\u2019agit d\u2019un principe g\u00e9n\u00e9ral qui s\u2019applique \u00e0 tous les contrats. En application des pr\u00e9dits articles, il incombe \u00e0SOCIETE1.)de prouver conform\u00e9ment \u00e0 la loi, les actes et faits n\u00e9cessaires au succ\u00e8s de ses pr\u00e9tentions, et plus pr\u00e9cis\u00e9ment le contrat conclu entre parties et les obligations contractuelles qui en d\u00e9coulent.Autrement dit, elle doit rapporter la preuve de la cr\u00e9ance qu\u2019elle all\u00e8gue, sinon de la commande et de l\u2019ex\u00e9cution de la prestation dont elle demande le paiement. En l\u2019esp\u00e8ce, le libell\u00e9 de la Facture du 20 f\u00e9vrier 2025 est notamment le suivant:<\/p>\n<p>14 \u00abNotre assistance pour le contr\u00f4le TVA de la p\u00e9riode 01\/2020 \u00e0 09\/2024 par l\u2019Administration de l\u2019Enregistrement et des Domaines Prestations d\u2019octobre 2024 \u00e0 janvier 2025 R\u00e9union avec M.PERSONNE1.)\u00bb. Pour ces prestations,SOCIETE1.)a factur\u00e9 un montant de 9.000,-EUR hors TVA. Pour rappel, l\u2019article 3 de la Lettre de mission stipule que: \u00abSur base de notre exp\u00e9rience nous estimons nos honoraires pour les prestations d\u00e9crites sous le point 1 compris dans une fourchette annuelle entre 3.000,-\u20ac et 6.000,- \u20ac HT. Si au cours de la mission, des frais suppl\u00e9mentaires devaient \u00eatre engag\u00e9s, ceux-ci seraient n\u00e9goci\u00e9s avec vous sur base de nos tarifs horaires qui varient en fonction des responsabilit\u00e9s de l\u2019exp\u00e9rience du personnel employ\u00e9\u00bb. Il ressort de l\u2019article 1 er de la m\u00eame lettre, quela mission deSOCIETE1.)comprend les prestations suivantes: \u00ab-Tenue des livres comptables et\/ou \u00e9tablissement des comptes annuels et autres reportings l\u00e9gaux (suivant d\u00e9tail donn\u00e9 en annexe 1); -Etablissement des d\u00e9clarations fiscales (suivant d\u00e9tail donn\u00e9 en annexe 2); -Secr\u00e9tariat juridique (suivant d\u00e9tail donn\u00e9 en annexe 3)\u00bb. Il d\u00e9coule de ce qui pr\u00e9c\u00e8de que, conform\u00e9ment aux d\u00e9veloppements de SOCIETE1.), les prestations en lien avec le contr\u00f4le TVA sur les ann\u00e9es 2020 \u00e0 2024 sont des prestations suppl\u00e9mentaires, ne tombant pas dans la fourchette de 3.000,- EUR \u00e0 6.000,-EUR pr\u00e9vue par exercice comptable. Le tribunal constate que le tableau\u00ab timesheet\u00bb, se rapportant \u00e0 la Facture du 20 f\u00e9vrier 2025, d\u00e9montre \u00e0 suffisance que SOCIETE2.)a b\u00e9n\u00e9fici\u00e9 d\u2019un accompagnement important de la part deSOCIETE1.)au niveau du contr\u00f4le TVA et des \u00e9changes subs\u00e9quents avec l\u2019AED et notamment avecMonsieurPERSONNE1.). Le tribunal rel\u00e8ve ensuite qu\u2019aux termes du courrier du 2 avril 2025SOCIETE2.)\u00abne conteste pas qu\u2019un certain nombre de prestations, d\u00e9passant le cadre d\u00e9fini par le contrat de mission, aient \u00e9t\u00e9 r\u00e9alis\u00e9es. C\u2019est pr\u00e9cis\u00e9ment en raison de ces prestations exceptionnelles qu\u2019elle a consenti \u00e0 s\u2019acquitter de paiements suppl\u00e9mentaires\u00bb. De m\u00eame, SOCIETE2.)ne conteste ni avoir demand\u00e9 \u00e0 SOCIETE1.)de l\u2019accompagner au niveau du contr\u00f4le TVA de 2020 \u00e0 2024, ni avoir donn\u00e9 l\u2019accord pour que ce contr\u00f4le se d\u00e9roule dans les locaux deSOCIETE1.). Ainsi,SOCIETE1.)apporte la preuve que les prestations litigieuses exc\u00e8dent le cadre de la mission, de sorte qu\u2019elles ne sont pas couvertes par l\u2019estimation annuelle des honoraires pr\u00e9vus dans la Lettre de mission, et qu\u2019elles ont \u00e9t\u00e9 ex\u00e9cut\u00e9es sur instruction deSOCIETE2.). Ainsi,SOCIETE2.)ne saurait utilement invoquer le r\u00e8glement des factures n\u00b0 I21109823 du 29 novembre 2023 de 3.654,-EUR et n\u00b0 I21117979 du 31 mai 2024 de<\/p>\n<p>15 5.862,20 EUR pour en d\u00e9duire que la fourchette annuelle pr\u00e9vue dans la Lettre de mission aurait d\u00e9j\u00e0 \u00e9t\u00e9 atteinte de sorte que les Factures ne seraient pas dues. Elle ne saurait pas non plus invoquer un manque de pr\u00e9cision de la Facture du 20 f\u00e9vrier 2025 pour remettre en question la r\u00e9alit\u00e9 des prestations deSOCIETE1.), alors que leur ex\u00e9cution effective est \u00e9tablie par la demanderesse. SOCIETE2.)consid\u00e8re encore qu\u2019elle ne devrait supporter pas une facture manifestement excessive en l\u2019absence de toute n\u00e9gociation pr\u00e9alable des tarifs appliqu\u00e9s parSOCIETE1.). A ce titre,SOCIETE1.)fait \u00e0 juste titre valoir qu\u2019\u00e0 la suite de la pr\u00e9sentation, lors de la r\u00e9union du 20 d\u00e9cembre 2024, du d\u00e9tail des prestations relatives \u00e0 la Facture du 27 ao\u00fbt 2024, comprenant notamment les tarifs horaires,SOCIETE2.)n\u2019a formul\u00e9 aucune contestation pr\u00e9cise \u00e0 leur \u00e9gard. Ces \u00e9l\u00e9ments r\u00e9sultent notamment d\u2019un courriel envoy\u00e9 par SOCIETE1.)\u00e0 SOCIETE2.)en date du 21 janvier 2025 et dont la teneur est la suivante : \u00ab3. HonorairesSOCIETE1.)et factures impay\u00e9es Lors de notre r\u00e9union du 20 d\u00e9cembre 2024, je vous avais expliqu\u00e9 en d\u00e9tail nos prestations toutes confondues depuis novembre 2023 \u00e0 septembre 2024 sur base des fichiers interne de production deSOCIETE1.)pourSOCIETE4.)etSOCIETE2.)dont je vous r\u00e9sume encore une fois les points cl\u00e9s tenant en compte notamment un geste commercial de notre part de l\u2019ordre de EUR 15.000 (HTVA par soci\u00e9t\u00e9)\u00bb. Lorsque par courriel du 28 janvier 2025,SOCIETE2.)a demand\u00e9 \u00e0SOCIETE1.)\u00ables factures des prestations avec d\u00e9tails\u00bb,SOCIETE1.)a r\u00e9pondu par courriel de la m\u00eame date : \u00abComme je l\u2019ai expliqu\u00e9 dans le point 3)Honoraires de mon courriel du 21 janvier 2025, il s\u2019agit des prestations encourues de novembre 2023 au 30 septembre 2024 sur base des fichiers internes de productionSOCIETE1.)et que nous avions l\u2019occasion de parcourir ensemble lors de notre r\u00e9union du 20 d\u00e9cembre 2024\u00bb. Le tribunal rel\u00e8ve qu\u2019il ne r\u00e9sulte d\u2019aucun \u00e9l\u00e9ment du dossier, ni des d\u00e9veloppements \u00e0 l\u2019audience des plaidoiries, queSOCIETE2.)aurait contest\u00e9 la pr\u00e9sentation par SOCIETE1.)du d\u00e9tail des prestations lors de la r\u00e9union du 20 d\u00e9cembre 2024. Il est encore relev\u00e9 que ces d\u00e9tails, \u00e9galement produits aux d\u00e9bats, ont \u00e9t\u00e9 fournis parSOCIETE1.)sous forme d\u2019un tableau \u00abtimesheet\u00bb, se rapportant \u00e0 la Facture du 27 ao\u00fbt 2024, pr\u00e9cisant non seulement la date d\u2019ex\u00e9cution et le libell\u00e9 de chaque prestation, mais encore le nom du collaborateur, le temps pass\u00e9, le temps factur\u00e9 et le prix par prestation. Il s\u2019ensuit queSOCIETE2.)a \u00e9t\u00e9 inform\u00e9e, au plus tard \u00e0 cette date, des tarifs horaires appliqu\u00e9es parSOCIETE1.)en fonction de l\u2019exp\u00e9rience du personnel intervenant.<\/p>\n<p>16 Toutefois, il ne r\u00e9sulte d\u2019aucun \u00e9l\u00e9ment soumis \u00e0 l\u2019appr\u00e9ciation du tribunal que SOCIETE2.)ait, par la suite, manifest\u00e9 son d\u00e9saccord aupr\u00e8s deSOCIETE1.)quant auxdits tarifs, ni qu\u2019elle ait demand\u00e9 \u00e0SOCIETE1.)de cesser l\u2019ex\u00e9cution des prestations non comprises dans le champ de mission tel que d\u00e9fini \u00e0 l\u2019article 1 er de la Lettre de mission. Au contraire, il r\u00e9sulte des \u00e9changes de courriels vers\u00e9s au dossier queSOCIETE2.)a, d\u00e8s le d\u00e9but du mois janvier 2025, sollicit\u00e9 de nouvelles prestations aupr\u00e8s deSOCIETE1.). Lestarifs mis en compte parSOCIETE1.)pour des prestations d\u00e9passant le cadre d\u00e9fini \u00e0 l\u2019article 1 er de la Lettre de mission ayant d\u00e8s lors \u00e9t\u00e9 accept\u00e9s parSOCIETE2.) dans le cadre de la Facture du 27 ao\u00fbt 2024, elle ne saurait se pr\u00e9valoir utilement d\u2019une \u00ababsence de toute n\u00e9gociation pr\u00e9alable\u00bb des tarifs appliqu\u00e9s parSOCIETE1.) dans le cadre de la Facture du 20 f\u00e9vrier 2025. SOCIETE2.)reste par ailleurs en d\u00e9faut de prouver en quoi le tarif horaire appliqu\u00e9 parSOCIETE1.)serait excessif par rapport auxtarifs habituellement pratiqu\u00e9s pour le m\u00eame type de prestations de service. En outre,tel que d\u00e9j\u00e0 d\u00e9velopp\u00e9 ci-dessus pour la Facture du 27 ao\u00fbt 2024,la proposition parSOCIETE1.)d\u2019un geste commercial de 15.000,-EUR, destin\u00e9e \u00e0 encourager le r\u00e8glement des Factures, ne constitue, \u00e0 elle seule, un \u00e9l\u00e9ment probant d\u2019un taux horaire excessif ou d\u2019un majoration artificielle des montants factur\u00e9s. Enfin,SOCIETE2.)invoque l\u2019absence, voire la mauvaise ex\u00e9cution des prestations, en se fondant sur des amendes de l\u2019AEDpour non-d\u00e9p\u00f4t de d\u00e9clarations de TVA. Le tribunal rappelle qu\u2019il s\u2019agit, contrairement \u00e0 ce qui est plaid\u00e9 parSOCIETE2.), d\u2019une seule amende et de deux acomptes provisionnels. Le tribunal rel\u00e8ve ensuite qu\u2019il ressort des \u00e9changes de courriels entre les parties que SOCIETE1.)n\u2019avait plus mandat pour d\u00e9poser les d\u00e9clarations TVA en question. Plus pr\u00e9cis\u00e9ment, en date du 22 janvier 2025,SOCIETE2.)a indiqu\u00e9 \u00abpour 2025 la fiduciaire intracommunautaire MR.PERSONNE2.)reprendrait la compta pour les deux soci\u00e9t\u00e9s merci de prendre en consid\u00e9rations et respecter votre mandat afin de cl\u00f4turer et transf\u00e9rer les dossiers en ordre\u00bb. Par courriel du m\u00eame jour,SOCIETE1.) a r\u00e9pondu\u00abvoussavez tr\u00e8s bien que la comptabilit\u00e9 de 2024 n\u2019a pas \u00e9t\u00e9 entam\u00e9e et que la priorit\u00e9 jusqu\u2019\u00e0 la fin de l\u2019ann\u00e9e 2024 \u00e9tait le d\u00e9p\u00f4t des comptes annuels et de la d\u00e9claration fiscale au titre de l\u2019ann\u00e9e 2023. Le mandat de l\u2019ann\u00e9e 2024 n&#039;a pas encore \u00e9t\u00e9 souscrit et le budget fix\u00e9. Sur base de votre courriel je vous prierais donc de demander \u00e9galement \u00e0 la Fiduciaire Intracommunautaire de reprendre la comptabilit\u00e9 de l\u2019exercice 2024\u00bb. Ce moyen invoqu\u00e9 parSOCIETE2.)pour refuser le paiement de la Facture du 20 f\u00e9vrier 2025 est donc \u00e9galement inop\u00e9rant. Au regard des \u00e9l\u00e9ments qui pr\u00e9c\u00e8dent,SOCIETE1.)rapporte la preuve de l\u2019ex\u00e9cution des prestations et du bien-fond\u00e9 de la facture dont elle demande le paiement.<\/p>\n<p>17 Ainsi, la demande deSOCIETE1.)visant \u00e0 obtenir le paiement de la Facture du 20 f\u00e9vrier 2025 est \u00e0 dire fond\u00e9e, sur base du droit commun des contrats, pour le montant r\u00e9clam\u00e9 de11.161,80 EUR. 3.Conclusion Par cons\u00e9quent, la demande deSOCIETE1.)visant \u00e0 obtenir le paiement des Factures est d\u00e8s lors \u00e0 dire fond\u00e9e pour le montant total de 29.764,80 EUR. Il y a lieu de condamnerSOCIETE2.)\u00e0 payer \u00e0SOCIETE1.)la somme de 29.764,80 EUR avec les int\u00e9r\u00eats de retard applicables aux cr\u00e9ances r\u00e9sultant de transactions commerciales, tels que pr\u00e9vus \u00e0 l\u2019article 3 de la Loi de 2004,\u00e0 compter de la date d\u2019\u00e9ch\u00e9ance respective des Factures, soit, conform\u00e9ment aux conditions g\u00e9n\u00e9rales jointes \u00e0 la Lettre de mission, trente jours apr\u00e8s leur date de r\u00e9ception telle que retenue dans le pr\u00e9sent jugement,jusqu\u2019\u00e0 solde. II.Sur les demandes accessoires 1.Sur les demandes au titre des indemnit\u00e9s de proc\u00e9dure En application de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile, le juge condamne la partie tenue aux d\u00e9pens ou qui perd son proc\u00e8s \u00e0 payer \u00e0 l\u2019autre partie la somme qu\u2019il d\u00e9termine, au titre des frais expos\u00e9s et non compris dans les d\u00e9pens. L\u2019application de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile rel\u00e8ve du pouvoir discr\u00e9tionnaire du juge (Cour de cassation 2 juillet 2015, arr\u00eat n\u00b0 60\/15, JTL 2015, n\u00b0 42, page 166). Dans tous les cas, le juge tient compte de l\u2019\u00e9quit\u00e9 ou de la situation \u00e9conomique de la partie condamn\u00e9e. Il peut, m\u00eame d\u2019office, pour des raisons tir\u00e9es des m\u00eames consid\u00e9rations, dire qu\u2019il n\u2019y a pas lieu \u00e0 ces condamnations. En l\u2019esp\u00e8ce, l\u2019\u00e9quit\u00e9 commande de ne pas laisser \u00e0 la charge deSOCIETE1.) l\u2019int\u00e9gralit\u00e9 des frais non compris dans les d\u00e9pens qu\u2019elle a d\u00fb exposer afin de faire valoir ses droits en justice. Eu \u00e9gard aux \u00e9l\u00e9ments d\u2019appr\u00e9ciation \u00e0 la disposition du tribunal, celui-ci \u00e9valueex aequo et bonoles frais expos\u00e9s non compris dans les d\u00e9pens au montant de 1.500,- EUR et condamneSOCIETE2.)\u00e0 payer cette somme, au titre de l\u2019indemnit\u00e9 de proc\u00e9dure, \u00e0SOCIETE1.). Eu \u00e9gard \u00e0 l\u2019issue du litige,SOCIETE2.)est \u00e0 d\u00e9bouter de sa demande bas\u00e9e sur l\u2019article 240 du Nouveau Code de proc\u00e9dure civile. 2.Sur l\u2019ex\u00e9cution provisoire Aux termes de l\u2019article 567 du Nouveau Code de proc\u00e9dure civile\u00ables tribunaux d&#039;arrondissement si\u00e9geant en mati\u00e8re commerciale pourront ordonner l&#039;ex\u00e9cution provisoire de leurs jugements, nonobstant l&#039;appel, et sans caution, lorsqu&#039;il y aura titre non attaqu\u00e9, ou condamnation pr\u00e9c\u00e9dente dont il n&#039;y aura pas d&#039;appel: dans les autres cas, l&#039;ex\u00e9cution provisoire n&#039;aura lieu qu&#039;\u00e0 la charge de donner caution, ou de justifier de solvabilit\u00e9 suffisante\u00bb.<\/p>\n<p>18 En application du m\u00eame article, les jugements rendus en mati\u00e8re commerciale sont, de plein droit, ex\u00e9cutoires par provision, sans que l\u2019ex\u00e9cution provisoire doive \u00eatre prononc\u00e9e. Si le tribunal n\u2019a cependant pas dispens\u00e9 de la production d\u2019une caution ou de la preuve d\u2019une solvabilit\u00e9 suffisante, le jugement n\u2019est ex\u00e9cutoire que si une caution est fournie. Il n\u2019y a pas lieu d\u2019ordonner l\u2019ex\u00e9cution provisoire sans caution du pr\u00e9sent jugement alors que les conditions de l\u2019article 567 du Nouveau Code de proc\u00e9dure civile ne sont pas donn\u00e9es en l\u2019esp\u00e8ce. 3.Sur les d\u00e9pens En application de l\u2019article 238 du Nouveau Code de proc\u00e9dure civile, la partie perdante est condamn\u00e9e aux d\u00e9pens, \u00e0 moins que le juge, par d\u00e9cision sp\u00e9ciale et motiv\u00e9e, n\u2019en mette la totalit\u00e9 ou une fraction \u00e0 la charge d\u2019une autre partie. SOCIETE2.), succombant \u00e0 l\u2019instance, est \u00e0 condamner aux frais et d\u00e9pens de l\u2019instance. Parcesmotifs: le tribunal d\u2019arrondissement de et \u00e0 Luxembourg, vingt-cinqui\u00e8me chambre, si\u00e9geant en mati\u00e8re commerciale, statuantcontradictoirement, re\u00e7oitla demande en la forme; laditfond\u00e9e, partant, condamnela soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.)SARL \u00e0 payer \u00e0 la soci\u00e9t\u00e9 anonymeSOCIETE1.)SA la somme de 29.764,80 EUR avec les int\u00e9r\u00eats de retard applicables aux cr\u00e9ances r\u00e9sultant de transactions commerciales en vertu de la loi modifi\u00e9e du 18 avril 2004 relative aux d\u00e9lais de paiement et aux int\u00e9r\u00eats de retard, \u00e0 compter de la date d\u2019\u00e9ch\u00e9ance respective des factures, soit trente jours apr\u00e8s leur r\u00e9ception, jusqu\u2019\u00e0 solde; ditfond\u00e9ela demande de la soci\u00e9t\u00e9 anonymeSOCIETE1.)SA sur base de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile, partant, condamnela soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.)SARL \u00e0 payer \u00e0 la soci\u00e9t\u00e9 anonymeSOCIETE1.)SA la somme de 1.500,-EUR sur base de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile; ditnon fond\u00e9ela demande de la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.)SARL en allocation d\u2019une indemnit\u00e9 de proc\u00e9dure sur base de l\u2019article 240 du Nouveau Code de proc\u00e9dure civile, partant larejette; ditqu\u2019iln\u2019y a pas lieu d\u2019ordonner l\u2019ex\u00e9cution provisoire sans caution du pr\u00e9sent jugement;<\/p>\n<p>19 condamnela soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9eSOCIETE2.)SARL aux frais et d\u00e9pens de l\u2019instance.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-luxembourg-commerce\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-luxembourg-commerce\/20260329-230800\/20260312-talch25-tal-2025-09383-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jugement commercial 2026TALCH25\/00180 Audience publique dujeudi,douzemarsdeux mille vingt-six. Num\u00e9roTAL-2025-09383du r\u00f4le Composition: Tania CARDOSO, Vice-pr\u00e9sidente; Geraldine HEIN, juge-d\u00e9l\u00e9gu\u00e9e; Serge BERNARD, juge-d\u00e9l\u00e9gu\u00e9; KenBERENS, greffier. E n t r e : la soci\u00e9t\u00e9anonymeSOCIETE1.)SA, \u00e9tablie et ayant son si\u00e8ge social \u00e0L- ADRESSE1.), repr\u00e9sent\u00e9e par sonconseil d\u2019administrationactuellement en fonctions et\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[24938],"kji_year":[7610],"kji_subject":[7625],"kji_keyword":[23584,15419,23061,24939,7636],"kji_language":[7733],"class_list":["post-609069","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_chamber-commerce","kji_year-7610","kji_subject-commercial","kji_keyword-arrondissement","kji_keyword-commercial","kji_keyword-jugement","kji_keyword-talch","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 12 mars 2026, n\u00b0 2025-09383 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 12 mars 2026, n\u00b0 2025-09383\" \/>\n<meta property=\"og:description\" content=\"Jugement commercial 2026TALCH25\/00180 Audience publique dujeudi,douzemarsdeux mille vingt-six. Num\u00e9roTAL-2025-09383du r\u00f4le Composition: Tania CARDOSO, Vice-pr\u00e9sidente; Geraldine HEIN, juge-d\u00e9l\u00e9gu\u00e9e; Serge BERNARD, juge-d\u00e9l\u00e9gu\u00e9; KenBERENS, greffier. E n t r e : la soci\u00e9t\u00e9anonymeSOCIETE1.)SA, \u00e9tablie et ayant son si\u00e8ge social \u00e0L- ADRESSE1.), repr\u00e9sent\u00e9e par sonconseil d\u2019administrationactuellement en fonctions et\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-19T16:29:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"36 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-12-mars-2026-n-2025-09383\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-12-mars-2026-n-2025-09383\\\/\",\"name\":\"Tribunal d'arrondissement, 12 mars 2026, n\u00b0 2025-09383 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2026-04-19T16:29:51+00:00\",\"dateModified\":\"2026-04-19T16:29:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-12-mars-2026-n-2025-09383\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-12-mars-2026-n-2025-09383\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-12-mars-2026-n-2025-09383\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 12 mars 2026, n\u00b0 2025-09383\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 12 mars 2026, n\u00b0 2025-09383 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/","og_locale":"zh_CN","og_type":"article","og_title":"Tribunal d'arrondissement, 12 mars 2026, n\u00b0 2025-09383","og_description":"Jugement commercial 2026TALCH25\/00180 Audience publique dujeudi,douzemarsdeux mille vingt-six. Num\u00e9roTAL-2025-09383du r\u00f4le Composition: Tania CARDOSO, Vice-pr\u00e9sidente; Geraldine HEIN, juge-d\u00e9l\u00e9gu\u00e9e; Serge BERNARD, juge-d\u00e9l\u00e9gu\u00e9; KenBERENS, greffier. E n t r e : la soci\u00e9t\u00e9anonymeSOCIETE1.)SA, \u00e9tablie et ayant son si\u00e8ge social \u00e0L- ADRESSE1.), repr\u00e9sent\u00e9e par sonconseil d\u2019administrationactuellement en fonctions et\u2026","og_url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-19T16:29:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"36 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/","url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/","name":"Tribunal d'arrondissement, 12 mars 2026, n\u00b0 2025-09383 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#website"},"datePublished":"2026-04-19T16:29:51+00:00","dateModified":"2026-04-19T16:29:55+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-12-mars-2026-n-2025-09383\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 12 mars 2026, n\u00b0 2025-09383"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/zh-hans\/#website","url":"https:\/\/kohenavocats.com\/zh-hans\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision\/609069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=609069"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_country?post=609069"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_court?post=609069"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_chamber?post=609069"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_year?post=609069"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_subject?post=609069"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_keyword?post=609069"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_language?post=609069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}