{"id":623700,"date":"2026-04-20T15:30:55","date_gmt":"2026-04-20T13:30:55","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/"},"modified":"2026-04-20T15:30:59","modified_gmt":"2026-04-20T13:30:59","slug":"tribunal-darrondissement-9-juillet-2025-25","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 9 juillet 2025"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Jugementn\u00b02181\/2025 not.:12703\/25\/CD (irrecevable) (incomp.) AUDIENCE PUBLIQUE DU 9 JUILLET2025 Le Tribunal d&#039;arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit: Dans la cause entre: PERSONNE1.) n\u00e9eleDATE1.)\u00e0ADRESSE1.)(France), demeurant \u00e0F-ADRESSE2.), comparant parMa\u00eetreRadu DUTA,Avocat\u00e0 la Cour,demeurant \u00e0Luxembourg, \u2013citantedirecteet demanderesse au civil\u2013 et PERSONNE2.) n\u00e9 leDATE2.)\u00e0ADRESSE3.)(France) demeurant \u00e0 L-ADRESSE4.), comparanten personne,assist\u00e9 deMa\u00eetreLaurence LELEU, Avocat,\u00e0 la Cour, demeurant \u00e0 Luxembourg, \u2013cit\u00e9directet d\u00e9fendeur au civil\u2013 en pr\u00e9sence du Minist\u00e8re Public, partie jointe. FAITS : Par actedu21 janvier 2025,de l\u2019huissier de justicePatrick KURDYBAN, demeurant \u00e0 Luxembourg,PERSONNE1.)a fait donner citation \u00e0PERSONNE2.)de compara\u00eetre\u00e0 l\u2019audience publiquedu14 mars 2025duTribunal correctionnelde et \u00e0 Luxembourgafin de le<\/p>\n<p>2 voir condamner selon les peines \u00e0 requ\u00e9rir par le Minist\u00e8re Public duchef desinfractions mentionn\u00e9esdans la citation directe. L\u2019exploitdu21 janvier 2025 fut une nouvelle fois signifi\u00e9le 6 mars 2025\u00e0PERSONNE2.)avec citationde compara\u00eetre \u00e0 l\u2019audience publique du 1 er avril 2025 du Tribunal correctionnel de et \u00e0Luxembourg. \u00c0 l\u2019audience publique du1 er avril 2025, l\u2019affaire futremisecontradictoirement \u00e0 l\u2019audience publique du24 juin2025. \u00c0cette audience,MonsieurleVice-Pr\u00e9sident constata l&#039;identit\u00e9 ducit\u00e9 directPERSONNE2.) et l\u2019informa deson droitde garder le silence et de ne pas s\u2019incriminersoi-m\u00eame,conform\u00e9ment \u00e0 l\u2019article 190-1 (2) du Code de proc\u00e9dure p\u00e9nale. Ma\u00eetreRadu DUTA, Avocat \u00e0 la Cour,demeurant Luxembourg, donna lecture de la citation directe et exposa les moyensdePERSONNE1.),citantedirecte. Lecit\u00e9directPERSONNE2.)futentenduenses explications. Ma\u00eetre Radu DUTA, Avocat \u00e0 la Cour, demeurant\u00e0Luxembourg, se constitua partie civile au nom et pour compte dePERSONNE1.), citantedirecte et demanderesse au civil, contre le cit\u00e9 directPERSONNE2.), pr\u00e9qualifi\u00e9, d\u00e9fendeur au civil. Ma\u00eetreLaurence LELEU, Avocat,\u00e0 la Cour,demeurant \u00e0Luxembourg,exposa les moyensde d\u00e9fensedu cit\u00e9 direct. La mandataire de lacitantedirecte, Ma\u00eetreRadu DUTA, r\u00e9pliqua. Larepr\u00e9sentantedu Minist\u00e8re Public,Jennifer NOWAK, SubstitutPrincipaldu Procureur d\u2019\u00c9tat, fut entendueen ses conclusions. Le cit\u00e9 direct eut la parole en dernier. Le Tribunal prit l&#039;affaire end\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l&#039;audience publique de ce jour, date \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9, le JUGEMENT quisuit: Parexploitd\u2019huissier de justice du21 janvier 2025,PERSONNE1.)a fait donner citation \u00e0 PERSONNE2.)de compara\u00eetre devant leTribunal correctionnel afin de le voir condamner selon les peines \u00e0 requ\u00e9rir par le Minist\u00e8re Publicduchefdenon-repr\u00e9sentationd\u2019enfant et abandon de famille. Sur le plan civil,la citante directePERSONNE1.) demande la condamnation de PERSONNE2.)\u00e0 lui payer lemontant de30.000 euros correspondant au pr\u00e9judice mat\u00e9riel et moralsubi en relation avec l\u2019infractiondenon-pr\u00e9sentation d\u2019enfant, sinon tout autre montant \u00e0 arbitrer par le Tribunal avec les int\u00e9r\u00eats au taux l\u00e9gal \u00e0 partir de la demande en justice jusqu\u2019\u00e0 solde.<\/p>\n<p>3 En outre, la partie demanderesse au civil r\u00e9clame le montant de 6.400 euros correspondant aux arri\u00e9r\u00e9s de pension alimentaires, sinon tout autre montant \u00e0 arbitrer par le Tribunal avec les int\u00e9r\u00eats au taux l\u00e9gal \u00e0 partir de la demande en justice jusqu\u2019\u00e0 solde. Lacitantedirecter\u00e9clame par ailleurs le montant de2.000euros \u00e0 titre d\u2019indemnit\u00e9 de proc\u00e9dure sur base de l\u2019article 194 alin\u00e9a 2 du Code de proc\u00e9dure p\u00e9nale. AU P\u00c9NAL Quant au moyen soulev\u00e9 in limine litis \u00c0 l\u2019audiencepublique du 24 juin 2025,Ma\u00eetreLaurence LELEU,a soulev\u00e9,in limine litiset avant toute d\u00e9fense au fond,l\u2019incomp\u00e9tence territoriale du Tribunalpour conna\u00eetre de l\u2019infraction de non-repr\u00e9sentation d\u2019enfant. Il est de principe que leTribunal comp\u00e9tent est celui du lieu o\u00f9 l\u2019infraction a \u00e9t\u00e9 commise. Pour d\u00e9terminer le lieu de la commission de l\u2019infraction en cas de non-repr\u00e9sentation d\u2019enfant, il y a lieu de se r\u00e9f\u00e9rer \u00e0 la d\u00e9cision de justice qui ordonne le droit de visite ou d\u2019h\u00e9bergement de l\u2019enfant. Au cas o\u00f9 la d\u00e9cision de justice pr\u00e9voit le lieu de la remise de l\u2019enfant, la repr\u00e9sentation de l\u2019enfant doit avoir lieu \u00e0 l\u2019endroit indiqu\u00e9. Si, au contraire, la d\u00e9cision de justice accordant \u00e0 l\u2019un des parents de l\u2019enfant un droit de visite et d\u2019h\u00e9bergement ne pr\u00e9cise pas le lieu de la remise, l\u2019enfant doit \u00eatre remis au domicile du parent dont le droit de visite et d\u2019h\u00e9bergement doit \u00eatre exerc\u00e9 et l\u2019infraction pr\u00e9vue \u00e0 l\u2019article 371-1 du Code p\u00e9nal est localis\u00e9e au lieu o\u00f9 l\u2019enfant aurait d\u00fb demeurer pendant l\u2019exercice du droit de visite et d\u2019h\u00e9bergement (CSJ corr. 10 juillet 2019, n\u00b0 253\/19 X). Or, en l\u2019esp\u00e8ce, le jugement duTribunal judiciaire de Verdun du 22 janvier 2022pr\u00e9voitque \u00abPendant les vacances scolaires: la moiti\u00e9 de toutes les vacances scolaires d\u2019une dur\u00e9e sup\u00e9rieure \u00e0 cinq jours cons\u00e9cutifs (premi\u00e8re moiti\u00e9, les ann\u00e9es P\u00e8re, seconde moiti\u00e9 les ann\u00e9es impaires), enfant pris et ramen\u00e9 \u00e0 leur r\u00e9sidence habituelle par Monsieur PERSONNE2.)ou par une personne honorable\u00bb. Il estd\u00e8s lors constantque l\u2019enfant aurait d\u00fb \u00eatre remis par lecit\u00e9 direct au domicile de PERSONNE1.)qui demeureen France. Le Tribunal de c\u00e9ans est partantterritorialementincomp\u00e9tent pour statuer sur l\u2019infraction\u00e0 l\u2019article 371-1 du Code p\u00e9nal. Quant \u00e0 la recevabilit\u00e9 de la citation directepour l\u2019infraction d\u2019abandon de famille Aux termes de l\u2019article 391bis alin\u00e9a 5 du Code p\u00e9nal,\u00abLa poursuite des infractions sera pr\u00e9c\u00e9d\u00e9e d\u2019une interpellation, constat\u00e9e par proc\u00e8s-verbal du d\u00e9biteur d\u2019aliments par un agent de la police grand-ducale. Si le d\u00e9biteur d\u2019aliments n\u2019a pas de r\u00e9sidence connue, l\u2019interpellation n\u2019est pas requise\u00bb.<\/p>\n<p>4 En l\u2019esp\u00e8ce, ily a lieu de constaterque le d\u00e9biteur d\u2019aliments a une r\u00e9sidence connue.Iln\u2019a cependantpas \u00e9t\u00e9 proc\u00e9d\u00e9 \u00e0 une interpellation constat\u00e9e par proc\u00e8s-verbal par un agent de laPolice grand-ducale telqu\u2019exig\u00e9par l\u2019article 391bis du Code p\u00e9nal de la part de la citante directe. La citation directe \u00e9manant de la victime est soumise aux r\u00e8gles de forme applicables \u00e0 la citation d\u00e9livr\u00e9e par le Minist\u00e8re Public (cf. MERLE et VITU, Trait\u00e9 de droit criminel, proc\u00e9dure p\u00e9nale n\u00b01095, p.312). Le d\u00e9lit d\u2019abandon de famille est une infraction volontaire dont l\u2019\u00e9l\u00e9ment moral est constitu\u00e9 par le dol g\u00e9n\u00e9ral, c\u2019est-\u00e0-dire la pleine intelligence du caract\u00e8re illicite du comportement \u00e0 laquelle s\u2019ajoute la volont\u00e9 coupable de ne pas faire ce que la loi ordonne. L\u2019interpellation par la police pr\u00e9vue \u00e0 l\u2019article 391 bis du Code p\u00e9nal permet en effet \u00e0 l\u2019agent de police d\u2019expliquer au d\u00e9biteur de dettes alimentaires cette disposition l\u00e9gislative et l\u2019avertit sur les sanctions encourues en cas de non-respect de la loi. D\u2019autre part, le l\u00e9gislateur a ainsi souhait\u00e9 donner au d\u00e9biteur l\u2019occasion de payer les dettes alimentaires avant de compara\u00eetre devant le tribunal (cf. travaux parlementaires, document 1782, page 1782). Si le d\u00e9biteur interpell\u00e9 continue \u00e0 n\u00e9gliger son obligation, il est \u00e9tabli que le d\u00e9faut de payer la pension alimentaire n\u2019est pas d\u00fb \u00e0 une simple n\u00e9gligence de sa part, mais qu\u2019il est intentionnel. D\u00e8s lors, \u00e0 d\u00e9faut d\u2019interpellation, leTribunal ne saura appr\u00e9cier l\u2019\u00e9l\u00e9ment moral du cit\u00e9 direct alors que celui-ci n\u2019a pas \u00e9t\u00e9 inform\u00e9 par les agents de police du caract\u00e8re illicite de son comportement. Au vu du non-respect de la formalit\u00e9 pr\u00e9alable \u00e0 la poursuite du d\u00e9biteur d\u2019aliments par la partie citante r\u00e9sultant du d\u00e9faut d\u2019une interpellation polici\u00e8re exig\u00e9e par l\u2019article 391bis du Code p\u00e9nal, la citation directe doit \u00eatre d\u00e9clar\u00e9e irrecevable. Lacitation directe est d\u00e8s lors \u00e0 d\u00e9clarerirrecevable. AU CIVIL Dans l\u2019acte de citation directe,PERSONNE1.), demanderesseau civil, r\u00e9clame la condamnationdu cit\u00e9 directau paiement du montant de30.000euros\u00e0 titre de dommages mat\u00e9riel et moralavec les int\u00e9r\u00eatsau taux l\u00e9gal\u00e0 partir du jourde l\u2019infraction \u00e0 savoir le 11 ao\u00fbt 2020, jusqu\u2019\u00e0 solde. En outre, la partie demanderesse au civil r\u00e9clame le montant de 6.400 euros correspondant aux arri\u00e9r\u00e9s de pensionalimentaires. Elle r\u00e9clame finalementle montant de 2.000 euros \u00e0 titre d\u2019indemnit\u00e9 de proc\u00e9dure sur base de l\u2019article 194 alin\u00e9a 2 du Code de proc\u00e9dure p\u00e9nale. Il y a lieu de donner acte \u00e0 la partie demanderesse au civil de sa constitution de partie civile. Quant au pr\u00e9judice d\u00e9coulantde l\u2019infraction \u00e0 l\u2019article 371-1 du Code p\u00e9nal, le Tribunal estau vu de son incomp\u00e9tence territoriale \u00e9galementincomp\u00e9tent pour conna\u00eetrede lademande civiledePERSONNE1.)formul\u00e9e \u00e0 ce titre.<\/p>\n<p>5 Si lacitation directe est irrecevable, le Tribunal r\u00e9pressif ne peut statuer ni sur l&#039;action civile, ni sur l&#039;action publique (cf. Van Roye, Manuel de la partie civile, n\u00b0213, page 256). En effet, le volet civil est l\u2019accessoire du volet p\u00e9nal. La citation directe \u00e9tant irrecevableen ce qui concerne l\u2019abandon de famille, la demande civile relative \u00e0 cette infractionsuit le m\u00eame sort et doit \u00eatre d\u00e9clar\u00e9eirrecevable. PARCESMOTIFS le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant enmati\u00e8re correctionnelle,statuantcontradictoirement,le cit\u00e9 direct entendu en ses explications,le mandataire de lacitantedirecte, demanderesse au civil,et le mandataire ducit\u00e9 direct, d\u00e9fendeur au civil,entendus en leurs explications et moyens et larepr\u00e9sentantedu Minist\u00e8re Public entendueenson r\u00e9quisitoire, statuant au p\u00e9nal r e \u00e7 o i tla citation directe en la forme, sed \u00e9 c l a r eincomp\u00e9tentrationae locipour conna\u00eetre de l\u2019infraction\u00e0 l\u2019article 371-1 du Code p\u00e9nal, pour le surplus, lad \u00e9 c l a r eirrecevable, l a i s s eles frais \u00e0 charge de lacitantedirecte, statuant au civil donne acte\u00e0 la partie demanderesseau civilPERSONNE1.)de sa constitution de partie civile, sed \u00e9 c l a r eincomp\u00e9tentpour conna\u00eetrede ladePERSONNE1.)en relation avec l\u2019infraction de non-repr\u00e9sentation d\u2019enfant, d \u00e9 c l a r ela demande civile dePERSONNE1.)en relation avec l\u2019infraction d\u2019abandon de familleirrecevable, l a i s s eles frais de cette demande civile \u00e0 charge dePERSONNE1.). Par application des articles 14, 15 et 371-1 du Code p\u00e9nal ainsi que des articles1, 2, 3,179, 182,183-1,184, 189, 190, 190-1, 194, 195et196du Code de proc\u00e9dure p\u00e9nale, dont mention a \u00e9t\u00e9 faite. Ainsi fait et jug\u00e9 par Julien GROSS, Vice-Pr\u00e9sident, Laura LUDWIG, Juge, etPaula GAUB, Juge, et prononc\u00e9 en audience publique au Tribunal d\u2019arrondissement de Luxembourg, assist\u00e9<\/p>\n<p>6 deMorgane LEFEBVRE,Greffi\u00e8re, en pr\u00e9sence deClaire KOOB, Substitut du Procureur d\u2019\u00c9tat, qui, \u00e0 l\u2019exception de larepr\u00e9sentantedu Minist\u00e8re Public, ont sign\u00e9 le pr\u00e9sent jugement. Ce jugement est susceptible d&#039;appel. L\u2019appel doit \u00eatre interjet\u00e9 dans les formes et d\u00e9lais pr\u00e9vus aux articles 202 et suivants du Code de proc\u00e9dure p\u00e9nale et il doit \u00eatre form\u00e9 par le pr\u00e9venu ou son avocat, la partie civile ainsi que la partie civilement responsable ou leurs avocats respectifs dans les 40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement, aupr\u00e8s du greffe du Tribunal d\u2019arrondissement de Luxembourg, en se pr\u00e9sentantpersonnellementpour signer l\u2019acte d\u2019appel. L\u2019appel peut \u00e9galement \u00eatre interjet\u00e9, dans les40 joursde la date du prononc\u00e9 du pr\u00e9sent jugement par voie decourrier \u00e9lectronique\u00e0 adresser au guichet du greffe du Tribunal d\u2019arrondissement de Luxembourg \u00e0 l\u2019adressetalgug@justice.etat.lu. L\u2019appel interjet\u00e9 par voie \u00e9lectronique le jour d\u2019expiration du d\u00e9lai de recours peut parvenir au greffe jusqu\u2019\u00e0 minuit de cejour. Le courrier \u00e9lectronique par lequel appel est interjet\u00e9 doit \u00e9maner de l\u2019appelant, de son avocat ou de tout autre fond\u00e9 depouvoir sp\u00e9cial. Dans ce dernier cas, le pouvoir est annex\u00e9 au courrier \u00e9lectronique. Si le pr\u00e9venu estd\u00e9tenu,il peut d\u00e9clarer son appel au greffe du Centre p\u00e9nitentiaire.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-luxembourg-penal\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-luxembourg-penal\/20250721-012329\/20250709-talch16-2181-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jugementn\u00b02181\/2025 not.:12703\/25\/CD (irrecevable) (incomp.) AUDIENCE PUBLIQUE DU 9 JUILLET2025 Le Tribunal d&#8217;arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit: Dans la cause entre: PERSONNE1.) n\u00e9eleDATE1.)\u00e0ADRESSE1.)(France), demeurant \u00e0F-ADRESSE2.), comparant parMa\u00eetreRadu DUTA,Avocat\u00e0 la Cour,demeurant \u00e0Luxembourg, \u2013citantedirecteet demanderesse au civil\u2013 et\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[25729],"kji_year":[8463],"kji_subject":[7632],"kji_keyword":[23584,25730,8600,7636],"kji_language":[7733],"class_list":["post-623700","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_chamber-penal","kji_year-8463","kji_subject-penal","kji_keyword-arrondissement","kji_keyword-jugementn","kji_keyword-juillet","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 9 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 9 juillet 2025\" \/>\n<meta property=\"og:description\" content=\"Jugementn\u00b02181\/2025 not.:12703\/25\/CD (irrecevable) (incomp.) AUDIENCE PUBLIQUE DU 9 JUILLET2025 Le Tribunal d&#039;arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit: Dans la cause entre: PERSONNE1.) n\u00e9eleDATE1.)\u00e0ADRESSE1.)(France), demeurant \u00e0F-ADRESSE2.), comparant parMa\u00eetreRadu DUTA,Avocat\u00e0 la Cour,demeurant \u00e0Luxembourg, \u2013citantedirecteet demanderesse au civil\u2013 et\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T13:30:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-9-juillet-2025-25\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-9-juillet-2025-25\\\/\",\"name\":\"Tribunal d'arrondissement, 9 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2026-04-20T13:30:55+00:00\",\"dateModified\":\"2026-04-20T13:30:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-9-juillet-2025-25\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-9-juillet-2025-25\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-9-juillet-2025-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 9 juillet 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 9 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/","og_locale":"zh_CN","og_type":"article","og_title":"Tribunal d'arrondissement, 9 juillet 2025","og_description":"Jugementn\u00b02181\/2025 not.:12703\/25\/CD (irrecevable) (incomp.) AUDIENCE PUBLIQUE DU 9 JUILLET2025 Le Tribunal d'arrondissement de et \u00e0 Luxembourg,seizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, a rendu le jugement qui suit: Dans la cause entre: PERSONNE1.) n\u00e9eleDATE1.)\u00e0ADRESSE1.)(France), demeurant \u00e0F-ADRESSE2.), comparant parMa\u00eetreRadu DUTA,Avocat\u00e0 la Cour,demeurant \u00e0Luxembourg, \u2013citantedirecteet demanderesse au civil\u2013 et\u2026","og_url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-20T13:30:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"10 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/","url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/","name":"Tribunal d'arrondissement, 9 juillet 2025 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#website"},"datePublished":"2026-04-20T13:30:55+00:00","dateModified":"2026-04-20T13:30:59+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-9-juillet-2025-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 9 juillet 2025"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/zh-hans\/#website","url":"https:\/\/kohenavocats.com\/zh-hans\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision\/623700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=623700"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_country?post=623700"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_court?post=623700"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_chamber?post=623700"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_year?post=623700"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_subject?post=623700"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_keyword?post=623700"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_language?post=623700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}