{"id":630610,"date":"2026-04-21T03:16:35","date_gmt":"2026-04-21T01:16:35","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/"},"modified":"2026-04-21T03:16:40","modified_gmt":"2026-04-21T01:16:40","slug":"tribunal-darrondissement-7-decembre-2023-33","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 7 d\u00e9cembre 2023"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>1 Jugt.no.2468\/2023 not.270\/23\/CD 3x ex.p.\/(sp) DEFAUT sub 1) JUGEMENT R\u00c9PUT\u00c9 CONTRADICTOIRE sub 2) AUDIENCE PUBLIQUE DU 7 D\u00c9CEMBRE2023 Letribunal d\u2019arrondissement de et \u00e0 Luxembourg,treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle,a rendu le jugement qui suit: Dans la cause duMinist\u00e8re Publiccontre 1)PERSONNE1.), n\u00e9 leDATE1.)\u00e0ADRESSE1.)(Cameroun), demeurant \u00e0 L\u2013ADRESSE2.), 2)PERSONNE2.), n\u00e9 leDATE2.)\u00e0ADRESSE3.)(Congo), demeurant \u00e0 L\u2013ADRESSE4.), 3)PERSONNE3.), n\u00e9 leDATE3.)\u00e0ADRESSE5.)(Syrie), actuellement d\u00e9tenu au Centre p\u00e9nitentiaire d&#039;Uerschterhaff -p r \u00e9 v e n us- en pr\u00e9sence de : PERSONNE4.), demeurant \u00e0 L-ADRESSE6.),<\/p>\n<p>2 comparant par Ma\u00eetreGennaro PIETROPAOLO,avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg, partie civileconstitu\u00e9e contrePERSONNE1.),PERSONNE2.)etPERSONNE3.), pr\u00e9qualifi\u00e9s,<\/p>\n<p>3 F A I T S : Par citation du31 mai2023,le Procureur d\u2019\u00c9tat pr\u00e8s leTribunald\u2019arrondissement de Luxembourg acit\u00e9 lespr\u00e9venusPERSONNE1.),PERSONNE2.)etPERSONNE3.)de compara\u00eetre \u00e0 l\u2019audience publique du8 juin2023devant leTribunalcorrectionnel de ce si\u00e8ge pour y entendre statuer sur les pr\u00e9ventions suivantes: I.infraction aux articles 461 et 468 du Code p\u00e9nal, II.infraction \u00e0 l\u2019article 528 du Code p\u00e9nal. \u00c0 cette audience publique, Madame lePremierVice-Pr\u00e9sident constata l\u2019identit\u00e9 des pr\u00e9venus et leur donna connaissance del\u2019acte qui a saisi le Tribunal. Conform\u00e9ment \u00e0 l\u2019article 190-1 (2) du Code de proc\u00e9dure p\u00e9nale, les pr\u00e9venus ont \u00e9t\u00e9 instruits de leur droit de garder le silence et de ne pas s\u2019incriminer eux-m\u00eames. En application de l\u2019article 3-6 du Code de proc\u00e9dure p\u00e9nale, lespr\u00e9venusPERSONNE1.)et PERSONNE2.)ont\u00e9t\u00e9 instruitsdeleurdroit de se faire assister par un avocat, droit auquel ils ontrenonc\u00e9 formellement. Lest\u00e9moinsPERSONNE5.)etV.B.furent entendusenleurs d\u00e9clarations orales apr\u00e8s avoir pr\u00eat\u00e9 leserment pr\u00e9vu par la loi. Apr\u00e8s suspension d\u2019audience suite \u00e0 l\u2019information selon laquelle le t\u00e9moin V.B. aurait re\u00e7u des menaces ant\u00e9rieurement \u00e0 l\u2019audience en relation avec les faits en cause,Adrien DE WATAZZI, Premier Substitut duProcureur d\u2019\u00c9tat,donna lecture d\u2019unerequ\u00eate sollicitantune nouvelle audition du t\u00e9moinV.B.par des moyens de t\u00e9l\u00e9communication audiovisuelle garantissant la confidentialit\u00e9 de la transmissiondans la pr\u00e9sente affaire, conform\u00e9ment auxarticles 553 et suivantsdu Code de proc\u00e9dure p\u00e9nale; il fut entendu en ses r\u00e9quisitions et le mandataire d\u2019PERSONNE3.), en ses conclusions. Le Tribunalprit l\u2019affaire en d\u00e9lib\u00e9r\u00e9 etfixa le prononc\u00e9 du jugement interlocutoire au 13 juin 2023; la continuation des d\u00e9bats fut fix\u00e9e au 20 septembre 2023. Apr\u00e8splusieursremises, le Tribunal pronon\u00e7a la rupture du d\u00e9lib\u00e9r\u00e9du jugement interlocutoire en date du 14 novembre 2023. Par nouvelle citation \u00e0 pr\u00e9venus du 29 septembre 2023,l\u2019affaire fut utilement retenue \u00e0 l\u2019audience publique du16 novembre2023,audience \u00e0 laquelle V.B. n\u2019a plus \u00e9t\u00e9 convoqu\u00e9e par le Minist\u00e8re Public et \u00e0 l\u2019audition de laquelle ilrenon\u00e7a.La d\u00e9fense ne s\u2019opposa pas \u00e0 ladite renonciation du Minist\u00e8re Public. Les pr\u00e9venusPERSONNE1.)etPERSONNE2.)ne comparurent pas \u00e0 cette audience. Madame lePremierVice-Pr\u00e9sident constata l\u2019identit\u00e9 dupr\u00e9venuPERSONNE3.)et luidonna connaissance de l\u2019acte qui a saisi le Tribunal. Conform\u00e9ment \u00e0 l\u2019article 190-1 (2) du Code de proc\u00e9dure p\u00e9nale, le pr\u00e9venuPERSONNE3.)a \u00e9t\u00e9 instruit desondroit de garder le silence et de ne pas s\u2019incriminerlui-m\u00eame.<\/p>\n<p>4 Lest\u00e9moinsPERSONNE5.),PERSONNE6.)etPERSONNE4.)furent entendus s\u00e9par\u00e9ment en leursd\u00e9clarations orales apr\u00e8s avoir pr\u00eat\u00e9 le serment pr\u00e9vupar la loi; pendant la d\u00e9position des t\u00e9moins, le pr\u00e9venuPERSONNE3.)fut assist\u00e9 de l\u2019interpr\u00e8te Nadia TLEMCANI, asserment\u00e9 \u00e0 l\u2019audience. Le pr\u00e9venuPERSONNE3.)fut entenduensesexplications et moyens de d\u00e9fense. Ma\u00eetreGennaro PIETROPAOLO,avocat \u00e0 la Cour, demeurant \u00e0Luxembourg, seconstitua partie civile au nom et pour le compte d\u2019PERSONNE4.), pr\u00e9qualifi\u00e9, demandeur au civil, contre PERSONNE1.),PERSONNE2.)etPERSONNE3.), pr\u00e9qualifi\u00e9s, d\u00e9fendeurs au civil.Il donna lecture desconclusions \u00e9crites qu\u2019il d\u00e9posa ensuite sur le bureau du Tribunal et qui furent sign\u00e9es par Madame lePremierVice-Pr\u00e9sident et par la greffi\u00e8re et qui sont annex\u00e9es au pr\u00e9sent jugement. Le repr\u00e9sentantdu Minist\u00e8re Public,Adrien DE WATAZZI,Premier Substitut duProcureur d\u2019\u00c9tat,r\u00e9suma l\u2019affaire et fut entenduen son r\u00e9quisitoire. Ma\u00eetreFr\u00e9d\u00e9ric VENEAU, avocat\u00e0 la Cour, demeurant \u00e0 Luxembourg, exposa plus amplement les moyens du pr\u00e9venuPERSONNE3.). LeTribunalprit l\u2019affaire en d\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l\u2019audience publique de ce jour, date \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9, L E J UG E M E N T Q U I S U I T : Vu l\u2019ordonnance num\u00e9ro492\/23rendue le 28 f\u00e9vrier2023par la Chambre du conseil du Tribunal d\u2019arrondissement de et \u00e0 Luxembourg renvoyantPERSONNE1.),PERSONNE2.)et PERSONNE3.)du chefd\u2019infractionaux articles461et468du Code p\u00e9nal, par application de circonstances att\u00e9nuantes, devant une chambre correctionnelle du m\u00eame Tribunal. Vu l\u2019ensemble du dossier r\u00e9pressif constitu\u00e9 sous la notice num\u00e9ro270\/23\/CD. Vu l\u2019information donn\u00e9e par courrier du 29 septembre 2023\u00e0 la Caisse Nationale de Sant\u00e9 en application de l\u2019article 453 du Code de la s\u00e9curit\u00e9 sociale. Vu l\u2019information men\u00e9e par le Juge d\u2019instruction. Vu la citation \u00e0 pr\u00e9venus du29 septembre 2023r\u00e9guli\u00e8rement notifi\u00e9e \u00e0PERSONNE1.), PERSONNE2.)etPERSONNE3.). Le pr\u00e9venuPERSONNE1.), quoique r\u00e9guli\u00e8rement cit\u00e9, ne comparut pas \u00e0 l&#039;audience publique du 16 novembre 2023, de sorte qu\u2019il y a lieu de statuer par d\u00e9faut \u00e0 son \u00e9gard. Quoique r\u00e9guli\u00e8rement cit\u00e9 et touch\u00e9 \u00e0 personne le2 octobre2023,PERSONNE2.)ne comparut pas \u00e0 l\u2019audience du16novembre 2023, de sorte qu\u2019il y a lieu, conform\u00e9ment \u00e0 l\u2019article 185 paragraphe 2bisdu Code de proc\u00e9dure p\u00e9nale, de statuer par jugement r\u00e9put\u00e9 contradictoire \u00e0son\u00e9gard. AU PENAL<\/p>\n<p>5 Aux termes de la citation \u00e0 pr\u00e9venus, ensemble l\u2019ordonnance de renvoi, le Minist\u00e8re Public reproche aux pr\u00e9venusPERSONNE1.),PERSONNE2.)etPERSONNE3.): \u00abcomme auteurs, coauteurs ou complices, le 22 d\u00e9cembre 2021 vers 20.30 heures, \u00e0 Luxembourg, dans la rue de la Poste, sans pr\u00e9judice des circonstances de temps et de lieu exactes, I. en infraction aux articles 461 et 468 du Code p\u00e9nal, d&#039;avoir soustrait frauduleusement une chose qui ne lui appartenait pas, le vol ayant \u00e9t\u00e9 commis \u00e0 l&#039;aide de violences ou de menaces, en l&#039;esp\u00e8ce, d&#039;avoir soustrait frauduleusement au pr\u00e9judicePERSONNE4.), n\u00e9 leDATE4.)\u00e0 Luxembourg, notamment un montant de 30 EUR, uniPhone Apple 11, des AirPods pro ainsi qu&#039;une \u00e9charpe, avec la circonstance que le vol a \u00e9t\u00e9 commis \u00e0 l&#039;aide de violences \u00e0 l&#039;\u00e9gard dePERSONNE4.), pr\u00e9qualifi\u00e9, notamment en lui donnant des coups de poing sur le visage et sur le corps. II. en infraction \u00e0 l&#039;article 528 du Code p\u00e9nal, d&#039;avoirvolontairement d\u00e9truit, d\u00e9t\u00e9rior\u00e9 et caus\u00e9 tout d\u00e9g\u00e2t aux propri\u00e9t\u00e9s mobili\u00e8res d&#039;autrui \u00e0 l&#039;aide de violences, avec la circonstance que la destruction et les d\u00e9g\u00e2ts ont \u00e9t\u00e9 op\u00e9r\u00e9s, \u00e0 l&#039;aide de violences et de menaces, en l&#039;esp\u00e8ce, d&#039;avoir volontairement endommag\u00e9 les biens immobiliers dePERSONNE4.), n\u00e9 le DATE5.)\u00e0 Luxembourg, notamment en d\u00e9truisant sa veste de la marque &quot;Just Over the Top&quot; d&#039;une valeur de 199 euros, avec la circonstance que la destruction et les d\u00e9g\u00e2ts ont \u00e9t\u00e9 op\u00e9r\u00e9s, \u00e0 l&#039;aide de violences \u00e0 l&#039;encontre dePERSONNE4.), pr\u00e9 qualifi\u00e9\u00bb. Les faits Les faits tels qu\u2019ilsr\u00e9sultent du dossier r\u00e9pressifet des d\u00e9bats \u00e0 l\u2019audience peuvent se r\u00e9sumer comme suit: Le 22 d\u00e9cembre 2021, vers 20.45 heures, la police a \u00e9t\u00e9 d\u00e9p\u00each\u00e9e \u00e0Luxembourg-Ville,rue de la Poste, un vol \u00e0 l\u2019aide de violences y ayant eu lieu. Dans la rue de la Poste, sur la terrasse duENSEIGNE1.), la police a trouv\u00e9 la victime PERSONNE4.)ainsi que les t\u00e9moinsPERSONNE7.),PERSONNE8.),PERSONNE9.), PERSONNE10.)etPERSONNE11.). PERSONNE4.)a expliqu\u00e9 qu\u2019en traversant la rue de la Poste avecPERSONNE10.)et PERSONNE11.), ils ont crois\u00e9 un groupe de 10 \u00e0 15 jeunes venant de la direction oppos\u00e9e,<\/p>\n<p>6 habill\u00e9s en noir et dont certains masquaient leur visage \u00e0 l\u2019aide d\u2019une cagoule. Ils auraient demand\u00e9 de la monnaie \u00e0PERSONNE4.)et ses deux amis, ce qu\u2019ils n\u2019avaient pas sur eux, et ces derniers auraient ensuite tent\u00e9 de continuer leur chemin vers le centre-ville mais les jeunes les en auraient emp\u00each\u00e9s. Les jeunes se seraient alors dirig\u00e9s versPERSONNE4.)et un d\u2019eux, ayant le teint fonc\u00e9, aurait mis son pied sur celui dePERSONNE4.)afin de l\u2019emp\u00eacher de quitter les lieux. Ce dernier aurait ensuite \u00e9t\u00e9 s\u00e9par\u00e9 de ses deux amis par le groupe de jeunes qui a form\u00e9un cercleautour de lui etqui l\u2019a pouss\u00e9en direction du mur de la maison n\u00b011. Tout \u00e0 coup, trois des jeunes auraient commenc\u00e9 \u00e0 fouiller les poches de lavesteet du pantalon dePERSONNE4.)et comme ce dernier a tent\u00e9 de se d\u00e9fendre, les trois jeunes auraient commenc\u00e9 \u00e0 le frapper, principalement sur la t\u00eate et au visage. Il aurait \u00e9galement re\u00e7u un coup sur la t\u00eate avec une bouteille probablement en verre. Ensuite, un des jeunes aurait pris les \u00e9couteurs et le t\u00e9l\u00e9phone portable se trouvant dans la poche dePERSONNE4.)et le groupe de jeunes aurait pris la fuite en direction de la place EmileHamilius. Suite aux faits, trois t\u00e9moins et ses amis l\u2019auraient aid\u00e9 en l\u2019accompagnant auENSEIGNE1.) o\u00f9 un m\u00e9decin ou infirmer, passant par hasard, a trait\u00e9 ses blessures. Sur place, la police n\u2019a cependant pas trouv\u00e9 de bouteille en verre ou tout autre objet ayant pu servir pour frapperPERSONNE4.)\u00e0 la t\u00eate. Elle a \u00e9galement constat\u00e9 une plaie b\u00e9ante\u00e0 la t\u00eate de ce dernier. Apr\u00e8s avoir contact\u00e9 son p\u00e8re,PERSONNE4.)a \u00e9t\u00e9 emmen\u00e9 au CHLpar une ambulance o\u00f9 il a d\u00e9pos\u00e9 plainte, en pr\u00e9sence de son p\u00e8re. Il a r\u00e9it\u00e9r\u00e9 ses pr\u00e9c\u00e9dentes d\u00e9clarations et a pr\u00e9cis\u00e9 que les auteurs du fait auraient entre 17 et 18 ans. Une fille d\u2019environ 16 ans aurait \u00e9galement \u00e9t\u00e9 pr\u00e9sente dans le groupe et ils lui auraient vol\u00e9 son t\u00e9l\u00e9phone portable, ses AirPods Pro et probablement les 30 euros qu\u2019il avait encore dans sa poche. Il a finalement indiqu\u00e9 que savesteaurait \u00e9t\u00e9d\u00e9chir\u00e9e lors du vol et queletout aurait dur\u00e9 environ 5 \u00e0 10 minutes. Le p\u00e8re dePERSONNE4.)a \u00e9galement remisune facture relative \u00e0 la veste d\u00e9chir\u00e9e etle certificat m\u00e9dical \u00e9tabli par le DrPERSONNE12.)constatant une fracture de la lame papyrac\u00e9e \u00e0 gauche, un h\u00e9matome \u00e9picr\u00e2nien fronto-pari\u00e9tal droit, une plaie pari\u00e9tal droit d\u2019environ 4 cm de diam\u00e8tre profond etune plaie parieto-occipital,4 cm de diam\u00e8tre superficiel. Le m\u00e9decin lui a \u00e9galement prescrit une incapacit\u00e9 de travail de 8 jours. Lesagents de police ont ensuite proc\u00e9d\u00e9 \u00e0 la documentation photographiquede la blessurede PERSONNE4.). Auditionn\u00e9s sur les lieux du fait, les t\u00e9moinsPERSONNE7.),PERSONNE8.),PERSONNE9.), PERSONNE10.)etPERSONNE11.)ont confirm\u00e9 les d\u00e9clarations dePERSONNE4.), tout en pr\u00e9cisant quePERSONNE7.),PERSONNE8.)etPERSONNE9.)sont arriv\u00e9es sur les lieux qu\u2019apr\u00e8s quePERSONNE4.)se faisait d\u00e9j\u00e0 frapper. Le 7 janvier 2022, la police a \u00e9t\u00e9 contact\u00e9e par le service psychologique de l\u2019\u00e9cole \u00abArts et M\u00e9tiers\u00bb,fr\u00e9quent\u00e9 par la victime alors que cette derni\u00e8re aurait reconnu la fille du groupe, V.B.,qui n\u2019aurait cependant pas particip\u00e9 au vol et qui aurait m\u00eame essay\u00e9 de les en dissuader, connaissantPERSONNE4.)de l\u2019\u00e9cole. La police a convoqu\u00e9 les diff\u00e9rents t\u00e9moins etV.B.aux fins d\u2019audition.<\/p>\n<p>7 PERSONNE10.)a \u00e9t\u00e9 auditionn\u00e9 le 26 mars 2022 etPERSONNE11.)le 3 avril 2022. PERSONNE10.)a confirm\u00e9 les d\u00e9clarations polici\u00e8res dePERSONNE4.)en pr\u00e9cisant que le groupe de jeunes \u00e9tait accompagn\u00e9 de trois filles qui ont, apr\u00e8s avoir \u00e9t\u00e9 s\u00e9par\u00e9 de PERSONNE4.), constamment parl\u00e9 avec lui etPERSONNE11.)afin de les distraire et ainsi les emp\u00eacher de venir en aide \u00e0PERSONNE4.). PERSONNE11.)a confirm\u00e9 les d\u00e9clarations dePERSONNE10.)et dePERSONNE4.)en pr\u00e9cisant qu\u2019une des filles du groupe se serait, \u00e0 un moment, approch\u00e9ede lui et lui aurait enjoint, en criant, de vider ses poches, ce qu\u2019il n\u2019a cependant pas fait.PERSONNE10.)et lui n\u2019auraient \u00e9galement pas r\u00e9ussi \u00e0 venir en aide \u00e0PERSONNE4.), le groupe de jeunes lesen emp\u00eachant.Selonlui, une ou deux personnes du groupe ont film\u00e9 l\u2019ensemble des faits.Il a encore d\u00e9clar\u00e9 avoir ramass\u00e9 l\u2019\u00e9charpe dePERSONNE4.), qui \u00e9tait tomb\u00e9e par terrependant la bagarre, et qu\u2019\u00e0 ce moment, un des jeunes du groupe se serait approch\u00e9 de lui pour lui prendre l\u2019\u00e9charpe, ce qu\u2019il aurait au final r\u00e9ussi. PERSONNE8.)a\u00e9t\u00e9 auditionn\u00e9e le 2 avril 2022 tandis que,niPERSONNE9.), ni PERSONNE7.)nese sontpr\u00e9sent\u00e9es. PERSONNE8.)a d\u00e9clar\u00e9 \u00eatre arriv\u00e9e, ensemble avecPERSONNE7.)etPERSONNE9.), dans la rue de la Poste et d\u2019avoir vu une personne se faisant frapper par un groupe de jeunes l\u2019encerclant tandis qu\u2019unjeunedu groupe aurait\u00e9t\u00e9 en train de filmerletout et que lorsqu\u2019elles sont arriv\u00e9es \u00e0 hauteur du groupe, celui-ci aurait pris la fuite. Elles seraient ensuite venues en aide \u00e0 la victime. Suite aux d\u00e9clarations des t\u00e9moinsPERSONNE10.)etPERSONNE11.),V.B.a \u00e9t\u00e9 convoqu\u00e9e en tant que personne suspect\u00e9e d\u2019avoir particip\u00e9 \u00e0 une infraction. Elle a, lors de son audition,confirm\u00e9 le d\u00e9roulement des faits telle que relat\u00e9par la victime PERSONNE4.)et les diff\u00e9rents t\u00e9moins et elle a confirm\u00e9 quePERSONNE4.)s\u2019est \u00e9galement fait voler de l\u2019argent lors des faits. Elle a cependant contest\u00e9 avoir tent\u00e9 de distraire PERSONNE10.)etPERSONNE11.)en leur demandant de l\u2019argent. Elle aidentifi\u00e9\u00abPERSONNE13.)\u00bb, \u00abPERSONNE1.)\u00bb et \u00abPERSONNE14.)\u00bb comme les personnesayantagress\u00e9PERSONNE4.),et \u00abPERSONNE2.)\u00bb comme la personne ayant arrach\u00e9 l\u2019\u00e9charpe de la main dePERSONNE11.)et, suite \u00e0 son audition,elle a montr\u00e9quatre photosdesauteurs pr\u00e9sum\u00e9s,lesquellesont\u00e9t\u00e9 saisies par la police. Apr\u00e8s publicationdes photos dans l\u2019intranet de la police, les quatre jeunes ont pu \u00eatre identifi\u00e9s comme \u00e9tantPERSONNE3.),PERSONNE2.),PERSONNE1.)etPERSONNE15.). Le 21 d\u00e9cembre 2022,PERSONNE4.)a \u00e9t\u00e9 convoqu\u00e9 aupr\u00e8s de la police aux fins d\u2019une confrontation r\u00e9alis\u00e9emoyennant pr\u00e9sentation detroisplanches photographiques sur lesquelles il a reconnu le pr\u00e9venuPERSONNE3.)etPERSONNE15.). Auditions polici\u00e8res PERSONNE2.)a d\u00e9clar\u00e9 ne pas savoir o\u00f9 il s\u2019\u00e9tait trouv\u00e9 le jour des faits \u00e0 20.45 heures mais a indiqu\u00e9 \u00eatre certain de ne pas s\u2019\u00eatre trouv\u00e9 au centre-ville alors qu\u2019il prendrait normalement<\/p>\n<p>8 le bus vers 20.10 heures pour rentrer \u00e0 la maison. Il a encore d\u00e9clar\u00e9 connaitrePERSONNE1.) mais pasun certainPERSONNE3.). PERSONNE1.)a d\u00e9clar\u00e9 penser s\u2019\u00eatre trouv\u00e9 \u00e0 la maison le jour du fait litigieux en pr\u00e9sence de ses parents et de ses fr\u00e8res et s\u0153urs et qu\u2019il serait s\u00fbr de ne pas s\u2019\u00eatre trouv\u00e9 au centre-ville. Il a encore indiqu\u00e9 avoir d\u00e9j\u00e0 entendu parler du nom de \u00abPERSONNE3.)\u00bb et conna\u00eetre PERSONNE2.). PERSONNE15.)a indiqu\u00e9 avoir fr\u00e9quent\u00e9, le jour du fait litigieux, l\u2019\u00e9cole et de s\u2019\u00eatre rendu \u00e0 Echternach aupr\u00e8s de sa copine, dont il n\u2019a pas voulu donner le nom, \u00e0 16.00 heures, \u00e0 la fin des cours. Il a encore d\u00e9clar\u00e9 conna\u00eetre \u00abPERSONNE13.)\u00bb et \u00abPERSONNE14.)\u00bb, qui seraient des connaissances, mais de n\u2019avoir jamais entendu parler dePERSONNE2.)ou de PERSONNE1.). PERSONNE3.)a d\u00e9clar\u00e9 avoir pass\u00e9 la soir\u00e9e du 22 d\u00e9cembre 2022\u00e0 la maison avec sa copine, PERSONNE16.), et de ne pas s\u2019\u00eatre trouv\u00e9 au centre-ville. De plus, ayant habit\u00e9 \u00e0 Stolzembourg au moment des faits, il n\u2019aurait pas pu rentrer \u00e0 la maison s\u2019ils\u2019\u00e9taittrouv\u00e9 \u00e0 Luxembourg-Ville \u00e0 20.45 heures, aucun bus ne circulant \u00e0 cette heure. Il a encore ajout\u00e9 conna\u00eetre de nomPERSONNE1.)mais de ne l\u2019avoir encore jamais rencontr\u00e9 et ne pas conna\u00eetre, niPERSONNE2.), niPERSONNE15.). \u00c0l\u2019audience Le t\u00e9moinPERSONNE17.)a r\u00e9it\u00e9r\u00e9, sous la foi du serment,les constatations act\u00e9esdans le proc\u00e8s-verbalet rapportde police dress\u00e9sen cause. Le t\u00e9moinPERSONNE6.)a, sous la foi du serment, confirm\u00e9 les d\u00e9clarations du t\u00e9moin PERSONNE17.). La victimePERSONNE4.)a, sous la foi du serment, r\u00e9it\u00e9r\u00e9 ses d\u00e9clarations polici\u00e8res en ajoutant que 6 \u00e0 7 personnes l\u2019ont frapp\u00e9 lors du fait litigieux, dont faisaient partie les pr\u00e9venus et qu\u2019il reconnait le pr\u00e9venuPERSONNE3.)comme une des personnes l\u2019ayant frapp\u00e9 et lui ayant vol\u00e9 son t\u00e9l\u00e9phone portable, son \u00e9charpeet ses \u00e9couteurs. Sur question, il a indiqu\u00e9 ne pas avoir eu besoin de l\u2019aide de V.B. pour reconnaitrePERSONNE3.)sur la planche photographique lui soumise par la police et qu\u2019il reconnait formellement\u00e0 l\u2019audience PERSONNE3.)comme un de ses agresseurs. Le pr\u00e9venuPERSONNE3.)a contest\u00e9 avoir commis les infractions lui reproch\u00e9es et a r\u00e9it\u00e9r\u00e9 ses d\u00e9clarations polici\u00e8res. Le mandataire du pr\u00e9venuPERSONNE3.)a conclu \u00e0 son acquittement alors qu\u2019il ne se serait pas trouv\u00e9 \u00e0 Luxembourg-Ville au moment des faits, ce qui aurait \u00e9t\u00e9 confirm\u00e9 par sa copine. M\u00eame si la victime atteste que le pr\u00e9venu l\u2019aurait agress\u00e9, il subsisterait cependant un doute par rapport \u00e0 sa pr\u00e9sence \u00e0 Luxembourg-Ville, doute qui devrait lui profiter. En droit Quant \u00e0 la mat\u00e9rialit\u00e9 des faits reproch\u00e9s aupr\u00e9venu Les pr\u00e9venus ontcontest\u00e9avoir commisles infractionsleurreproch\u00e9es par le Minist\u00e8re Public.<\/p>\n<p>9 En mati\u00e8re p\u00e9nale, en cas de contestations \u00e9mises par le pr\u00e9venu, il incombe au Minist\u00e8re Public de rapporter la preuve de la mat\u00e9rialit\u00e9 del\u2019infraction lui reproch\u00e9e, tant en fait qu\u2019en droit. Dans ce contexte,le Tribunalrel\u00e8ve que le Code de proc\u00e9dure p\u00e9nale adopte le syst\u00e8me de la libre appr\u00e9ciation de la preuve par le juge qui forme son intime conviction librement sans \u00eatre tenu par telle preuve plut\u00f4t que par telle autre. Il interroge sa conscience et d\u00e9cide en fonction de son intime conviction (FRANCHIMONT, Manuel de proc\u00e9dure p\u00e9nale, p.764). Le juge r\u00e9pressif appr\u00e9cie souverainement en fait, la valeur probante des \u00e9l\u00e9ments sur lesquels il fonde son intime conviction (Cass. Belge, 31 d\u00e9cembre 1985, Pas. Belge 1986, I, 549). Cependant, si le juge p\u00e9nal peut fonder sa d\u00e9cision sur l\u2019intime conviction, il faut cependant que cette conviction r\u00e9sulte de moyens de preuve l\u00e9galement admis etadministr\u00e9s en la forme. En d\u2019autres termes, sa conviction doit \u00eatre l\u2019effet d\u2019une conclusion, d\u2019un travail pr\u00e9liminaire de r\u00e9flexion et de raisonnement, ne laissant plus de doute dans l\u2019esprit d\u2019une personne raisonnable. Concernant la valeur probante des d\u00e9clarations de t\u00e9moins,le Tribunalretient que le juge a un droit d\u2019appr\u00e9ciation souverain sur la valeur des t\u00e9moignages produits ; il n\u2019est li\u00e9 ni par le nombre ni par la qualit\u00e9 des t\u00e9moins produits. Aucune disposition l\u00e9gale ne s\u2019oppose \u00e0 ce qu\u2019ilfonde sa conviction sur les seules d\u00e9clarations de la victime (Cass. belge, 9 juin 1969, Pas. Bel. 1969, I, p. 912). Une appr\u00e9ciation critique du t\u00e9moignage doit faire porter l\u2019examen du juge sur les points suivants : a)quelle est la valeur morale dut\u00e9moin (moralit\u00e9 g\u00e9n\u00e9rale, capacit\u00e9 intellectuelle, dispositions affectives par rapport au proc\u00e8s\u2026) ? b)quelle est la valeur des facult\u00e9s psychologiques du t\u00e9moin telles qu\u2019elles sont mises en jeu dans le t\u00e9moignage (notamment relatives \u00e0 la perception desfaits et \u00e0 la conservation au niveau de la m\u00e9moire) ? c)enfin, quelle est la valeur de la d\u00e9position elle-m\u00eame ? (R. Merle et A. Vitu cit\u00e9 in M. FRANCHIMONT, op. cit\u00e9, p. 1053). Dans l\u2019appr\u00e9ciation de la cr\u00e9dibilit\u00e9des d\u00e9clarationsdePERSONNE4.),leTribunaltient compte des \u00e9l\u00e9ments suivants : Les d\u00e9clarations dePERSONNE4.)sont constantesquant au d\u00e9roulement des faits. PERSONNE4.)n\u2019avait pas de motif \u00e0 cr\u00e9er des probl\u00e8mes aux pr\u00e9venus, puisqu\u2019il ne les connaissait pas.Il a, \u00e0 l\u2019audience, d\u00e9clar\u00e9 sous la foi du serment, que les pr\u00e9venus l\u2019ont agress\u00e9 la nuit litigieuse. Il a \u00e9galement pu identifier deux de ses agresseurs, dont notamment le pr\u00e9venuPERSONNE3.) tant \u00e0 l\u2019audience que sur les planches photographiques lui soumises au commissariat de police. V.B., ayant fait partie du groupe de jeunes, a identifi\u00e9 les pr\u00e9venus, lors de son audition polici\u00e8re, comme les personnes ayant particip\u00e9 au vol \u00e0 l\u2019aide de violences dont a \u00e9t\u00e9 victime PERSONNE4.).<\/p>\n<p>10 Le Tribunalconstate encore que ni l\u2019examen du dossier, y compris les d\u00e9clarations des diff\u00e9rents t\u00e9moinset des pr\u00e9venus, ni la personnalit\u00e9 dePERSONNE4.), n\u2019ont mis en \u00e9vidence des \u00e9l\u00e9ments susceptibles de mettre en doute la cr\u00e9dibilit\u00e9 de ses d\u00e9clarationsquant \u00e0 l\u2019identit\u00e9 de ses agresseurs. Le Tribunalvient \u00e0 la conclusion qu\u2019aucun \u00e9l\u00e9ment du dossier r\u00e9pressif ne permet de mettre en doute la v\u00e9racit\u00e9 des d\u00e9clarations de la victimequant \u00e0 l\u2019identit\u00e9 de ses agresseurs. Au vu des d\u00e9veloppements qui pr\u00e9c\u00e8dent, les d\u00e9clarations dePERSONNE4.)emportent la convictiondu Tribunal. Quant\u00e0 l\u2019infraction de vol commis\u00e0 l\u2019aide de violencessurPERSONNE4.) Dans la mesure o\u00f9 le Tribunal n\u2019accorde aucun cr\u00e9dit aux explicationsdespr\u00e9venuset que PERSONNE4.)a d\u00e9clar\u00e9 sous la foi du serment queson t\u00e9l\u00e9phone portable, ses \u00e9couteurs ainsi que son \u00e9charpe lui ont \u00e9t\u00e9 vol\u00e9spar lespr\u00e9venus, il y a lieu de retenir cesderniersdans les liens de l\u2019infraction de vol. Le Minist\u00e8re Public reproche encore auxpr\u00e9venusque le vol a \u00e9t\u00e9 commis \u00e0 l\u2019aide de violences, en exer\u00e7ant des violences contrePERSONNE4.). Pour qu\u2019il y ait vol avec violences ou menaces au sens del\u2019article 468 du Code p\u00e9nal, il faut que le vol et les violences ou menaces soient attach\u00e9s par un rapport de causalit\u00e9, c\u2019est-\u00e0-dire que les violences ou les menaces aient eu pour objet ou pour cause le vol (R.P.D.B. verbo vol, n\u00b0598 ; Raymond Charles, Introduction \u00e0 l\u2019Etude du Vol, n\u00b0598 et r\u00e9f\u00e9rences y cit\u00e9es ; TA Lux. 24 avril 1990, LJUS n\u00b099013692). D\u2019apr\u00e8s l\u2019article 468 du Code p\u00e9nal, l\u2019utilisation par le voleur de violences constitue une circonstance aggravante de l\u2019infraction de vol. Par violencesl\u2019article 483 du Code p\u00e9nal vise \u00ab les actes de contrainte physique exerc\u00e9s contre des personnes \u00bb ; des violences simples ou l\u00e9g\u00e8res, par opposition aux violences qualifi\u00e9es de l\u2019article 473 et 474 du Code p\u00e9nal, \u00e9tant suffisantes pourentra\u00eener la qualification de \u00abviolences\u00bb. La Cour de cassation, dans son arr\u00eat du 25 mars 1982 (Pas.15, 252), inclut encore dans la d\u00e9finition de \u00ab violences \u00bb les atteintes directes \u00e0 l\u2019int\u00e9grit\u00e9 physique, et tout acte ou voie de fait de nature \u00e0 exercer une influencecoercitive sur la victime, sans qu\u2019il ne soit requis que celle-ci ait \u00e9t\u00e9 expos\u00e9e \u00e0 un danger s\u00e9rieux. En l\u2019esp\u00e8ce, il r\u00e9sulte des d\u00e9positions faites sous la foi du serment parPERSONNE4.)qu\u2019il a \u00e9t\u00e9 frapp\u00e9 par les trois pr\u00e9venus avant que ceux-cineluivolent son t\u00e9l\u00e9phone portable et ses \u00e9couteurs, qui se trouvaient dans la poche de sa veste, faits confirm\u00e9s par l\u2019ensemble des t\u00e9moins auditionn\u00e9s par la police.Il r\u00e9sulte \u00e9galement desd\u00e9clarationsde la victime et des t\u00e9moins V.B.,PERSONNE10.)etPERSONNE11.)que l\u2019\u00e9charpe de la victime, laquelle avait \u00e9t\u00e9 ramass\u00e9e parPERSONNE11.),a \u00e9t\u00e9 arrach\u00e9e des mainsde ce dernierpar le pr\u00e9venu PERSONNE2.).Les violences ressortent \u00e9galementdu certificat m\u00e9dical vers\u00e9 en cause par la victime ainsi que desblessures document\u00e9es par les photos prises par la police.<\/p>\n<p>11 Lespr\u00e9venussontpartant \u00e0 retenir dans les liens de la pr\u00e9vention de vol \u00e0 l\u2019aide de violences telle que libell\u00e9e \u00e0leurencontre. Quant \u00e0 l\u2019infraction \u00e0 l\u2019article 528 du Code p\u00e9nal Les d\u00e9clarations polici\u00e8res dePERSONNE4.), r\u00e9it\u00e9r\u00e9es sous la foi du serment \u00e0 l\u2019audience publique, sont cr\u00e9dibles et coh\u00e9rentes. Elles sont encore corrobor\u00e9es par les constatations du proc\u00e8s-verbal n\u00b02021\/103138-1\/BAMA du 23 d\u00e9cembre 2021contenant une photo de la veste d\u00e9chir\u00e9e Il est partant \u00e9tabli que lors du vol \u00e0 l\u2019aide de violences, commis par lespr\u00e9venus, la veste de la victime de lamarque\u00abJust Over the Top\u00bbd\u2019une valeur de199euros a \u00e9t\u00e9 endommag\u00e9e. Lespr\u00e9venussontpartant \u00e0 retenir dansles liens de l\u2019infraction \u00e0 l\u2019article 528 duCode p\u00e9nal telle que libell\u00e9e \u00e0leurencontre. Au vu des d\u00e9veloppements ci-avant,PERSONNE1.),PERSONNE2.)etPERSONNE3.)sont partantconvaincus: \u00abcommeauteurs,ayant commis les infractions ensemble, le 22 d\u00e9cembre 2021 vers 20.30 heures, \u00e0 Luxembourg, dans la rue de la Poste, I. en infraction aux articles 461 et 468 du Code p\u00e9nal, d&#039;avoir soustrait frauduleusement une chose qui ne lui appartenait pas, le vol ayant \u00e9t\u00e9 commis \u00e0 l&#039;aide de violences, en l&#039;esp\u00e8ce, d&#039;avoir soustrait frauduleusement au pr\u00e9judicedePERSONNE4.), n\u00e9 le DATE4.)\u00e0 Luxembourg, notamment un montant de 30 EUR, uniPhone Apple 11, des AirPods pro ainsi qu&#039;une \u00e9charpe, avec la circonstance que le vol a \u00e9t\u00e9 commis \u00e0 l&#039;aide de violences \u00e0 l&#039;\u00e9gard dePERSONNE4.), pr\u00e9qualifi\u00e9, notamment en lui donnant des coups de poing sur le visage et sur le corps, II. en infraction \u00e0 l&#039;article 528 du Code p\u00e9nal, d&#039;avoir volontairement d\u00e9t\u00e9rior\u00e9 et caus\u00e9 tout d\u00e9g\u00e2t aux propri\u00e9t\u00e9s mobili\u00e8res d&#039;autrui \u00e0 l&#039;aide de violences, avec la circonstance queles d\u00e9g\u00e2ts ont \u00e9t\u00e9 op\u00e9r\u00e9s\u00e0 l&#039;aide de violences, en l&#039;esp\u00e8ce, d&#039;avoir volontairement endommag\u00e9 les biensmobiliers dePERSONNE4.), n\u00e9 le DATE5.)\u00e0 Luxembourg, notamment en d\u00e9truisant sa vestede la marque \u00abJust Over the Top\u00bbd&#039;une valeur de 199 euros, avec la circonstance que les d\u00e9g\u00e2ts ont \u00e9t\u00e9 op\u00e9r\u00e9s \u00e0 l&#039;aide de violences \u00e0 l&#039;encontre de PERSONNE4.), pr\u00e9qualifi\u00e9\u00bb.<\/p>\n<p>12 La peine Les infractions retenues \u00e0 chargedePERSONNE1.),PERSONNE2.)etPERSONNE3.)se trouvent en concoursid\u00e9al pour avoir \u00e9t\u00e9 commis dans une intention unique, de sorte qu\u2019il y a lieu \u00e0 application de l\u2019article65du Code p\u00e9nal. Le vol \u00e0 l\u2019aide de violences est puni en vertu de l\u2019article468du Code p\u00e9nal de la r\u00e9clusion de cinq \u00e0 dix ans. En vertu de la d\u00e9criminalisation op\u00e9r\u00e9e par la Chambre du Conseil et en application de l\u2019article 74 du Code p\u00e9nal, la r\u00e9clusion est commu\u00e9e enpeine d\u2019emprisonnement de trois mois au moins. Le maximum encouru du chef de cette infraction est un emprisonnement de cinq ans. En vertu de l\u2019article 77 du Code p\u00e9nal, une amende facultative de 251 \u00e0 10.000 euros peut en outre \u00eatre prononc\u00e9e. L\u2019article 528alin\u00e9a 2du Code p\u00e9nal punit l\u2019endommagement d\u2019objets mobiliers d\u2019autrui ex\u00e9cut\u00e9 \u00e0 l\u2019aide de violences d\u2019un emprisonnement de trois mois \u00e0 cinq ans et d&#039;une amende de 500 euros \u00e0 25.000 euros, ou d&#039;une de ces peines seulement. La peine la plus forte est partant celle pr\u00e9venu par l\u2019article528du Code p\u00e9nal. Eu \u00e9gard \u00e0 la gravit\u00e9desfaitset de la gratuit\u00e9 des violences exerc\u00e9es,leTribunalcondamne chacun des troispr\u00e9venusPERSONNE1.),PERSONNE2.)etPERSONNE3.)\u00e0 unepeine d\u2019emprisonnement de24moisainsi qu\u2019\u00e0 une amende correctionnelle de1.500 euros. PERSONNE2.)ne semble cependant pas indigne d\u2019une certaine indulgence du Tribunal au vu de l\u2019absence, jusqu\u2019\u00e0 ce jour, de condamnation excluant le sursis \u00e0 l\u2019ex\u00e9cution despeines. Cependant, le Tribunal est d\u2019avis qu\u2019au vu de de la gravit\u00e9 et de la brutalit\u00e9 des faits, de l\u2019absence de repentir dans son chefet de tout d\u00e9sint\u00e9r\u00eat par rapport \u00e0 la proc\u00e9dure en cours \u00e0 son encontre, n\u2019ayant daign\u00e9 de se pr\u00e9senter \u00e0 l\u2019audience publique du 16 novembre 2023, il y a uniquement lieu de lui accorder la faveur dusursis partielquant \u00e0 l\u2019ex\u00e9cution de12moisde la peine d\u2019emprisonnement \u00e0 prononcer \u00e0 son encontre. PERSONNE3.)ne semble\u00e9galementpas indigne d\u2019une certaine indulgence du Tribunal au vu de l\u2019absence,au moment des faits, de condamnation excluant le sursis \u00e0 l\u2019ex\u00e9cution des peines. Cependant, le Tribunal est d\u2019avis qu\u2019au vu de de la gravit\u00e9 et de la brutalit\u00e9 des faits et de l\u2019absence de repentir dans son chef, il y a uniquement lieu de lui accorder la faveur dusursis partielquant \u00e0 l\u2019ex\u00e9cution de12 moisde la peine d\u2019emprisonnement \u00e0 prononcer \u00e0 son encontre. AU CIVIL \u00c0 l\u2019audience publique du16 novembre 2023,Ma\u00eetreGennaro PIETROPAOLO,avocat \u00e0 la Cour, demeurant \u00e0Luxembourg, seconstitua partie civile au nom et pour le compte d\u2019PERSONNE4.), pr\u00e9qualifi\u00e9, demandeur au civil, contrePERSONNE1.),PERSONNE2.)et PERSONNE3.), pr\u00e9qualifi\u00e9s, d\u00e9fendeurs au civilpour les voir condamn\u00e9s \u00e0 lui payer solidairement, sinonin solidum, sinon chacun pour le tout, le montant total de5.684euros\u00e0 titre de son pr\u00e9judicemoral et mat\u00e9rielaccru. Il sollicite encore le paiementdu montantde1.000 euros \u00e0 titre d\u2019indemnit\u00e9 de proc\u00e9dure. Le Tribunalest comp\u00e9tent pour conna\u00eetre de la demande civile, eu \u00e9gard \u00e0 la d\u00e9cision \u00e0 intervenir au p\u00e9nal.<\/p>\n<p>13 La demande civile est recevable pour avoir \u00e9t\u00e9 faite dans les forme et d\u00e9lai de la loi. Au vu des \u00e9l\u00e9ments du dossier r\u00e9pressif etdu certificat m\u00e9dicalvers\u00e9 en cause,duquelil ressort que la partie civile s\u2019est trouv\u00e9e, au vu des blessures subies,en arr\u00eat de maladiependant huit jours,le Tribunal \u00e9valuele pr\u00e9judice moraldudemandeur au civil,ex aequo et bono,toutes causes confondues,dumontantde3.500 euros. S\u2019agissant du pr\u00e9judice mat\u00e9riel, le Tribunal le dit fond\u00e9, au vu des pi\u00e8ces vers\u00e9es,\u00e0 hauteur du montant de 934 euros r\u00e9clam\u00e9. Au vu de qui pr\u00e9c\u00e8de, il y alieu de condamnerPERSONNE1.),PERSONNE2.)et PERSONNE3.)solidairement\u00e0 payer \u00e0PERSONNE4.)le montantde4.434euros,avec les int\u00e9r\u00eats au taux l\u00e9gal \u00e0 partir du21 d\u00e9cembre 2021, date des faits, jusqu\u2019\u00e0 solde. Le mandataire dePERSONNE4.)r\u00e9clame encore une indemnit\u00e9 de proc\u00e9dure de1.000euros. Etant donn\u00e9 qu\u2019il serait in\u00e9quitable de laisser \u00e0 charge dePERSONNE4.)tous les frais par lui expos\u00e9s et non compris dans les d\u00e9pens, il y a lieu de lui allouer une indemnit\u00e9 de proc\u00e9dure queleTribunal \u00e9value \u00e0500euros. Le Tribunal condamne partantPERSONNE1.),PERSONNE2.)etPERSONNE3.) solidairement\u00e0 payer \u00e0PERSONNE4.)le montantde500euros\u00e0 titre d\u2019indemnit\u00e9 de proc\u00e9dure. PARCESMOTIFS: le Tribunal d\u2019arrondissement de et \u00e0 Luxembourg,treizi\u00e8mechambre, si\u00e9geant en mati\u00e8re correctionnelle, statuantpar d\u00e9faut\u00e0 l\u2019\u00e9garddu pr\u00e9venuPERSONNE1.),par jugement r\u00e9put\u00e9 contradictoire\u00e0 l\u2019\u00e9garddu pr\u00e9venuPERSONNE2.)etcontradictoirement,\u00e0 l\u2019\u00e9gard du pr\u00e9venuPERSONNE3.), ce dernier entendu en ses explicationset moyens de d\u00e9fense, le mandataire du demandeur au civil entendu en sesconclusions,lerepr\u00e9sentant duMinist\u00e8re Publicen son r\u00e9quisitoire,le mandataired\u2019PERSONNE3.)entendu ensesexplications et moyens de d\u00e9fenseau p\u00e9nal et au civil,PERSONNE3.)ayant la parole le dernier, AU PENAL PERSONNE1.) c o n d a m n ePERSONNE1.)du chef des infractions retenues \u00e0 sa charge, qui se trouvent en concoursid\u00e9al, \u00e0 une peine d\u2019emprisonnement deVINGT-QUATRE (24)mois,\u00e0 une amendedeMILLE CINQ CENTS (1.500) euros,ainsi qu\u2019aux frais de sa poursuite p\u00e9nale, ces frais liquid\u00e9s \u00e022,79euros, f i x ela dur\u00e9e de la contrainte par corps en cas de non-paiement de l&#039;amende \u00e0QUINZE (15) jours, PERSONNE2.)<\/p>\n<p>14 c o n d a m n ePERSONNE2.)du chef des infractions retenues \u00e0 sa charge, qui se trouvent en concoursid\u00e9al, \u00e0 une peine d\u2019emprisonnement deVINGT-QUATRE (24)mois,\u00e0 une amendedeMILLE CINQ CENTS (1.500) euros,ainsi qu\u2019aux frais de sa poursuite p\u00e9nale, ces frais liquid\u00e9s \u00e022,79euros, f i x ela dur\u00e9e de la contrainte par corps en cas de non-paiement de l&#039;amende \u00e0QUINZE (15) jours, d i tqu&#039;il serasursis\u00e0 l&#039;ex\u00e9cution dedouze (12) moisde cette peine d\u2019emprisonnement, a v e r t i tle pr\u00e9venuPERSONNE2.)qu\u2019au cas o\u00f9,dans un d\u00e9lai de cinq ans \u00e0 dater du pr\u00e9sent jugement, il aura commis une nouvelle infraction ayant entra\u00een\u00e9 une condamnation \u00e0 une peine d\u2019emprisonnement ou \u00e0 une peine plus grave pour crime ou d\u00e9lit de droit commun, la peine d\u2019emprisonnement prononc\u00e9e ci-devant sera ex\u00e9cut\u00e9e sans confusion possible avec la nouvelle peine et que les peines de la r\u00e9cidive seront encourues dans les termes de l\u2019article 56 al. 2 du Code p\u00e9nal, PERSONNE3.) c o n d a m n ePERSONNE3.)du chef des infractions retenues \u00e0 sa charge, qui se trouvent en concoursid\u00e9al, \u00e0 une peine d\u2019emprisonnement deVINGT-QUATRE(24) mois,\u00e0 une amendedeMILLE CINQ CENTS (1.500) euros,ainsi qu\u2019aux frais de sa poursuite p\u00e9nale, ces frais liquid\u00e9s \u00e015,49euros, f i x ela dur\u00e9e de la contrainte par corps en cas de non-paiement de l&#039;amende \u00e0QUINZE (15) jours, d i tqu&#039;il serasursis\u00e0 l&#039;ex\u00e9cution dedouze (12) moisde cette peine d\u2019emprisonnement, a v e r t i tle pr\u00e9venuPERSONNE3.)qu\u2019au cas o\u00f9, dans un d\u00e9lai decinq ans \u00e0 dater du pr\u00e9sent jugement, il aura commis une nouvelle infraction ayant entra\u00een\u00e9 une condamnation \u00e0 une peine d\u2019emprisonnement ou \u00e0 une peine plus grave pour crime ou d\u00e9lit de droit commun, la peine d\u2019emprisonnement prononc\u00e9e ci-devant sera ex\u00e9cut\u00e9e sans confusion possible avec la nouvelle peine et que les peines de la r\u00e9cidive seront encourues dans les termes de l\u2019article 56 al. 2 du Code p\u00e9nal, AU CIVIL d o n n e a c t e\u00e0PERSONNE4.)de sa constitution de partie civile contrePERSONNE1.), PERSONNE2.)etPERSONNE3.), se d \u00e9 c l a r ecomp\u00e9tent pour en conna\u00eetre, d i tcette demande recevable, d i tla demande en r\u00e9paration du dommage mat\u00e9riel et moralfond\u00e9e pour le montantde QUATRE MILLE QUATRE CENT TRENTE -QUATRE(4.434)euros, c o n d a m n ePERSONNE1.),PERSONNE2.)etPERSONNE3.)solidairement\u00e0 payer \u00e0 PERSONNE4.)la somme deQUATRE MILLE QUATRE CENT TRENTE -QUATRE<\/p>\n<p>15 (4.434) euros, avec les int\u00e9r\u00eats au taux l\u00e9gal \u00e0 partir du21 d\u00e9cembre 2021, jour des faits, jusqu\u2019\u00e0 solde, d i tla demande en allocation d\u2019une indemnit\u00e9 de proc\u00e9dure fond\u00e9e pour le montant deCINQ CENTS(500)euros, c o n d a m n ePERSONNE1.),PERSONNE2.)etPERSONNE3.)solidairement\u00e0 payer \u00e0 PERSONNE4.)le montant deCINQ CENTS(500) euros, c o n d a m n ePERSONNE1.),PERSONNE2.)etPERSONNE3.)solidairement aux frais de cette demande civile. Par application des articles14,15,16,27, 28, 29, 30,6566,77,461, 468, 483et528duCode p\u00e9naletdes articles1, 2, 3,155,179, 182,183-1,184, 185, 189, 190,190-1,194, 195,196, 626, 627,628 et 628-1duCodede proc\u00e9dure p\u00e9nale,dont mention a \u00e9t\u00e9 faite. Ainsi fait et jug\u00e9 par Sylvie CONTER,PremierVice-Pr\u00e9sident,Lynn STELMESet Yashar AZARMGIN,PremiersJuges, et prononc\u00e9 par Madame lePremierVice-Pr\u00e9sident en audience publique auTribunal d\u2019arrondissement de et \u00e0 Luxembourg, Cit\u00e9 Judiciaire, Plateau du Saint Esprit, en pr\u00e9sence deSylvie BERNARDO, Substitutdu Procureur d\u2019Etat, et de Chantal REULAND, greffi\u00e8re, qui, \u00e0 l\u2019exception de la repr\u00e9sentantedu Minist\u00e8re Public, ont sign\u00e9 le pr\u00e9sent jugement.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-luxembourg-penal\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-luxembourg-penal\/20240828-021336\/20231207-tal13-2468-pseudonymise-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 Jugt.no.2468\/2023 not.270\/23\/CD 3x ex.p.\/(sp) DEFAUT sub 1) JUGEMENT R\u00c9PUT\u00c9 CONTRADICTOIRE sub 2) AUDIENCE PUBLIQUE DU 7 D\u00c9CEMBRE2023 Letribunal d\u2019arrondissement de et \u00e0 Luxembourg,treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle,a rendu le jugement qui suit: Dans la cause duMinist\u00e8re Publiccontre 1)PERSONNE1.), n\u00e9 leDATE1.)\u00e0ADRESSE1.)(Cameroun), demeurant \u00e0 L\u2013ADRESSE2.),\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[25729],"kji_year":[24566],"kji_subject":[7632],"kji_keyword":[23584,8464,7636],"kji_language":[7733],"class_list":["post-630610","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_chamber-penal","kji_year-24566","kji_subject-penal","kji_keyword-arrondissement","kji_keyword-decembre","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 7 d\u00e9cembre 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 7 d\u00e9cembre 2023\" \/>\n<meta property=\"og:description\" content=\"1 Jugt.no.2468\/2023 not.270\/23\/CD 3x ex.p.\/(sp) DEFAUT sub 1) JUGEMENT R\u00c9PUT\u00c9 CONTRADICTOIRE sub 2) AUDIENCE PUBLIQUE DU 7 D\u00c9CEMBRE2023 Letribunal d\u2019arrondissement de et \u00e0 Luxembourg,treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle,a rendu le jugement qui suit: Dans la cause duMinist\u00e8re Publiccontre 1)PERSONNE1.), n\u00e9 leDATE1.)\u00e0ADRESSE1.)(Cameroun), demeurant \u00e0 L\u2013ADRESSE2.),\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T01:16:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"29 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-7-decembre-2023-33\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-7-decembre-2023-33\\\/\",\"name\":\"Tribunal d'arrondissement, 7 d\u00e9cembre 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2026-04-21T01:16:35+00:00\",\"dateModified\":\"2026-04-21T01:16:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-7-decembre-2023-33\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-7-decembre-2023-33\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-7-decembre-2023-33\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 7 d\u00e9cembre 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 7 d\u00e9cembre 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/","og_locale":"zh_CN","og_type":"article","og_title":"Tribunal d'arrondissement, 7 d\u00e9cembre 2023","og_description":"1 Jugt.no.2468\/2023 not.270\/23\/CD 3x ex.p.\/(sp) DEFAUT sub 1) JUGEMENT R\u00c9PUT\u00c9 CONTRADICTOIRE sub 2) AUDIENCE PUBLIQUE DU 7 D\u00c9CEMBRE2023 Letribunal d\u2019arrondissement de et \u00e0 Luxembourg,treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle,a rendu le jugement qui suit: Dans la cause duMinist\u00e8re Publiccontre 1)PERSONNE1.), n\u00e9 leDATE1.)\u00e0ADRESSE1.)(Cameroun), demeurant \u00e0 L\u2013ADRESSE2.),\u2026","og_url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-21T01:16:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"29 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/","url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/","name":"Tribunal d'arrondissement, 7 d\u00e9cembre 2023 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#website"},"datePublished":"2026-04-21T01:16:35+00:00","dateModified":"2026-04-21T01:16:40+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-7-decembre-2023-33\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 7 d\u00e9cembre 2023"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/zh-hans\/#website","url":"https:\/\/kohenavocats.com\/zh-hans\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision\/630610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=630610"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_country?post=630610"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_court?post=630610"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_chamber?post=630610"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_year?post=630610"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_subject?post=630610"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_keyword?post=630610"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_language?post=630610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}