{"id":747517,"date":"2026-04-29T08:02:45","date_gmt":"2026-04-29T06:02:45","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/"},"modified":"2026-04-29T08:02:49","modified_gmt":"2026-04-29T06:02:49","slug":"tribunal-darrondissement-20-mai-2020","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/","title":{"rendered":"Tribunal d&#8217;arrondissement, 20 mai 2020"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Jugt n\u00b0 1181\/ 2020 Not. 35473\/ 19\/CC<\/p>\n<p>2x i.c.(s.) (i.c. prov.)<\/p>\n<p>AUDIENCE PUBLIQUE DU 20 MAI 2020 Le Tribunal d&#039;arrondissement de et \u00e0 Luxembourg, treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique , a rendu le jugement qui suit: dans la cause du Minist\u00e8re Public contre<\/p>\n<p>P.1.), n\u00e9 le (\u2026) \u00e0 (\u2026), demeurant L-(\u2026),<\/p>\n<p>&#8211; p r \u00e9 v e n u &#8211;<\/p>\n<p>___________________________________________________________________________<\/p>\n<p>F A I T S :<\/p>\n<p>Par citation du 21 avril 2020, Monsieur le procureur d&#039;Etat pr\u00e8s le Tribunal d&#039;arrondissement de Luxembourg a requis le pr\u00e9venu de compara\u00eetre \u00e0 l&#039;audience publique du 7 mai 2020 devant le Tribunal correctionnel de ce si\u00e8ge, pour y entendre statuer sur les pr\u00e9ventions suivantes:<\/p>\n<p>circulation: ivresse ( 1,08 mg par litre d\u2019air expir\u00e9); contravention.<\/p>\n<p>A cette audience, Monsieur le premier juge-pr\u00e9sident constata l&#039;identit\u00e9 du pr\u00e9venu et lui donna connaissance de l&#039;acte qui a saisi le Tribunal.<\/p>\n<p>Conform\u00e9ment \u00e0 l\u2019article 190-1 (2) du Code de proc\u00e9dure p\u00e9nale, le pr\u00e9venu a \u00e9t\u00e9 instruit de son droit de garder le silence et de ne pas s\u2019auto- incriminer.<\/p>\n<p>En application de l\u2019article 3-6 du Code de proc\u00e9dure p\u00e9nale, le pr\u00e9venu a \u00e9t\u00e9 instruit de son droit de se faire assister par un avocat, droit auquel il a renonc\u00e9 formellement.<\/p>\n<p>Le pr\u00e9venu P.1.) fut entendu en ses explications et moyens de d\u00e9fense.<\/p>\n<p>Le repr\u00e9sentant du Minist\u00e8re Public, Monsieur Claude EISCHEN, substitut du Procureur d\u2019Etat, r\u00e9suma l&#039;affaire et fut entendu en son r\u00e9quisitoire.<\/p>\n<p>Le Tribunal prit l&#039;affaire en d\u00e9lib\u00e9r\u00e9 et rendit \u00e0 l&#039;audience publique de ce jour, date \u00e0 laquelle le prononc\u00e9 avait \u00e9t\u00e9 fix\u00e9,<\/p>\n<p>le jugement qui suit:<\/p>\n<p>Vu la citation \u00e0 pr\u00e9venu du 21 avril 2020 r\u00e9guli\u00e8rement notifi\u00e9e au pr\u00e9venu.<\/p>\n<p>Vu le proc\u00e8s-verbal n\u00b0 21997 du 9 d\u00e9cembre 2019 dress\u00e9 par la police grand -ducale, Commissariat Luxembourg (C3R).<\/p>\n<p>Vu le r\u00e9sultat de l&#039;analyse par \u00e9thylom\u00e8tre de l&#039;haleine \u00e9tablissant l&#039;alcool\u00e9mie du pr\u00e9venu \u00e0 1,08 mg\/l d\u2019air expir\u00e9 au moment des faits.<\/p>\n<p>Le Minist\u00e8re Public reproche au pr\u00e9venu P.1.), d\u2019avoir le 9 d\u00e9cembre 2019 vers 01.00 heure \u00e0 Luxembourg, boulevard (\u2026), circul\u00e9 en \u00e9tat d\u2019ivresse avec un taux d\u2019alcool de 1,08 mg par litre d\u2019air expir\u00e9 ainsi que d\u2019avoir contrevenu \u00e0 une prescription \u00e9nonc\u00e9e \u00e0 l\u2019article 140 de l\u2019arr\u00eat\u00e9 grand- ducal du 23 novembre 1955 portant r\u00e8glement de la circulation sur toutes les voies publiques.<\/p>\n<p>Le Tribunal correctionnel est comp\u00e9tent pour conna\u00eetre de la contravention libell\u00e9e \u00e0 charge de P.1.) dans la mesure o\u00f9 celle- ci est connexe au d\u00e9lit libell\u00e9 sub 1).<\/p>\n<p>Les \u00e9l\u00e9ments du dossier r\u00e9pressif, et l\u2019instruction \u00e0 l\u2019audience ont permis d\u2019\u00e9tablir les faits suivants :<\/p>\n<p>Le 9 d\u00e9cembre 2019 vers 00.55 heure, la police a \u00e9t\u00e9 appel\u00e9e \u00e0 intervenir en raison d\u2019un vol d\u2019un v\u00e9hicule dans le parking souterrain de l\u2019H\u00f4tel ETS .1.).<\/p>\n<p>Sur place, les agents de police ont \u00e9t\u00e9 inform\u00e9s que le plaignant, identifi\u00e9 en la personne de P.1.), avait entretemps r\u00e9ussi \u00e0 retrouver son v\u00e9hicule et qu\u2019il avait quitt\u00e9 les lieux.<\/p>\n<p>Afin de s\u2019assurer que c\u2019\u00e9tait bien le l\u00e9gitime propri\u00e9taire qui avait r\u00e9cup\u00e9r\u00e9 son v\u00e9hicule et ayant pour le surplus \u00e9t\u00e9 inform\u00e9s que P.1.) n\u2019avait pas r\u00e9gl\u00e9 le prix de boissons consomm\u00e9s au bar de l\u2019h\u00f4tel, les policiers ont demand\u00e9 au pr\u00e9venu de se repr\u00e9senter sur les lieux.<\/p>\n<p>Une fois que P.1.) \u00e9tait retourn\u00e9 \u00e0 l\u2019h\u00f4tel, les policiers ont constat\u00e9 que ce dernier pr\u00e9sentait des indices d\u2019une consommation d\u2019alcool, son haleine sentant l\u2019alcool et ses yeux \u00e9tant rouge\u00e2tres et aqueux, de sorte qu\u2019il a \u00e9t\u00e9 invit\u00e9 \u00e0 se soumettre \u00e0 un test sommaire de l\u2019haleine et, eu \u00e9gard au r\u00e9sultat positif de ce test, \u00e0 un examen de l\u2019air expir\u00e9 qui r\u00e9v\u00e9la \u00e0 01.51 heure, un taux d\u2019alcool\u00e9mie de 1,08 mg\/l d\u2019air expir\u00e9.<\/p>\n<p>Lors de son audition polici\u00e8re, P.1.) a indiqu\u00e9 qu\u2019il avait consomm\u00e9 un vin chaud et un verre de ros\u00e9 durant la journ\u00e9e et qu\u2019il a consomm\u00e9 trois gin tonic lorsqu\u2019il \u00e9tait rentr\u00e9 chez lui pour f\u00eater le fait qu\u2019il avait retrouv \u00e9 son v\u00e9hicule qu\u2019il avait cru vol\u00e9. Quand il aurait \u00e9t\u00e9 appel\u00e9 par la police, il serait retourn\u00e9 \u00e0 l\u2019h\u00f4tel sans r\u00e9fl\u00e9chir.<\/p>\n<p>Tout d\u2019abord, le Tribunal rappelle qu\u2019il est de jurisprudence que si un conducteur consomme de l\u2019alcool entre le moment des faits et l\u2019arriv\u00e9e sur place des agents verbalisateurs et s\u2019il affirme avoir bu apr\u00e8s les faits, il lui appartient de prouver qu\u2019il a bu apr\u00e8s le fait p\u00e9nal et<\/p>\n<p>3 qu\u2019auparavant il ne se trouvait pas dans un des \u00e9tats d\u2019impr\u00e9gnation alcoolique sanctionn\u00e9s par la loi (cf. Cour, arr\u00eat n\u00b0232\/95 du 23 mai 1995).<\/p>\n<p>Le pr\u00e9venu n\u2019a pas rapport\u00e9 la preuve d\u2019avoir consomm\u00e9 des boissons alcooliques apr\u00e8s \u00eatre rentr\u00e9 chez lui.<\/p>\n<p>En tout \u00e9tat de cause, m\u00eame \u00e0 supposer \u00e9tablie pareille consommation, toujours est-il que le pr\u00e9venu a encore une fois pris le volant apr\u00e8s cette pr\u00e9tendue consommation, de sorte qu\u2019il est \u00e9tabli qu\u2019il a pris le volant en connaissance de cause de sa consommation de boissons alcooliques.<\/p>\n<p>La conduite en \u00e9tat d\u2019ivresse es t partant \u00e9tablie \u00e0 charge du pr\u00e9venu.<\/p>\n<p>La contravention libell\u00e9e \u00e0 charge du pr\u00e9venu est \u00e9galement \u00e9tablie sur base des \u00e9l\u00e9ments du dossier r\u00e9pressif, \u00e9tant \u00e0 pr\u00e9ciser que la mise en danger d\u2019autrui est inh\u00e9rente \u00e0 la circulation en \u00e9tat d\u2019ivresse sur la voie publique.<\/p>\n<p>Le pr\u00e9venu P.1.) se trouve partant convaincu par les \u00e9l\u00e9ments du dossier r\u00e9pressif, ensemble ses aveux partiels \u00e0 l\u2019audience :<\/p>\n<p>\u00ab \u00e9tant conducteur d\u2019un v\u00e9hicule automoteur sur la voie publique,<\/p>\n<p>le 9 d\u00e9cembre 2019 vers 01.00 heure \u00e0 Luxembourg, boulevard (\u2026),<\/p>\n<p>1) avoir circul\u00e9 avec un taux d\u2019alcool d\u2019au moins 0,55 mg par litre d\u2019air expir\u00e9 , en l\u2019esp\u00e8ce de 1,08 mg par litre d\u2019air expir\u00e9,<\/p>\n<p>2) d\u00e9faut de se comporter raisonnablement et prudemment de fa\u00e7on \u00e0 ne pas constituer un danger pour la circulation. \u00bb<\/p>\n<p>Les infractions retenues \u00e0 charge du pr\u00e9venu sub 1 ) et 2) se trouvent en concours id\u00e9al , de sorte qu\u2019il y a lieu de faire application de l\u2019 articles 65 du C ode p\u00e9nal.<\/p>\n<p>L\u2019infraction \u00e0 l\u2019article 12 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 concernant la r\u00e9glementation de la circulation sur toutes les voies publiques retenue \u00e0 charge de P.1.) est punie des peines pr\u00e9vues au paragraphe 1 er dudit article, \u00e0 savoir une peine d\u2019emprisonnement de huit jours \u00e0 trois ans et une amende de 500 \u00e0 10.000 euros ou l\u2019une de ces peines seulement.<\/p>\n<p>La contravention retenue \u00e0 charge du pr\u00e9venu sont punissables d\u2019une amende de police de 25 \u00e0 250 euros.<\/p>\n<p>L\u2019article 13.1 de la loi du 14 f\u00e9vrier 1955 permet au juge saisi d\u2019une ou de plusieurs infractions \u00e0 la r\u00e9glementation de la circulation sur toutes les voies publiques ou de d\u00e9lits ou de crimes qui se sont joints \u00e0 ces infractions, de prononcer une interdiction de conduire de huit jours \u00e0 un an en mati\u00e8re de contraventions et de trois mois \u00e0 quinze ans en mati\u00e8re de d\u00e9lits ou de crimes. Cette interdiction de conduire \u00ab sera toujours prononc\u00e9e en cas de condamnation du chef des d\u00e9lits vis\u00e9s au point 1 du paragraphe 2 de l\u2019article 12 et au poin1 du paragraphe 4bis de l&#039;article 12 et en cas de r\u00e9cidive pr\u00e9vue au point 5 du paragraphe 2 du m\u00eame article. \u00bb<\/p>\n<p>4 En circulant sur la voie publique en \u00e9tat d&#039;impr\u00e9gnation alcoolique, le pr\u00e9venu a gravement mis en danger tant sa propre s\u00e9curit\u00e9 que celle des autres usagers.<\/p>\n<p>Au vu de la gravit\u00e9 des infractions commises, le Tribunal condamne P.1.) \u00e0 une amende correctionnelle de 1.000 euros et \u00e0 une peine d\u2019interdiction de conduire de 25 mois, qui tiennent compte de l\u2019atteinte \u00e0 l\u2019ordre public et des revenus disponibles du pr\u00e9venu.<\/p>\n<p>En vertu de l\u2019article 628 alin\u00e9a 4 du Code de proc\u00e9dure p\u00e9nale , les Cours et Tribunaux peuvent, \u00ab dans le cas o\u00f9 ils prononcent une interdiction de conduire un v\u00e9hicule automoteur sur la voie publique, ordonner par la m\u00eame d\u00e9cision motiv\u00e9e qu\u2019il sera sursis \u00e0 l\u2019ex\u00e9cution de tout ou partie de cette peine accessoire, \u00e0 condition que le condamn\u00e9 n\u2019ait pas \u00e9t\u00e9, avant le fait motivant sa poursuite, l\u2019objet d\u2019une condamnation irr\u00e9vocable \u00e0 une peine d\u2019emprisonnement correctionnel du chef d\u2019infraction aux lois et r\u00e8glements r\u00e9gissant la circulation sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour infraction aux lois et r\u00e8glements concernant la vente de substances m\u00e9dicamenteuses. \u00bb<\/p>\n<p>Le Tribunal d\u00e9cide d\u2019assortir l\u2019interdiction de conduire \u00e0 prononcer \u00e0 l\u2019\u00e9gard du pr\u00e9venu du sursis partiel quant \u00e0 l\u2019ex\u00e9cution de 20 mois de cette interdiction de conduire.<\/p>\n<p>L\u2019article 13.1ter de la loi pr\u00e9cit\u00e9e du 14 f\u00e9vrier 1955 permet \u00e0 la juridiction r\u00e9pressive d\u2019excepter de l&#039;interdiction de conduire \u00e0 prononcer un ou plusieurs des trajets limitativement \u00e9num\u00e9r\u00e9s ci-apr\u00e8s:<\/p>\n<p>a) les trajets effectu\u00e9s dans l\u2019int\u00e9r\u00eat prouv\u00e9 de la profession de la personne concern\u00e9e,<\/p>\n<p>b) le trajet d\u2019aller et de retour effectu\u00e9 entre la r\u00e9sidence principale, une r\u00e9sidence secondaire pr\u00e9sentant un caract\u00e8re de stabilit\u00e9 ou tout autre lieu o\u00f9 la personne concern\u00e9e se rend de fa\u00e7on habituelle pour des motifs d\u2019ordre familial et le lieu du travail.<\/p>\n<p>Le Tribunal d\u00e9cide d\u2019excepter des 5 mois restants de l\u2019interdiction de conduire \u00e0 prononcer, le trajet d\u2019aller et de retour effectu\u00e9 entre la r\u00e9sidence principale, une r\u00e9sidence secondaire pr\u00e9sentant un caract\u00e8re de stabilit\u00e9 ou tout autre lieu o\u00f9 le pr\u00e9venu se rend de fa\u00e7on habituelle pour des motifs d\u2019ordre familial et le lieu du travail et le retour ainsi que les trajets effectu\u00e9s dans l\u2019int\u00e9r\u00eat prouv\u00e9 de son employeur.<\/p>\n<p>P A R C E S M O T I F S :<\/p>\n<p>la treizi\u00e8me chambre du Tribunal d&#039;arrondissement de et \u00e0 Luxembourg, compos\u00e9e de son premier juge-pr\u00e9sident, statuant contradictoirement, le pr\u00e9venu entendu en ses explications et moyens de d\u00e9fense, le repr\u00e9sentant du Minist\u00e8re Public entendu en son r\u00e9quisitoire,<\/p>\n<p>c o n d a m n e P.1.) du chef des infractions retenues \u00e0 sa charge qui se trouvent en concours id\u00e9al \u00e0 une amende de MILLE (1.000) euros, ainsi qu&#039;aux frais de sa poursuite p\u00e9nale, ces frais liquid\u00e9s \u00e0 24,52 euros ,<\/p>\n<p>f i x e la dur\u00e9e de la contrainte par corps en cas de non-paiement de l\u2019amende \u00e0 DIX (10 ) jours,<\/p>\n<p>5 p r o n o n c e contre P.1.) du chef des infractions retenues \u00e0 sa charge pour la dur\u00e9e de VINGT-CINQ (25) mois l&#039;interdiction de conduire un v\u00e9hicule automoteur des cat\u00e9gories A &#8211; F sur la voie publique,<\/p>\n<p>d i t qu&#039;il sera sursis \u00e0 l&#039;ex\u00e9cution de VINGT (20 ) mois de cette interdiction de conduire,<\/p>\n<p>a v e r t i t P.1.) qu\u2019au cas o\u00f9, dans un d\u00e9lai de cinq ans \u00e0 dater du pr\u00e9sent jugement, il aura commis une nouvelle infraction ayant entra\u00een\u00e9 une condamnation \u00e0 une interdiction de conduire un v\u00e9hicule sur la voie publique ou \u00e0 une peine privative de libert\u00e9 pour crimes ou d\u00e9lits pr\u00e9vus par la l\u00e9gislation sur la circulation sur les voies publiques ou sur la vente de substances m\u00e9dicamenteuses et la lutte contre la toxicomanie, l\u2019interdiction de conduire prononc\u00e9e ci- devant sera ex\u00e9cut\u00e9e sans confusion possible avec la nouvelle peine,<\/p>\n<p>e x c e p t e des CINQ (5) mois restants de cette interdiction de conduire le trajet d\u2019aller et de retour effectu\u00e9 entre la r\u00e9sidence principale, une r\u00e9sidence secondaire pr\u00e9sentant un caract\u00e8re de stabilit\u00e9 ou tout autre lieu o\u00f9 P.1.) se rend de fa\u00e7on habituelle pour des motifs d\u2019ordre familial et le lieu du travail et le retour ainsi que les trajets effectu\u00e9s dans l\u2019int\u00e9r\u00eat prouv\u00e9 de son employeur.<\/p>\n<p>Par application des articles 27, 28, 29 et 30 du Code p\u00e9nal, des articles 154, 179, 182, 184, 189, 190, 190- 1, 194, 195, 196, 628 et 628- 1 du Code de proc\u00e9dure p\u00e9nale, des articles 12 et 13 de la loi modifi\u00e9e du 14 f\u00e9vrier 1955 et de l\u2019article 140 de l\u2019arr\u00eat\u00e9 grand- ducal modifi\u00e9 du 23 novembre 1955 qui furent d\u00e9sign\u00e9s \u00e0 l&#039;audience par le premier juge-pr\u00e9sident.<\/p>\n<p>Ainsi fait, jug\u00e9 et prononc\u00e9 par Bob PIRON, premier juge-pr\u00e9sident, en audience publique au Tribunal d\u2019arrondissement de et \u00e0 Luxembourg, en pr\u00e9sence de Pascal COLAS, premier substitut du procureur d\u2019Etat et de Josiane CENDECKI , greffi\u00e8re, qui, \u00e0 l&#039;exception du repr\u00e9sentant du Minist\u00e8re Public, ont sign\u00e9 le pr\u00e9sent jugement.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/tribunal-darrondissement-luxembourg-penal\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/tribunal-darrondissement-luxembourg-penal\/20240828-013133\/20200520-talux13-1181a-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jugt n\u00b0 1181\/ 2020 Not. 35473\/ 19\/CC 2x i.c.(s.) (i.c. prov.) AUDIENCE PUBLIQUE DU 20 MAI 2020 Le Tribunal d&#8217;arrondissement de et \u00e0 Luxembourg, treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique , a rendu le jugement qui suit: dans la\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[23583],"kji_chamber":[25729],"kji_year":[41198],"kji_subject":[7632],"kji_keyword":[23584,7636],"kji_language":[7733],"class_list":["post-747517","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-tribunal-darrondissement","kji_chamber-penal","kji_year-41198","kji_subject-penal","kji_keyword-arrondissement","kji_keyword-tribunal","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tribunal d&#039;arrondissement, 20 mai 2020 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal d&#039;arrondissement, 20 mai 2020\" \/>\n<meta property=\"og:description\" content=\"Jugt n\u00b0 1181\/ 2020 Not. 35473\/ 19\/CC 2x i.c.(s.) (i.c. prov.) AUDIENCE PUBLIQUE DU 20 MAI 2020 Le Tribunal d&#039;arrondissement de et \u00e0 Luxembourg, treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique , a rendu le jugement qui suit: dans la\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T06:02:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-20-mai-2020\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-20-mai-2020\\\/\",\"name\":\"Tribunal d'arrondissement, 20 mai 2020 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2026-04-29T06:02:45+00:00\",\"dateModified\":\"2026-04-29T06:02:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-20-mai-2020\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-20-mai-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/tribunal-darrondissement-20-mai-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal d&rsquo;arrondissement, 20 mai 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tribunal d'arrondissement, 20 mai 2020 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/","og_locale":"zh_CN","og_type":"article","og_title":"Tribunal d'arrondissement, 20 mai 2020","og_description":"Jugt n\u00b0 1181\/ 2020 Not. 35473\/ 19\/CC 2x i.c.(s.) (i.c. prov.) AUDIENCE PUBLIQUE DU 20 MAI 2020 Le Tribunal d'arrondissement de et \u00e0 Luxembourg, treizi\u00e8me chambre, si\u00e9geant en mati\u00e8re correctionnelle, statuant en composition de juge unique , a rendu le jugement qui suit: dans la\u2026","og_url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-29T06:02:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"11 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/","url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/","name":"Tribunal d'arrondissement, 20 mai 2020 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#website"},"datePublished":"2026-04-29T06:02:45+00:00","dateModified":"2026-04-29T06:02:49+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/tribunal-darrondissement-20-mai-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Tribunal d&rsquo;arrondissement, 20 mai 2020"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/zh-hans\/#website","url":"https:\/\/kohenavocats.com\/zh-hans\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision\/747517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=747517"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_country?post=747517"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_court?post=747517"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_chamber?post=747517"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_year?post=747517"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_subject?post=747517"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_keyword?post=747517"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_language?post=747517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}