{"id":791266,"date":"2026-05-01T00:11:40","date_gmt":"2026-04-30T22:11:40","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/"},"modified":"2026-05-01T00:11:45","modified_gmt":"2026-04-30T22:11:45","slug":"cour-superieure-de-justice-19-avril-2018","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 19 avril 2018"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Arr\u00eat N\u00b0 49\/18 &#8211; VIII &#8211; Travail<\/p>\n<p>Exempt \u2013 appel en mati\u00e8re de droit du travail<\/p>\n<p>Audience publique du dix -neuf avril d eux mille dix-huit<\/p>\n<p>Num\u00e9ro 44477 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Agn\u00e8s ZAGO, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain BERNARD, greffier.<\/p>\n<p>Entre:<\/p>\n<p>Ma\u00eetre Yann BADEN, avocat \u00e0 la Cour, demeurant \u00e0 L- 6187 Gonderange, Zone d\u2019Activit\u00e9 Gehaansr\u00e4ich, agissant en sa qualit\u00e9 de curateur de la soci\u00e9t\u00e9 anonyme SOC.1.), ayant \u00e9t\u00e9 \u00e9tablie et ayant eu son si\u00e8ge social \u00e0 L- (\u2026), d\u00e9clar\u00e9e en \u00e9tat de faillite par jugement du tribunal d\u2019arrondissement de Luxembourg du 15 octobre 2010, appelant aux termes d\u2019un acte de l\u2019huissier de justice Pierre BIEL de Luxembourg du 27 janvier 2017, comparant par Ma\u00eetre Yann BADEN , avocat \u00e0 la Cour, demeurant \u00e0 Gonderange,<\/p>\n<p>et: X.), demeurant \u00e0 L-(\u2026), intim\u00e9e aux fins du pr\u00e9dit acte BIEL , comparant par Ma\u00eetre Nicolas FRANCOIS , avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>2 LA COUR D\u2019APPEL:<\/p>\n<p>X.) a \u00e9t\u00e9 au service de la soci\u00e9t\u00e9 anonyme SOC.1.) , en tant que comptable, du 1 er mars 2008 au 15 octobre 2010, date \u00e0 laquelle la soci\u00e9t\u00e9 qui l\u2019employait a \u00e9t\u00e9 d\u00e9clar\u00e9e en \u00e9tat de faillite par le tribunal d\u2019arrondissement de et \u00e0 Luxembourg.<\/p>\n<p>Le 5 novembre 2010, X.) a d\u00e9pos\u00e9 au greffe du tribunal d\u2019arrondissement deux d\u00e9clarations de cr\u00e9ance. La premi\u00e8re, enregistr\u00e9e sous le num\u00e9ro 71, a \u00e9t\u00e9 admise au passif superprivil\u00e9gi\u00e9 de la faillite pour le montant de 14.959,50 EUR sur base des dispositions de l\u2019article L. 125- 1(1) du Code du travail. La seconde, enregistr\u00e9e sous le num\u00e9ro 66, porte sur le montant de 7.700. &#8211; EUR auquel X.) estime avoir droit sur base du plan social, qui avait \u00e9t\u00e9 conclu le 10 ao\u00fbt 2010, soit deux mois avant la survenance de la faillite, entre la soci\u00e9t\u00e9 SOC.1.), les d\u00e9l\u00e9gu\u00e9s du personnel et l\u2019OGB-L en vue de licenciements collectifs envisag\u00e9s afin d\u2019assurer la survie de l\u2019entreprise.<\/p>\n<p>Le curateur de la soci\u00e9t\u00e9 faillie s\u2019est oppos\u00e9 \u00e0 l\u2019admission au passif de la cr\u00e9ance au motif que la salari\u00e9e n\u2019avait pas fait l\u2019objet du licenciement collectif mis en place par la soci\u00e9t\u00e9 SOC.1.) , mais que son contrat de travail avait \u00e9t\u00e9 r\u00e9sili\u00e9 par l\u2019effet de la cessation de l\u2019activit\u00e9 de son employeur suite \u00e0 la survenance de la faillite. Il estime, par cons\u00e9quent, que la cr\u00e9ance de X.) devrait se limiter au montant d\u00fb en vertu de l\u2019article L. 125-1(1) pr\u00e9cit\u00e9.<\/p>\n<p>Les contestations relatives \u00e0 cette d\u00e9claration de cr\u00e9ance ont \u00e9t\u00e9 renvoy\u00e9es, par jugement du 18 d\u00e9cembre 2015, devant le tribunal du travail. Celui-ci a \u00e9t\u00e9 saisi par la requ\u00eate de X.) d\u00e9pos\u00e9e au greffe le 9 mars 2016.<\/p>\n<p>X.) a augment\u00e9 sa demande au cours de l\u2019instance pendante devant le tribunal du travail \u00e0 hauteur d\u2019un montant de 21.316,21 EUR.<\/p>\n<p>Le tribunal du travail a, par jugement du 19 d\u00e9cembre 2016, d\u00e9clar\u00e9 la demande de X.) fond\u00e9e et a fix\u00e9 la cr\u00e9ance de la salari\u00e9e au montant de 7.700.- EUR. Pour d\u00e9cider ainsi, les premiers juges ont retenu<\/p>\n<p>&#8211; que le plan social sign\u00e9 le 10 ao\u00fbt 2010 sur base des dispositions de l\u2019article L. 166-1 et suivants du Code du travail avait pour but de fixer les conditions de licenciement du personnel dans le cadre du licenciement collectif de 24 salari\u00e9s sur les 37 salari\u00e9s occup\u00e9s par la soci\u00e9t\u00e9,<\/p>\n<p>&#8211; que les articles L. 166- 2 et L. 166- 3 du Code du travail ont \u00e9t\u00e9 introduits en droit luxembourgeois en application des directives europ\u00e9ennes 75\/129, 92\/56 et 98\/59 destin\u00e9es \u00e0 assurer le rapprochement des l\u00e9gislations des Etats- membres relatives aux licenciements collectifs,<\/p>\n<p>&#8211; qu\u2019ainsi, l\u2019article 2 de la directive 98\/59 concernant le rapprochement des l\u00e9gislations des Etats membres relatives aux licenciements collectifs impose \u00e0 l\u2019employeur qui envisage des licenciements collectifs de proc\u00e9der \u00e0 des consultations avec les repr\u00e9sentants des travailleurs afin d\u2019\u00e9valuer les possibilit\u00e9s d\u2019\u00e9viter ou de r\u00e9duire les licenciements collectifs ou d\u2019en att\u00e9nuer les cons\u00e9quences par le recours \u00e0 des mesures sociales d\u2019accompagnement,<\/p>\n<p>&#8211; que la directive 98\/59 s\u2019applique aux licenciements effectu\u00e9s par un employeur pour un ou plusieurs motifs non inh\u00e9rents \u00e0 la personne des travailleurs ainsi qu\u2019aux licenciements collectifs suite \u00e0 une cessation des activit\u00e9s de l\u2019\u00e9tablissement qui r\u00e9sulte d\u2019une d\u00e9cision de justice ordonnant sa dissolution et sa liquidation, alors m\u00eame que dans le cas d\u2019une telle cessation, la l\u00e9gislation nationale pr\u00e9voit la r\u00e9siliation avec effet imm\u00e9diat des contrats de travail des travailleurs (cf. en ce sens, l\u2019arr\u00eat C-235\/10 du 3 mars 2011, Cl. c. La.),<\/p>\n<p>&#8211; que selon la jurisprudence de la Cour de justice de l\u2019Union europ\u00e9enne, il appartient au juge national d\u2019interpr\u00e9ter le droit national \u00e0 la lumi\u00e8re du texte et des objectifs de la directive 98\/59, afin que les obligations figurant aux articles 2 et 3 soient respect\u00e9es et ex\u00e9cut\u00e9es,<\/p>\n<p>&#8211; qu\u2019outre son cadre l\u00e9gal, les termes du plan social litigieux visent son application \u00e0 tous les salari\u00e9s licenci\u00e9s pour cause \u00e9conomique dans l\u2019ann\u00e9e de sa signature, et ce m\u00eame en cas de cessation compl\u00e8te des activit\u00e9s de la soci\u00e9t\u00e9,<\/p>\n<p>&#8211; qu\u2019en d\u00e9duction de ces d\u00e9veloppements, le plan social avait vocation \u00e0 s\u2019appliquer \u00e9galement \u00e0 X.) , dont le contrat de travail avait pris fin par la survenance de la faillite de son employeur, deux mois apr\u00e8s la signature du plan en question,<\/p>\n<p>&#8211; que le montant de la cr\u00e9ance que la salari\u00e9e demandait \u00e0 voir fixer devait \u00eatre limit\u00e9 au montant indiqu\u00e9 par X.) dans sa d\u00e9claration de cr\u00e9ance.<\/p>\n<p>Le curateur de la soci\u00e9t\u00e9 SOC.1.) en faillite a r\u00e9guli\u00e8rement relev\u00e9 appel du jugement du 19 d\u00e9cembre 2016 par exploit d\u2019huissier de justice du 27 janvier 2017. Il demande, par r\u00e9formation, le rejet de la demande de X.) pour n\u2019\u00eatre pas fond\u00e9e.<\/p>\n<p>Le curateur de la faillite, Ma\u00eetre Yann BADEN, fait valoir que le contrat de travail qui liait X.) \u00e0 la soci\u00e9t\u00e9 SOC.1.) a pris fin par la survenance de la faillite de l\u2019employeur et que le plan social en cause a \u00e9t\u00e9 \u00e9tabli pour r\u00e9pondre aux exigences des articles L. 166 -1 et suivants du Code du travail prescrites pour les cas de licenciements collectifs. Ainsi, un salari\u00e9 dont le contrat de travail a pris fin par la survenance de la faillite de son employeur ne saurait r\u00e9clamer, outre les indemnit\u00e9s l\u00e9gales dues sur base de l\u2019article L. 125- 1(1) du Code du travail, des indemnit\u00e9s dues en vertu du plan social. Selon Ma\u00eetre Yann BADEN, il y aurait lieu de distinguer, en l\u2019esp\u00e8ce, entre les salari\u00e9s de la soci\u00e9t\u00e9 SOC.1.) dont le contrat de travail a \u00e9t\u00e9 r\u00e9solu, avant la survenance de la faillite, dans le cadre d\u2019un licenciement collectif et ceux, dont X.) , dont le contrat a cess\u00e9 par la mise en faillite de leur employeur. La nature des indemnit\u00e9s auxquelles ils auraient droit d\u00e9pendrait de ce crit\u00e8re.<\/p>\n<p>L\u2019appelant analyse de fa\u00e7on d\u00e9taill\u00e9e, l\u2019arr\u00eat de la Cour de justice C-235\/10 par rapport au cas d\u2019esp\u00e8ce, ainsi que les travaux parlementaires relatifs \u00e0 l\u2019article 30 de la loi du 24 mai 1989, article qui correspond aux deux premiers alin\u00e9as de l\u2019article L. 125-1(1) du Code du travail.<\/p>\n<p>En ordre subsidiaire, le curateur d\u00e9nie \u00e0 X.) le b\u00e9n\u00e9fice des points IX (indemnisation pour licenciement collectif : 6.200.- EUR) et X (dans le cas d\u2019une renonciation de la part du salari\u00e9 \u00e0 une mesure sociale d\u2019accompagnement : 1.500.- EUR) du plan social, puisque ces points ne pr\u00e9voiraient pas les modalit\u00e9s \u00e0 remplir par le salari\u00e9 pour b\u00e9n\u00e9ficier d\u2019une indemnisation en cas de faillite.<\/p>\n<p>X.) conclut \u00e0 la confirmation du jugement entrepris en ce que les premiers juges ont retenu l\u2019applicabilit\u00e9 du plan social \u00e0 son \u00e9gard. Elle fait valoir que le propre d\u2019un plan social serait d\u2019accorder aux salari\u00e9s concern\u00e9s par un licenciement collectif des mesures de compensation financi\u00e8re qui vont au- del\u00e0 des indemnit\u00e9s pr\u00e9vues par la loi ou par une convention collective, de sorte qu\u2019il ne saurait lui \u00eatre oppos\u00e9 de choix entre l\u2019une ou l\u2019autre de ses d\u00e9clarations de cr\u00e9ance. Tel serait le cas, en l\u2019esp\u00e8ce, des articles VI \u00e0 X du plan social. La salari\u00e9e demande acte de ce qu\u2019elle augmente la cr\u00e9ance litigieuse au montant de 21.316,21 EUR suivant un d\u00e9compte qu\u2019elle fournit en pi\u00e8ce num\u00e9ro 7, premi\u00e8re page.<\/p>\n<p>X.) conteste l\u2019existence d\u2019un manque de respect de sa part de la proc\u00e9dure qu\u2019elle aurait d\u00fb suivre selon l\u2019annexe 6) du plan social, \u00e0 savoir, la notification par la salari\u00e9e au curateur de son acceptation ou de son renoncement au b\u00e9n\u00e9fice d\u2019une assistance dans la recherche d\u2019un nouvel emploi. Elle souligne que la clause en question pr\u00e9voirait \u00e0 cet \u00e9gard une possibilit\u00e9 de notifier son choix et non pas une obligation.<\/p>\n<p>Elle critique \u00e9galement l\u2019interpr\u00e9tation que fait le curateur du plan social en ce que celui-ci estime que si la salari\u00e9e renonce aux mesures sociales d\u2019accompagnement, elle renonce aux avantages sociaux garantis par le plan social en cas de faillite et, \u00ab qu\u2019en cas de renonciation, les mesures d\u2019accompagnement se transforment en indemnit\u00e9 volontaire, mais l\u2019indemnisation du salari\u00e9 n\u2019est pas envisag\u00e9e par le plan social \u00bb. X.) renvoie \u00e0 l\u2019article X, \u00a711 du plan social, lequel garantirait le cumul des indemnit\u00e9s r\u00e9clam\u00e9es.<\/p>\n<p>Le curateur de la soci\u00e9t\u00e9 SOC.1.) en faillite s\u2019oppose \u00e0 l\u2019augmentation de sa d\u00e9claration de cr\u00e9ance par X.) .<\/p>\n<p>Motifs de la d\u00e9cision<\/p>\n<p>&#8211; Le cadre normatif L\u2019article L. 125- 1(1) du Code du travail pr\u00e9voit que le contrat de travail est r\u00e9sili\u00e9 avec effet imm\u00e9diat en cas de cessation des affaires par suite de d\u00e9c\u00e8s, d\u2019incapacit\u00e9 physique ou de d\u00e9claration en \u00e9tat de faillite de l\u2019employeur. Il pr\u00e9voit encore que le salari\u00e9 a droit au maintien des salaires se rapportant au mois de la survenance de la faillite et au mois subs\u00e9quent, et \u00e0 l\u2019attribution d\u2019une indemnit\u00e9 \u00e9gale \u00e0 cinquante pour cent des mensualit\u00e9s se rapportant au d\u00e9lai de pr\u00e9avis auquel le salari\u00e9 aurait pu pr\u00e9tendre conform\u00e9ment aux dispositions de l\u2019article L. 124- 3 du Code du travail.<\/p>\n<p>5 Il pr\u00e9cise toutefois que cette solution ne vaut que \u00ab sauf continuation des affaires par le curateur ou le successeur de l\u2019employeur \u00bb.<\/p>\n<p>Cette solution l\u00e9gislative, qui semble impliquer que la faillite produit un effet imm\u00e9diat et in\u00e9luctable de cessation du contrat de travail, est cependant contraire, dans certains cas, \u00e0 une r\u00e8gle de droit europ\u00e9en que le l\u00e9gislateur luxembourgeois a transpos\u00e9e aux articles L. 166- 1 et suivants du Code du travail, lesquels s\u2019appliquent non point \u00e0 toutes les cessations de contrats de travail cons\u00e9cutifs \u00e0 une faillite, mais uniquement aux cessations collectives (\u00ab licenciements collectifs \u00bb), c\u2019est-\u00e0-dire, en droit luxembourgeois, aux licenciements d\u2019au moins 7 salari\u00e9s pour une m\u00eame p\u00e9riode de 30 jours et aux licenciements d\u2019au moins 15 salari\u00e9s pour une m\u00eame p\u00e9riode de 90 jours.<\/p>\n<p>Cette r\u00e8gle applicable aux licenciements collectifs prend son origine dans une s\u00e9rie de directives europ\u00e9ennes, \u00e0 partir de la directive 70\/129\/CEE du Conseil, du 17 f\u00e9vrier 1975. Selon cette derni\u00e8re directive, elle ne s\u2019appliquait pas aux travailleurs touch\u00e9s par la cessation des activit\u00e9s de l\u2019\u00e9tablissement lorsque celle-ci r\u00e9sultait d\u2019une d\u00e9cision de justice telle la faillite. Depuis la directive 92\/56 CEE du Conseil du 24 juin 1992, cette restriction au champ d\u2019application de la directive a \u00e9t\u00e9 supprim\u00e9e. La directive 75\/129, telle que modifi\u00e9e par la directive 92\/56, a \u00e9t\u00e9 abrog\u00e9e et remplac\u00e9e par la directive 98\/59, actuellement en vigueur, qui maintient l\u2019inclusion des licenciements collectifs suite \u00e0 une faillite dans son champ d\u2019application.<\/p>\n<p>Il r\u00e9sulte de cette directive, ainsi que de l\u2019article L. 166- 2 du Code du travail, que lorsque la faillite est susceptible d\u2019entra\u00eener des licenciements qui en raison du nombre des salari\u00e9s concern\u00e9s sont \u00e0 qualifier de licenciements collectifs, elle ne peut, par exception \u00e0 l\u2019article L. 125(1) du Code du travail, pas entra\u00eener automatiquement la cessation des contrats de travail ; au contraire, la proc\u00e9dure de licenciements collectifs, telle qu\u2019elle est pr\u00e9vue par la directive et par l\u2019article L. 166- 2 du Code du travail, doit \u00eatre suivie au pr\u00e9alable, avant que le licenciement puisse \u00eatre notifi\u00e9 au salari\u00e9 par le curateur de faillite.<\/p>\n<p>Cette incidence de la proc\u00e9dure europ\u00e9enne des licenciements collectifs sur les faillites luxembourgeoises a donn\u00e9 lieu \u00e0 une s\u00e9rie d\u2019arr\u00eats de la Cour de cassation du 29 avril 2010 (num\u00e9ros 28\/10 et suivants) saisissant la Cour de justice de l\u2019Union europ\u00e9enne de la question de savoir si la directive 98\/59\/CEE \u00e9tait \u00e0 interpr\u00e9ter en ce sens qu\u2019elle s\u2019appliquait \u00e0 une cessation des affaires par suite d\u2019une d\u00e9claration de faillite de l\u2019employeur et, dans l\u2019affirmative, si le curateur \u00e9tait \u00e0 assimiler \u00e0 un employeur ayant envisag\u00e9 des licenciements collectifs et \u00e9tant en mesure d\u2019accomplir, dans cette perspective, les actes vis\u00e9s aux articles 2 et 3 de la directive et d\u2019effectuer les licenciements.<\/p>\n<p>Dans son arr\u00eat pr\u00e9judiciel du 3 mars 2011 (Claes et autres, affaires jointes C- 235\/10 \u00e0 C-239\/10), la CJUE r\u00e9pondit, dans le contexte particulier de la liquidation d\u2019un \u00e9tablissement de cr\u00e9dit par l\u2019affirmative \u00e0 la premi\u00e8re question de la Cour de cassation. Elle r\u00e9pondit comme suit \u00e0 la deuxi\u00e8me question :<\/p>\n<p>\u00ab Jusqu\u2019\u00e0 l\u2019extinction d\u00e9finitive de la personnalit\u00e9 juridique d\u2019un \u00e9tablissement dont la dissolution et la liquidation sont ordonn\u00e9es, les obligations d\u00e9coulant des<\/p>\n<p>6 articles 2 et 3 de la directive 98\/59 doivent \u00eatre remplies. Les obligations qui incombent \u00e0 l\u2019employeur en vertu de ces articles doivent \u00eatre ex\u00e9cut\u00e9es par la direction de l\u2019\u00e9tablissement en cause, lorsqu\u2019elle reste en place, m\u00eame avec des pouvoirs limit\u00e9s quant \u00e0 la gestion de cet \u00e9tablissement, ou par le liquidateur de celui-ci, dans la mesure o\u00f9 la gestion de cet \u00e9tablissement, ou par le liquidateur de celui-ci, dans la mesure o\u00f9 la gestion dudit \u00e9tablissement est reprise enti\u00e8rement par ce liquidateur \u00bb.<\/p>\n<p>Apr\u00e8s cassation de l\u2019arr\u00eat d\u00e9f\u00e9r\u00e9 (Cass. 27 octobre 2011, arr\u00eats num\u00e9ros 60\/11 et suivants), la composition de la Cour d\u2019appel \u00e0 laquelle l\u2019affaire avait \u00e9t\u00e9 renvoy\u00e9e (ordonnances de la Cour d\u2019appel du 8 d\u00e9cembre 2011), d\u00e9cida que la situation dans laquelle se trouvaient les salari\u00e9s (en l\u2019esp\u00e8ce, il s\u2019agissait de salari\u00e9s prot\u00e9g\u00e9s) concern\u00e9s par le jugement d\u00e9claratif de l\u2019insolvabilit\u00e9 de leur employeur, un \u00e9tablissement bancaire, ne relevait pas de la cessation automatique des contrats de travail, mais d\u2019un licenciement collectif qu\u2019il convenait de d\u00e9clarer irr\u00e9gulier.<\/p>\n<p>Les conclusions juridiques qu\u2019il convient de tirer de ces arr\u00eats sont claires et sont transposables, sans difficult\u00e9s, au pr\u00e9sent cas bien que celui-ci ne concerne pas un salari\u00e9 prot\u00e9g\u00e9, mais un salari\u00e9 ordinaire et qu\u2019il a trait \u00e0 une proc\u00e9dure de faillite et non \u00e0 une proc\u00e9dure de liquidation d\u2019un \u00e9tablissement bancaire (cf. en ce sens les arr\u00eats de la Cour de cassation du 29 avril 2010).<\/p>\n<p>Il est constant qu\u2019en l\u2019esp\u00e8ce, 13 salari\u00e9s ont perdu leur emploi du fait de la faillite, ce qui est un nombre suffisant pour que l\u2019application de la proc\u00e9dure pour licenciements collectifs ait \u00e9t\u00e9 obligatoire ; avant le jugement d\u00e9claratif de la faillite, 24 autres salari\u00e9s avaient, par ailleurs, fait l\u2019objet d\u2019un plan social moins de 90 jours avant la faillite et leur nombre peut \u00eatre ajout\u00e9 au nombre de salari\u00e9s directement concern\u00e9s par la faillite conform\u00e9ment \u00e0 l\u2019article L. 166- 1 du Code du travail. N\u00e9anmoins, Ma\u00eetre Yann BADEN a appliqu\u00e9, \u00e0 tort, l\u2019article L. 125- 1 du Code du travail (cessation automatique des contrats de travail) au lieu de suivre la proc\u00e9dure de l\u2019article L. 166- 2 du Code du travail.<\/p>\n<p>La question dont le tribunal du travail a \u00e9t\u00e9 saisi n\u2019est toutefois pas celle de la r\u00e9gularit\u00e9 du licenciement, mais celle du droit de la salari\u00e9e de b\u00e9n\u00e9ficier des stipulations du plan social conclu avant le jugement d\u00e9claratif, et dont la clause II (alin\u00e9as 3 et 4) stipule que \u00ab Le Plan social s\u2019applique \u00e0 compter de sa signature et jusqu\u2019au 12 \u00e8me mois suivant sa signature, et cela exclusivement aux salari\u00e9s qui doivent \u00eatre licenci\u00e9s pour des motifs d\u2019ordre \u00e9conomique. Par cons\u00e9quent, dans l\u2019hypoth\u00e8se o\u00f9 SOC.1.) devait \u00eatre amen\u00e9e \u00e0 stopper totalement ses activit\u00e9s dans l\u2019ann\u00e9e suivant la signature du Plan social et suivant les licenciements des personnes vis\u00e9es \u00e0 l\u2019annexe 1, les salari\u00e9s restant aupr\u00e8s de SOC.1.) b\u00e9n\u00e9ficieront \u00e9galement des avantages sociaux li\u00e9s au pr\u00e9sent Plan social, sans qu\u2019une nouvelle proc\u00e9dure de licenciements collectifs soit mis en place \u00bb.<\/p>\n<p>&#8211; L\u2019applicabilit\u00e9 du plan social<\/p>\n<p>Le plan social a \u00e9t\u00e9 sign\u00e9 le 10 ao\u00fbt 2010 et la date de la faillite, trait\u00e9e par le curateur de la soci\u00e9t\u00e9 employeuse comme entrainant automatiquement la<\/p>\n<p>7 cessation des contrats de travail est le 10 octobre 2010. Il s\u2019ensuit que la stipulation selon laquelle le plan social s\u2019applique pendant les 12 mois suivant sa signature aux salari\u00e9s qui doivent \u00eatre licenci\u00e9s pour des motifs d\u2019ordre \u00e9conomique s\u2019applique \u00e0 X.) .<\/p>\n<p>&#8211; Les cons\u00e9quences p\u00e9cuniaires pour la salari\u00e9e<\/p>\n<p>Le plan social s\u2019appliquant pour les raisons pr\u00e9cit\u00e9es \u00e0 X.), il y a lieu d\u2019analyser les moyens que le curateur de la faillite SOC.1.) S.A. soul\u00e8ve, en ordre subsidiaire, afin de d\u00e9montrer que la cr\u00e9ance de la salari\u00e9e n\u2019est pas fond\u00e9e.<\/p>\n<p>La salari\u00e9e revendique, aux termes de sa d\u00e9claration de cr\u00e9ance num\u00e9ro 66, les montants de (31 mois d\u2019anciennet\u00e9 x 200.- EUR) 6.200.- EUR sur base de l\u2019article IX du plan social et le montant de 1.500.- EUR sur base l\u2019article X. L\u2019augmentation de sa cr\u00e9ance a \u00e9t\u00e9 d\u00e9clar\u00e9e irrecevable en premi\u00e8re instance. Elle r\u00e9it\u00e8re, en instance d\u2019appel, sa demande en augmentation au montant de 21.316,21 EUR ; ce montant r\u00e9sulte de la diff\u00e9rence entre les montants qu\u2019elle aurait d\u00fb percevoir en cas d\u2019application du plan social et les sommes qu\u2019elle a per\u00e7ues en vertu de l\u2019article L. 125-1 du Code du travail, augment\u00e9e des indemnit\u00e9s de 6.200.- EUR et 1.500.- EUR d\u00e9finies ci- avant.<\/p>\n<p>A la date du jugement d\u00e9claratif de faillite, X.) avait une anciennet\u00e9 de service de 31 mois. Elle a, partant, droit, en vertu de l\u2019article IX du plan social, \u00e0 une indemnit\u00e9 volontaire de licenciement \u00e9gale \u00e0 (31 x 200 =) 6.200.- EUR.<\/p>\n<p>Concernant l\u2019indemnit\u00e9 pr\u00e9vue \u00e0 l\u2019article X, la salari\u00e9e r\u00e9clame l\u2019indemnit\u00e9 de 1.500.- EUR due aux salari\u00e9s ayant renonc\u00e9 \u00e0 une mesure sociale d\u2019accompagnement ; l\u2019appelant s\u2019y oppose au motif que la salari\u00e9e n\u2019aurait pas suivi les formalit\u00e9s impos\u00e9es par l\u2019article en question ainsi que par l\u2019annexe 6).<\/p>\n<p>L\u2019article X pr\u00e9voit, en son dernier alin\u00e9a, que \u00ab Si le salari\u00e9 renonce \u00e0 ces mesures (mesures sociales d\u2019accompagnement), il pourra demander en contrepartie le paiement du montant de 1.500.- EUR par courrier \u00e0 SOC.1.) dans l\u2019ann\u00e9e suivant la fin du pr\u00e9avis. Ce choix pourra \u00eatre notifi\u00e9 \u00e0 l\u2019Employeur \u00e0 l\u2019aide de l\u2019annexe 6. Ce montant sera alors consid\u00e9r\u00e9 comme une indemnit\u00e9 volontaire au m\u00eame titre que les indemnit\u00e9s pr\u00e9vues \u00e0 l\u2019article IX. Ce montant sera pay\u00e9 dans un d\u00e9lai d\u2019un mois suivant la demande du salari\u00e9, et au plus t\u00f4t en m\u00eame temps que le versement des indemnit\u00e9s volontaires vis\u00e9es \u00e0 l\u2019article IX du Plan social(\u2026) \u00bb.<\/p>\n<p>L\u2019annexe 6) repr\u00e9sente un courrier d\u2019information \u00e0 l\u2019adresse de l\u2019employeur par lequel le salari\u00e9 informe la soci\u00e9t\u00e9 SOC.1.) de son choix parmi les trois possibilit\u00e9s qui lui sont offertes (assistance dans la recherche d\u2019emploi, b\u00e9n\u00e9fice de formations pour un budget de 1.500.- EUR ou renonciation aux mesures d\u2019accompagnement avec allocation d\u2019une indemnit\u00e9 de 1.500.- EUR) ; il suffisait aux salari\u00e9s int\u00e9ress\u00e9s de copier ou d\u2019envoyer la page en question \u00e0 SOC.1.) S.A. pour informer celle- ci de son choix dans l\u2019ann\u00e9e suivant la fin du pr\u00e9avis.<\/p>\n<p>Il n\u2019est pas contest\u00e9 en cause que X.) , qui se pr\u00e9vaut de sa renonciation \u00e0 toute mesure d\u2019accompagnement, n\u2019a pas inform\u00e9 la soci\u00e9t\u00e9 SOC.1.) S.A. de son choix<\/p>\n<p>8 par l\u2019envoi d\u2019un courrier ; elle fait valoir que suivant les termes de l\u2019article X, dernier alin\u00e9a, la notification d\u2019une renonciation \u00e9tait facultative (\u00ab ce choix pourra \u00eatre notifi\u00e9 (\u2026) \u00bb).<\/p>\n<p>La Cour ne partage pas cette interpr\u00e9tation. En effet, il y a lieu de consid\u00e9rer l\u2019int\u00e9gralit\u00e9 de la phrase pour comprendre que le verbe \u00ab pourra \u00bb laisse la facult\u00e9 au salari\u00e9 de notifier son choix \u00ab \u00e0 l\u2019aide de l\u2019annexe 6 \u00bb ou par tout autre moyen. Le fait que le choix doit \u00eatre port\u00e9 \u00e0 la connaissance de l\u2019employeur dans un d\u00e9lai d\u00e9limit\u00e9 confirme cette interpr\u00e9tation : en effet, dans l\u2019optique d\u2019une bonne administration par les dirigeants de la soci\u00e9t\u00e9, et, ensuite, par le curateur des suites du plan social, il est n\u00e9cessaire que les salari\u00e9s lui soumettent leur choix dans le d\u00e9lai imparti. En l\u2019esp\u00e8ce, X.) a d\u00e9pos\u00e9 sa d\u00e9claration de cr\u00e9ance relative \u00e0 l\u2019indemnit\u00e9 pr\u00e9vue \u00e0 l\u2019article X, le 3 novembre 2010 au greffe du tribunal de commerce. Par ce d\u00e9p\u00f4t, elle a, \u00e0 suffisance de droit, notifi\u00e9 son choix au curateur de la faillite dans le d\u00e9lai imparti.<\/p>\n<p>X.) critique encore l\u2019interpr\u00e9tation que fait le curateur du plan social en ce qu\u2019il estime que si un salari\u00e9 renonce aux mesures sociales d\u2019accompagnement, il renonce aux avantages sociaux garantis par le plan social en cas de faillite et, \u00ab qu\u2019en cas de renonciation, les mesures d\u2019accompagnement se transforment en indemnit\u00e9 volontaire, mais l\u2019indemnisation du salari\u00e9 n\u2019est pas envisag\u00e9e par le plan social \u00bb.<\/p>\n<p>L\u2019article X, dernier alin\u00e9a du Plan social garantit le cumul des indemnit\u00e9s r\u00e9clam\u00e9es par X.) sur base des articles IX et X du Plan social. Le moyen soulev\u00e9 par l\u2019appelant n\u2019est, par cons\u00e9quent, pas fond\u00e9 et la cr\u00e9ance de la salari\u00e9e, bas\u00e9e sur l\u2019article X, dernier alin\u00e9a du Plan social pr\u00e9cit\u00e9 est justifi\u00e9e pour le montant de 1.500.- EUR.<\/p>\n<p>Le curateur de la soci\u00e9t\u00e9 SOC.1.) en faillite s\u2019oppose \u00e0 l\u2019augmentation de sa d\u00e9claration de cr\u00e9ance par X.) en invoquant le contrat judiciaire qui se serait form\u00e9 entre eux par la d\u00e9claration de cr\u00e9ance num\u00e9ro 66, que la salari\u00e9e avait limit\u00e9e au montant de 7.700.- EUR.<\/p>\n<p>En vertu du principe de l&#039;immutabilit\u00e9 du litige tel qu&#039;il \u00e9tait entendu sous l&#039;empire de l&#039;ancien code de proc\u00e9dure civile, il \u00e9tait interdit au demandeur de changer, en cours d&#039;instance, tant l&#039;objet, \u00e0 savoir ses pr\u00e9tentions, que la cause de sa demande, c&#039;est-\u00e0-dire l&#039;ensemble des faits se trouvant \u00e0 la base de la demande, \u00e0 moins que le d\u00e9fendeur n&#039;y consente.<\/p>\n<p>La port\u00e9e de ce principe se trouve modifi\u00e9e depuis l&#039;entr\u00e9e en vigueur du Nouveau code de proc\u00e9dure civile, dont l&#039;article 53 est ainsi r\u00e9dig\u00e9: \u00ab L\u2019objet du litige est d\u00e9termin\u00e9 par les pr\u00e9tentions respectives des parties. Ces pr\u00e9tentions sont fix\u00e9es par l&#039;acte introductif d&#039;instance et par les conclusions en d\u00e9fense. Toutefois l&#039;objet du litige peut \u00eatre modifi\u00e9 par des demandes incidentes lorsque celles-ci se rattachent aux pr\u00e9tentions originaires par un lien suffisant \u00bb.<\/p>\n<p>Cette modification l\u00e9gislative a substitu\u00e9 le crit\u00e8re, plus souple, du lien suffisant entre la demande originaire et la demande nouvelle au crit\u00e8re, qui existait sous<\/p>\n<p>9 l&#039;ancienne l\u00e9gislation telle qu&#039;elle \u00e9tait interpr\u00e9t\u00e9e en jurisprudence, de l&#039;identit\u00e9 de leurs objets et causes.<\/p>\n<p>En l&#039;esp\u00e8ce, le tribunal estime qu&#039;il existe un lien suffisant entre la demande originaire de X.) r\u00e9sultant de sa d\u00e9claration de cr\u00e9ance et l\u2019augmentation de sa demande formul\u00e9e devant les juridictions du travail, de sorte qu\u2019il y a lieu d\u2019appliquer l&#039;article 53 du Nouveau code de proc\u00e9dure civile et de d\u00e9clarer cette demande recevable.<\/p>\n<p>Aux termes de son d\u00e9compte (pi\u00e8ce no 7), X.) r\u00e9clame les indemnit\u00e9s que les autres salari\u00e9s de la soci\u00e9t\u00e9 SOC.1.), qui ont fait l\u2019objet du licenciement collectif en ao\u00fbt 2010, ont per\u00e7ues sur base des articles VI, VII et VIII du plan social. Ces montants correspondent aux pi\u00e8ces vers\u00e9es en cause et ne sont pas contest\u00e9s en tant que tels par le curateur. Il y a, partant, lieu de fixer la cr\u00e9ance de X.) au montant de 21.316,21 EUR, conform\u00e9ment au d\u00e9compte qu\u2019elle verse en cause (cf. pi\u00e8ce n\u00b0 7).<\/p>\n<p>&#8211; Les indemnit\u00e9s de proc\u00e9dure<\/p>\n<p>Au vu de l\u2019issue du litige, il y a lieu de d\u00e9clarer la demande de l\u2019appelante bas\u00e9e sur l\u2019article 240 du Nouveau code de proc\u00e9dure civile non fond\u00e9e.<\/p>\n<p>Il en est de m\u00eame de la demande de X.), celle-ci restant en d\u00e9faut de justifier de l\u2019iniquit\u00e9 requise par l\u2019article 240 du nouveau code de proc\u00e9dure civile.<\/p>\n<p>PAR CES MOTIFS :<\/p>\n<p>la Cour d\u2019appel, huiti\u00e8me chambre, si\u00e9geant en mati\u00e8re de droit du travail, statuant contradictoirement, sur le rapport du magistrat de la mise en \u00e9tat,<\/p>\n<p>re\u00e7oit l\u2019appel principal et l\u2019appel incident,<\/p>\n<p>dit l\u2019appel principal non fond\u00e9 ; dit l\u2019appel incident fond\u00e9 ;<\/p>\n<p>fixe la cr\u00e9ance de X.) au montant de 21.316,21 EUR ;<\/p>\n<p>confirme le jugement du tribunal du travail de Luxembourg du 19 d\u00e9cembre 2016 pour le surplus ;<\/p>\n<p>d\u00e9clare non fond\u00e9es les demandes des parties en paiement d\u2019une indemnit\u00e9 de proc\u00e9dure pour l\u2019instance d\u2019appel ;<\/p>\n<p>met les frais et d\u00e9pens de l\u2019instance d\u2019appel \u00e0 charge de la masse de la faillite de la soci\u00e9t\u00e9 anonyme SOC.1.) .<\/p>\n<p>10 La lecture de cet arr\u00eat a \u00e9t\u00e9 faite \u00e0 l\u2019audience publique indiqu\u00e9e ci-dessus par Lotty PRUSSEN, pr\u00e9sident de chambre, en pr\u00e9sence du greffier Alain BERNARD.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-8\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-8\/20240827-204642\/20180419-ca8-44477-faillite-a-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arr\u00eat N\u00b0 49\/18 &#8211; VIII &#8211; Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du dix -neuf avril d eux mille dix-huit Num\u00e9ro 44477 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Agn\u00e8s ZAGO, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[21144],"kji_year":[47917],"kji_subject":[7724],"kji_keyword":[8683,8601,9055,12307,9688],"kji_language":[7733],"class_list":["post-791266","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-8","kji_year-47917","kji_subject-civil","kji_keyword-arret","kji_keyword-avril","kji_keyword-justice","kji_keyword-superieure","kji_keyword-travail","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 19 avril 2018 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 19 avril 2018\" \/>\n<meta property=\"og:description\" content=\"Arr\u00eat N\u00b0 49\/18 - VIII - Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du dix -neuf avril d eux mille dix-huit Num\u00e9ro 44477 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Agn\u00e8s ZAGO, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T22:11:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-19-avril-2018\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-19-avril-2018\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 19 avril 2018 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2026-04-30T22:11:40+00:00\",\"dateModified\":\"2026-04-30T22:11:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-19-avril-2018\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-19-avril-2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-19-avril-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 19 avril 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 19 avril 2018 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/","og_locale":"zh_CN","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 19 avril 2018","og_description":"Arr\u00eat N\u00b0 49\/18 - VIII - Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du dix -neuf avril d eux mille dix-huit Num\u00e9ro 44477 du r\u00f4le. Composition: Lotty PRUSSEN, pr\u00e9sident de chambre; Agn\u00e8s ZAGO, premier conseiller; Jeanne GUILLAUME, premier conseiller; Alain\u2026","og_url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-04-30T22:11:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"23 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/","url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/","name":"Cour sup\u00e9rieure de justice, 19 avril 2018 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#website"},"datePublished":"2026-04-30T22:11:40+00:00","dateModified":"2026-04-30T22:11:45+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-19-avril-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 19 avril 2018"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/zh-hans\/#website","url":"https:\/\/kohenavocats.com\/zh-hans\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision\/791266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=791266"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_country?post=791266"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_court?post=791266"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_chamber?post=791266"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_year?post=791266"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_subject?post=791266"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_keyword?post=791266"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_language?post=791266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}