{"id":811674,"date":"2026-05-02T00:21:47","date_gmt":"2026-05-01T22:21:47","guid":{"rendered":"https:\/\/kohenavocats.com\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/"},"modified":"2026-05-02T00:21:51","modified_gmt":"2026-05-01T22:21:51","slug":"cour-superieure-de-justice-12-juin-2017-2","status":"publish","type":"kji_decision","link":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/","title":{"rendered":"Cour sup\u00e9rieure de justice, 12 juin 2017"},"content":{"rendered":"<div class=\"kji-decision\">\n<div class=\"kji-full-text\">\n<p>Arr\u00eat N\u00b0 83\/17 &#8211; VIII &#8211; Travail<\/p>\n<p>Exempt \u2013 appel en mati\u00e8re de droit du travail<\/p>\n<p>Audience publique du douze juin deux mille dix -sept<\/p>\n<p>Num\u00e9ro 43373 du r\u00f4le. Composition: Serge THILL, premier conseiller, pr\u00e9sident; Agn\u00e8s ZAGO, premier conseiller; Marie-Paule BISDORFF, conseiller; Alain BERNARD, greffier.<\/p>\n<p>Entre:<\/p>\n<p>1) la soci\u00e9t\u00e9 anonyme SOC1.) S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L- (\u2026), (\u2026), en liquidation volontaire suivant acte du 19 mai 2014, repr\u00e9sent\u00e9e par son liquidateur Christophe RAVIGNAT, 2) la soci\u00e9t\u00e9 anonyme SOC2.) GROUP S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L-(\u2026), (\u2026), repr\u00e9sent\u00e9e par son conseil d\u2019administration, 3) la soci\u00e9t\u00e9 anonyme SOC2.) S.A., \u00e9tablie et ayant son si\u00e8ge social \u00e0 L- (\u2026), (\u2026), repr\u00e9sent\u00e9e par son conseil d\u2019administration, appelantes aux termes d\u2019 un acte de l\u2019huissier de justice Frank SCHAAL de Luxembourg du 26 f\u00e9vrier 2016, comparaissant par Ma\u00eetre Claude SPEICHER, avocat \u00e0 la Cour, demeurant \u00e0 Diekirch,<\/p>\n<p>et: B.), demeurant \u00e0 F-(\u2026), (\u2026), intim\u00e9 aux fins du pr\u00e9dit acte SCHAAL,<\/p>\n<p>2 comparaissant par Ma\u00eetre Fran\u00e7ois REINARD , avocat \u00e0 la Cour, demeurant \u00e0 Luxembourg.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>LA COUR D\u2019APPEL:<\/p>\n<p>Expos\u00e9 du litige<\/p>\n<p>Par requ\u00eate d\u00e9pos\u00e9e le 16 f\u00e9vrier 2015, B.) , entr\u00e9 au service de la soci\u00e9t\u00e9 anonyme SOC1.) SA (ci-apr\u00e8s la soci\u00e9t\u00e9 SOC1.)) en qualit\u00e9 de chauffeur routier suivant contrat de travail du 19 juillet 1999, a saisi le tribunal du travail de Diekirch d\u2019une action contre la soci\u00e9t\u00e9 SOC1.), en liquidation volontaire suivant acte du 19 mai 2014, la soci\u00e9t\u00e9 anonyme SOC2.) GROUP SA (ci- apr\u00e8s la soci\u00e9t\u00e9 SOC2.) GROUP) et la soci\u00e9t\u00e9 anonyme SOC2.) SA (ci-apr\u00e8s la soci\u00e9t\u00e9 SOC2.)), tendant principalement \u00e0 voir constater la reprise, depuis le 16 octobre 2013, par la soci\u00e9t\u00e9 SOC2.) GROUP SA, sinon la soci\u00e9t\u00e9 SOC2.) SA, des activit\u00e9s et des contrats de travail conclus par la soci\u00e9t\u00e9 SOC1.) SA, d\u00e9clarer abusif le licenciement avec pr\u00e9avis du 29 avril 2014, et condamner la soci\u00e9t\u00e9 SOC2.) GROUP, sinon la soci\u00e9t\u00e9 SOC2.) , au paiement de la somme de 162.536,79 \u20ac du chef de diverses indemnit\u00e9s, au titre, notamment, des dommages et int\u00e9r\u00eats pour licenciement abusif et des cong\u00e9s suppl\u00e9mentaires non octroy\u00e9s, ainsi que d\u2019une indemnit\u00e9 de proc\u00e9dure de 2.000 \u20ac.<\/p>\n<p>A titre subsidiaire, l\u2019action tend \u00e0 voir constater que la soci\u00e9t\u00e9 SOC1.) fait partie du groupe de soci\u00e9t\u00e9s SOC2.) GROUP, d\u00e9clarer abusif le licenciement avec pr\u00e9avis du 29 avril 2014 et condamner les soci\u00e9t\u00e9s SOC1.), SOC2.) GROUP, et SOC2.) au paiement solidaire, sinon in solidum, sinon par chacune pour le tout, sinon par chacune pour sa part, de la somme de 162.536,79 \u20ac au titre de diverses indemnit\u00e9s et de 2.000 \u20ac \u00e0 titre d\u2019indemnit\u00e9 de proc\u00e9dure.<\/p>\n<p>Par jugement contradictoire n\u00b0 143\/16 du 1 er f\u00e9vrier 2016, le tribunal du travail de Diekirch, recevant la demande en la forme, a d\u00e9clar\u00e9 le licenciement abusif et d\u00e9bout\u00e9 B.) de sa demande en dommages et int\u00e9r\u00eats pour non- respect de la proc\u00e9dure de l\u2019entretien pr\u00e9alable. Pour le surplus, il a sursis \u00e0 statuer sur la demande.<\/p>\n<p>Pour statuer ainsi, cette juridiction, apr\u00e8s avoir soulign\u00e9 que la sanction du non- respect de la proc\u00e9dure de l\u2019entretien pr\u00e9alable n\u2019intervenait qu\u2019en cas de licenciement r\u00e9gulier quant au fond, a conclu au caract\u00e8re abusif de ce dernier en retenant que :<\/p>\n<p>\u2022 \u00ab le contrat de travail conclu entre B.) et la soci\u00e9t\u00e9 anonyme SOC1.) a \u00e9galement \u00e9t\u00e9 r\u00e9sili\u00e9 par cette derni\u00e8re et (qu\u2019) il y a partant lieu d\u2019analyser le bien- fond\u00e9 du cong\u00e9diement litigieux dans cette optique. Au vu des pi\u00e8ces vers\u00e9es en cause, il est cependant incontestable que la soci\u00e9t\u00e9 anonyme SOC1.) faisait partie du groupe SOC2.) \u00bb<\/p>\n<p>3 \u2022 \u00ab force est de constater qu\u2019en l\u2019esp\u00e8ce, le motif du licenciement de B.) , de nature \u00e9conomique, n\u2019a pas \u00e9t\u00e9 \u00e9nonc\u00e9 avec la pr\u00e9cision requise par la loi. En effet, il a \u00e9t\u00e9 indiqu\u00e9 que la soci\u00e9t\u00e9 anonyme SOC1.) a \u00e9t\u00e9 mise en liquidation volontaire par d\u00e9cision d\u2019une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire des actionnaires, ceci suite \u00e0 un ralentissement net de l\u2019activit\u00e9 de l\u2019entreprise depuis plusieurs mois. On indique \u00e9galement l\u2019absence de perspective d\u2019am\u00e9lioration. Cependant, ce ralentissement de l\u2019activit\u00e9 respectivement le d\u00e9faut de perspective n\u2019est \u00e9tay\u00e9 par aucun chiffre concret \u00bb<\/p>\n<p>\u2022 \u00ab d\u2019autre part et comme \u00e9nonc\u00e9 ci-avant, il est incontestable que la soci\u00e9t\u00e9 anonyme SO C1.) fait respectivement faisait partie du groupe SOC2.). Partant, il ne suffit pas dans le cadre d\u2019un licenciement d\u2019un salari\u00e9 d\u2019une soci\u00e9t\u00e9 faisant partie d\u2019un groupe de soci\u00e9t\u00e9s de prendre en consid\u00e9ration seulement la situation de la situation de la soci\u00e9t\u00e9 employeuse, mais bien celle du groupe entier dont il n\u2019est pas en l\u2019esp\u00e8ce all\u00e9gu\u00e9 qu\u2019il rencontre des probl\u00e8mes \u00e9conomiques \u00bb.<\/p>\n<p>De ce jugement, les soci\u00e9t\u00e9s SOC1.), SOC2.) GROUP et SOC2.) ont r\u00e9guli\u00e8rement relev\u00e9 appel par exploit d\u2019huissier de justice du 26 f\u00e9vrier 2016. Elles demandent, par r\u00e9formation du jugement entrepris, de d\u00e9clarer le licenciement r\u00e9gulier et de d\u00e9bouter B.) de toutes ses revendications.<\/p>\n<p>Au soutien de leur recours, les soci\u00e9t\u00e9s appelantes font valoir que m\u00eame si la soci\u00e9t\u00e9 SOC1.), employeuse de B.) , peut \u00e9ventuellement \u00eatre consid\u00e9r\u00e9e comme appartenant au m\u00eame groupe de soci\u00e9t\u00e9s, elle constitue cependant une entit\u00e9 juridique distincte libre de d\u00e9cider &#8211; en vertu de son pouvoir de direction et sans possibilit\u00e9 de remise en cause par le salari\u00e9 &#8211; de la cessation de son entreprise sans qu\u2019il ne soit n\u00e9cessaire de justifier cette d\u00e9cision par des chiffres concrets, de sorte que par r\u00e9formation du jugement entrepris ayant \u00e0 tort d\u00e9clar\u00e9 le licenciement abusif, il y aurait lieu de dire que le motif invoqu\u00e9 \u00e0 l\u2019appui du licenciement avec pr\u00e9avis est pr\u00e9cis, r\u00e9el et s\u00e9rieux.<\/p>\n<p>Objectant que les d\u00e9bats en premi\u00e8re instance \u00e9taient limit\u00e9s \u00e0 la question du caract\u00e8re abusif du licenciement et que le volet de l\u2019indemnisation n\u2019y avait pas encore \u00e9t\u00e9 tois\u00e9, B.) conclut \u00e0 la confirmation du jugement entrepris en ce qu\u2019il a dit le licenciement abusif.<\/p>\n<p>Il fait valoir \u00e0 cet \u00e9gard qu\u2019aux termes de la lettre de motivation du 27 mai 2014, le licenciement litigieux est intervenu \u00ab pour motif \u00e9conomique \u00bb, tir\u00e9 du \u00ab net ralentissement constat\u00e9 depuis plusieurs mois au niveau de l\u2019activit\u00e9 de l\u2019entreprise, sp\u00e9cialis\u00e9e dans le transport de marchandises entre Marseille et le Maghreb \u00bb, sans \u00ab perspective d\u2019am\u00e9lioration de ce contexte \u00e9conomique \u00bb, et de ce que l\u2019assembl\u00e9e g\u00e9n\u00e9rale extraordinaire des actionnaires aurait d\u00fb prononcer la dissolution anticip\u00e9e et mise en liquidation de la soci\u00e9t\u00e9 en date du 19 mai 2014, \u00ab impliquant, \u00e0 terme, la cessation des contrats en cours et la fermeture de l\u2019entreprise \u00bb.<\/p>\n<p>Aussi, selon B.) , la totalit\u00e9 des sept chauffeurs routiers de la soci\u00e9t\u00e9 SOC1.) aurait-elle \u00e9t\u00e9 licenci\u00e9e au courant de la p\u00e9riode d\u2019avril \u00e0 juin 2014.<\/p>\n<p>Or, il serait document\u00e9 par des photos prises pendant les mois de juin 2014 \u00e0 mai 2015 que les transports initialement assur\u00e9s par les chauffeurs routiers licenci\u00e9s continuent \u00e0 \u00eatre effectu\u00e9s au d\u00e9part du port de Marseille et de Vitrolles par des chauffeurs venus de divers pays de l\u2019Est, notamment de la Roumanie, avec les m\u00eames camions et les m\u00eames remorques que ceux initialement utilis\u00e9s par les salari\u00e9s licenci\u00e9s de SOC1.) , y compris ceux de B.) .<\/p>\n<p>Le motif \u00e9conomique serait donc fallacieux pour ne constituer qu\u2019un pr\u00e9texte, le pr\u00e9tendu ralentissement d\u2019activit\u00e9 n\u2019\u00e9tant pas \u00e9tabli en cause.<\/p>\n<p>Par voie d\u2019appel incident, il demande toutefois \u00e0 la Cour d\u2019appel, par r\u00e9formation du jugement entrepris, de constater principalement \u00ab que les activit\u00e9s et les contrats de travail conclus par SOC1.) SA ont \u00e9t\u00e9 repris par SOC2.) GROUP S.A., sinon SOC2.) S.A. \u00bb, et de d\u00e9clarer \u00ab fond\u00e9e en son principe la demande en indemnisation contre SOC2.) GROUP S.A., sinon SOC2.) S.A. \u00bb ou, subsidiairement, de \u00ab constater que SOC1.) S.A. fait partie du groupe de soci\u00e9t\u00e9s SOC2.) GROUP \u00bb et de \u00ab d\u00e9clarer fond\u00e9e en son principe la demande en indemnisation contre SOC1.) S.A.<\/p>\n<p>Les parties appelantes concluent d\u2019abord \u00e0 l\u2019irrecevabilit\u00e9 de l\u2019appel incident en soutenant que m\u00eame s\u2019il r\u00e9sulte implicitement de la motivation du jugement entrepris que la soci\u00e9t\u00e9 SOC1.) \u00e9tait l\u2019employeur de B.) au moment des faits, les juges de premi\u00e8re instance ne l\u2019auraient pas tranch\u00e9 au dispositif de leur d\u00e9cision, de sorte que le jugement ne pourrait \u00eatre attaqu\u00e9 sur ce point.<\/p>\n<p>Elles soul\u00e8vent ensuite en instance d\u2019appel le d\u00e9faut de qualit\u00e9 dans le chef des soci\u00e9t\u00e9s SOC2.) GROUP et SOC2.) en absence de transfert \u00e0 ces deux soci\u00e9t\u00e9s du contrat de travail conclu avec B.) , et demandent \u00e0 la Cour d\u2019appel de mettre lesdites soci\u00e9t\u00e9s appelantes hors de cause.<\/p>\n<p>Au fond, elles concluent au rejet de l\u2019appel incident d\u00e8s lors que, l\u2019employeur pouvant librement mettre un terme \u00e0 l\u2019activit\u00e9 de l\u2019entreprise, le licenciement serait r\u00e9gulier et il serait alors sans importance pour l\u2019issue du litige de savoir si la soci\u00e9t\u00e9 SOC1.) appartient au groupe SOC2.) ou non.<\/p>\n<p>B.) s\u2019oppose aux moyens adverses en faisant valoir que le tribunal du travail a statu\u00e9 au dispositif du jugement critiqu\u00e9 sur la question du caract\u00e8re abusif du licenciement alors que, pour ce faire, il aurait d\u2019abord d\u00fb d\u00e9terminer si les activit\u00e9s et les contrats de travail conclus par la soci\u00e9t\u00e9 SOC1.) ont \u00e9t\u00e9 repris par la soci\u00e9t\u00e9 SOC2.) GROUP, sinon par la soci\u00e9t\u00e9 SOC2.), la r\u00e9ponse \u00e0 cette question n\u2019ayant pas seulement une incidence sur l\u2019appr\u00e9ciation de la r\u00e9gularit\u00e9 du licenciement, mais \u00e9galement sur la question de savoir laquelle ou lesquelles des soci\u00e9t\u00e9s parties \u00e0 l\u2019instance seront tenues de l\u2019indemniser.<\/p>\n<p>Or, contrairement \u00e0 l\u2019argumentation adverse, le raisonnement des juges de premi\u00e8re instance expos\u00e9 dans les motifs du jugement entrepris non seulement ne ferait pas sous-entendre que la soci\u00e9t\u00e9 SOC1.) \u00e9tait l\u2019employeur de B.) lors du licenciement mais, de plus, le tribunal du travail aurait omis de statuer sur les chefs de demande tendant \u00e0 voir constater principalement que les activit\u00e9s<\/p>\n<p>5 et contrats de travail de la soci\u00e9t\u00e9 SOC1.) ont \u00e9t\u00e9 repris par les soci\u00e9t\u00e9s SOC2.) GROUP, sinon SOC2.) , ou, subsidiairement, que la soci\u00e9t\u00e9 SOC1.) fait partie du groupe de soci\u00e9t\u00e9s SOC2.), de sorte que l\u2019appel incident serait recevable.<\/p>\n<p>Il faudrait d\u00e9duire notamment de la nomination, en date du 16 octobre 2013, de la soci\u00e9t\u00e9 SOC2.) GROUP comme administrateur de la soci\u00e9t\u00e9 SOC1.) , des communications adress\u00e9es \u00e0 B.) par le service des ressources humaines de la soci\u00e9t\u00e9 SOC2.) GROUP, laquelle a \u00e9galement \u00e9tabli les documents de travail de sortie de celui-ci \u00e0 la suite de son licenciement, et de la correspondance li\u00e9e au licenciement lui envoy\u00e9e par la soci\u00e9t\u00e9 SOC1.) mais portant le logo du groupe SOC2.) GROUP et l\u2019adresse du site internet dudit groupe, que tant l\u2019activit\u00e9 que le contrat de travail conclu avec B.) ont \u00e9t\u00e9 repris par la soci\u00e9t\u00e9 SOC2.) GROUP, sinon la soci\u00e9t\u00e9 SOC2.) .<\/p>\n<p>A d\u00e9faut, il y aurait lieu de conclure au vu de ces \u00e9l\u00e9ments, ainsi que des autres documents produits en cause, tels la liste des principaux employeurs \u00e9mise par l\u2019Institut national de la statistique et des \u00e9tudes \u00e9conomiques ou encore les notes d\u2019information, que la soci\u00e9t\u00e9 SOC1.) appartient au groupe de soci\u00e9t\u00e9s SOC2.) GROUP qui l\u2019a contr\u00f4lerait d\u2019un point de vue administratif, des activit\u00e9s et des int\u00e9r\u00eats financiers.<\/p>\n<p>Les juges de premi\u00e8re instance auraient \u00e0 juste titre qualifi\u00e9 le licenciement d\u2019abusif pour impr\u00e9cision des motifs, les pr\u00e9tendues difficult\u00e9s \u00e9conomiques y \u00e9nonc\u00e9es n\u2019ayant par ailleurs pas \u00e9t\u00e9 mises en rapport avec la situation \u00e9conomique du groupe entier.<\/p>\n<p>Pour le surplus, B.) demande le renvoi de l\u2019affaire en pros\u00e9cution de cause devant le tribunal du travail de Diekirch.<\/p>\n<p>Appr\u00e9ciation<\/p>\n<p>Sur l\u2019appel incident La recevabilit\u00e9 de l\u2019appel incident d\u00e9pend de la recevabilit\u00e9 de l\u2019appel principal. L\u2019appel principal \u00e9tant recevable en l\u2019esp\u00e8ce, cette premi\u00e8re condition de recevabilit\u00e9 de l\u2019appel incident est remplie. S\u2019y ajoute toutefois une condition de recevabilit\u00e9 suppl\u00e9mentaire : l\u2019int\u00e9r\u00eat \u00e9tant la mesure des actions, l\u2019appel incident n\u2019est recevable que si la partie intim\u00e9e qui le forme est l\u00e9s\u00e9e par la d\u00e9cision entreprise. Pour savoir si un jugement fait grief \u00e0 une partie, il y a lieu de se r\u00e9f\u00e9rer \u00e0 son dispositif. Si comme en l\u2019esp\u00e8ce, le jugement, dans son dispositif, ne tranche que certains points de la demande tout en r\u00e9servant d\u2019autres, il y a lieu de v\u00e9rifier si l\u2019omission de la juridiction du premier degr\u00e9 de r\u00e9pondre \u00e0 un chef de demande particulier, bien que cela lui e\u00fbt express\u00e9ment \u00e9t\u00e9 demand\u00e9, est volontaire ou non.<\/p>\n<p>6 Si l\u2019omission est volontaire et que le chef de la demande fait partie de ceux sur lesquels la juridiction du premier degr\u00e9 a sursis \u00e0 statuer, alors l\u2019appel incident est irrecevable.<\/p>\n<p>Si, par contre, l\u2019omission est involontaire, alors la partie intim\u00e9e a un int\u00e9r\u00eat \u00e0 la voir r\u00e9parer par la r\u00e9formation de la d\u00e9cision incompl\u00e8te et l\u2019appel incident est recevable.<\/p>\n<p>Les juges de premi\u00e8re instance ont d\u00e9clar\u00e9 le licenciement abusif sans se prononcer, au dispositif de la d\u00e9cision entreprise, sur le transfert du contrat de travail conclu avec la soci\u00e9t\u00e9 SOC1.) \u00e0 la soci\u00e9t\u00e9 SOC2.) GROUP, sinon \u00e0 la soci\u00e9t\u00e9 SOC2.), ou sur l\u2019appartenance de la soci\u00e9t\u00e9 SOC1.) au groupe SOC2.) GROUP.<\/p>\n<p>C\u2019est \u00e0 bon escient que B.) fait valoir qu\u2019en l\u2019esp\u00e8ce, l\u2019action tendant \u00e0 voir d\u00e9clarer le licenciement abusif est dirig\u00e9e contre plusieurs employeurs par ordre de subsidiarit\u00e9 et que dans ce cas de figure, le licenciement ne peut \u00eatre d\u00e9clar\u00e9 abusif sans que les juges ne d\u00e9terminent concomitamment contre lequel des employeurs \u00e9ventuels l\u2019action est recevable et fond\u00e9e.<\/p>\n<p>En l\u2019esp\u00e8ce, les juges de premi\u00e8re instance ont d\u2019une part motiv\u00e9 leur d\u00e9cision en constatant que le contrat de travail conclu entre B.) et la soci\u00e9t\u00e9 SOC1.) a \u00e9t\u00e9 r\u00e9sili\u00e9 par cette derni\u00e8re. D\u2019autre part, ils ont dit dans la motivation du jugement d\u00e9f\u00e9r\u00e9 qu\u2019au vu des pi\u00e8ces vers\u00e9es en cause, il \u00e9tait incontestable que la soci\u00e9t\u00e9 SOC1.) faisait partie du groupe SOC2.) GROUP.<\/p>\n<p>Le pouvoir de r\u00e9siliation du contrat de travail revenant \u00e0 l\u2019employeur, ils ont donc implicitement retenu que la soci\u00e9t\u00e9 SOC1.) restait l\u2019employeur de B.) .<\/p>\n<p>En omettant de dire pour droit de que de ce fait est exclue l\u2019hypoth\u00e8se d\u2019un transfert du contrat de travail \u00e0 la soci\u00e9t\u00e9 SOC2.) GROUP ou \u00e0 la soci\u00e9t\u00e9 SOC2.), ils ont par contre omis de r\u00e9pondre \u00e0 la demande y aff\u00e9rente de B.) .<\/p>\n<p>Il s\u2019en d\u00e9duit que l\u2019omission par les juges du premier degr\u00e9 d\u2019exprimer au dispositif du jugement entrepris leur constatation de l\u2019appartenance de la soci\u00e9t\u00e9 SOC1.) au groupe SOC2.) GROUP et de l\u2019absence de transfert du contrat de travail \u00e0 une autre soci\u00e9t\u00e9 du groupe constitue une omission involontaire, de sorte que l\u2019appel incident est recevable \u00e0 cet \u00e9gard. En revanche, l\u2019appel incident est irrecevable en ce qu\u2019il tend \u00e0 voir d\u00e9clarer \u00ab fond\u00e9e en son principe la demande en indemnisation contre SOC2.) GROUP S.A., sinon SOC2.) S.A. \u00bb, sinon \u00e0 voir \u00ab d\u00e9clarer fond\u00e9e en son principe la demande en indemnisation contre SOC1.) S.A \u00bb \u00e9tant donn\u00e9 que le tribunal du travail a r\u00e9serv\u00e9 l\u2019int\u00e9gralit\u00e9 du volet de l\u2019indemnisation en refixant l\u2019affaire pour continuation des d\u00e9bats.<\/p>\n<p>Concernant le bien- fond\u00e9 de l\u2019appel incident, la Cour d\u2019appel souligne d\u2019abord que m\u00eame si B.) , dans l\u2019\u00e9tat de ses derni\u00e8res conclusions, soutient que l\u2019activit\u00e9 de la soci\u00e9t\u00e9 SOC1.) \u00ab \u00e0 savoir le transport de marchandises entre le Maghreb, Marseille et notamment la Belgique \u00bb a \u00e9t\u00e9 continu\u00e9e apr\u00e8s sa mise en liquidation volontaire et apr\u00e8s le licenciement de B.) \u00ab par le groupe SOC2.)<\/p>\n<p>7 GROUP SA, via une ou plusieurs entit\u00e9s appartenant audit groupe et en ayant recours \u00e0 une main d\u2019\u0153uvre vraisemblablement venue des pays de l\u2019Est \u00bb, il n\u2019a cependant jamais soutenu pour fondement de sa demande de constater la reprise des activit\u00e9s et des contrats de travail de la soci\u00e9t\u00e9 SOC1.) que le transfert des activit\u00e9s et des contrats de travail \u00e0 une autre soci\u00e9t\u00e9 du groupe avait eu lieu \u00e0 l\u2019occasion de la liquidation volontaire de la soci\u00e9t\u00e9 SOC1.) , mais, au contraire, il l\u2019a toujours bas\u00e9e sur l\u2019hypoth\u00e8se que cette \u00ab reprise des activit\u00e9s et des contrats de travail \u00bb s\u2019\u00e9tait faite \u00e0 la fin de l\u2019ann\u00e9e 2013, de mani\u00e8re \u00e0 consid\u00e9rer qu\u2019elle \u00e9tait d\u2019ores et d\u00e9j\u00e0 intervenue \u00e0 la date de la r\u00e9siliation avec pr\u00e9avis du contrat de travail.<\/p>\n<p>La Cour d\u2019appel rel\u00e8ve ensuite que la \u00ab reprise des activit\u00e9s et des contrats de travail \u00bb d\u2019une soci\u00e9t\u00e9 s\u2019apparente \u00e0 un transfert d\u2019entreprise lequel, \u00e0 son tour, implique un changement d\u2019employeur (cf., notamment, arr\u00eat CJUE du 12 novembre 1998, E. SA, C-399\/96)<\/p>\n<p>Or, il n\u2019est produit en cause aucun \u00e9l\u00e9ment probant de nature \u00e0 \u00e9tablir qu\u2019au courant de la p\u00e9riode allant du 16 octobre 2013 au 29 avril 2014, avant la mise en liquidation volontaire de la soci\u00e9t\u00e9 SOC1.) , un transfert d\u2019entreprise se serait op\u00e9r\u00e9 de la soci\u00e9t\u00e9 SOC1.) \u00e0 une autre soci\u00e9t\u00e9 et que la soci\u00e9t\u00e9 SOC1.) aurait ainsi perdu sa qualit\u00e9 d\u2019employeur \u00e0 l\u2019\u00e9gard de B.) .<\/p>\n<p>La demande y aff\u00e9rente de B.) est donc \u00e0 \u00e9carter.<\/p>\n<p>C\u2019est \u00e0 bon droit que les juges de premi\u00e8re instance ont retenu au vu de l\u2019ensemble des pi\u00e8ces produites en cause que la soci\u00e9t\u00e9 SOC1.) faisait partie du groupe de soci\u00e9t\u00e9s SOC2.) GROUP, notamment par rapport \u00e0 l\u2019activit\u00e9 dans le domaine du transport, les pouvoirs de direction en la personne de A.) et des synergies au niveau de la gestion du personnel.<\/p>\n<p>Par contre &#8211; et contrairement \u00e0 l\u2019affirmation de B.) selon lequel la soci\u00e9t\u00e9 SOC2.) GROUP contr\u00f4lerait la soci\u00e9t\u00e9 SOC1.) d\u2019un point de vue administratif, des activit\u00e9s et des int\u00e9r\u00eats financiers &#8211; il ne r\u00e9sulte d\u2019aucun \u00e9l\u00e9ment de preuve que du fait de son appartenance au groupe de soci\u00e9t\u00e9s SOC2.) GROUP, la soci\u00e9t\u00e9 SOC1.), entit\u00e9 juridique distincte des autres, aurait perdu son autonomie. Il s\u2019en d\u00e9duit que la soci\u00e9t\u00e9 SOC1.) est l\u2019unique employeur de B.) , \u00e0 l\u2019exclusion des soci\u00e9t\u00e9s SOC2.) GROUP ou SOC2.), et qu\u2019elle peut seule \u00eatre rendue d\u00e9bitrice \u00e0 son \u00e9gard, en d\u00e9pit des liens qu\u2019elle puisse avoir eu, notamment au travers de son administrateur, avec d\u2019autres soci\u00e9t\u00e9s du groupe, de sorte qu\u2019il n\u2019y a pas de solidarit\u00e9 entre elles.<\/p>\n<p>Il convient donc, d\u2019un c\u00f4t\u00e9, de constater au dispositif de l\u2019arr\u00eat et par r\u00e9formation du jugement entrepris incomplet \u00e0 cet \u00e9gard, que la soci\u00e9t\u00e9 SOC1.) appartient au groupe de soci\u00e9t\u00e9 SOC2.) GROUP et, de l\u2019autre, de dire fond\u00e9 le moyen tir\u00e9 du d\u00e9faut de qualit\u00e9 dans le chef des soci\u00e9t\u00e9s SOC2.) GROUP et SOC2.) en ce que l\u2019action en justice est dirig\u00e9e contre elles et, par voie de cons\u00e9quence, de d\u00e9clarer celle- ci irrecevable \u00e0 leur \u00e9gard et de mettre ces soci\u00e9t\u00e9s hors de cause.<\/p>\n<p>8 Sur la r\u00e9gularit\u00e9 du licenciement avec pr\u00e9avis<\/p>\n<p>La soci\u00e9t\u00e9 appelante SOC1.) conteste le jugement frapp\u00e9 d\u2019appel en faisant valoir que le motif \u00e9conomique est pr\u00e9cis, r\u00e9el et s\u00e9rieux et que, la d\u00e9cision de fermeture de l\u2019entreprise appartenant \u00e0 l\u2019employeur en vertu de son pouvoir de direction, elle \u00e9tait libre de d\u00e9cider d\u2019arr\u00eater son commerce et de mettre fin \u00e0 son activit\u00e9 sans qu\u2019il ne soit n\u00e9cessaire d\u2019indiquer des chiffres concrets et de justifier la d\u00e9cision. Par ailleurs, il serait faux qu\u2019il aurait lieu d\u2019examiner la situation \u00e9conomique de l\u2019ensemble du groupe.<\/p>\n<p>B.) conclut \u00e0 la confirmation de la d\u00e9cision entreprise en ce qu\u2019elle a retenu l\u2019impr\u00e9cision du motif \u00e9conomique du licenciement.<\/p>\n<p>La Cour d\u2019appel retient en premier lieu qu\u2019en faisant \u00e9tat d\u2019un net ralentissement de l\u2019activit\u00e9 de l\u2019entreprise et de l\u2019absence de perspective d\u2019am\u00e9lioration de ce contexte \u00e9conomique, l\u2019employeur a indiqu\u00e9 de mani\u00e8re suffisamment pr\u00e9cise les raisons \u00e0 l\u2019origine de la d\u00e9cision de la soci\u00e9t\u00e9 SOC1.) de se mettre en liquidation volontaire. La partie appelante a encore \u00e0 suffisance pr\u00e9cis\u00e9 que cette mise en liquidation aboutira \u00e0 la cessation des contrats en cours et \u00e0 la fermeture de l\u2019entreprise.<\/p>\n<p>Par r\u00e9formation du jugement d\u00e9f\u00e9r\u00e9, il convient donc de dire que le motif \u00e9conomique \u00e0 la base du licenciement avec pr\u00e9avis a \u00e9t\u00e9 \u00e9nonc\u00e9 de mani\u00e8re suffisamment pr\u00e9cise pour permettre au salari\u00e9 et aux juridictions du travail de v\u00e9rifier si le licenciement est intervenu pour un motif est r\u00e9el et s\u00e9rieux, un tel contr\u00f4le n\u2019impliquant aucune immixtion du juge dans la gestion de l\u2019entreprise ou atteinte \u00e0 la libert\u00e9 d\u2019entreprendre.<\/p>\n<p>En vertu de l\u2019article L.124- 11(3) du code du travail, la charge de la preuve de la mat\u00e9rialit\u00e9 et du caract\u00e8re r\u00e9el et s\u00e9rieux des motifs incombe \u00e0 l\u2019employeur.<\/p>\n<p>En l\u2019esp\u00e8ce, la n\u00e9cessit\u00e9 \u00e9conomique all\u00e9gu\u00e9e de liquider l\u2019entreprise et de mettre fin \u00e0 son activit\u00e9 n\u2019est nullement document\u00e9e par les pi\u00e8ces produites en cause.<\/p>\n<p>Il ressort par contre des extraits du site internet (farde de 22 pi\u00e8ces du mandataire de B.) ) du groupe de soci\u00e9t\u00e9s SOC2.) GROUP, auquel la soci\u00e9t\u00e9 SOC1.) a fait partie depuis le mois de septembre 2011 avec les sites de Dendermonde (B), Paris (F), Tilburg (NL) et Casablanca (M), que le groupe a rachet\u00e9 les activit\u00e9s de la soci\u00e9t\u00e9 SOC1.) en pr\u00e9cisant que : \u00ab afin d\u2019assurer la continuit\u00e9 du service, les sites de Dendermonde, Paris, Tilburg et Casablanca sont maintenus, et les \u00e9quipes op\u00e9rationnelles et manag\u00e9riales seront renforc\u00e9es et int\u00e9gr\u00e9es \u00e0 l\u2019organisation de SOC2.) Group \u00bb, la partie appelante n\u2019ayant par ailleurs \u00e0 aucun moment contest\u00e9 l\u2019authenticit\u00e9 desdits extraits ainsi que la r\u00e9alit\u00e9 de la reprise des activit\u00e9s de la soci\u00e9t\u00e9 SOC1.) par le groupe apr\u00e8s sa mise en liquidation volontaire.<\/p>\n<p>Contrairement \u00e0 l\u2019affirmation de la soci\u00e9t\u00e9 SOC1.) quant \u00e0 un pouvoir discr\u00e9tionnaire de l\u2019employeur, seule une cessation compl\u00e8te de l\u2019activit\u00e9 de l\u2019employeur peut constituer en elle- m\u00eame une cause \u00e9conomique de<\/p>\n<p>9 licenciement, quand elle n\u2019est pas due \u00e0 une faute ou \u00e0 une l\u00e9g\u00e8ret\u00e9 bl\u00e2mable de ce dernier (cf., en ce sens, notamment, Cass. soc. fr., 10 octobre 2006, n\u00b0 04-43.453 ; Cass. soc. fr., 23 mars 2017, n\u00b0 15- 21.183)<\/p>\n<p>Or, en l\u2019esp\u00e8ce, la reprise et continuation de l\u2019activit\u00e9 de la soci\u00e9t\u00e9 SOC1.) en dissolution par le groupe de soci\u00e9t\u00e9s auquel elle appartient constitue, en l\u2019absence de preuve des difficult\u00e9s \u00e9conomiques all\u00e9gu\u00e9s par la soci\u00e9t\u00e9 SOC1.), la n\u00e9gation m\u00eame du motif de la suppos\u00e9 cessation d\u2019entreprise invoqu\u00e9 \u00e0 la base du licenciement litigieux, de sorte que la preuve du caract\u00e8re r\u00e9el et s\u00e9rieux du motif \u00e9conomique en soubassement du licenciement de B.) n\u2019est pas rapport\u00e9e.<\/p>\n<p>Il s\u2019ensuit que le jugement frapp\u00e9 d\u2019appel est \u00e0 confirmer en ce qu\u2019il a dit que le licenciement litigieux est abusif.<\/p>\n<p>Sur les demandes accessoires Les soci\u00e9t\u00e9s appelantes sollicitent une indemnit\u00e9 de proc\u00e9dure de 2.000 \u20ac et la condamnation de B. ) aux frais et d\u00e9pens des deux instances. La condition d\u2019iniquit\u00e9 pos\u00e9e par l\u2019article 240 du nouveau Code de proc\u00e9dure civile n\u2019\u00e9tant pas \u00e9tablie dans le chef des soci\u00e9t\u00e9s SOC2.) GROUP et SOC2.) , leur demande en obtention d\u2019une indemnit\u00e9 de proc\u00e9dure est \u00e0 \u00e9carter comme non fond\u00e9e. Il y a lieu de d\u00e9bouter la soci\u00e9t\u00e9 SOC1.) de sa demande en obtention d\u2019une indemnit\u00e9 de proc\u00e9dure au vu du r\u00e9sultat de l\u2019instance d\u2019appel. B.) sollicite de son c\u00f4t\u00e9 la condamnation solidaire, sinon in solidum, sinon de chacune pour le tout, sinon de chacune pour sa part, des soci\u00e9t\u00e9s appelantes au paiement d\u2019une indemnit\u00e9 de proc\u00e9dure de 2.000 \u20ac pour l\u2019instance d\u2019appel et aux frais et d\u00e9pens des deux instances avec distraction au profit de Ma\u00eetre Fran\u00e7ois REINARD. Les soci\u00e9t\u00e9s appelantes contestent la demande adverse.<\/p>\n<p>L\u2019\u00e9quit\u00e9 commande de ne pas laisser \u00e0 la charge de B.) l\u2019int\u00e9gralit\u00e9 des frais non compris dans les d\u00e9pens qu\u2019il a expos\u00e9s pour obtenir gain de cause en instance d\u2019appel.<\/p>\n<p>Compte tenu de l\u2019issue de l\u2019instance d\u2019appel, la demande n\u2019est cependant \u00e0 d\u00e9clarer fond\u00e9e qu\u2019\u00e0 l\u2019\u00e9gard de la soci\u00e9t\u00e9 SOC1.) pour le montant de 1.500 \u20ac auquel la Cour d\u2019appel \u00e9value l\u2019indemnit\u00e9 de proc\u00e9dure eu \u00e9gard aux \u00e9l\u00e9ments d\u2019appr\u00e9ciation dont elle dispose.<\/p>\n<p>Vu le r\u00e9sultat de l\u2019instance d\u2019appel et par r\u00e9formation du jugement de premi\u00e8re instance, il y a lieu de mettre les frais des deux instances \u00e0 la charge de B.) dans la mesure o\u00f9 son action est dirig\u00e9e contre les soci\u00e9t\u00e9s SOC2.) GROUP et SOC2.).<\/p>\n<p>En revanche, en consid\u00e9ration de ce r\u00e9sultat, il y a lieu de condamner la soci\u00e9t\u00e9 SOC1.) aux frais et d\u00e9pens de l\u2019instance d\u2019appel &#8211; ceux de premi\u00e8re instance restant r\u00e9serv\u00e9s \u00e0 son \u00e9gard &#8211; dans la mesure o\u00f9 la demande de B.) est dirig\u00e9e contre elle, avec distraction au profit de Ma\u00eetre Fran\u00e7ois REINARD qui la demande.<\/p>\n<p>PAR CES MOTIFS :<\/p>\n<p>La Cour d\u2019appel, huiti\u00e8me chambre, si\u00e9geant en mati\u00e8re de droit du travail, statuant contradictoirement, sur le rapport du conseiller d\u00e9sign\u00e9 \u00e0 cet effet ;<\/p>\n<p>dit l\u2019appel principal recevable et partiellement fond\u00e9 ;<\/p>\n<p>dit l\u2019appel incident partiellement recevable et partiellement fond\u00e9 ;<\/p>\n<p>r\u00e9formant :<\/p>\n<p>constate l\u2019appartenance de la soci\u00e9t\u00e9 anonyme SOC1.) S.A., en liquidation volontaire, au groupe de soci\u00e9t\u00e9s SOC2.) GROUP et dit pour droit que le contrat de travail de B.) n\u2019a pas \u00e9t\u00e9 transf\u00e9r\u00e9 \u00e0 l\u2019une des autres soci\u00e9t\u00e9s du groupe de soci\u00e9t\u00e9s SOC2.) GROUP ;<\/p>\n<p>dit la fin de non- recevoir du d\u00e9faut de qualit\u00e9 dans le chef des soci\u00e9t\u00e9s anonymes SOC2.) GROUP S.A. et SOC2.) S.A. fond\u00e9e ;<\/p>\n<p>par cons\u00e9quent, dit l\u2019action en justice irrecevable \u00e0 leur \u00e9gard et les met hors de cause ;<\/p>\n<p>pour le surplus :<\/p>\n<p>confirme le jugement entrepris ;<\/p>\n<p>renvoie l\u2019affaire en pros\u00e9cution de cause devant le tribunal du travail de Diekirch ;<\/p>\n<p>dit la demande des soci\u00e9t\u00e9s anonymes SOC1.) S.A., en liquidation volontaire, SOC2.) GROUP S.A. et SOC2.) S.A. en obtention d\u2019une indemnit\u00e9 de proc\u00e9dure non fond\u00e9e et les en d\u00e9boute ;<\/p>\n<p>condamne la soci\u00e9t\u00e9 anonyme SOC1.) S.A., en liquidation volontaire, \u00e0 payer \u00e0 B.) une indemnit\u00e9 de proc\u00e9dure de 1.500 \u20ac pour l\u2019instance d\u2019appel ;<\/p>\n<p>condamne la soci\u00e9t\u00e9 anonyme SOC1.) S.A., en liquidation volontaire, aux frais et d\u00e9pens de l\u2019instance d\u2019appel dans la mesure o\u00f9 l\u2019action est dirig\u00e9e \u00e0 son encontre et en ordonne la distraction au profit de Ma\u00eetre Fran\u00e7ois REINARD, avocat constitu\u00e9, qui la demande, affirmant en avoir fait l\u2019avance ;<\/p>\n<p>11 condamne B.) aux frais et d\u00e9pens des deux instances dans la mesure o\u00f9 l\u2019action est dirig\u00e9e contre les soci\u00e9t\u00e9s anonymes SOC2.) GROUP S.A. et SOC2.) S.A..<\/p>\n<p>La lecture de cet arr\u00eat a \u00e9t\u00e9 faite \u00e0 l\u2019audience publique indiqu\u00e9e ci-dessus par Serge THILL, premier conseiller, pr\u00e9sident, en pr\u00e9sence du greffier Alain BERNARD.<\/p>\n<\/div>\n<hr class=\"kji-sep\" \/>\n<p class=\"kji-source-links\"><strong>Sources officielles :<\/strong> <a class=\"kji-source-link\" href=\"https:\/\/data.public.lu\/fr\/datasets\/cour-superieure-de-justice-chambre-8\/\" target=\"_blank\" rel=\"noopener noreferrer\">consulter la page source<\/a> &middot; <a class=\"kji-pdf-link\" href=\"https:\/\/download.data.public.lu\/resources\/cour-superieure-de-justice-chambre-8\/20240827-204328\/20170612-ca8-43373a-accessible.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">PDF officiel<\/a><\/p>\n<p class=\"kji-license-note\"><em>Licence CC BY-ND 4.0 (Administration judiciaire, data.public.lu). Republication autorisee avec attribution, sans modification editoriale du texte integral.<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Arr\u00eat N\u00b0 83\/17 &#8211; VIII &#8211; Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du douze juin deux mille dix -sept Num\u00e9ro 43373 du r\u00f4le. Composition: Serge THILL, premier conseiller, pr\u00e9sident; Agn\u00e8s ZAGO, premier conseiller; Marie-Paule BISDORFF, conseiller; Alain BERNARD, greffier.\u2026<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_crdt_document":""},"kji_country":[8418],"kji_court":[12305],"kji_chamber":[21144],"kji_year":[52833],"kji_subject":[7724],"kji_keyword":[8683,9055,12307,9688],"kji_language":[7733],"class_list":["post-811674","kji_decision","type-kji_decision","status-publish","hentry","kji_country-luxembourg","kji_court-cour-superieure-de-justice","kji_chamber-chambre-8","kji_year-52833","kji_subject-civil","kji_keyword-arret","kji_keyword-justice","kji_keyword-superieure","kji_keyword-travail","kji_language-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cour sup\u00e9rieure de justice, 12 juin 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cour sup\u00e9rieure de justice, 12 juin 2017\" \/>\n<meta property=\"og:description\" content=\"Arr\u00eat N\u00b0 83\/17 - VIII - Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du douze juin deux mille dix -sept Num\u00e9ro 43373 du r\u00f4le. Composition: Serge THILL, premier conseiller, pr\u00e9sident; Agn\u00e8s ZAGO, premier conseiller; Marie-Paule BISDORFF, conseiller; Alain BERNARD, greffier.\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T22:21:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"24 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-12-juin-2017-2\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-12-juin-2017-2\\\/\",\"name\":\"Cour sup\u00e9rieure de justice, 12 juin 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2026-05-01T22:21:47+00:00\",\"dateModified\":\"2026-05-01T22:21:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-12-juin-2017-2\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-12-juin-2017-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/cour-superieure-de-justice-12-juin-2017-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurisprudences\",\"item\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/jurisprudences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cour sup\u00e9rieure de justice, 12 juin 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"name\":\"Kohen Avocats\",\"description\":\"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#organization\",\"name\":\"Kohen Avocats\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"contentUrl\":\"https:\\\/\\\/kohenavocats.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-2-1.webp\",\"width\":2114,\"height\":1253,\"caption\":\"Kohen Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/kohenavocats.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cour sup\u00e9rieure de justice, 12 juin 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/","og_locale":"zh_CN","og_type":"article","og_title":"Cour sup\u00e9rieure de justice, 12 juin 2017","og_description":"Arr\u00eat N\u00b0 83\/17 - VIII - Travail Exempt \u2013 appel en mati\u00e8re de droit du travail Audience publique du douze juin deux mille dix -sept Num\u00e9ro 43373 du r\u00f4le. Composition: Serge THILL, premier conseiller, pr\u00e9sident; Agn\u00e8s ZAGO, premier conseiller; Marie-Paule BISDORFF, conseiller; Alain BERNARD, greffier.\u2026","og_url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/","og_site_name":"Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","article_modified_time":"2026-05-01T22:21:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"24 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/","url":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/","name":"Cour sup\u00e9rieure de justice, 12 juin 2017 - Ma\u00eetre Hassan Kohen, avocat en droit p\u00e9nal \u00e0 Paris","isPartOf":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#website"},"datePublished":"2026-05-01T22:21:47+00:00","dateModified":"2026-05-01T22:21:51+00:00","breadcrumb":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/cour-superieure-de-justice-12-juin-2017-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kohenavocats.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Jurisprudences","item":"https:\/\/kohenavocats.com\/zh-hans\/jurisprudences\/"},{"@type":"ListItem","position":3,"name":"Cour sup\u00e9rieure de justice, 12 juin 2017"}]},{"@type":"WebSite","@id":"https:\/\/kohenavocats.com\/zh-hans\/#website","url":"https:\/\/kohenavocats.com\/zh-hans\/","name":"Kohen Avocats","description":"Ma\u00eetre Hassan Kohen, avocat p\u00e9naliste \u00e0 Paris, intervient exclusivement en droit p\u00e9nal pour la d\u00e9fense des particuliers, notamment en mati\u00e8re d\u2019accusations de viol. Il assure un accompagnement rigoureux d\u00e8s la garde \u00e0 vue jusqu\u2019\u00e0 la Cour d\u2019assises, veillant au strict respect des garanties proc\u00e9durales.","publisher":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kohenavocats.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/kohenavocats.com\/zh-hans\/#organization","name":"Kohen Avocats","url":"https:\/\/kohenavocats.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","contentUrl":"https:\/\/kohenavocats.com\/wp-content\/uploads\/2026\/01\/Logo-2-1.webp","width":2114,"height":1253,"caption":"Kohen Avocats"},"image":{"@id":"https:\/\/kohenavocats.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision\/811674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_decision"}],"about":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/types\/kji_decision"}],"wp:attachment":[{"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=811674"}],"wp:term":[{"taxonomy":"kji_country","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_country?post=811674"},{"taxonomy":"kji_court","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_court?post=811674"},{"taxonomy":"kji_chamber","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_chamber?post=811674"},{"taxonomy":"kji_year","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_year?post=811674"},{"taxonomy":"kji_subject","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_subject?post=811674"},{"taxonomy":"kji_keyword","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_keyword?post=811674"},{"taxonomy":"kji_language","embeddable":true,"href":"https:\/\/kohenavocats.com\/zh-hans\/wp-json\/wp\/v2\/kji_language?post=811674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}